{"id":100123,"date":"2017-10-31T00:42:56","date_gmt":"2017-10-30T22:42:56","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=100123"},"modified":"2017-10-31T01:07:16","modified_gmt":"2017-10-30T23:07:16","slug":"la-grande-mutation-souterraine-de-nos-societes-par-francois-leclerc","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2017\/10\/31\/la-grande-mutation-souterraine-de-nos-societes-par-francois-leclerc\/","title":{"rendered":"<b>LA GRANDE MUTATION SOUTERRAINE DE NOS SOCI\u00c9T\u00c9S<\/b>, par Fran\u00e7ois Leclerc"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9.<\/p><\/blockquote>\n<p>Nos soci\u00e9t\u00e9s mettent progressivement en place les instruments d\u2019un contr\u00f4le social sophistiqu\u00e9. Aliment\u00e9e par les r\u00e9v\u00e9lations sur la NSA am\u00e9ricaine, cette alarme a ensuite pris corps. Puis elle a \u00e9t\u00e9 confort\u00e9e en Chine, o\u00f9 ce contr\u00f4le s\u2019installe dans une version accomplie, sous les auspices d\u2019un comit\u00e9 ad hoc que pr\u00e9side Xi-Jinping, son nouvel empereur.<\/p>\n<p><!--more--><\/p>\n<p>Les projets d\u2019applications associant algorithmes et banques de donn\u00e9es massives se multiplient. En vertu de l\u2019application de ces nouvelles technologies et des progr\u00e8s substantiels de l\u2019Intelligence Artificielle, notre environnement a d\u00e9j\u00e0 consid\u00e9rablement chang\u00e9. Plus inqui\u00e9tant, nous ne nous en rendons m\u00eame pas compte, nous n\u2019en sommes pas la plupart du temps avertis, les recours contre des d\u00e9cisions pouvant nous \u00eatre pr\u00e9judiciables, ou le r\u00e9sultat d\u2019une erreur, n\u2019\u00e9tant tout simplement pas pr\u00e9vus. Particuli\u00e8rement sensibilis\u00e9s, des juristes nous interpellent \u00e0 cet \u00e9gard, mais sans \u00eatre entendus.<\/p>\n<p>La reconnaissance faciale est au premier rang de ces nouvelles applications ambivalentes, porteuses \u00e0 la fois d\u2019un service et d\u2019une menace. Le nouveau t\u00e9l\u00e9phone portable d\u2019Apple reconna\u00eetra le visage de son propri\u00e9taire et le d\u00e9bloquera, et pas question de le d\u00e9jouer en lui pr\u00e9sentant une photographie. Rien n\u2019interdira par contre \u00e0 un policier de le braquer sur le visage d\u2019un suspect pour pouvoir fouiller tous ses contenus ou \u00e0 un voleur pour acc\u00e9der sous la contrainte \u00e0 des donn\u00e9es financi\u00e8res. Coupl\u00e9e avec les r\u00e9seaux de cam\u00e9ras de surveillance, on pressent ce que permettra la biom\u00e9trie.<\/p>\n<p>Mais le principal risque n\u2019est pas l\u00e0. Il r\u00e9side dans la banalisation de la reconnaissance faciale, dans son utilisation marketing ainsi que polici\u00e8re. Tr\u00e8s avanc\u00e9s, les projets chinois montrent \u00e0 cet \u00e9gard que les deux s\u2019\u00e9paulent parfaitement. L&rsquo;association American Civil Liberties Union (ACLU) rel\u00e8ve que \u00ab\u00a0Il y a de vraies raisons de s&rsquo;inqui\u00e9ter du fait que la reconnaissance faciale se fraye progressivement un chemin dans notre culture et qu&rsquo;elle devienne un outil de surveillance d\u00e9tourn\u00e9\u00a0\u00bb. Des chercheurs de l&rsquo;universit\u00e9 de Georgetown de Washington ont d\u00e9j\u00e0 d\u00e9couvert qu&rsquo;environ 117 millions d&rsquo;adultes figuraient \u00e0 leur insu dans des bases de donn\u00e9es permettant la reconnaissance faciale utilis\u00e9es par les forces de l&rsquo;ordre.<\/p>\n<p>Le caract\u00e8re insidieux de nombre de ces nouvelles applications n\u2019est plus \u00e0 d\u00e9montrer. Prises isol\u00e9ment, elles peuvent conduire \u00e0 consid\u00e9rer comme n\u00e9gligeable la menace qu\u2019elles repr\u00e9sentent\u00a0; mises toutes ensemble, cela prend une autre dimension et devient une toute autre affaire. Banalis\u00e9es, procurant en contrepartie un service r\u00e9el ou factice, leur d\u00e9ploiement \u00e0 grande \u00e9chelle en cours est au final accept\u00e9. Est-il encore temps de r\u00e9agir, le pli \u00e9tant pris ?<\/p>\n<p>La soci\u00e9t\u00e9 de surveillance ne repose sur la r\u00e9pression qu\u2019en seconde instance. En premi\u00e8re approche, elle vise \u00e0 rep\u00e9rer les comportements d\u00e9viants de toutes natures, pour mieux les enregistrer et si n\u00e9cessaire les punir. Plus fort encore, elle a pour objet d\u2019int\u00e9grer dans le comportement de tous la n\u00e9cessit\u00e9 de respecter des r\u00e8gles, chacun ayant conscience qu\u2019il est susceptible d\u2019\u00eatre rep\u00e9r\u00e9 s\u2019il d\u00e9vie des normes \u00e9tablies. Il n\u2019est plus possible d&rsquo;escompter l&rsquo;impunit\u00e9 en application du vieux principe \u00ab\u00a0pas vu, pas pris\u00a0!\u00a0\u00bb.<\/p>\n<p>Toutefois, une certaine d\u00e9fiance pourrait laisser esp\u00e9rer que l\u2019encadrement de l\u2019utilisation de ces nouvelles technologies finira par pr\u00e9valoir. Les GAFA alimentent pour leur part un mouvement de r\u00e9sistance, soucieux des r\u00e9actions de leur client\u00e8le et de prot\u00e9ger leur fonds de commerce. Mais il ne faut pas se leurrer, les r\u00e9v\u00e9lations explosives sur la NSA et ses homologues n\u2019ont strictement rien chang\u00e9 \u00e0 la surveillance qu\u2019ils continuent d\u2019exercer !<\/p>\n<p>Les hackers d\u2019aujourd\u2019hui n\u2019op\u00e8rent plus depuis leur garage comme de petits artisans. Les \u00c9tats ont pris le relais et la guerre a acquis une dimension \u00e9lectronique primordiale. Ayant fait le choix de s\u2019investir dans ce domaine, que peut-on attendre des plus hautes autorit\u00e9s ? qu\u2019elles prot\u00e8gent la vie priv\u00e9e de leurs citoyens ou qu\u2019elles en fassent leur miel ? Il est loin le temps o\u00f9 les gr\u00e9vistes pouvaient d\u00e9jouer les charges \u00e0 cheval des gendarmes mobiles en lan\u00e7ant des billes sous les pattes de leurs montures. Les leviers de la soci\u00e9t\u00e9 de contr\u00f4le et de surveillance sont aujourd\u2019hui inaccessibles, prot\u00e9g\u00e9s par le plus opaque des Secret d\u00e9fense&#8230;<\/p>\n<p>En son temps, la R\u00e9publique d\u00e9mocratique allemande (RDA) a repr\u00e9sent\u00e9 le nec plus ultra de ce contr\u00f4le \u00e0 tr\u00e8s grande \u00e9chelle avec des moyens qui apparaissent aujourd\u2019hui surann\u00e9s. Mais l\u2019appareil de coercition d\u00e9ploy\u00e9 n\u2019employait que pour partie les \u00e9coutes et les filatures, comme il a \u00e9t\u00e9 constat\u00e9 \u00e0 l\u2019ouverture des dossiers de la Stasi. Les \u00e9l\u00e9ments \u00e0 charge reposaient en premier lieu sur les d\u00e9nonciations de <i>bons citoyens<\/i> endoctrin\u00e9s, souvent de proches amis et m\u00eame des membres de la famille.<\/p>\n<p>Enfin, la r\u00e9pression n\u2019est jamais plus forte que lorsqu\u2019elle est int\u00e9rioris\u00e9e, car il ne reste plus alors que des petites minorit\u00e9s de rebelles \u00e0 traiter par des moyens plus conventionnels, dans lesquelles la majorit\u00e9 ne se reconnait pas et qu\u2019il est facile d\u2019isoler pour les r\u00e9primer.<\/p>\n<p>\u00ab Moi, je n\u2019ai rien \u00e0 cacher\u00a0\u00bb r\u00e9pondent les na\u00effs qui n\u2019y voient pas malice.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. Nos soci\u00e9t\u00e9s mettent progressivement en place les instruments d\u2019un contr\u00f4le social sophistiqu\u00e9. Aliment\u00e9e par les r\u00e9v\u00e9lations sur la NSA am\u00e9ricaine, cette alarme a ensuite pris corps. Puis elle a \u00e9t\u00e9 confort\u00e9e en Chine, o\u00f9 ce contr\u00f4le s\u2019installe dans une version accomplie, sous les auspices d\u2019un comit\u00e9 ad hoc que pr\u00e9side Xi-Jinping, son nouvel [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2597,2668,725],"tags":[3538],"class_list":["post-100123","post","type-post","status-publish","format-standard","hentry","category-democratie-2","category-guerre-civile-numerique","category-technologie-2","tag-hyper-surveillance"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/100123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=100123"}],"version-history":[{"count":17,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/100123\/revisions"}],"predecessor-version":[{"id":100141,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/100123\/revisions\/100141"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=100123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=100123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=100123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}