{"id":100567,"date":"2017-11-13T11:12:16","date_gmt":"2017-11-13T10:12:16","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=100567"},"modified":"2017-11-13T11:13:13","modified_gmt":"2017-11-13T10:13:13","slug":"le-colloque-walter-lippmann-aux-origines-du-neo-liberalisme-par-serge-audier-x-vers-un-liberalisme-constructeur","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2017\/11\/13\/le-colloque-walter-lippmann-aux-origines-du-neo-liberalisme-par-serge-audier-x-vers-un-liberalisme-constructeur\/","title":{"rendered":"Le colloque Walter Lippmann&nbsp;: aux origines du \u00ab\u00a0n\u00e9o-lib\u00e9ralisme\u00a0\u00bb, par Serge Audier (X), Vers un \u00ab\u00a0lib\u00e9ralisme constructeur\u00a0\u00bb"},"content":{"rendered":"<blockquote>\n<p class=\"p1\"><b>Le colloque Walter Lippmann : aux origines du \u00ab\u00a0n\u00e9o-lib\u00e9ralisme\u00a0\u00bb<\/b>, pr\u00e9face de Serge Audier &#8211; Penser le\u00a0\u00ab\u00a0n\u00e9o-lib\u00e9ralisme\u00a0\u00bb, \u00e9ditions Le bord de l\u2019eau, 2012. Madeleine Th\u00e9odore nous propose un r\u00e9sum\u00e9 en plusieurs parties de cette r\u00e9flexion essentielle. Ouvert aux commentaires.<\/p>\n<\/blockquote>\n<p class=\"p1\"><span class=\"s1\"> La n\u00e9cessit\u00e9 de promouvoir un \u00ab\u00a0lib\u00e9ralisme constructeur\u00a0\u00bb devient un th\u00e8me li\u00e9 au discours de <a href=\"https:\/\/www.pauljorion.com\/blog\/2017\/11\/05\/le-colloque-walter-lippmann-aux-origines-du-neo-liberalisme-par-serge-audier-v-louis-rougier-1889-1982\/\" target=\"_blank\" rel=\"noopener\">Louis Rougier<\/a>. Il avait voulu, dans les ann\u00e9es 1930, d\u00e9passer les diff\u00e9rentes \u00ab\u00a0mystiques\u00a0\u00bb dans le domaine \u00e9conomique (<i>La Mystique d\u00e9mocratique, ses origines, ses illusions<\/i>, 1929). <!--more-->\u00ab\u00a0La m\u00e9thode d\u2019analyse logique s\u2019applique aux doctrines qui, g\u00e9n\u00e9ralement, m\u00e9langent deux sortes de propositions: des jugements th\u00e9oriques et des r\u00e8gles d\u2019action. En ce qui concerne les premiers, il convient d\u2019examiner dans quelle mesure ils sont fond\u00e9s sur l\u2019exp\u00e9rience et en ce qui concerne les secondes, il faut examiner si les fins qu\u2019elles proposent sont compatibles<span class=\"Apple-converted-space\">\u00a0 <\/span>et si les moyens qu\u2019elles pr\u00e9conisent sont adapt\u00e9s \u00e0 ces fins\u00a0\u00bb. Ainsi, le \u00ab\u00a0laisser-faire, laisser-passer\u00a0\u00bb n\u2019est pas une condition sine qua non de l\u2019\u00e9conomie de march\u00e9\u00a0\u00bb. Par ailleurs, les moyens que le socialisme pr\u00e9conise sont mal adapt\u00e9s aux fins g\u00e9n\u00e9reuses qu\u2019il poursuit.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Pour Rougier, il exige une \u00ab\u00a0mystique lib\u00e9rale\u00a0\u00bb, tout comme il y a une \u00ab\u00a0mystique corporative\u00a0\u00bb ou une \u00ab\u00a0mystique marxiste\u00a0\u00bb.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> \u00ab\u00a0Le \u00ab\u00a0lib\u00e9ralisme constructeur\u00a0\u00bb n\u2019aura rien \u00e0 voir avec le socialisme lib\u00e9ral, qui est une contradiction dans les termes : le socialisme est autoritaire ou il n\u2019est pas, et l\u2019on ne peut d\u00e9fendre les droits de l\u2019homme et du citoyen tout en planifiant l\u2019\u00e9conomie\u00a0\u00bb. Rougier d\u00e9fend la Cit\u00e9 libre, en r\u00e9f\u00e9rence \u00e0 l\u2019ouvrage de Lippmann, avec une allusion appuy\u00e9e \u00e0 l\u2019Antiquit\u00e9. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Dans sa critique de la \u00ab\u00a0mystique lib\u00e9rale\u00a0\u00bb, Rougier rappelle que la science \u00e9conomique d\u00e9montre que le maximum de satisfaction pour les \u00e9changistes est r\u00e9alis\u00e9 en r\u00e9gime de libre concurrence. La question laiss\u00e9e dans l\u2019ombre est la suivante, que les th\u00e9oriciens de l\u2019Economie optimiste ne posent pas : \u00ab\u00a0A un moment donn\u00e9, pour une soci\u00e9t\u00e9 donn\u00e9e, la distribution du pouvoir d\u2019achat est-elle la plus d\u00e9sirable possible et l\u2019Etat ne doit-il pas intervenir pour la modifier ?\u00a0\u00bb.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> La th\u00e9orie du \u00ab\u00a0laisser-faire, laisser-passer\u00a0\u00bb de l\u2019 Economie optimiste peut \u00eatre appel\u00e9e la \u00ab\u00a0premi\u00e8re mystique \u00e9conomique en date\u00a0\u00bb. Cette vision ne trouve pas ses sources dans l\u2019observation et l\u2019exp\u00e9rience, mais dans une matrice th\u00e9ologique ou m\u00e9taphysique. Chez les Physiocrates, elle est sous-tendue par la croyance en un \u00ab\u00a0ordre naturel et essentiel des soci\u00e9t\u00e9s humaines\u00a0\u00bb, r\u00e9sultat spontan\u00e9 des lois institu\u00e9es par Dieu et la nature. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Rougier \u00e9tablit, contre le dogmatisme lib\u00e9ral, la port\u00e9e et les limites de la \u00ab\u00a0science \u00e9conomique\u00a0\u00bb. Celle-ci indique comment l\u2019\u00e9quilibre s\u2019\u00e9tablit mais elle ne cherche pas \u00e0 le comprendre, ni \u00e0 le modifier. Elle ne se soucie pas de savoir si la distribution est la plus juste possible, pour, selon Pareto, l\u2019\u00e9quilibre sociologique du pays. Il faut r\u00e9int\u00e9grer les probl\u00e8mes \u00e9conomiques dans l\u2019ensemble des probl\u00e8mes politiques. L\u2019erreur de l\u2019\u00e9cole optimiste m\u00e9thodologique est qu\u2019elle se pr\u00e9sente comme une th\u00e9orie sociologique. Il y a un postulat implicite, le primat de l\u2019\u00e9conomique sur le politique, que l\u2019on retrouve, en vue d\u2019autres utilisations, dans le mat\u00e9rialisme historique de Karl Marx. Cette \u00ab\u00a0mystique \u00e9conomique\u00a0\u00bb <\/span><span class=\"s1\">m\u00e9conna\u00eet ou sous-estime par ailleurs l\u2019importance du facteur national : les populations restent cloisonn\u00e9es en nations, et un protectionnisme peut se justifier en ce sens, y compris du point de vue des lib\u00e9raux. Apr\u00e8s tout, c\u2019est Adam Smith lui-m\u00eame qui jugeait que \u00ab\u00a0la s\u00e9curit\u00e9 vaut mieux que la richesse\u00a0\u00bb, au point de voir dans l\u2019\u00ab\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Actes_de_navigation\" target=\"_blank\" rel=\"noopener\">Act of Navigation<\/a>\u00a0\u00bb, une des mesures les plus sages qu\u2019ait prises l\u2019Angleterre. De m\u00eame, un pays peut faire le choix de sauver l\u2019un de ses groupes sociaux menac\u00e9s, par exemple la paysannerie.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Mais cela ne signifie pas que toute intervention de l\u2019Etat soit recommandable. Les interventionnistes raisonnent \u00e0 priori en faisant abstraction du contexte global. La t\u00e2che des hommes d\u2019Etat est de voir la solidarit\u00e9 des probl\u00e8mes et de rester ind\u00e9pendants \u00e0 l\u2019\u00e9gard des entra\u00eenements aveugles de majorit\u00e9s passag\u00e8res irresponsables qui ne repr\u00e9sentent que par une fiction contestable, les int\u00e9r\u00eats permanents d\u2019une nation. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Une autre erreur de la \u00ab\u00a0mystique lib\u00e9rale\u00a0\u00bb qui ob\u00e8re enti\u00e8rement sa capacit\u00e9 \u00e0 pr\u00e9coniser des politiques \u00e9conomiques pertinentes est que son discours est sous-tendu par un partage strict entre deux domaines de l\u2019activit\u00e9 collective : le premier serait soumis \u00e0 la loi, tandis que le second serait soustrait \u00e0 toute r\u00e8glementation juridique. Or, l\u2019erreur est patente : la propri\u00e9t\u00e9, l\u2019h\u00e9ritage, les contrats, la monnaie\u2013 sont des cr\u00e9ations de la loi, n\u2019existent que par un ensemble de droits, de garanties et d\u2019obligations sanctionn\u00e9es par l\u2019autorit\u00e9 de l\u2019Etat. Cette erreur \u00e9claire l\u2019\u00e9volution de plus en plus conservatrice de l\u2019Ecole lib\u00e9rale, alors qu\u2019elle \u00e9tait apparue sous un jour progressiste. L\u2019erreur des lib\u00e9raux manchest\u00e9riens fut de prendre l\u2019ordre social r\u00e9gnant \u00e0 leur \u00e9poque pour un ordre absolu et \u00e9ternel, de transformer le r\u00e9gime de la propri\u00e9t\u00e9 et des contrats de leur temps en un droit imprescriptible et naturel. Ce faisant, ils devinrent conformistes et conservateurs. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> L\u2019\u00e9conomie lib\u00e9rale, loin d\u2019\u00eatre \u00ab\u00a0abstentionniste\u00a0\u00bb, suppose un mode juridique, actif et progressiste. Le probl\u00e8me de l\u2019interventionnisme tient \u00e0 son caract\u00e8re essentiellement conservateur : il a eu pour effet de r\u00e9sister au progr\u00e8s de la technique et de l\u2019organisation scientifique, traduisant une d\u00e9fiance extr\u00eame envers le machinisme et un rejet de l\u2019inventivit\u00e9 technique. Il a \u00e9touff\u00e9 les brevets d\u2019invention en mena\u00e7ant d\u2019ostracisme les inventeurs. Il faut assurer plusieurs types d\u2019adaptations \u00e9conomiques et sociales que le vieux lib\u00e9ralisme r\u00e9alisait mal : celle de la production aux besoins r\u00e9els rendus solvables, celle de l\u2019\u00e9pargne enfin prot\u00e9g\u00e9e aux besoins d\u2019investissement des entreprises conditionn\u00e9s par la demande, et enfin celle de l\u2019emploi de la main d\u2019oeuvre, progressivement lib\u00e9r\u00e9e, aux possibilit\u00e9s r\u00e9elles<span class=\"Apple-converted-space\">\u00a0 <\/span>de la technique productive et du march\u00e9.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Rougier reprend \u00e0 son compte la distinction de Lippmann : l\u2019Etat socialiste \u00ab\u00a0administre les affaires des hommes\u00a0\u00bb, l\u2019Etat lib\u00e9ral \u00ab\u00a0administre la justice entre les hommes\u00a0qui m\u00e8nent eux-m\u00eames leurs propres affaires\u00a0\u00bb.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Quant \u00e0 la justice sociale, le jeu r\u00e9gulateur des forces \u00e9conomiques conduit \u00e0 \u00e9galiser les conditions, non par nivellement mais gr\u00e2ce au renforcement des classes moyennes. Celles-ci absorbent progressivement la masse des prol\u00e9taires et la \u00ab\u00a0classe abusive\u00a0\u00bb des grands capitalistes.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> En d\u00e9finitive, le \u00ab\u00a0lib\u00e9ralisme constructeur\u00a0\u00bb reconna\u00eet le caract\u00e8re b\u00e9n\u00e9fique de l\u2019ing\u00e9rence juridique de l\u2019Etat, mais dans des buts bien pr\u00e9cis. Rougier utilise une m\u00e9taphore, celle du code de la route : \u00ab\u00a0Le lib\u00e9ralisme manchest\u00e9rien pourrait se comparer \u00e0 un r\u00e9gime routier qui laisserait les autos circuler \u00e0 leur guise sans code de la route : les encombrements, les embarras de la circulation, les accidents seraient innombrables, \u00e0 moins que les grosses voitures n\u2019exigent que les plus petites c\u00e9dassent toujours la route, ce qui serait la loi de la jungle. L\u2019Etat socialiste est semblable \u00e0 un r\u00e9gime de circulation o\u00f9 une autorit\u00e9 centrale fixerait imp\u00e9rativement \u00e0 chacun quand il doit sortir sa voiture, o\u00f9 il doit se rendre et par quel chemin. L\u2019Etat v\u00e9ritablement lib\u00e9ral est celui o\u00f9 les automobilistes sont libres d\u2019aller o\u00f9 bon leur semble mais en respectant le code de la route\u00a0\u00bb. Pour Rougier, tout se passe comme s\u2019il fallait opter entre les deux modalit\u00e9s de \u00ab\u00a0socialisme autoritaire\u00a0\u00bb : le fascisme et le communisme.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> L\u2019enterrement du lib\u00e9ralisme constitue une catastrophe sur tous les plans. Les Etats totalitaires, pour \u00e9tablir une planification rationnelle et g\u00e9n\u00e9ralis\u00e9e de la production, mettent en place une \u00e9conomie de guerre g\u00e9n\u00e9ratrice d\u2019appauvrissement g\u00e9n\u00e9ralis\u00e9. Les producteurs n\u2019ont plus, \u00e0 la limite, pour seul client que l\u2019Etat. De m\u00eame, les consommateurs tendent \u00e0 n\u2019avoir plus pour fournisseur que l\u2019Etat, et c\u2019est encore celui-ci qui devient \u00ab\u00a0le seul patron des travailleurs\u00a0\u00bb.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Il s\u2019agit de prendre conscience du projet d\u00e9mocratique en lui-m\u00eame quant \u00e0 son ambigu\u00eft\u00e9. Si le premier principe, d\u2019essence lib\u00e9rale, est une garantie absolument indispensable de la libert\u00e9 individuelle et publique, le second principe, d\u00e9mocratique, porterait avec lui les pires menaces. Celles-ci apparaissent chez Jean-Jacques Rousseau, qui aurait vulgaris\u00e9 le principe majoritaire en y ajoutant le double sophisme du dogme indiscutble de la volont\u00e9 g\u00e9n\u00e9rale et de son identit\u00e9 avec la volont\u00e9 particuli\u00e8re d\u2019un chacun, en tant que celle-ci est appel\u00e9e \u00e0 se prononcer sur l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Il faut d\u00e9truire plusieurs pr\u00e9jug\u00e9s sur le lib\u00e9ralisme. Le premier consiste \u00e0 croire que les processus de l\u2019histoire humaine sont irr\u00e9versibles. Le second r\u00e9side dans la conviction que l\u2019Etat \u00ab\u00a0ne peut pas d\u00e9truire la richesse\u00a0\u00bb mais qu\u2019il faut seulement \u00ab\u00a0la distribuer plus \u00e9quitablement\u00a0\u00bb. La plus grande menace qui p\u00e8se sur l\u2019Occident, c\u2019est l\u2019interventionnisme \u00e9tatique g\u00e9n\u00e9ralis\u00e9. Rougier s\u2019appuie sur les sages que sont Bertrand Russell, Jos\u00e9 Ortega y Gasset, Aldous Huxley, Guglielmo Ferrero. Si les d\u00e9mocraties veulent se sauver, il faut qu\u2019elles optent en faveur du principe de la limitation des droits de l\u2019Etat et le mettent \u00e0 la base du droit constitutionnel et du droit. L\u2019histoire a d\u00e9j\u00e0 d\u00e9montr\u00e9 que l\u2019Etat n\u2019a acquis respect et force que durant la p\u00e9riode o\u00f9 il s\u2019est limit\u00e9 \u00e0 ses fonctions propres.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> Le plaidoyer de Rougier pour un retour au lib\u00e9ralisme s\u2019exprime dans un compte-rendu de trois livres : \u00ab\u00a0Le Socialisme\u00a0\u00bb de von Mises, \u00ab\u00a0La Cit\u00e9 libre\u00a0\u00bb de Lippmann et le sien propre. Ils montrent tous les trois que c\u2019est le choix entre lib\u00e9ralisme et totalitarisme qui est l\u2019alternative pertinente. Rougier souligne d\u2019abord l\u2019apport du livre de von Mises, qui a r\u00e9fut\u00e9 sur un plan strictement scientifique les pr\u00e9dictions du marxisme en les r\u00e9duisant \u00e0 n\u00e9ant : le socialisme n\u2019est pas r\u00e9alisable. La notion d\u2019\u00e9conomie politique implique celle de calcul \u00e9conomique : les prix de consommation expriment le taux de d\u00e9sid\u00e9rabilit\u00e9 finale de chaque produit et de chaque service en concurrence sur le march\u00e9. L\u2019ordre lib\u00e9ral r\u00e8gne en vue de satisfaire les consommateurs de la fa\u00e7on la plus appropri\u00e9e \u00e0 leurs besoins, il y aurait correspondance \u00e9troite entre la d\u00e9mocratie des consommateurs et la d\u00e9mocratie lib\u00e9rale. Du c\u00f4t\u00e9 constructeur du lib\u00e9ralisme, Rougier valorise Lippmann : la vie \u00e9conomique se d\u00e9roule dans un cadre juridique pr\u00e9alable, les masses seraient sur le point de d\u00e9truire le syst\u00e8me \u00e9conomique qui a pourtant permis \u00e0 la population de l\u2019Europe de tripler en un si\u00e8cle et \u00e0 celle des Etats-Unis de quadrupler, avec un niveau de vie toujours accru. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le colloque Walter Lippmann : aux origines du \u00ab\u00a0n\u00e9o-lib\u00e9ralisme\u00a0\u00bb, pr\u00e9face de Serge Audier &#8211; Penser le\u00a0\u00ab\u00a0n\u00e9o-lib\u00e9ralisme\u00a0\u00bb, \u00e9ditions Le bord de l\u2019eau, 2012. Madeleine Th\u00e9odore nous propose un r\u00e9sum\u00e9 en plusieurs parties de cette r\u00e9flexion essentielle. Ouvert aux commentaires. La n\u00e9cessit\u00e9 de promouvoir un \u00ab\u00a0lib\u00e9ralisme constructeur\u00a0\u00bb devient un th\u00e8me li\u00e9 au discours de Louis Rougier. Il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5318],"tags":[5649,2784],"class_list":["post-100567","post","type-post","status-publish","format-standard","hentry","category-ultraliberalisme","tag-louis-rougier","tag-walter-lippmann"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/100567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=100567"}],"version-history":[{"count":4,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/100567\/revisions"}],"predecessor-version":[{"id":100575,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/100567\/revisions\/100575"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=100567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=100567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=100567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}