{"id":101573,"date":"2017-12-24T15:06:20","date_gmt":"2017-12-24T14:06:20","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=101573"},"modified":"2017-12-22T18:07:45","modified_gmt":"2017-12-22T17:07:45","slug":"maintenant-que-la-plaisanterie-touche-a-sa-fin-iv-phil-glass","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2017\/12\/24\/maintenant-que-la-plaisanterie-touche-a-sa-fin-iv-phil-glass\/","title":{"rendered":"Maintenant que la plaisanterie touche \u00e0 sa fin (IV) Phil Glass"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/6Stu7h7Qup8\" frameborder=\"0\" gesture=\"media\" allow=\"encrypted-media\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[2218],"class_list":["post-101573","post","type-post","status-publish","format-standard","hentry","category-arts","tag-phil-glass"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/101573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=101573"}],"version-history":[{"count":1,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/101573\/revisions"}],"predecessor-version":[{"id":101574,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/101573\/revisions\/101574"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=101573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=101573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=101573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}