{"id":102524,"date":"2018-02-07T14:20:03","date_gmt":"2018-02-07T13:20:03","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=102524"},"modified":"2018-02-24T09:21:47","modified_gmt":"2018-02-24T08:21:47","slug":"le-temps-quil-fait-le-2-fevrier-retranscription","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2018\/02\/07\/le-temps-quil-fait-le-2-fevrier-retranscription\/","title":{"rendered":"LE TEMPS QU&rsquo;IL FAIT LE 2 F\u00c9VRIER 2018 &#8211; Retranscription"},"content":{"rendered":"<blockquote><p>Retranscription de <a href=\"https:\/\/www.pauljorion.com\/blog\/2018\/02\/02\/le-temps-quil-fait-le-2-fevrier-2018\/\" target=\"_blank\" rel=\"noopener\">Le temps qu&rsquo;il fait le 2 f\u00e9vrier 2018<\/a>. Merci \u00e0 Marianne Oppitz et Catherine Cappuyns.<\/p><\/blockquote>\n<p>Bonjour, nous sommes le vendredi 2 f\u00e9vrier 2018 et je ne sais pas si c\u2019est la m\u00eame chose chez vous, mais ici en Bretagne, \u00e0 Vannes, eh bien, il a gel\u00e9 cette nuit. Alors, un beau d\u00e9menti \u00e0 la face des gens qui vous parlent de r\u00e9chauffement climatique puisqu\u2019il a gel\u00e9 dans la r\u00e9gion du Morbihan cette nuit.<\/p>\n<p><!--more-->Bon, je sais que je ne devrais pas faire ce genre de plaisanterie parce qu\u2019il y a des gens qui tombent sur la vid\u00e9o pour la premi\u00e8re fois, qui vont prendre \u00e7a au s\u00e9rieux (rires), qui vont m\u2019\u00e9crire des mails enflamm\u00e9s. Ce fut le cas quand j\u2019ai dit aux gens\u00a0: \u00ab\u00a0Arrangez-vous pour surtout ne pas avoir de retraite\u00a0\u00bb. Il y a quelqu\u2019un qui m\u2019a dit\u00a0:\u00a0\u00ab\u00a0Comment osez-vous dire \u00e7a\u00a0?\u00a0\u00bb. Heureusement, dans l\u2019autre sens, il y a quelqu\u2019un qui a dit\u00a0: \u00ab\u00a0N\u2019encouragez pas les gens \u00e0 votre imprudence\u00a0!\u00a0\u00bb, en roulant de gros yeux et en m\u2019envoyant de nombreux mails \u00e0 ce sujet.<\/p>\n<p>Vous avez d\u00fb voir ce chiffre\u00a0: Monsieur Trump a retir\u00e9 72\u00a0% du budget consacr\u00e9 aux \u00e9nergies renouvelables. Et, par cons\u00e9quent, on va mettre le paquet, aux \u00c9tats-Unis, sur le p\u00e9trole et probablement \u00e9galement sur le charbon qui est une ressource naturelle et qui n\u2019exige pas que les Chinois s\u2019en m\u00ealent. Alors, on est bien parti\u00a0!<\/p>\n<p>Et puisqu\u2019on parle de la Chine, une puissance qui monte, petit \u00e0 petit, depuis, voil\u00e0, 1945, avec pas mal d\u2019\u00e0-coups, pas mal de drames mais qui refait son chemin. Et, en face de \u00e7a, on a une puissance internationale qui tombe en vrille sous les coups de son pr\u00e9sident d\u00e9mocratiquement \u00e9lu. Ils vont se croiser bient\u00f4t. La Chine va bient\u00f4t devenir, bien entendu, la premi\u00e8re puissance \u00e9conomique dans un contexte comme celui-l\u00e0. Ah\u00a0! Non, j\u2019oubliais\u00a0! J\u2019allais encore faire une plaisanterie (rires). J\u2019allais dire\u00a0: j\u2019oubliais que Monsieur Trump permet aux entreprises d\u2019acc\u00e9l\u00e9rer la concentration de la richesse en baissant leurs imp\u00f4ts. \u00c7a va participer bien entendu \u00e0 ce mouvement\u2026 vous verrez dans un article que je publie la semaine prochaine dans Trends\u2026 Ah, ben non, \u00e7a a d\u00fb para\u00eetre\u2026 \u00e7a a d\u00fb para\u00eetre hier, en fait. Enfin bon\u00a0! On verra, je donne les chiffres de la richesse aux \u00c9tats-Unis et, c\u2019est abominable\u00a0: il ne reste pratiquement plus rien \u00e0 la moiti\u00e9 la plus pauvre des \u00c9tats-Unis. Les 40\u00a0% des moins riches aux \u00c9tats-Unis, ne poss\u00e8dent rien, comme patrimoine. Pourquoi\u00a0? Parce que dans les 40\u00a0%, il y en a beaucoup qui doivent de l\u2019argent \u00e0 quelqu\u2019un d\u2019autre. Et dans l\u2019ensemble, les 40\u00a0% les moins riches n\u2019ont absolument rien de la richesse nationale. Quand on monte \u00e0 50, alors on grappille quelques pourcents [P.J. m\u00eame pas\u00a0: 1,1%]. [1,1%] pour la moiti\u00e9 la moins riche des \u00c9tats-Unis et, Monsieur Trump met un coup d\u2019acc\u00e9l\u00e9rateur dans ce sens l\u00e0. \u00c7\u00e0 va \u00eatre joli\u00a0! Sans parler de tout le reste\u00a0: le d\u00e9tricotage de tout ce qu\u2019on peut faire pour essayer de sauver la plan\u00e8te. Si vous \u00eates Am\u00e9ricains et, vous le savez, j\u2019ai des Am\u00e9ricains dans ma famille, excusez-moi\u00a0: r\u00e9veillez-vous\u00a0! Il y a un monsieur qui essaye de lancer un impeachment contre votre pr\u00e9sident. Il y a des choses qui suivent leur cours, je sais bien, mais ce type fait du d\u00e9g\u00e2t tous les jours. Si vous \u00eates Am\u00e9ricains, faites quelque chose\u00a0!<\/p>\n<p>Faites quelque chose, voil\u00e0, dans les minutes qui suivent le moment o\u00f9 vous m\u2019avez vu. Tout \u00e7a est tr\u00e8s, tr\u00e8s grave. Ce n\u2019est pas que j\u2019aie de l\u2019antipathie pour la Chine, mais quand elles se croiseront \u00e0 une telle vitesse, la Chine \u00e0 monter et les \u00c9tats-Unis \u00e0 descendre, alors que les \u00c9tats-Unis sont encore une grande puissance militaire, la plus grande puissance militaire, tout \u00e7a peut faire d\u2019\u00e9normes d\u00e9g\u00e2ts. Il y a quelqu\u2019un qui m\u2019\u00e9crivait hier pour me rappeler \u00e7a, il se reconna\u00eetra au passage. Oui, bien entendu\u00a0! Oui, bien entendu\u00a0!<\/p>\n<p>De quoi voulais-je vous parler\u00a0d\u2019autre? Hier, j\u2019\u00e9tais \u00e0 Brest, aux <a href=\"http:\/\/www.lesgeopolitiques.com\/les-geopolitiques-de-brest.php\" target=\"_blank\" rel=\"noopener\">G\u00e9opolitiques de Brest<\/a>. Nous \u00e9tions trois \u00e0 parler dans l\u2019apr\u00e8s-midi. J\u2019\u00e9tais le premier \u00e0 parler et je voudrais encore remercier la personne qui m\u2019a pr\u00e9sent\u00e9 parce que \u00e7a fait plaisir quand on est pr\u00e9sent\u00e9 avec de l\u2019information correcte. Le fait que ce soit tr\u00e8s flatteur n\u2019est pas g\u00eanant, mais surtout qu\u2019on explique bien qui vous \u00eates et qu\u2019on souligne les avantages que \u00e7a a, comme acc\u00e8s \u00e0 la connaissance, d\u2019\u00eatre un franc tireur, ce que l\u2019on mettra encore sur mon prochain bouquin \u00ab\u00a0Qui \u00e9tions-nous\u00a0?\u00a0\u00bb.<\/p>\n<p>De quoi j\u2019ai parl\u00e9\u00a0? De quoi les autres parlaient aussi\u00a0? Eh bien, c\u2019\u00e9tait le bilan apr\u00e8s 10 ans de la crise, le 10e anniversaire de la crise de 2008. Est-ce qu\u2019on a fait quelque chose\u00a0? Est-ce qu\u2019on n\u2019a pas fait grand-chose\u00a0? Eh bien, vous savez ce que j\u2019ai d\u00fb dire\u00a0: incomp\u00e9tence, biais id\u00e9ologique, science \u00e9conomique dans un pi\u00e8tre \u00e9tat et qui nous dit pas mal de fadaises. Madame <a href=\"http:\/\/www.cepii.fr\/CEPII\/fr\/page_perso\/page_perso.asp?nom_complet=J%C3%A9zabel+Couppey-Soubeyran\" target=\"_blank\" rel=\"noopener\">J\u00e9zabel Couppey-Soubeyran<\/a> qui m\u2019a suivi, en fait, a r\u00e9p\u00e9t\u00e9 \u00e0 peu pr\u00e8s la m\u00eame chose, dans une perspective peut-\u00eatre un peu plus, je dirais, aimable envers les autorit\u00e9s, mais en tout cas, pour ce qui \u00e9tait des faits, elle n\u2019a pas pu dire autre chose que ce que j\u2019ai pu rapporter.<\/p>\n<p>Vous \u00e9tiez tr\u00e8s nombreux. Vous \u00e9tiez 400 \u00e0 cela, l\u2019auditoire \u00e9tait plein. Il y avait des gens sur les escaliers mais, il faudrait quand m\u00eame ajouter qu\u2019un certain nombre d\u2019entre vous, des personnes qui \u00e9taient l\u00e0, hier, \u00e9taient des personnes qui \u00e9taient oblig\u00e9es pour un examen &#8211; ceci, cela \u2013 d\u2019\u00eatre l\u00e0. Et, l\u00e0, \u00e0 un moment donn\u00e9, au moment o\u00f9 j\u2019allais partir, Madeleine \u00e9tait assise au fond, et elle a quand m\u00eame attir\u00e9 mon attention sur le fait que beaucoup d\u2019\u00e9tudiants qui \u00e9taient l\u00e0 \u00e0 prendre des notes de mani\u00e8re compulsive (rires) sur ce qui \u00e9tait dit &#8211; ce n\u2019\u00e9tait pas mon expos\u00e9, je vous rassure, c\u2019\u00e9tait un expos\u00e9 suivant \u2013 faisaient vraiment tout autre chose qu\u2019\u00e9couter ceux qui \u00e9taient l\u00e0, ce qui se passait l\u00e0. Et \u00e7a, vous le savez, on vient maintenant au cours avec un ordinateur, ce qui vous permet de faire des tas de choses en m\u00eame temps, qui sont diff\u00e9rentes du cours.<\/p>\n<p>Et, on a bavard\u00e9 un peu de \u00e7a &#8211; Madeleine a \u00e9t\u00e9 professeur de lyc\u00e9e &#8211; et, moi, je me pose la question, moi qui n\u2019ai pas \u00e9t\u00e9 professeur de lyc\u00e9e mais professeur de l\u2019enseignement sup\u00e9rieur \u2013 comme on dit \u2013 et qui donne encore un cours, en ce moment, d\u2019\u00e9thique financi\u00e8re \u00e0 l\u2019Universit\u00e9 Catholique de Lille, est-ce qu\u2019il est encore n\u00e9cessaire de rassembler dans un auditoire, des gens, en leur disant qu\u2019ils vont \u00e9couter le <em>nec plus ultra <\/em>sur une question quelconque, parce qu\u2019il se fait que leurs professeurs d\u2019universit\u00e9 ou de lyc\u00e9e, savent de quoi il retourne\u00a0? Tout le monde sait &#8211; enfin, on le savait d\u00e9j\u00e0, on s\u2019en doutait d\u00e9j\u00e0 \u00e0 mon \u00e9poque, mais il \u00e9tait plus difficile d\u2019avoir acc\u00e8s aux textes proprement dit &#8211; ou sous forme audio, ou sous forme vid\u00e9o \u2013 qu\u2019il est quand m\u00eame tr\u00e8s rare, maintenant &#8211; c\u2019est exceptionnel &#8211; que vous soyez dans un auditoire et que la personne qui vous parle d\u2019un sujet soit la personne la plus autoris\u00e9e au monde et o\u00f9 la connaissance est la mieux exprim\u00e9e. Est-ce que cette forme d\u2019enseignement, est-ce qu\u2019elle a encore un sens aujourd\u2019hui\u00a0? Alors, vous allez me taper dessus si vous \u00eates enseignant, parce que vous ferez comme tout le monde dans un monde o\u00f9 le travail se rar\u00e9fie\u00a0: vous essayerez de justifier le fait que vous ne soyez pas remplac\u00e9 par un robot. Mais, permettez-moi, quand m\u00eame, de poser la question.<\/p>\n<p>Il y a un truc dont on a parl\u00e9 il y a quelques ann\u00e9es, on en parle encore, ce sont les <a href=\"https:\/\/www.elaee.com\/2014\/06\/12\/20306-mouc-moque-mohoque-mooc-kezako\" target=\"_blank\" rel=\"noopener\">MOOC<\/a> \u2013 Massive Open Online Course \u2013 si j\u2019ai bon souvenir. Un cours massif ouvert en ligne, voil\u00e0\u00a0! Et, il y a beaucoup de gens qui m\u2019ont parl\u00e9 de \u00e7a, autour de moi, dans les endroits o\u00f9 j\u2019enseigne, en disant\u00a0: \u00ab\u00a0On va faire \u00e7a\u00a0! On sera comme les autres, on aura un grand cours en ligne.\u00a0\u00bb<\/p>\n<p>Et puis, bien entendu, les \u00e9tudiants ou les gens qui veulent apprendre quelque chose ne sont pas stupides\u00a0! Qu\u2019est-ce qu\u2019ils font\u00a0? Eh bien ils vont au cours qui parle le mieux du sujet. Ce qui veut dire qu\u2019on est, l\u00e0 aussi, comme dans le reste de l\u2019\u00e9conomie maintenant, dans une perspective de \u00ab\u00a0The Winner Takes All\u00a0\u00bb, le vainqueur remporte tout. C\u2019est-\u00e0-dire qu\u2019il y a des cours &#8211; des MOOC &#8211; o\u00f9 tout le monde vient \u00e9couter, tout le monde vient voir comment \u00e7a marche, parce qu\u2019ils sont bien faits et puis il y en a d\u2019autres &#8211; tous ceux qui sont faits par le tout-venant &#8211; eh bien, ils ne sont pas de la meilleure qualit\u00e9 et comme c\u2019est ouvert et comme la comp\u00e9tition, la concurrence, joue pleinement, eh bien il n\u2019y a que quelques vainqueurs qui emportent toute la mise. Mais \u00e7a ne veut pas dire qu\u2019il ne faut pas essayer.<\/p>\n<p>Et moi j\u2019y r\u00e9fl\u00e9chissais parce que quand m\u00eame\u00a0: si j\u2019ai la chance que quand je fais un expos\u00e9 sur la finance, les gens \u00e9coutent, c\u2019est parce qu\u2019en g\u00e9n\u00e9ral, ils entendent l\u00e0 dire une chose pour la premi\u00e8re fois, parce qu\u2019il n\u2019y a pas tellement d\u2019endroits &#8211; il n\u2019y a pas tellement d\u2019endroits au monde &#8211; \u00e0 part mes cours et mes vid\u00e9os, o\u00f9 l\u2019on puisse entendre une critique de la finance comme je la fais.<\/p>\n<p>Je peux peut-\u00eatre dire un petit mot l\u00e0\u00a0: si \u00e7a vous int\u00e9resserait qu\u2019on fasse un cours en fran\u00e7ais ou en anglais ou les deux, sur la finance, comment \u00e7a marche vraiment, contactez-moi. Vous savez comment me contacter &#8211; sinon c\u2019est indiqu\u00e9 l\u00e0 sur le blog &#8211; d\u2019une mani\u00e8re ou d\u2019une autre, comment me contacter si \u00e7a vous int\u00e9resse vraiment. Parce que moi, je trouverais \u00e7a pas mal\u00a0: un cours critique de finance. Parce que vous le savez, quand on pose la question\u00a0: \u00ab\u00a0Qu\u2019est-ce qui a chang\u00e9 depuis dix ans dans les choses qui ont un rapport avec la crise, dans les cours de finance\u00a0?\u00a0\u00bb \u00c0 ma connaissance, je n\u2019ai rien vu qui change, on continue. On continue \u00e0 dire que la courbe \u00e0 terme des taux, c\u2019est une pr\u00e9diction qui va sans doute se r\u00e9aliser sur les taux qui vont avoir lieu. \u00c7a n\u2019a aucun sens d\u2019un point de vue scientifique. \u00c7a ne tient absolument pas debout, \u00e7a a \u00e9t\u00e9 r\u00e9fut\u00e9 par un million de th\u00e9ories scientifiques, en physique en particulier. Pourquoi est-ce qu\u2019on continue \u00e0 r\u00e9p\u00e9ter \u00e7a, alors que c\u2019\u00e9tait d\u00e9j\u00e0 tr\u00e8s dangereux en 2008, et que \u00e7a l\u2019est toujours\u00a0? Enfin bon, c\u2019est un exemple.<\/p>\n<p>Ce qui ne veut pas dire que ce n\u2019est pas int\u00e9ressant de se r\u00e9unir parfois. Comme quand Bruno Colmant et moi, il y a quelques semaines, on s\u2019est retrouv\u00e9s \u00e0 l\u2019Universit\u00e9 catholique de Lille. Le cours lui-m\u00eame, le d\u00e9bat qu\u2019on a eu devant les \u00e9tudiants en master d\u2019\u00e9conomie et finance n\u2019a pas \u00e9t\u00e9 film\u00e9 mais vous avez peut-\u00eatre vu, il y a <a href=\"https:\/\/www.pauljorion.com\/blog\/2018\/01\/30\/bruno-colmant-et-paul-jorion-a-luniversite-catholique-de-lille-le-23-janvier-2018\/\" target=\"_blank\" rel=\"noopener\">une petite vid\u00e9o<\/a> o\u00f9 on \u00e9tait interview\u00e9s par Didier Van Peteghem qui est le doyen de cette facult\u00e9 d\u2019\u00e9conomie et gestion-finance. Et l\u00e0 bon, on a eu une discussion et \u00e9videmment, je dirais, \u00e7a m\u00e9rite d\u2019\u00eatre vu. Parce que \u00e7a se compl\u00e8te quand m\u00eame pas mal. On ne dit pas la m\u00eame chose, sinon \u00e0 quoi \u00e7a sert\u00a0? on pourrait aussi bien inviter l\u2019un des deux. On n\u2019est pas d\u2019accord souvent sur les implications politiques de ce qu\u2019on dit, qui est la m\u00eame analyse parce qu\u2019on a en tout cas la conviction l\u2019un et l\u2019autre que l\u2019autre ne fait pas d\u2019erreurs techniques, mais voil\u00e0, \u00e7a \u00e9tend un peu plus la mani\u00e8re d\u2019envisager les choses puisqu\u2019on \u00e9tire un petit peu d\u2019un bord ou d\u2019un autre. Et, on m\u2019a dit que hier, sur un site, en ligne en tout cas, du magazine belge <em>Le Vif<\/em>, <a href=\"https:\/\/www.pauljorion.com\/blog\/2018\/02\/02\/le-vif-migrants-carrefour-1er-fevrier-2018\/\" target=\"_blank\" rel=\"noopener\">on parle de nos opinions<\/a> \u00e0 l\u2019un et \u00e0 l\u2019autre sur une certaine d\u00e9cadence, d\u00e9g\u00e9n\u00e9rescence, effondrement de notre soci\u00e9t\u00e9, qui pose la question de savoir &#8211; bon on en a discut\u00e9, Bruno Colmant et moi, ce n\u2019est pas un secret d\u2019\u00c9tat\u00a0&#8211; \u00ab\u00a0Est-ce qu\u2019il ne faudrait pas faire quelque chose, davantage, au niveau politique classique, en Belgique\u00a0?\u00a0\u00bb. Pourquoi en Belgique\u00a0? Parce qu\u2019on a un passeport belge tous les deux et donc ce serait l\u2019endroit o\u00f9 le faire. Je vais essayer de vous trouver aujourd\u2019hui l\u2019article qui a paru en ligne parce qu\u2019il est r\u00e9serv\u00e9 aux abonn\u00e9s du Vif et je vais vous montrer \u00e7a. Je vais d\u00e9couvrir moi-m\u00eame ce que Monsieur Mouton, le reporter, journaliste, aura fait de nos propos qui ont \u00e9t\u00e9 pris s\u00e9par\u00e9ment.<\/p>\n<p>Qu\u2019est-ce qu\u2019on peut faire\u00a0? Est-ce qu\u2019il faut se contenter, voil\u00e0, d\u2019annoncer les choses, comme je le fais en disant\u00a0: \u00ab\u00a0casse-cou, encore une connerie, etc.\u00a0\u00bb ou bien est-ce qu\u2019il faut quand m\u00eame, quand m\u00eame mettre la main \u00e0 la p\u00e2te dans la r\u00e9alit\u00e9 quotidienne, la politique, en sachant que \u00e7a ne donne pas grand-chose. En sachant qu\u2019il y a beaucoup de choses verrouill\u00e9es autour de nous, o\u00f9 on nous interdit tout simplement les retours en arri\u00e8re parce que ces braves gens de droite qui font les choses, ils sont tr\u00e8s intelligents et ils s\u2019arrangent d\u2019une mani\u00e8re ou d\u2019une autre pour qu\u2019on ne puisse pas renverser les d\u00e9cisions qu\u2019ils prennent.<\/p>\n<p>Bon, c\u2019est tout \u00e0 fait anti-d\u00e9mocratique mais vous savez, c\u2019est tr\u00e8s facile \u00e0 faire. J\u2019avais donn\u00e9 un exemple \u00e0 propos de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Centrale_nucl%C3%A9aire_de_Fessenheim\" target=\"_blank\" rel=\"noopener\">Fessenheim<\/a>. Vous dites, voil\u00e0, vous \u00e9crivez dans le texte\u00a0: \u00ab\u00a0il faut absolument que les questions de s\u00e9curit\u00e9 passent avant tout ! \u00bb. Et puis vous faites un petit contrat o\u00f9 vous dites\u00a0: \u00ab\u00a0s\u2019il y avait un probl\u00e8me de s\u00e9curit\u00e9, il faudrait qu\u2019on paie six milliards \u00e0 telle firme\u00a0\u00bb et bien entendu, le jour o\u00f9 on regarde, on se dit\u00a0: \u00ab\u00a0Eh bien, il y a le probl\u00e8me de s\u00e9curit\u00e9 mais on n\u2019a pas les six milliards, donc que voulez-vous qu\u2019on fasse\u00a0? Il y a un contrat en bonne et due forme ! \u00bb. C\u2019est comme \u00e7a que nos soci\u00e9t\u00e9s fonctionnent maintenant.<\/p>\n<p>Ce n\u2019est pas \u00e9vident de faire sauter <a href=\"https:\/\/www.pauljorion.com\/blog\/2014\/10\/14\/le-monde-leffet-de-cliquet-ennemi-de-la-democratie-le-mardi-14-octobre-2014\/\" rel=\"noopener\" target=\"_blank\">ces cliquets<\/a> parce que voil\u00e0 ces gens, c\u2019est une politique, ce sont ces Messieurs von Mises, von Hayek, conseillers \u00e0 certaines \u00e9poques &#8211; que ce soit la Hongrie ou que ce soit le Chili &#8211; conseillers \u00e0 certaines \u00e9poques de dictatures militaires, de r\u00e9gimes fascistes, etc. et dont nous consid\u00e9rons \u2013 j\u2019ajoute Monsieur Milton Friedman, hein, qui \u00e9tait aussi all\u00e9 donner de tr\u00e8s bons conseils et encenser Monsieur Pinochet \u2013 nous consid\u00e9rons que tous ces gens-l\u00e0 sont de braves d\u00e9mocrates, que ce n\u2019est pas du \u00ab\u00a0fascisme en col blanc\u00a0\u00bb comme je les appelle, que tout cela est relativement innocent, qu\u2019on peut dire du bien de Monsieur von Hayek dans des cours universitaires en particulier et que \u00e7a ne pose pas de probl\u00e8me : \u00ab\u00a0C\u2019est un penseur, n\u2019est-ce pas\u00a0?\u00a0\u00bb C\u2019est un penseur\u00a0? Non, non, non, c\u2019est un id\u00e9ologue, c\u2019est un ami des dictateurs fascistes et autres dictatures militaires.<\/p>\n<p>Non, non, tout cela, c\u2019est du c\u00f4t\u00e9 de Monsieur <a href=\"https:\/\/www.pauljorion.com\/blog\/2007\/03\/25\/le-philosophe-h\/\" rel=\"noopener\" target=\"_blank\">Heidegger<\/a>. Monsieur Heidegger n\u2019\u00e9tait pas un Nazi comme \u00e7a par hasard parce qu\u2019il fallait bien prendre une carte de parti. Monsieur Heidegger, si vous ne le savez pas encore, ce n\u2019est pas seulement un penseur nazi, c\u2019est aussi le penseur du nazisme au niveau de la philosophie. Quand on a voulu faire du nazisme une philosophie, on en a fait le syst\u00e8me de Heidegger. Et je le disais l\u2019autre jour \u00e0 quelques amis\u00a0: \u00ab\u00a0Il y a des gens que j\u2019aime bien, que j\u2019aime bien lire, dont je trouve que ce sont des penseurs intelligents\u00a0: Monsieur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Jean-Paul_Sartre\" rel=\"noopener\" target=\"_blank\">Sartre<\/a>, Monsieur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Jacques_Lacan\" rel=\"noopener\" target=\"_blank\">Lacan<\/a>, Monsieur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Alexandre_Koj%C3%A8ve\" rel=\"noopener\" target=\"_blank\">Koj\u00e8ve<\/a>, mais quand m\u00eame \u00e7a me chipote que ce soient des gens qui \u00e0 une \u00e9poque de leur vie ont admir\u00e9 Heidegger parce que \u00e7a montre quand m\u00eame un manque de discernement assez catastrophique.<\/p>\n<p>Bon, ils ont chang\u00e9 d\u2019avis, heureusement, mais, qu\u2019ils se soient laiss\u00e9s s\u00e9duire quand m\u00eame par ce machin-l\u00e0\u00a0: le nazisme mis sous forme de philosophie, \u00e7a m\u2019inqui\u00e8te quand m\u00eame un petit peu par rapport aux choses qu\u2019ils disent. Et je vous dis, bon, c\u2019est des gens que j\u2019aime bien. J\u2019ai d\u00e9j\u00e0 dit tout le bien que je pensais de Lacan\u00a0: de l\u2019avoir rencontr\u00e9, de ce qu\u2019il a pu dire. Sartre, je ne l\u2019ai pas dit autant, mais c\u2019est vrai, et Koj\u00e8ve, j\u2019ai une \u00e9norme admiration, je trouve que c\u2019est vraiment un tr\u00e8s tr\u00e8s grand philosophe du XXe si\u00e8cle. Il a fait comprendre <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Georg_Wilhelm_Friedrich_Hegel\" rel=\"noopener\" target=\"_blank\">Hegel<\/a> aux Fran\u00e7ais &#8211; ce qui n\u2019est d\u00e9j\u00e0 pas mal en soi &#8211; mais qui aussi a pouss\u00e9 Hegel encore plus loin dans la r\u00e9flexion. Bon, par ailleurs, c\u2019est un fonctionnaire europ\u00e9en qui a essay\u00e9 de pousser les choses dans la bonne direction \u00e0 une \u00e9poque.<\/p>\n<p>Alors voil\u00e0, je crois que j\u2019ai fait le tour de ce que je voulais dire. Ce n\u2019est pas encore l\u2019avant-derni\u00e8re mais presque de cette formule de mes causeries du vendredi. Apr\u00e8s, je vous l\u2019ai dit, je ferai des choses plus th\u00e9matiques. Je parlerai encore, comme \u00e7a je ferai des videos, je ne sais pas \u00e0 quelle fr\u00e9quence, sur une id\u00e9e particuli\u00e8re que j\u2019aurai envie de mettre sous cette forme-l\u00e0 plut\u00f4t que de venir devant vous r\u00e9guli\u00e8rement tous les vendredis. Parce que c\u2019est quand m\u00eame une contrainte, parce que j\u2019en ai d\u00e9j\u00e0 fait \u2013 quand m\u00eame &#8211; plus de cinq cents sous cette forme-l\u00e0 et qu\u2019il faut se renouveler. Allez, \u00e0 bient\u00f4t, \u00e0 la semaine prochaine\u00a0!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retranscription de Le temps qu&rsquo;il fait le 2 f\u00e9vrier 2018. Merci \u00e0 Marianne Oppitz et Catherine Cappuyns. Bonjour, nous sommes le vendredi 2 f\u00e9vrier 2018 et je ne sais pas si c\u2019est la m\u00eame chose chez vous, mais ici en Bretagne, \u00e0 Vannes, eh bien, il a gel\u00e9 cette nuit. Alors, un beau d\u00e9menti \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4489,2095,72,20],"tags":[189,2462,40,3268,155,2430,4740,1300,2633],"class_list":["post-102524","post","type-post","status-publish","format-standard","hentry","category-chine","category-education","category-etats-unis","category-philosophie","tag-alexandre-kojeve","tag-bruno-colmant","tag-chine","tag-fascisme-en-col-blanc","tag-jacques-lacan","tag-jean-paul-sartre","tag-martin-heidegger","tag-von-hayek","tag-von-mises"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/102524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=102524"}],"version-history":[{"count":9,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/102524\/revisions"}],"predecessor-version":[{"id":102541,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/102524\/revisions\/102541"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=102524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=102524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=102524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}