{"id":103514,"date":"2018-04-05T16:51:33","date_gmt":"2018-04-05T14:51:33","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=103514"},"modified":"2018-04-05T16:51:33","modified_gmt":"2018-04-05T14:51:33","slug":"un-courrier-de-jean-claude-balbot-sur-la-gratuite-de-lalimentation","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2018\/04\/05\/un-courrier-de-jean-claude-balbot-sur-la-gratuite-de-lalimentation\/","title":{"rendered":"Un courrier de Jean-Claude Balbot, sur la gratuit\u00e9 de l&rsquo;alimentation"},"content":{"rendered":"<blockquote><p>Ouvert aux commentaires.<\/p><\/blockquote>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/VJN4GgakYpA\" width=\"700\" height=\"394\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Je suis enchant\u00e9 \u00e0 l&rsquo;id\u00e9e que la gratuit\u00e9 soit non seulement port\u00e9e sur l&rsquo;agora mais qu&rsquo;en plus elle soul\u00e8ve l\u2019enthousiasme. Depuis 2012 je bosse la question de l&rsquo;aide alimentaire et de ce qu&rsquo;elle signifie\u00a0 pour les producteurs et pour les consommateurs ;\u00a0du ressentiment grandissant que provoque cette activit\u00e9. Je suis depuis longtemps aux premi\u00e8res loges pour voir comment les \u00ab\u00a0aides\u00a0\u00bb vers\u00e9es aux agriculteurs pour contrebalancer la faiblesse des revenus est int\u00e9gralement capt\u00e9e par les satellites : consommations interm\u00e9diaires, banques et autres complices du complexe agro-industriel.\u00a0Ce sont des sommes faramineuses, dont la fonction essentielle semble \u00eatre de maintenir le prix (et le revenu) au seuil de survie du vendeur.<\/p>\n<p><!--more-->Partant de l&rsquo;analyse de la mise en place en 1944 de la gratuit\u00e9 des soins, j&rsquo;ai\u00a0propos\u00e9 \u00e0 plusieurs reprises la <em>gratuit\u00e9 de l&rsquo;alimentation<\/em> comme objectif \u00e0 mes camarades. J&rsquo;ai vu beaucoup d&rsquo;incompr\u00e9hension dans leurs yeux.\u00a0Et cela malgr\u00e9 un constat partag\u00e9. Il y a entre autre \u00e0 franchir l&rsquo;obstacle de ce qu&rsquo;est r\u00e9ellement le travail : pour des \u00ab\u00a0travailleurs ind\u00e9pendants\u00a0\u00bb\u00a0il faut un effort tr\u00e8s grand pour comprendre que gratuit\u00e9 et don ne rel\u00e8vent pas de la m\u00eame logique.<\/p>\n<p>Aussi je te soumets ces r\u00e9flexions dans l&rsquo;espoir d&rsquo;affermir mon argumentation :<\/p>\n<p>Le don (ici l&rsquo;aide alimentaire) s&rsquo;il ne prend pas place dans un cycle bien identifi\u00e9 (donner-recevoir-rendre) rel\u00e8ve de la charit\u00e9 qui m\u00eame modernis\u00e9e aura les m\u00eames cons\u00e9quences connues.<\/p>\n<ul>\n<li>La gratuit\u00e9 est une organisation sociale demandant l&rsquo;adh\u00e9sion (cotisations ou autres) des parties en pr\u00e9sence \u00e0 une m\u00eame \u00ab\u00a0vision\u00a0\u00bb des rapports sociaux, tout du moins \u00e0 un m\u00eame \u00ab\u00a0compromis\u00a0\u00bb social.<\/li>\n<li>La gratuit\u00e9 (contrairement au don ?) a un prix ; prix qui serait donc la traduction d&rsquo;un rapport de forces. Du coup, sans doute pas entre vendeur et acheteur,\u00a0 mais alors entre qui et qui ? En 44 ce rapport de forces entre classes a tellement bascul\u00e9 qu&rsquo;il n&rsquo;\u00e9tait plus question qu&rsquo;au terme de la transaction l&rsquo;ordre social se reconstitue identique \u00e0 ce qu&rsquo;il \u00e9tait pr\u00e9c\u00e9demment.<\/li>\n<li>Aujourd&rsquo;hui, peut-on attendre de la mise en place de la gratuit\u00e9 pour l&rsquo;indispensable, telle que tu l&rsquo;avances tr\u00e8s clairement, un changement des rapports sociaux qui en feront autre chose qu&rsquo;un don sans r\u00e9ciprocit\u00e9 ? Doit-on penser que c&rsquo;est le basculement des rapports de force qui donnera \u00e0 cette gratuit\u00e9 toute la puissance d&rsquo;un Commun ?<\/li>\n<\/ul>\n<p>D\u00e9sol\u00e9 si ceci te parait trop na\u00eff mais ces questions sont au \u00ab\u00a0c\u0153ur invisible\u00a0\u00bb du travail que je coordonne en ce moment sur\u00a0<i>l&rsquo;acc\u00e8s durablement, de tous \u00e0 une alimentation de qualit\u00e9<\/i>. Et une op\u00e9ration \u00e0 c\u0153ur ouvert\u00a0 demande de s\u00e9rieux arguments pour convaincre le patient. L&rsquo;approche de la mort ne suffit pas toujours \u00e0 la convaincre !<\/p>\n<p>Bien \u00e0 toi<\/p>\n<p>jean-claude<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ouvert aux commentaires. Je suis enchant\u00e9 \u00e0 l&rsquo;id\u00e9e que la gratuit\u00e9 soit non seulement port\u00e9e sur l&rsquo;agora mais qu&rsquo;en plus elle soul\u00e8ve l\u2019enthousiasme. Depuis 2012 je bosse la question de l&rsquo;aide alimentaire et de ce qu&rsquo;elle signifie\u00a0 pour les producteurs et pour les consommateurs ;\u00a0du ressentiment grandissant que provoque cette activit\u00e9. Je suis depuis longtemps [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5367],"tags":[1166,156,948],"class_list":["post-103514","post","type-post","status-publish","format-standard","hentry","category-gratuite","tag-alimentation","tag-don","tag-gratuite"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/103514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=103514"}],"version-history":[{"count":2,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/103514\/revisions"}],"predecessor-version":[{"id":103516,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/103514\/revisions\/103516"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=103514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=103514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=103514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}