{"id":107627,"date":"2018-12-07T12:30:38","date_gmt":"2018-12-07T11:30:38","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=107627"},"modified":"2018-12-07T12:31:08","modified_gmt":"2018-12-07T11:31:08","slug":"demain-lhumain-paul-jorion-vs-nicolas-baverez-a-cannes-le-2-decembre-2018-retranscription","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2018\/12\/07\/demain-lhumain-paul-jorion-vs-nicolas-baverez-a-cannes-le-2-decembre-2018-retranscription\/","title":{"rendered":"Demain l&rsquo;humain ? &#8211; Paul Jorion vs. Nicolas Baverez \u00e0 Cannes, le 2 d\u00e9cembre 2018 &#8211; Retranscription"},"content":{"rendered":"<blockquote><p>Retranscription de <a href=\"https:\/\/www.pauljorion.com\/blog\/2018\/12\/02\/demain-lhumain-paul-jorion-vs-nicolas-baverez-a-cannes-le-1er-decembre-2018\/\" target=\"_blank&quot;\" rel=\"noopener\">Demain l&rsquo;humain ? &#8211; Paul Jorion vs. Nicolas Baverez \u00e0 Cannes, le 1er d\u00e9cembre 2018<\/a>, le 2 d\u00e9cembre 2018. Merci \u00e0 \u00c9ric Muller !<\/p><\/blockquote>\n<p>Bonjour, nous sommes dimanche, le second d\u00e9cembre. Non, je ne crois pas qu\u2019on dise le second d\u00e9cembre. On dit le premier d\u00e9cembre, mais pour une raison qui m\u2019\u00e9chappe, on ne dit pas le second d\u00e9cembre [sourire]. Toujours est-il que je suis toujours \u00e0 <a href=\"http:\/\/rencontresdecannes.fr\/\" target=\"_blank\" rel=\"noopener\">Cannes<\/a>. J\u2019assisterai encore cet apr\u00e8s-midi \u00e0 un expos\u00e9 sur l\u2019Intelligence Artificielle. Hier, je suis intervenu <a href=\"https:\/\/www.pauljorion.com\/blog\/2018\/12\/02\/cannes-jorion-vs-baverez\/\" target=\"_blank\" rel=\"noopener\">dans un d\u00e9bat<\/a> avec <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nicolas_Baverez\" target=\"_blank\" rel=\"noopener\">Nicolas Baverez<\/a> sur la question du monde de demain. Le th\u00e8me g\u00e9n\u00e9ral, c\u2019est l\u2019humain demain. Il y avait, apr\u00e8s nous, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Dominique_M%C3%A9da\" target=\"_blank\" rel=\"noopener\">Dominique M\u00e9da<\/a> et <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pierre-No%C3%ABl_Giraud\" target=\"_blank\" rel=\"noopener\">Pierre-No\u00ebl Giraud<\/a> qui ont parl\u00e9 de l\u2019avenir du travail.<\/p>\n<p><!--more--><\/p>\n<p>Alors, l\u00e0 il s\u2019est pass\u00e9 quelque chose pour moi qui est bien tomb\u00e9 [sourire] . \u00c7a m\u2019a fait pens\u00e9 au finale du film <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nashville_(film)\" target=\"_blank\" rel=\"noopener\">Nashville<\/a> de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Robert_Altman\" target=\"_blank\" rel=\"noopener\">Robert Altman<\/a>. Vous savez, les choses me font toujours penser soit \u00e0 de la musique, soit \u00e0 du cin\u00e9ma. \u00c0 la fin du film de Altman, si vous ne l\u2019avez pas vu, il y a l\u2019assassinat d\u2019une chanteuse qui est en train de chanter sur la sc\u00e8ne. Et la jeune femme qu\u2019on a vu dans tout le film essayer de faire valoir qu\u2019elle sait chanter, elle se trouve l\u00e0, elle est seule sur sc\u00e8ne, avec derri\u00e8re elle un ch\u0153ur de <i>Gospel singing<\/i>. Et on lui dit, pour meubler : \u00ab Vas-y, chante ! \u00bb Et elle chante, [sourire] et c\u2019est ce final splendide de ce film de Altman.<\/p>\n<p><iframe loading=\"lazy\" width=\"700\" height=\"466\" src=\"https:\/\/www.youtube.com\/embed\/4BYyDusJYJo\" class=\"aligncenter\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Ce qui s\u2019est pass\u00e9 pour moi, c\u2019est l\u2019\u00e9quivalent. C\u2019est la chose suivante. C\u2019est que, voil\u00e0, nous \u00e9tions interrog\u00e9s &#8211; donc les quatre dont je viens de mentionner les noms &#8211; et, \u00e0 cause du fait que trois d\u2019entre eux devaient repartir sur Paris et que les <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Mouvement_des_gilets_jaunes\" target=\"_blank\" rel=\"noopener\">Gilets jaunes<\/a> bloquaient l\u2019acc\u00e8s \u00e0 l\u2019a\u00e9roport de Cannes, je suppose [sourire], ils sont partis en vitesse, et je me suis retrouv\u00e9 \u00e0 r\u00e9pondre seul aux questions de la salle. On a fait revenir <a href=\"http:\/\/www.lcsp.univ-paris-diderot.fr\/Flipo\" target=\"_blank\" rel=\"noopener\">Fabrice Flipo<\/a> sur la sc\u00e8ne parce qu\u2019il \u00e9tait intervenu le jour pr\u00e9c\u00e9dent, mais c\u2019est essentiellement moi qui ai pu r\u00e9pondre aux questions qui avaient \u00e9t\u00e9 soulev\u00e9es par les quatre expos\u00e9s.<\/p>\n<p><iframe loading=\"lazy\" class=\"aligncenter\" src=\"https:\/\/www.youtube.com\/embed\/Z6LYPTiCpPI?start=157\" width=\"700\" height=\"394\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Alors, je n\u2019ai pas \u00e9t\u00e9 surpris que sur toutes les questions techniques, M. Baverez et moi nous ayons la m\u00eame opinion. C\u2019est pour moi quelque chose de connu, j\u2019ai souvent des dialogues avec l\u2019\u00e9conomiste belge <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Bruno_Colmant\" target=\"_blank\" rel=\"noopener\">Bruno Colmant<\/a>, qui est une personnalit\u00e9 de la droite lib\u00e9rale. M\u00eame chose pour M. Baverez, chroniqueur au Figaro. Mais pour ce qui est des questions techniques, de savoir si telle ou telle chose fonctionne de telle et telle mani\u00e8re, nous sommes d\u2019accord parce que, voil\u00e0, nous connaissons les dossiers. Et il se fait qu\u2019au fil des ann\u00e9es, \u00e7a fait un moment que je me retrouve dans des discussions avec lui. \u00c7a a commenc\u00e9, si j\u2019ai bon souvenir, \u00e0 Lyon, sur le th\u00e8me de la r\u00e9volution, puis nous nous sommes retrouv\u00e9s sur un plateau en Belgique. Je crois qu\u2019il y a eu encore une autre occasion il n\u2019y a pas trop longtemps. Et voil\u00e0, nous sommes dans un dialogue, et en fait, ce que nous disons se compl\u00e8te assez bien, jusqu\u2019au moment o\u00f9 il faut en tirer des conclusions, je dirais, proprement politiques. \u00c0 ce moment-l\u00e0, nous divergeons. En particulier, M. Baverez trouve que le capitalisme est quelque chose qui a de l\u2019avenir, que la croissance, c\u2019est quelque chose qui a de l\u2019avenir. Et moi, il me semble que, et la croissance telle qu\u2019elle est con\u00e7ue maintenant &#8211; c\u2019est-\u00e0-dire qu\u2019elle contribue essentiellement \u00e0 la concentration de la richesse, avec les 82 % de la richesse cr\u00e9\u00e9e en 2017 par la croissance qui est all\u00e9 au 1% le plus riche de la population mondiale &#8211; et le capitalisme qui est un syst\u00e8me de pillage organis\u00e9 &#8211; dont on peut nous dire qu\u2019il nous a rendu riches, ceci, cela, etc. mais qui est un syst\u00e8me de pillage et, comme tout syst\u00e8me de pillage, il se termine quand il n\u2019y a plus de ressources.<\/p>\n<p>Mme M\u00e9da a fait un expos\u00e9, je dirais, assez classique pour elle, sur l\u2019avenir du travail. En gros, la diff\u00e9rence avec moi, c\u2019est qu\u2019elle met entre parenth\u00e8ses la disparition de l\u2019emploi. Elle cite le chiffre &#8211; le fameux chiffre d\u2019il y a quelques ann\u00e9es &#8211; de l\u2019OCDE, sur le fait qu\u2019il n\u2019y aurait que 9 % des emplois qui seraient rempla\u00e7ables par du num\u00e9rique \u00e0 br\u00e8ve \u00e9ch\u00e9ance. Ce chiffre allait bien entendu \u00e0 l\u2019encontre de ceux produits par diff\u00e9rents cabinets d\u2019\u00e9tude, par diff\u00e9rentes \u00e9tudes officielles, qui donnent des chiffres de 30, 40, 50, 60 % d\u2019emplois qui vont dispara\u00eetre. Donc, d\u2019un c\u00f4t\u00e9, les 9 % auxquels Mme M\u00e9da croit, et puis les autres chiffres donn\u00e9s par d\u2019autres personnes. Les chiffres, en g\u00e9n\u00e9ral, quand ils sont faibles, tiennent compte de l\u2019opinion des gens sur leur propre rempla\u00e7abilit\u00e9 par des machines ou des logiciels, ce qui est \u00e9videmment un tr\u00e8s, tr\u00e8s, tr\u00e8s mauvais indicateur. L\u2019\u00e9tude de l\u2019OCDE divisait les choses en t\u00e2ches plut\u00f4t qu\u2019en emploi. Elle ne pouvait pas cacher que les emplois qui r\u00e9appara\u00eetraient seraient non pas des emplois, voil\u00e0, d\u2019ing\u00e9nieur travaillant sur des logiciels essentiellement, mais plut\u00f4t des emplois justement pour remplir encore les quelques t\u00e2ches que les ordinateurs, les robots, les logiciels ne peuvent pas faire en g\u00e9n\u00e9ral, parce que ce sont des t\u00e2ches qui, comment dire, demandent un grand nombre d\u2019activit\u00e9s qu\u2019on n\u2019a pas encore r\u00e9unies dans une machine. C\u2019est la fameuse objection de M. <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Jean-Gabriel_Ganascia\" target=\"_blank\" rel=\"noopener\">Ganascia<\/a>, qu\u2019une machine qui gagne aux \u00e9checs ne peut pas vous servir du caf\u00e9.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/content.jwplatform.com\/players\/6SVYSiM9-e6Ya2Zt9.html\" width=\"700\" height=\"394\" frameborder=\"0\" scrolling=\"auto\"><\/iframe><\/p>\n<p>\u00c0 \u00e7a, la r\u00e9ponse, vous la connaissez, c\u2019est : dans un smartphone, maintenant, il y a des tas de choses qu\u2019on imaginait qui ne marcheraient jamais ensemble et qui sont l\u00e0 &#8211; des dizaines, peut-\u00eatre des centaines \u2013 des choses qu\u2019un smartphone peut faire et dont on n\u2019imaginait pas un instant qu\u2019une machine pourrait \u00eatre un t\u00e9l\u00e9phone, r\u00e9pondre au courrier, faire des calculs, qu\u2019on pourrait lui parler, demander des conseils, etc., qu&rsquo;il y ait une immense base de donn\u00e9es, qu\u2019on peut faire traduire ce qu\u2019on veut par ce smartphone, et ainsi de suite.<\/p>\n<p>Donc, eh bien, je dirais, le plus inqui\u00e9tant, \u00e7a a \u00e9t\u00e9 l\u2019intervention de M. Pierre-No\u00ebl Giraud. J\u2019\u00e9tais en position assez difficile de devoir le critiquer en son absence, en sachant qu&rsquo;il ne pouvait pas revenir, et l\u00e0, il nous a fait des objections en disant que l&rsquo;on ne savait pas trop ce que c&rsquo;\u00e9tait exactement la croissance, que quand une machine bat aux \u00e9checs M. Kasparov, en fait, eh bien, c&rsquo;est tout \u00e0 fait in\u00e9gal comme combat puisque c&rsquo;est toute l&rsquo;\u00e9quipe d&rsquo;IBM contre un monsieur isol\u00e9. M. Giraud n&rsquo;avait pas l&rsquo;air d&rsquo;\u00eatre au courant des logiciels qui battent maintenant les champions au jeu de go, au jeu de poker. Il n&rsquo;avait apparemment jamais entendu parler ni d\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/AlphaGo\" target=\"_blank\" rel=\"noopener\">AlphaGo<\/a>, ni d\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/AlphaZero\" target=\"_blank\" rel=\"noopener\">AlphaZero<\/a>, qui a appris simplement en jouant avec lui-m\u00eame et bat les premiers syst\u00e8mes comme AlphaGo, qui eux, apprenaient de parties jou\u00e9es par des \u00eatres humains. Les objections de M. Giraud, je dirais, le probl\u00e8me de son information, c&rsquo;est une information des ann\u00e9es 90, et apparemment, la difficult\u00e9 d\u2019int\u00e9grer les \u00e9l\u00e9ments qu\u2019il produit, c\u2019est le fait qu\u2019il ne semble pas qu\u2019il y ait d\u2019information du 21<sup>e<\/sup> si\u00e8cle dans ses objections. De dire que \u00ab la croissance, on ne sait pas exactement ce que c&rsquo;est \u00bb cela ne satisfait ni M. Baverez, ni moi. \u00c7a se pr\u00e9sente comme une objection mais, en fait, c\u2019est une ignorance proclam\u00e9e. On sait ce que c\u2019est, la croissance. On sait que ce sont des valeurs ajout\u00e9es. On sait que \u00e7a d\u00e9rive de la mani\u00e8re dont on calcule le profit chez nous, c\u2019est-\u00e0-dire la diff\u00e9rence entre le prix que l\u2019on a obtenu et l\u2019ensemble des co\u00fbts. Ce n\u2019est pas tr\u00e8s, tr\u00e8s compliqu\u00e9 de comprendre ce que c\u2019est, la croissance. \u00c9videmment, je dirais, il y a un aspect s\u00e9ducteur. Quand on s\u2019adresse \u00e0 un public qui ne conna\u00eet rien sur rien, et si on leur dit : \u00ab Eh bien, ne vous pr\u00e9occupez pas de la croissance parce que, en fait, c\u2019est un mot qui ne veut rien dire \u00bb on peut trouver quelques oreilles, je dirais, comment dire, encourageantes, qui disent : \u00ab Oui, oui, c\u2019est s\u00fbrement comme \u00e7a, parce que \u00e7a m\u2019\u00e9vite de devoir trop me remuer les m\u00e9ninges ! \u00bb<\/p>\n<p>Enfin, voil\u00e0. Donc, dans l\u2019ensemble, je dirais, de ce qui a \u00e9merg\u00e9, des visions \u00e0 la fois surann\u00e9es de l\u2019\u00eatre humain et de son avenir, et quelques visions, je dirais, d\u2019avenir, mais qui, l\u00e0, posent la question politique, c&rsquo;est-\u00e0-dire : \u00ab Qu\u2019est-ce qu\u2019on veut faire ? \u00bb Si on veut \u00e0 tout prix d\u00e9fendre le syst\u00e8me capitaliste, et sa croissance, et sa logique de profit et de propri\u00e9t\u00e9 priv\u00e9e qui sont sous-jacentes, c&rsquo;est un choix \u00e0 faire. \u00c0 mon sens, il est l\u00e9tal, comme on dit, il est mortel, parce qu&rsquo;on l&rsquo;a utilis\u00e9, et \u00e7a soutient essentiellement un syst\u00e8me de pillage qu&rsquo;on peut continuer jusqu&rsquo;\u00e0 ce que la musique s&rsquo;arr\u00eate, et dans ce cas-l\u00e0, eh bien, c\u2019est termin\u00e9. Ou bien, on peut prendre une approche diff\u00e9rente, l&rsquo;approche, je dirais, \u00ab\u00a0de gauche\u00a0\u00bb, d&rsquo;un certain socialisme qu&rsquo;il faut ressusciter parce qu&rsquo;il a \u00e9t\u00e9 vraiment tr\u00e8s, tr\u00e8s mis \u00e0 mal, mais qui, \u00e0 mon avis, est encore extr\u00eamement prometteur. Une logique du commun. Une logique que les ressources qui nous restent, il faut les mettre en commun, que les questions comme le climat, la destruction des ressources et tout \u00e7a, ce sont des questions que l&rsquo;on ne peut r\u00e9soudre qu&rsquo;en parlant tous ensemble parce que \u00e7a concerne tout le monde, et s&rsquo;il y a un petit endroit au monde o\u00f9 on ne participe pas \u00e0 la discussion, eh bien, c\u2019est cuit, parce qu&rsquo;il faudrait que ce petit pays n&rsquo;ait pas le moindre impact sur le reste. Sinon. Sinon, qu\u2019est-ce qui va se passer ? \u00c7a, on a \u00e9t\u00e9 plusieurs \u00e0 le dire. En fait, Baverez l\u2019a dit \u00e0 mi-mot, et moi, je l\u2019ai dit d&rsquo;une mani\u00e8re peut-\u00eatre un peu plus explicite, mais il le disait aussi. Sinon, simplement, nous allons \u00eatre \u00e0 la remorque de la Chine qui, elle, sait ce qu&rsquo;elle fait, le fait \u00e0 sa mani\u00e8re, et ne court pour le moment aucun risque, si ce n&rsquo;est que la premi\u00e8re puissance mondiale, en chute libre gr\u00e2ce \u00e0 son pr\u00e9sident, dans sa descente en vrille, n\u2019essaie de torpiller au passage sa concurrente qui serait la Chine.<\/p>\n<p>Alors, cela ne veut pas dire qu\u2019il n&rsquo;y ait pas des choses \u00e0 dire sur la mani\u00e8re dont on fait ses affaires en Chine, bien entendu. Vous le savez peut-\u00eatre, c&rsquo;est la derni\u00e8re partie de mon livre <a href=\"https:\/\/www.pauljorion.com\/blog\/?s=D%C3%A9fense+et+illustration+du+genre+humain\" target=\"_blank\" rel=\"noopener\">D\u00e9fense et illustration de genre humain<\/a>\u00a0: c&rsquo;est une grande discussion sur la Chine, sur son r\u00f4le aujourd&rsquo;hui, sur ce qu\u2019elle peut faire, sur ce qui repr\u00e9sente un danger pour nous, et ainsi de suite. Si \u00e7a vous int\u00e9resse, lisez ce livre, et parlez-en autour de vous.<\/p>\n<p>Moi, j\u2019ai \u00e9t\u00e9 tr\u00e8s satisfait, bien entendu, de la r\u00e9ponse de la salle \u00e0 mes interventions. C\u2019\u00e9tait le cas \u00e0 <a href=\"https:\/\/www.pauljorion.com\/blog\/2018\/12\/01\/saint-etienne-conference-de-lhotel-de-ville-se-debarrasser-du-capitalisme-est-une-question-de-survie-le-podcast\/\" target=\"_blank\" rel=\"noopener\">Saint-\u00c9tienne<\/a>, c\u2019\u00e9tait le cas lundi \u00e0 la <a href=\"https:\/\/www.pauljorion.com\/blog\/2018\/11\/28\/cour-de-cassation-colloque-lia-et-lexpertise-judiciaire-le-26-novembre-2018-2\/\" target=\"_blank\" rel=\"noopener\">Cour de Cassation<\/a>. Ce n\u2019est pas pour me lancer des fleurs, mais \u00e7a me fait tr\u00e8s, tr\u00e8s plaisir qu\u2019il y ait un tel enthousiasme, une telle ferveur dans les gens qui viennent \u00e9couter pour les id\u00e9es que je d\u00e9veloppe, de si grands sourires en disant : \u00ab Mais, monsieur, vous apportez quand m\u00eame quelques r\u00e9ponses \u00e0 des questions que je me pose depuis tr\u00e8s longtemps. \u00bb On me pose moins cette question du pessimisme ou de l&rsquo;optimisme, qui est une mani\u00e8re de disqualifier ce que l\u2019on dit. \u00ab Ah, mais c\u2019est pessimiste donc \u00e7a ne vaut rien ! \u00bb ou bien \u00ab Je n\u2019ai pas envie d\u2019y r\u00e9fl\u00e9chir parce que j&rsquo;ai envie de ne penser qu&rsquo;\u00e0 des choses positives et optimistes. \u00bb Donc \u00e7a me fait tr\u00e8s plaisir. La mani\u00e8re dont <a href=\"https:\/\/fr.wikipedia.org\/wiki\/%C3%89tienne_Klein\" target=\"_blank\" rel=\"noopener\">\u00c9tienne Klein<\/a> m\u2019a, comment dire, pos\u00e9 des questions, m\u2019a fait venir sur le podium pour \u00eatre avec lui, invit\u00e9 d\u2019honneur, \u00e0 r\u00e9pondre encore \u00e0 quelques questions, \u00e7a m\u2019a fait tr\u00e8s, tr\u00e8s plaisir. Et puis, les conversation par la suite, en fin de journ\u00e9e. Il y a eu une pr\u00e9sentation tr\u00e8s, tr\u00e8s int\u00e9ressante de &#8211; je ne me souviens plus, peut-\u00eatre, du nom de la personne &#8211; mais c&rsquo;est un philosophe &#8211; je mettrai son nom en-dessous de la vid\u00e9o [<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ollivier_Pourriol\" target=\"_blank\" rel=\"noopener\">Ollivier Pourriol<\/a>] &#8211; qui vous pr\u00e9sente une histoire de la philosophie illustr\u00e9e par des extraits de films de science-fiction [<i>Cin\u00e9 Philo<\/i>] . C&rsquo;est splendide. Je vais certainement vous mettre en-dessous de la vid\u00e9o le lien vers ce qu&rsquo;il fait par ailleurs.<\/p>\n<p>Voil\u00e0. Allez, passez une bonne journ\u00e9e, et on se tient au courant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retranscription de Demain l&rsquo;humain ? &#8211; Paul Jorion vs. Nicolas Baverez \u00e0 Cannes, le 1er d\u00e9cembre 2018, le 2 d\u00e9cembre 2018. Merci \u00e0 \u00c9ric Muller ! Bonjour, nous sommes dimanche, le second d\u00e9cembre. Non, je ne crois pas qu\u2019on dise le second d\u00e9cembre. On dit le premier d\u00e9cembre, mais pour une raison qui m\u2019\u00e9chappe, on [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4489,1627,4140,102],"tags":[40,2121,500],"class_list":["post-107627","post","type-post","status-publish","format-standard","hentry","category-chine","category-geopolitique-2","category-le-genre-humain","category-travail","tag-chine","tag-disparition-du-travail","tag-nicolas-baverez"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/107627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=107627"}],"version-history":[{"count":6,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/107627\/revisions"}],"predecessor-version":[{"id":107634,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/107627\/revisions\/107634"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=107627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=107627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=107627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}