{"id":107834,"date":"2018-12-20T19:31:57","date_gmt":"2018-12-20T18:31:57","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=107834"},"modified":"2018-12-21T15:27:29","modified_gmt":"2018-12-21T14:27:29","slug":"jai-reussi-maman-roi-du-monde","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2018\/12\/20\/jai-reussi-maman-roi-du-monde\/","title":{"rendered":"\u00ab\u00a0J&rsquo;ai r\u00e9ussi Maman ! Roi du monde !\u00a0\u00bb"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"700\" height=\"466\" src=\"https:\/\/www.youtube.com\/embed\/OjzKiEs_pHI\" class=\"aligncenter\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe><\/p>\n<p>Trump n&rsquo;ignore pas le probl\u00e8me majeur de sa nation pour sa propre image si elle devait avouer aux yeux du monde qu&rsquo;elle a laiss\u00e9 acc\u00e9der \u00e0 la pr\u00e9sidence soit, dans le meilleur des cas, une marionnette victime d&rsquo;un chantage russe, soit, carr\u00e9ment, un agent russe. Il pousse donc le bouchon.<\/p>\n<p>Hier c&rsquo;\u00e9tait un retrait de toutes les troupes US en Syrie, aujourd&rsquo;hui c&rsquo;est son refus du compromis r\u00e9publicain pour \u00e9viter le <em>shutdown<\/em>, la crise budg\u00e9taire du gouvernement f\u00e9d\u00e9ral, d\u00e9bouchant sur la non-r\u00e9mun\u00e9ration imminente de certains fonctionnaires et la fermeture de certains services publics, au cas o\u00f9 sa muraille entre les \u00c9tats-Unis et le Mexique, au co\u00fbt modeste de 5 milliards de $, n&rsquo;\u00e9tait pas b\u00e2tie (il s&rsquo;est fait une raison quant \u00e0 sa proposition [si l&rsquo;on peut dire] initiale que ce seraient les Mexicains qui r\u00e9gleraient l&rsquo;ardoise).<\/p>\n<p>Il joue son va-tout dans un bras de fer qui, s&rsquo;il est suicidaire, ne manquera cependant pas de panache. \u00ab\u00a0Made it Ma ! Top of the world !\u00a0\u00bb, s&rsquo;\u00e9criait James Cagney, dans le r\u00f4le d&rsquo;un gangster qui s&rsquo;est cru invincible, dans la fameuse sc\u00e8ne finale de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/L%27enfer_est_%C3%A0_lui\" rel=\"noopener\" target=\"_blank\"><em>White Heat<\/em><\/a> (1949) : \u00ab\u00a0J&rsquo;ai r\u00e9ussi Maman ! Roi du monde !\u00a0\u00bb, un instant avant d&rsquo;\u00eatre pulv\u00e9ris\u00e9 par une immense explosion.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trump n&rsquo;ignore pas le probl\u00e8me majeur de sa nation pour sa propre image si elle devait avouer aux yeux du monde qu&rsquo;elle a laiss\u00e9 acc\u00e9der \u00e0 la pr\u00e9sidence soit, dans le meilleur des cas, une marionnette victime d&rsquo;un chantage russe, soit, carr\u00e9ment, un agent russe. Il pousse donc le bouchon. Hier c&rsquo;\u00e9tait un retrait de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,72],"tags":[4442,6202],"class_list":["post-107834","post","type-post","status-publish","format-standard","hentry","category-arts","category-etats-unis","tag-donald-trump","tag-james-cagney"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/107834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=107834"}],"version-history":[{"count":7,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/107834\/revisions"}],"predecessor-version":[{"id":107872,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/107834\/revisions\/107872"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=107834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=107834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=107834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}