{"id":110707,"date":"2019-04-22T08:31:17","date_gmt":"2019-04-22T06:31:17","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=110707"},"modified":"2019-04-22T08:31:17","modified_gmt":"2019-04-22T06:31:17","slug":"place-publique-vote-des-adherents-mise-a-jour","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2019\/04\/22\/place-publique-vote-des-adherents-mise-a-jour\/","title":{"rendered":"Place Publique &#8211; vote des adh\u00e9rents, mise \u00e0 jour"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Courrier re\u00e7u \u00e0 8h21 :<\/p>\r\n\r\n\r\n\r\n<blockquote>\r\n<p class=\"wp-block-paragraph\">Bonjour,<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Un mail va \u00eatre envoy\u00e9 aujourd&rsquo;hui \u00e0 tous les adh\u00e9rents pour qu&rsquo;ils se prononcent sur la liste de 26 candidats aux \u00e9lections europ\u00e9ennes pr\u00e9sent\u00e9e par Place Publique. Celle liste a \u00e9t\u00e9 approuv\u00e9e par le comit\u00e9 ex\u00e9cutif qui s&rsquo;est r\u00e9uni au complet (100 % de participation) par 24 voix pour et 5 abstentions. Elle s&rsquo;ajoute \u00e0 la premi\u00e8re liste de 10 noms d\u00e9j\u00e0 adopt\u00e9e. Les adh\u00e9rents pourront voter d\u00e9s r\u00e9ception du courriel et jusqu&rsquo;au 23 avril \u00e0 23 h.<\/p>\r\n<\/blockquote>\r\n","protected":false},"excerpt":{"rendered":"<p>Courrier re\u00e7u \u00e0 8h21 : Bonjour, Un mail va \u00eatre envoy\u00e9 aujourd&rsquo;hui \u00e0 tous les adh\u00e9rents pour qu&rsquo;ils se prononcent sur la liste de 26 candidats aux \u00e9lections europ\u00e9ennes pr\u00e9sent\u00e9e par Place Publique. Celle liste a \u00e9t\u00e9 approuv\u00e9e par le comit\u00e9 ex\u00e9cutif qui s&rsquo;est r\u00e9uni au complet (100 % de participation) par 24 voix pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6175],"tags":[6174],"class_list":["post-110707","post","type-post","status-publish","format-standard","hentry","category-place-publique","tag-place-publique"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/110707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=110707"}],"version-history":[{"count":2,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/110707\/revisions"}],"predecessor-version":[{"id":110709,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/110707\/revisions\/110709"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=110707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=110707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=110707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}