{"id":113374,"date":"2019-09-20T17:45:02","date_gmt":"2019-09-20T15:45:02","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=113374"},"modified":"2019-09-20T20:14:00","modified_gmt":"2019-09-20T18:14:00","slug":"le-niveau-des-oceans-monte-notre-colere-aussi-une-greve-mondiale-historique-pour-le-climat-par-bruno-lecoeur","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2019\/09\/20\/le-niveau-des-oceans-monte-notre-colere-aussi-une-greve-mondiale-historique-pour-le-climat-par-bruno-lecoeur\/","title":{"rendered":"<b>\u00ab Le niveau des oc\u00e9ans monte, notre col\u00e8re aussi \u00bb : une gr\u00e8ve mondiale historique pour le climat<\/b>, par Bruno Lecoeur"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.pauljorion.com\/blog\/2019\/09\/15\/vous-faites-peur-aux-gens-avec-vos-trucs-dapocalypse\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"\u00ab Vous faites peur aux gens avec vos trucs d\u2019apocalypse ! \u00bb (ouverture dans un nouvel onglet)\">\u00ab Vous faites peur aux gens avec vos trucs d\u2019apocalypse\u00a0! \u00bb<\/a><\/p>\r\n\r\n\r\n<iframe loading=\"lazy\" title=\"New York Times Video - Embed Player\" width=\"700\" height=\"550\" frameborder=\"0\" class=\"aligncenter\" scrolling=\"no\" allowfullscreen=\"true\" marginheight=\"0\" marginwidth=\"0\" id=\"nyt_video_player\" src=\"https:\/\/www.nytimes.com\/video\/players\/offsite\/index.html?videoId=100000006728102\"><\/iframe>\r\n\r\n<p class=\"wp-block-paragraph\">Bonjour Paul,<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Pour avoir manifest\u00e9 cette apr\u00e8s-midi en compagnie de quelques jeunes et tr\u00e8s peu de moins jeunes \u00e0 Rennes (a priori, \u00e0 Rennes, tout le monde se fiche du r\u00e9chauffement climatique et des effondrements qu&rsquo;il va provoquer, c&rsquo;est sans doute cette notion qui n&rsquo;est pas encore assimil\u00e9e d&rsquo;ailleurs), en \u00e9changeant avec une personne contre la manifestation, celle-ci m&rsquo;avoue, au bout du rouleau, de ses arguments et de sa d\u00e9fense : \u00ab\u00a0Arr\u00eatez de manifester, vous nous faites peur\u00a0!\u00a0\u00bb.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Le constat est clair d\u00e9sormais.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Vous faites peur aux gens avec vos trucs d\u2019apocalypse\u00a0! \u00bb Bonjour Paul, Pour avoir manifest\u00e9 cette apr\u00e8s-midi en compagnie de quelques jeunes et tr\u00e8s peu de moins jeunes \u00e0 Rennes (a priori, \u00e0 Rennes, tout le monde se fiche du r\u00e9chauffement climatique et des effondrements qu&rsquo;il va provoquer, c&rsquo;est sans doute cette notion qui [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5799,6195],"tags":[4209,6132],"class_list":["post-113374","post","type-post","status-publish","format-standard","hentry","category-extinction","category-extinction-rebellion","tag-extinction-du-genre-humain","tag-extinction-rebellion"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/113374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=113374"}],"version-history":[{"count":5,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/113374\/revisions"}],"predecessor-version":[{"id":113378,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/113374\/revisions\/113378"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=113374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=113374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=113374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}