{"id":113670,"date":"2019-09-27T21:31:25","date_gmt":"2019-09-27T19:31:25","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=113670"},"modified":"2019-09-27T21:31:25","modified_gmt":"2019-09-27T19:31:25","slug":"arretez-de-vous-faire-du-souci-trois-trous-noirs-sur-le-point-dentrer-en-collision","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2019\/09\/27\/arretez-de-vous-faire-du-souci-trois-trous-noirs-sur-le-point-dentrer-en-collision\/","title":{"rendered":"<B>Arr\u00eatez de vous faire du souci : \u00ab\u00a0Trois trous noirs sur le point d\u2019entrer en collision\u00a0\u00bb<\/b>"},"content":{"rendered":"<a href=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Trous-noirs.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Trous-noirs.png\" alt=\"\" width=\"473\" height=\"463\" class=\"aligncenter size-full wp-image-113673\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Trous-noirs.png 473w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Trous-noirs-300x294.png 300w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" \/><\/a>\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Des astronomes ont d\u00e9couvert, \u00e0 pas moins d&rsquo;un milliard d&rsquo;ann\u00e9es-lumi\u00e8re de notre Terre, un syst\u00e8me de trois galaxies en collision. Trois galaxies qui abritent chacune <a href=\"https:\/\/www.futura-sciences.com\/sciences\/actualites\/trous-noirs-trois-trous-noirs-point-entrer-collision-77732\/#xtor=EPR-57-[ALERTE]-20190927\" rel=\"noopener noreferrer\" target=\"_blank\">un trou noir supermassif actif<\/a>.\u00a0<\/p><\/blockquote>\r\n\r\n<p>Donc, <em>Relax, Max ! Mets les choses en perspective !<\/em><\/p>\r\n\r\n<p>P.S. Il faudrait \u00e9videmment qu&rsquo;on nous explique ce que veut dire dans ce cas-l\u00e0 \u00ab\u00a0sur le point\u00a0\u00bb. Si c&rsquo;est dans un milliard d&rsquo;ann\u00e9es on a peut-\u00eatre le temps de d\u00e9compresser, mais si c&rsquo;est dans dix minutes&#8230;<\/p> ","protected":false},"excerpt":{"rendered":"<p>Des astronomes ont d\u00e9couvert, \u00e0 pas moins d&rsquo;un milliard d&rsquo;ann\u00e9es-lumi\u00e8re de notre Terre, un syst\u00e8me de trois galaxies en collision. Trois galaxies qui abritent chacune un trou noir supermassif actif.\u00a0 Donc, Relax, Max ! Mets les choses en perspective ! P.S. Il faudrait \u00e9videmment qu&rsquo;on nous explique ce que veut dire dans ce cas-l\u00e0 \u00ab\u00a0sur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6675,833],"tags":[6674,6673],"class_list":["post-113670","post","type-post","status-publish","format-standard","hentry","category-astronomie","category-la-vie-de-tous-les-jours","tag-burn-out","tag-trous-noirs"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/113670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=113670"}],"version-history":[{"count":5,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/113670\/revisions"}],"predecessor-version":[{"id":113676,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/113670\/revisions\/113676"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=113670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=113670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=113670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}