{"id":114814,"date":"2019-11-05T01:28:36","date_gmt":"2019-11-05T00:28:36","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=114814"},"modified":"2019-11-05T01:28:36","modified_gmt":"2019-11-05T00:28:36","slug":"qui-est-lauteur-de-a-warning-je-vous-ai-donne-son-nom-le-9-septembre-2018","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2019\/11\/05\/qui-est-lauteur-de-a-warning-je-vous-ai-donne-son-nom-le-9-septembre-2018\/","title":{"rendered":"<B>Qui est l&rsquo;auteur de \u00ab\u00a0A Warning\u00a0\u00bb&nbsp;? Je vous ai donn\u00e9 son nom le 9 septembre 2018<\/b>"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Mal-identifie\u00cc\u0081.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-112097\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Mal-identifie\u00cc\u0081.png\" alt=\"\" width=\"220\" height=\"335\" \/><\/a>M. Joseph Hunt, ministre de la Justice adjoint am\u00e9ricain, a \u00e9crit \u00e0 M. Carol Ross qui repr\u00e9sente la maison Hachette aux \u00c9tats-Unis, \u00e0 propos de l&rsquo;auteur anonyme du livre \u00e0 para\u00eetre \u00ab\u00a0A Warning\u00a0\u00bb, \u00ab\u00a0un avertissement\u00a0\u00bb :<\/p>\r\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Si l&rsquo;auteur est, en fait, un \u00ab\u00a0haut fonctionnaire\u00a0\u00bb pr\u00e9sent ou pass\u00e9 dans l&rsquo;administration Trump, la publication de ce livre viole \u00e9ventuellement les obligations l\u00e9gales de confidentialit\u00e9 de ce fonctionnaire.  <\/p><\/blockquote>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">C&rsquo;est bien le cas puisqu&rsquo;il s&rsquo;agit de M. Rod Rosenstein, le pr\u00e9d\u00e9cesseur de M. Hunt \u00e0 son poste, comme <a href=\"https:\/\/www.pauljorion.com\/blog\/2018\/09\/09\/qui-est-le-fier-combattant-de-lombre\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"je vous l'expliquais ici m\u00eame le 9 septembre 2018 (ouverture dans un nouvel onglet)\">je vous l&rsquo;expliquais ici m\u00eame le 9 septembre 2018<\/a>.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Vous vous souvenez sans doute de l&rsquo;affaire. Dans une tribune libre anonyme dans le New York Times, quelqu&rsquo;un (je l&rsquo;appelais : \u00ab\u00a0le fier combattant de l&rsquo;ombre\u00a0\u00bb) affirmait qu&rsquo;il ne fallait pas s&rsquo;inqui\u00e9ter : M. Trump \u00e9tait sans cesse neutralis\u00e9 par ses proches collaborateurs, qui allaient jusqu&rsquo;\u00e0 subtiliser des dossiers sensibles sur la tablette de son bureau (c&rsquo;\u00e9tait l&rsquo;\u00e9poque o\u00f9 M. Trump avait encore des collaborateurs,  l&rsquo;\u00e9poque o\u00f9 il n&rsquo;avait pas encore enti\u00e8rement fait le vide autour de lui). <\/p>\r\n\r\n<!--more-->\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Le Washington Post avait donn\u00e9 <a href=\"https:\/\/www.washingtonpost.com\/graphics\/2018\/politics\/who-wrote-the-resistance-op-ed\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"une liste de 26 suspects (ouverture dans un nouvel onglet)\">une liste de 26 suspects<\/a>. Le nom de Rosenstein ne s&rsquo;y trouvait pas. J&rsquo;\u00e9crivais moi :<\/p>\r\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Qui est le r\u00e9sistant auteur de la tribune libre du New York Times ? Rod Rosenstein, num\u00e9ro 2 du minist\u00e8re de la Justice. Qu\u2019est-ce qui me fait dire cela ? Le fait qu\u2019il ait d\u00e9j\u00e0 eu l\u2019occasion de tenir publiquement les m\u00eames propos exactement que ceux que l\u2019on trouve dans le communiqu\u00e9 de l\u2019arm\u00e9e de l\u2019ombre.<\/p><\/blockquote>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">J&rsquo;avais en effet regard\u00e9 deux mois plus t\u00f4t en streaming (\u00e0 une heure du matin pour nous) une table-ronde sur les questions de s\u00e9curit\u00e9 \u00e0 Aspen au Colorado, et quand j&rsquo;ai lu la tribune libre anonyme, j&rsquo;avais reconnu des propos que Rosenstein avait tenus l\u00e0-bas \u00e0 peu de choses pr\u00e8s.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Les choses ont chang\u00e9 depuis \u00e9videmment : si M. Hunt veut acc\u00e9der \u00e0 mon tuyau, il faut d\u00e9sormais qu&rsquo;il s&rsquo;abonne.  <\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>M. Joseph Hunt, ministre de la Justice adjoint am\u00e9ricain, a \u00e9crit \u00e0 M. Carol Ross qui repr\u00e9sente la maison Hachette aux \u00c9tats-Unis, \u00e0 propos de l&rsquo;auteur anonyme du livre \u00e0 para\u00eetre \u00ab\u00a0A Warning\u00a0\u00bb, \u00ab\u00a0un avertissement\u00a0\u00bb : Si l&rsquo;auteur est, en fait, un \u00ab\u00a0haut fonctionnaire\u00a0\u00bb pr\u00e9sent ou pass\u00e9 dans l&rsquo;administration Trump, la publication de ce livre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72],"tags":[6778,5988],"class_list":["post-114814","post","type-post","status-publish","format-standard","hentry","category-etats-unis","tag-a-warning","tag-rod-rosenstein"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/114814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=114814"}],"version-history":[{"count":5,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/114814\/revisions"}],"predecessor-version":[{"id":114820,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/114814\/revisions\/114820"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=114814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=114814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=114814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}