{"id":115716,"date":"2019-12-08T17:12:29","date_gmt":"2019-12-08T16:12:29","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=115716"},"modified":"2019-12-08T17:15:06","modified_gmt":"2019-12-08T16:15:06","slug":"croqueuses-de-diamants-de-1933","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2019\/12\/08\/croqueuses-de-diamants-de-1933\/","title":{"rendered":"<b>\u00ab\u00a0Croqueuses de diamants de 1933\u00a0\u00bb<\/b>"},"content":{"rendered":"<p><strong>\u00ab\u00a0Gold Diggers of 1933\u00a0\u00bb<\/strong> : seconde partie du fameux \u00ab\u00a0My Forgotten Men\u00a0\u00bb (les anciens combattants de 14-18 devenus ch\u00f4meurs en 1933), C&rsquo;est <a href=\"https:\/\/en.wikipedia.org\/wiki\/Joan_Blondell\" target=\"_blank\" rel=\"noopener noreferrer\">Joan Blondell<\/a> qui chante (doubl\u00e9e par Etta Moten Barnett &#8211; voir ci-dessous). <\/p>\n<p><iframe loading=\"lazy\" class=\"aligncenter\" src=\"https:\/\/www.youtube.com\/embed\/nnSZi5MIHMc\" width=\"700\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>\u00ab\u00a0Croqueuses de diamants de 1933\u00a0\u00bb (<em>Gold Diggers of 1933<\/em>) n&rsquo;a pas \u00e9t\u00e9 tourn\u00e9 par Busby Berkeley, il y intervient uniquement en tant que chor\u00e9graphe. Le metteur en sc\u00e8ne, c&rsquo;est Mervyn LeRoy, qui avait fait ses d\u00e9buts de r\u00e9alisateur en 1927 et fit quelques autres films m\u00e9morables : le <em>Little Women<\/em> (Les 4 filles du Docteur March) de 1949 (tout jeune homme qui n&rsquo;est pas tomb\u00e9 amoureux d&rsquo;Elizabeth Taylor alors \u00e2g\u00e9e de seize ans n&rsquo;a pas compris grand-chose \u00e0 la vie &#8211; voir le bonus * ) et <em>Quo Vadis<\/em> en 1951.<\/p>\n<p>\u00ab\u00a0Croqueuses de diamants de 1933\u00a0\u00bb est le seul de la s\u00e9rie o\u00f9 il n&rsquo;y a pas que de tr\u00e8s vagues allusions \u00e0 la Grande Crise. La r\u00e9f\u00e9rence ici est massive. De m\u00eame que j&rsquo;ai \u00e9voqu\u00e9 pour <a href=\"https:\/\/www.pauljorion.com\/blog\/2019\/12\/02\/croqueuses-de-diamants-de-1935\/\" rel=\"noopener noreferrer\" target=\"_blank\">\u00ab\u00a0Croqueuses de diamants de 1935\u00a0\u00bb<\/a> les influences r\u00e9ciproques de Busby Berkeley et de Leni Riefenstahl, il serait difficile de pr\u00e9tendre que Mervyn LeRoy n&rsquo;a jamais entendu parler du \u00ab\u00a0Cuirass\u00e9 Potemkine\u00a0\u00bb de Sergei Eisenstein en 1925.<\/p>\n<p>1933, c&rsquo;est encore le cin\u00e9ma hollywoodien \u00ab\u00a0pre-code\u00a0\u00bb (le code de la censure) : il y a deux versions de \u00ab\u00a0Croqueuses de diamants de 1933\u00a0\u00bb, l&rsquo;une tr\u00e8s habill\u00e9e, l&rsquo;autre beaucoup moins : les bobines \u00e9taient dispatch\u00e9es aux \u00c9tats-Unis selon la r\u00e9gion.<\/p>\n<p>\u00ab\u00a0On est l\u00e0 pour le fric\u00a0\u00bb (<em>We&rsquo;re In The Money<\/em>) : c&rsquo;est <a href=\"https:\/\/en.wikipedia.org\/wiki\/Ginger_Rogers\" target=\"_blank\" rel=\"noopener noreferrer\">Ginger Rogers<\/a> qui chante et qui danse ici, la plus fameuse partenaire de Fred Astaire bien entendu. Elle aurait malheureusement \u00e9t\u00e9 aujourd&rsquo;hui une fan de Trump, portant fi\u00e8rement sa casquette Make America Great Again. <\/p>\n<p><iframe loading=\"lazy\" class=\"aligncenter\" src=\"https:\/\/www.youtube.com\/embed\/UJOjTNuuEVw\" width=\"700\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Premi\u00e8re partie de \u00ab\u00a0My Forgotten Men\u00a0\u00bb, avec la chanteuse \u00ab\u00a0noire\u00a0\u00bb <a href=\"https:\/\/en.wikipedia.org\/wiki\/Etta_Moten_Barnett\" target=\"_blank\" rel=\"noopener noreferrer\">Etta Moten Barnett<\/a>, qui double partiellement Joan Blondell.<\/p>\n<p><iframe loading=\"lazy\" class=\"aligncenter\" src=\"https:\/\/www.youtube.com\/embed\/5MGYz3vRdzA\" width=\"700\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>* Bonus E.T. :<\/p>\n<p><iframe loading=\"lazy\" class=\"aligncenter\" src=\"https:\/\/www.youtube.com\/embed\/yUsicDpBB1o\" width=\"700\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Gold Diggers of 1933\u00a0\u00bb : seconde partie du fameux \u00ab\u00a0My Forgotten Men\u00a0\u00bb (les anciens combattants de 14-18 devenus ch\u00f4meurs en 1933), C&rsquo;est Joan Blondell qui chante (doubl\u00e9e par Etta Moten Barnett &#8211; voir ci-dessous). \u00ab\u00a0Croqueuses de diamants de 1933\u00a0\u00bb (Gold Diggers of 1933) n&rsquo;a pas \u00e9t\u00e9 tourn\u00e9 par Busby Berkeley, il y intervient uniquement en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[3950,1261,6901,4859,6902,6900,6899],"class_list":["post-115716","post","type-post","status-publish","format-standard","hentry","category-arts","tag-busby-berkeley","tag-elizabeth-taylor","tag-etta-moten-barnett","tag-ginger-rogers","tag-grande-crise","tag-joan-blondell","tag-mervyn-leroy"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/115716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=115716"}],"version-history":[{"count":24,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/115716\/revisions"}],"predecessor-version":[{"id":115752,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/115716\/revisions\/115752"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=115716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=115716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=115716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}