{"id":126662,"date":"2021-02-14T13:03:34","date_gmt":"2021-02-14T12:03:34","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=126662"},"modified":"2021-02-14T13:03:34","modified_gmt":"2021-02-14T12:03:34","slug":"si-je-suis-assassine-un-jour-ce-sera-par-quelquun-venu-du-futur","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2021\/02\/14\/si-je-suis-assassine-un-jour-ce-sera-par-quelquun-venu-du-futur\/","title":{"rendered":"<b>Si je suis assassin\u00e9 un jour ce sera par quelqu&rsquo;un venu du futur<\/b>"},"content":{"rendered":"<figure id=\"attachment_126663\" aria-describedby=\"caption-attachment-126663\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-126663\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/JIAJIA-300x218.png\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/JIAJIA-300x218.png 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/JIAJIA.png 483w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-126663\" class=\"wp-caption-text\">JiaJia, andro\u00efde. \u00c0 gauche sur la photo.<\/figcaption><\/figure>\n<p>Dans son excellent <em>Human Compatible. Artificial Intelligence and the problem of control<\/em> (Viking 2019), Stuart Russel \u00e9crit\u00a0:<\/p>\n<blockquote><p>Imaginez \u00e0 quel point il serait plus facile d&rsquo;\u00e9teindre et de recycler une bo\u00eete grise et cubique fonctionnant mal &#8211; m\u00eame si elle poussait des cris, disant qu&rsquo;elle ne veut pas qu&rsquo;on l&rsquo;\u00e9teigne &#8211; que de le faire \u00e0 JiaJia. Imaginez aussi comme il serait d\u00e9routant et perturbant pour des b\u00e9b\u00e9s et des petits enfants si s&rsquo;occupaient d&rsquo;eux des entit\u00e9s qui sembleraient humaines, comme leurs parents, mais ne le seraient pas &#8211; qui sembleraient prendre soin d&rsquo;eux, alors que ce ne serait pas le cas (p. 125).<\/p><\/blockquote>\n<p>Et je me dis aussit\u00f4t, qu&rsquo;il ne manquerait \u00e0 ces robots que de \u00ab\u00a0vraiment prendre soin\u00a0\u00bb de ces enfants &#8211; ce que rendrait possible ma contribution personnelle \u00e0 l&rsquo;Intelligence Artificielle, d&rsquo;avoir simul\u00e9 une dynamique d&rsquo;affect dans une IA, permettant \u00e0 un logiciel relativement rudimentaire en termes de programmation d&rsquo;avoir des conversations de plus en plus \u00ab\u00a0intelligentes\u00a0\u00bb avec son utilisateur *.<\/p>\n<p><!--more-->On pourrait bien entendu me r\u00e9pondre que mon innovation date d&rsquo;il y a d\u00e9j\u00e0 32 ans et que si elle avait d\u00fb servir, elle aurait d\u00e9j\u00e0 servi, mais \u00e0 \u00e7a Stuart Russell a d\u00e9j\u00e0 aussi pens\u00e9 :<\/p>\n<blockquote><p>Une bonne id\u00e9e &#8211; une vraie perc\u00e9e &#8211; passera souvent inaper\u00e7ue au moment-m\u00eame et il se peut qu&rsquo;on ne comprenne que plus tard qu&rsquo;elle constitue en fait la base d&rsquo;une avanc\u00e9e substantielle en IA, quand peut-\u00eatre quelqu&rsquo;un la r\u00e9invente \u00e0 un moment plus propice. [&#8230;] C&rsquo;est souvent le cas qu&rsquo;une id\u00e9e en elle-m\u00eame ne suffise pas \u00e0 g\u00e9n\u00e9rer une am\u00e9lioration substantielle des capacit\u00e9s, et qu&rsquo;elle doive attendre qu&rsquo;une autre id\u00e9e apparaisse pour que leur combinaison des deux apporte la preuve de la valeur qui \u00e9tait la sienne (p. 63).<\/p><\/blockquote>\n<p>Je ne suis donc peut-\u00eatre pas d\u00e9finitivement \u00e0 l&rsquo;abri du risque qu&rsquo;un humain courrouc\u00e9 venu du futur me fasse la peau (toute ressemblance avec une histoire de sci-fi bien connue serait purement fortuite).<\/p>\n<p>Mais une autre consid\u00e9ration de Stuart Russell me rassure\u00a0:<\/p>\n<blockquote><p>&#8230; la capacit\u00e9 basique \u00e0 transmettre une information non-verbale par l&rsquo;expression faciale et son mouvement &#8211; qui est \u00e0 la port\u00e9e m\u00eame de Bugs Bunny&#8230; (p. 126)<\/p><\/blockquote>\n<p>Le voyageur du futur s&rsquo;en prendra &#8211; plut\u00f4t qu&rsquo;\u00e0 moi &#8211; au premier qui a r\u00e9ussi \u00e0 vendre un gadget \u00e0 des gosses en leur faisant croire que c&rsquo;\u00e9tait Miquet ou Donald Duck qui le leur demandait gentiment.<\/p>\n<p><strong>Avertissement<\/strong> : N&rsquo;en profitez pas pour chercher \u00e0 m&rsquo;assassiner\u00a0: m\u00eame si on me croit sur beaucoup de choses, il n&rsquo;est pas s\u00fbr qu&rsquo;on me croie sur \u00e7a !<\/p>\n<p>* <a href=\"https:\/\/www.pauljorion.com\/blog\/?s=ANELLA\" target=\"_blank\" rel=\"noopener\">ANELLA<\/a> (Associative Network with Emergent Logical and Learning Abilities) : r\u00e9seau associatif \u00e0 capacit\u00e9s logique et d&rsquo;apprentissage \u00e9mergentes, l&rsquo;IA que j&rsquo;ai mis au point pour British Telecom (1988-89) et dont le concept est d\u00e9crit dans <em>Principes des syst\u00e8mes intelligents<\/em> (1989).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans son excellent Human Compatible. Artificial Intelligence and the problem of control (Viking 2019), Stuart Russel \u00e9crit\u00a0: Imaginez \u00e0 quel point il serait plus facile d&rsquo;\u00e9teindre et de recycler une bo\u00eete grise et cubique fonctionnant mal &#8211; m\u00eame si elle poussait des cris, disant qu&rsquo;elle ne veut pas qu&rsquo;on l&rsquo;\u00e9teigne &#8211; que de le faire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7483,13],"tags":[1935,940,7903,941,3777,7902],"class_list":["post-126662","post","type-post","status-publish","format-standard","hentry","category-principes-des-systemes-intelligents","category-intelligence-artificielle","tag-anella","tag-intelligence-artificielle-2","tag-jiajia","tag-principes-des-systemes-intelligents","tag-robots","tag-stuart-russell"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/126662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=126662"}],"version-history":[{"count":6,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/126662\/revisions"}],"predecessor-version":[{"id":126669,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/126662\/revisions\/126669"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=126662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=126662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=126662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}