{"id":127557,"date":"2021-04-28T16:28:35","date_gmt":"2021-04-28T14:28:35","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=127557"},"modified":"2021-04-28T16:31:48","modified_gmt":"2021-04-28T14:31:48","slug":"crises-financieres-pourquoi-lineluctable-retour-du-meme","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2021\/04\/28\/crises-financieres-pourquoi-lineluctable-retour-du-meme\/","title":{"rendered":"<b>Crises financi\u00e8res : pourquoi l&rsquo;in\u00e9luctable retour du m\u00eame&nbsp;?<\/b>"},"content":{"rendered":"<p><a href=\"https:\/\/www.pauljorion.com\/blog\/2021\/04\/28\/crises-financieres-pourquoi-lineluctable-retour-du-meme\/savoir-agir\/\" rel=\"attachment wp-att-127561\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Savoir-Agir.png\" alt=\"\" width=\"185\" height=\"247\" class=\"alignleft size-full wp-image-127561\" \/><\/a>Un exercice int\u00e9ressant aura lieu demain : je serai interrog\u00e9 par la revue <strong>Savoir\/Agir<\/strong> sur mon article intitul\u00e9 <em>La compr\u00e9hension des crises financi\u00e8res et de leur r\u00e9p\u00e9tition<\/em> qui parut en juin 2008 dans le num\u00e9ro 4 de la revue (pages 11\u201318). Je vous en avais propos\u00e9 ici <a href=\"https:\/\/www.pauljorion.com\/blog\/2008\/06\/20\/la-comprehension-des-crises-financieres-et-leur-repetition\/\" target=\"_blank\" rel=\"noopener\">le texte complet<\/a>, le 20 juin 2008.<\/p>\n<p>\u00ab\u00a0Juin 2008, pour la publication de l&rsquo;article ?\u00a0\u00bb, me direz-vous, \u00ab\u00a0n&rsquo;est-ce pas en septembre, trois mois plus tard, que la crise a eu lieu ?\u00a0\u00bb Si ! Les proph\u00e8tes, voyez-vous, c&rsquo;est comme \u00e7a ! Et jugez vous-m\u00eame si, avec trois mois d&rsquo;avance, il y avait quoi que ce soit qui manquait.<\/p>\n<p>Le pdf, <a href=\"https:\/\/www.pauljorion.com\/blog\/2021\/04\/28\/crises-financieres-pourquoi-lineluctable-retour-du-meme\/sava_004_0011\/\" rel=\"attachment wp-att-127558\">c&rsquo;est ici<\/a>. Texte complet : <!--more--><\/p>\n<p><strong>La compr\u00e9hension des crises financi\u00e8res et de leur r\u00e9p\u00e9tition<\/strong><\/p>\n<p><em>Science et int\u00e9r\u00eats<\/em><\/p>\n<p>Toute science associ\u00e9e \u00e0 un savoir appliqu\u00e9 a son destin li\u00e9 aux enjeux financiers que ce dernier suscite. Les profits g\u00e9n\u00e9r\u00e9s par ce savoir appliqu\u00e9 peuvent \u00eatre mobilis\u00e9s pour orienter les d\u00e9veloppements futurs de cette science en promouvant les vues qui lui sont favorables et en d\u00e9nigrant ou en n\u00e9gligeant d\u00e9lib\u00e9r\u00e9ment celles qui lui feraient obstacle. L\u2019\u00e9conomie et la finance n\u2019\u00e9chappent pas \u00e0 ce principe g\u00e9n\u00e9ral.<\/p>\n<p>L\u2019\u00e9conomie et la finance sont des activit\u00e9s serties dans le fonctionnement des soci\u00e9t\u00e9s humaines et sont d\u00e9termin\u00e9es par les rapports de forces qui caract\u00e9risent celles\u2013ci. La description scientifique de l\u2019\u00e9conomie et de la finance met en \u00e9vidence le m\u00e9canisme de ces rapports de forces, et souligne l\u2019arbitraire qui pr\u00e9side au fait qu\u2019ils b\u00e9n\u00e9ficient \u00e0 certains individus plut\u00f4t qu\u2019\u00e0 d\u2019autres. Il n\u2019est pas surprenant d\u00e8s lors que ces b\u00e9n\u00e9ficiaires entreprennent une promotion syst\u00e9matique des th\u00e9ories de ces deux champs qui les repr\u00e9sentent comme d\u00e9termin\u00e9s par d\u2019autres principes que les simples rapports de forces entre parties impliqu\u00e9es, voire qui repr\u00e9sentent ces deux champs comme n\u2019\u00e9tant pas m\u00eame sertis dans le fonctionnement des soci\u00e9t\u00e9s humaines, et font croire, par exemple, que leur m\u00e9canisme est autonome et est soumis, non pas \u00e0 des r\u00e8gles juridiques et \u00e9thiques, mais \u00e0 des forces du m\u00eame type que celles qui pr\u00e9sident aux mouvements d\u2019astres lointains.<\/p>\n<p>L\u2019<em>\u00e9conomie politique<\/em> qui proposa la description scientifique de l\u2019\u00e9conomie et de la finance jusqu\u2019\u00e0 la fin du XIX\u00e8me si\u00e8cle et qui \u00e9tait produite au sein des milieux scientifiques classiques, situait les rapports de forces au c\u0153ur des activit\u00e9s \u00e9conomiques et financi\u00e8res et d\u00e9crivait le processus de la formation du prix comme un ph\u00e9nom\u00e8ne de fronti\u00e8re entre une population de vendeurs et une population d\u2019acheteurs, le prix se constituant sur le fil de leur confrontation : il se maintient avec de faibles variations lorsque ces deux populations sont sensiblement \u00e9gales, il baisse lorsque les vendeurs sont en surnombre, il monte lorsque ce sont au contraire les acheteurs qui sont les plus nombreux ; un bas prix attire de nouveaux acheteurs, alors qu\u2019un haut prix attire de nouveaux vendeurs, ce qui conduit \u00e0 des oscillations qui peuvent le cas \u00e9ch\u00e9ant d\u00e9boucher sur une quasi-extinction des acheteurs (krach) ou une quasi-extinction des vendeurs (bulle financi\u00e8re sur le point d\u2019\u00e9clater). De telles oscillations se rencontrent d\u00e9j\u00e0 dans la nature, lorsque deux populations sont en concurrence.<\/p>\n<p>La <em>\u00ab science \u00bb \u00e9conomique<\/em>, produite par les milieux d\u2019affaires en leur sein-m\u00eame ou dans leurs antennes au sein du milieu universitaire, pr\u00e9senta au contraire la formation du prix comme un processus abstrait, n\u00e9 au point de rencontre de quantit\u00e9s repr\u00e9sentant d\u2019une part l\u2019offre et d\u2019autre part la demande. Dans la perspective adopt\u00e9e par l\u2019\u00e9conomie politique, l\u2019identit\u00e9 des acheteurs et des vendeurs est essentielle \u00e0 la compr\u00e9hension de la formation du prix. Dans celle adopt\u00e9e par la \u00ab science \u00bb \u00e9conomique, elle est bien entendu indiff\u00e9rente, ce qui assure \u00e0 ceux qui commanditent cette approche l\u2019anonymat qu\u2019ils recherchent.<\/p>\n<p>De m\u00eame, pour l\u2019\u00e9conomie politique, le rapport de forces entre trois populations, les salari\u00e9s qui apportent au processus de production, leur travail, les investisseurs qui font les avances en moyens de production (\u00e9quipement, mati\u00e8res premi\u00e8res) et les dirigeants d\u2019entreprises qui contractent avec les investisseurs, organisent et supervisent le processus de production, pr\u00e9side \u00e0 la distribution du <em>surplus<\/em> g\u00e9n\u00e9r\u00e9 par l\u2019activit\u00e9 humaine. Tout comme la formation du prix est un ph\u00e9nom\u00e8ne de fronti\u00e8re o\u00f9 le prix se constitue sur le fil de la confrontation entre acheteurs et vendeurs, l\u2019int\u00e9r\u00eat est lui un ph\u00e9nom\u00e8ne de fronti\u00e8re entre investisseurs et dirigeants d\u2019entreprise o\u00f9 le taux d\u2019int\u00e9r\u00eat se constitue sur le fil de leur confrontation, et l\u2019inflation est un ph\u00e9nom\u00e8ne de fronti\u00e8re entre dirigeants d\u2019entreprises et salari\u00e9s o\u00f9 son taux se constitue sur le fil de leur confrontation.<\/p>\n<p>Pour la \u00ab science \u00bb \u00e9conomique, le surplus n\u2019existe cependant pas et n\u2019existant pas, la question de sa distribution ne se pose pas non plus, ni a fortiori celle de la confrontation entre les parties impliqu\u00e9es dans le processus de sa cr\u00e9ation. L\u00e0 o\u00f9 elle aurait d\u00fb parler du surplus, elle parle \u00e0 la place de <em>masse mon\u00e9taire<\/em> et l\u00e0 o\u00f9 elle aurait d\u00fb \u00e9voquer la part du surplus revenant aux salari\u00e9s, elle met en avant les revendications salariales comme la principale cause de d\u00e9s\u00e9quilibre des syst\u00e8mes \u00e9conomiques car source d\u2019inflation, laquelle est pr\u00e9sent\u00e9e comme un ph\u00e9nom\u00e8ne de nature mon\u00e9taire pouvant \u00eatre combattu en manipulant les taux d\u2019int\u00e9r\u00eat, en raison de l\u2019impact de ceux\u2013ci sur la masse mon\u00e9taire.<\/p>\n<p>Dans les p\u00e9riodes qui pr\u00e9c\u00e8dent les crises : celles o\u00f9 la sp\u00e9culation bat son plein, les b\u00e9n\u00e9ficiaires des rapports de forces pr\u00e9valants ont l\u2019occasion de se constituer des fortunes personnelles consid\u00e9rables qui leur permettent d\u2019investir dans la production de la \u00ab science \u00bb \u00e9conomique v\u00e9hiculant une repr\u00e9sentation de l\u2019\u00e9conomie et de la finance o\u00f9 leur m\u00e9canisme r\u00e9el est cach\u00e9. Ils consacrent une partie des fonds auxquels ils ont acc\u00e8s \u00e0 la fondation et au financement d\u2019\u00e9tablissements de recherche, de chaires, de <em>think\u2013tanks<\/em>, de \u00ab bo\u00eetes \u00e0 id\u00e9es \u00bb, ayant \u00e0 leur t\u00eate des hommes \u00e0 eux. Comme l\u2019\u00e9crit Susan George : \u00ab L&rsquo;argent permet ainsi d&rsquo;organiser la notori\u00e9t\u00e9 et le \u00ab\u00a0champ\u00a0\u00bb dans lequel se d\u00e9rouleront des \u00ab\u00a0d\u00e9bats\u00a0\u00bb cr\u00e9\u00e9s de toutes pi\u00e8ces \u00bb (George 1996).<\/p>\n<p>Une dialectique s\u2019\u00e9tablit au fil des ans entre les th\u00e9oriciens qui, dans une perspective scientifique, s\u2019efforcent de repr\u00e9senter l\u2019\u00e9conomie et la finance telles qu\u2019elles sont, et ceux qui, coopt\u00e9s et promus par les b\u00e9n\u00e9ficiaires des savoirs appliqu\u00e9s \u00e9conomiques et financiers, s\u2019efforcent de les repr\u00e9senter de la mani\u00e8re la plus favorable \u00e0 la reproduction de ces b\u00e9n\u00e9fices.<\/p>\n<p><em>Les causes de la Grande Crise selon Bernanke<\/em><\/p>\n<p>L\u2019actuel Pr\u00e9sident de la Federal Reserve Bank, Ben S. Bernanke, est l\u2019un des b\u00e9n\u00e9ficiaires en vue du savoir appliqu\u00e9 \u00e9conomique et financier ; il offre aussi un excellent exemple de la mani\u00e8re dont est produite la \u00ab science \u00bb \u00e9conomique. Bernanke est aujourd\u2019hui reconnu comme l\u2019un des principaux experts des \u00e9v\u00e9nements de 1929 et des ann\u00e9es de crise qui s\u2019ensuivirent. Son livre <strong>Essays on the Great Depression<\/strong> (2005) fait, nous dit-on, autorit\u00e9 sur la question. Qu\u2019a-t-il apport\u00e9 \u00e0 notre compr\u00e9hension de la Grande Crise ? Son approche est, comme il fallait s\u2019y attendre, mon\u00e9tariste, et pour lui la cause majeure des \u00e9v\u00e9nements de 1929 se situe dans la d\u00e9cision de la Federal Reserve Bank de maintenir la parit\u00e9 du dollar avec l\u2019or, parit\u00e9 \u00e0 laquelle le Pr\u00e9sident Nixon renoncerait en 1971. Bernanke met en avant, comme facteur aggravant, la r\u00e9sistance des employeurs \u00e0 utiliser l\u2019arme du licenciement pour recourir de pr\u00e9f\u00e9rence \u00e0 la r\u00e9duction du temps de travail journalier des salari\u00e9s.<\/p>\n<p>Dans la recension qu\u2019il a consacr\u00e9e aux <strong>Essays on the Great Depression<\/strong>, en r\u00e9alit\u00e9 un recueil d\u2019articles, Robert Margo, professeur d\u2019\u00e9conomie \u00e0 Vanderbilt University, souligne le glissement qui s\u2019op\u00e8re au fil des ann\u00e9es sous la plume de Bernanke quand il \u00e9voque la d\u00e9cision des patrons de r\u00e9duire le temps de travail journalier plut\u00f4t que de recourir \u00e0 la suppression de postes : pr\u00e9sent\u00e9e initialement comme non-significative d\u2019un point de vue statistique, elle finit par devenir cause d\u00e9terminante (Margo 2000 : 2\u20133). Le Pr\u00e9sident de la Fed propose une interpr\u00e9tation de \u00ab science \u00bb \u00e9conomique de la Grande Crise, mon\u00e9tariste dans sa formulation, et mettant en avant la combativit\u00e9 des salari\u00e9s comme le principal obstacle \u00e0 l\u2019atteinte d\u2019un \u00e9quilibre \u00e9conomique. On verra, quand j\u2019aurai examin\u00e9 ci\u2013dessous les vraies causes de la Grande Crise, pourquoi il est possible d\u2019appliquer aux analyses de Bernanke l\u2019expression qu\u2019utilisa Galbraith pour caract\u00e9riser la politique du Pr\u00e9sident Hoover en 1929 : \u00ab le triomphe du dogme sur la pens\u00e9e \u00bb (1954 : 191).<\/p>\n<p><em>Les causes de la Grande Crise selon Galbraith<\/em><\/p>\n<p>Dans son livre intitul\u00e9 <em>The Great Crash \u2013 1929<\/em>, publi\u00e9 en 1954, John Kenneth Galbraith avait lui offert un tout autre portrait de la Grande Crise et avait analys\u00e9 les raisons qui devaient, selon lui, emp\u00eacher son renouvellement. Il envisageait aussi les rares circonstances qui pourraient permettre \u00e0 une crise similaire de se reproduire.<\/p>\n<p>Au moment o\u00f9 la crise \u00e9clata en 1929, la disparit\u00e9 des revenus s\u2019\u00e9tait dramatiquement creus\u00e9e aux \u00c9tats\u2013Unis. Galbraith expliquait pourquoi une catastrophe du m\u00eame ordre ne pouvait plus, selon lui, se reproduire en 1954, l\u2019ann\u00e9e de publication de son livre : \u00ab La r\u00e9partition des revenus n\u2019est plus aussi d\u00e9s\u00e9quilibr\u00e9e. Entre 1929 et 1948, la part des revenus attribu\u00e9e aux 5 % de la population aux revenus les plus \u00e9lev\u00e9s, qui \u00e9tait de pr\u00e8s d\u2019un tiers, est tomb\u00e9e \u00e0 moins d\u2019un cinqui\u00e8me du total \u00bb (1954 : 196). Les choses \u00e9volu\u00e8rent cependant rapidement dans les ann\u00e9es qui suivirent : la part attribu\u00e9e aux 5 % de la population am\u00e9ricaine la plus riche grimperait r\u00e9guli\u00e8rement pour atteindre 54,42 % en 1989 puis 57,70 % en 2000, date du recensement le plus r\u00e9cent. La finance a jou\u00e9 un r\u00f4le d\u00e9terminant dans la disparit\u00e9 croissante des revenus aux \u00c9tats\u2013Unis : en 1980, les salari\u00e9s du monde financier touchaient en moyenne 10 % de plus que ceux des autres secteurs ; en 2007, l\u2019\u00e9cart \u00e9tait pass\u00e9 \u00e0 50 %. Les profits du secteur financier am\u00e9ricain repr\u00e9sentaient 13 % du total en 1980 ; en 2007, la proportion avait plus que doubl\u00e9 avec 27 %. La part de la croissance consacr\u00e9e aux salaires repr\u00e9sentait aux \u00c9tats\u2013Unis 56,5 % en 1981 ; en 2006, elle \u00e9tait tomb\u00e9e \u00e0 51,7 %. Au premier rang des facteurs d\u00e9clencheurs des deux crises donc : la part croissante du surplus \u00e9conomique aboutissant entre les mains des dirigeants d\u2019entreprises et des investisseurs, au d\u00e9triment bien entendu des salari\u00e9s.<\/p>\n<p>En plus de la disparit\u00e9 des revenus, Galbraith mentionnait parmi les autres facteurs \u00e0 l\u2019origine de la crise de 1929 : le d\u00e9ficit de la balance commerciale des \u00c9tats\u2013Unis, un all\u00e9gement de la fiscalit\u00e9 pour les plus nantis et l\u2019indiff\u00e9rence envers la sp\u00e9culation \u2013 et en particulier l\u2019absence de mesures qui auraient pu ma\u00eetriser celle-ci en augmentant les marges exig\u00e9es des sp\u00e9culateurs lors de leurs op\u00e9rations. Tous ces facteurs jou\u00e8rent bien entendu un r\u00f4le similaire en 2007.<\/p>\n<p>Parmi les circonstances qui pouvaient emp\u00eacher, selon Galbraith, que les mesures n\u00e9cessaires ne soient envisag\u00e9es, malgr\u00e9 la prise de conscience de l\u2019imminence d\u2019une crise du m\u00eame ordre que celle de 1929 : le fait que les difficult\u00e9s apparaissent en p\u00e9riode pr\u00e9-\u00e9lectorale, interdisant de ce fait la prise de mesures impopulaires.<\/p>\n<p>Convaincu que le souvenir des \u00e9v\u00e9nements de 1929 constituerait un puissant repoussoir, Galbraith imaginait la Fed faisant preuve d\u2019une bien plus grande d\u00e9termination qu\u2019elle n\u2019en fit preuve durant les six premi\u00e8res ann\u00e9es des deux administrations George W. Bush. Il \u00e9crivait en effet : \u00ab Les pouvoirs du Conseil de la Federal Reserve \u2013 que l\u2019on appelle aujourd\u2019hui le Conseil des Gouverneurs, le Syst\u00e8me de la R\u00e9serve F\u00e9d\u00e9rale \u2013 ont \u00e9t\u00e9 renforc\u00e9s sous les deux aspects de la relation aux banques de R\u00e9serve et des banques membres \u00bb (1954 : 194). Allant plus loin, il n\u2019h\u00e9sitait pas \u00e0 imaginer que Wall Street aurait \u00e0 c\u0153ur d\u2019\u00e9touffer dans l\u2019\u0153uf une crise imminente. Il \u00e9crivait \u00e0 ce propos que \u00ab Puisqu\u2019un effondrement sp\u00e9culatif succ\u00e8de n\u00e9cessairement \u00e0 un boom sp\u00e9culatif, on peut esp\u00e9rer que Wall Street exercerait un contr\u00f4le strict en cas de r\u00e9surgence de la sp\u00e9culation. Les banquiers et les courtiers exigeraient que l\u2019on rel\u00e8ve jusqu\u2019\u00e0 leur limite les marges ; on demanderait \u00e0 Wall Street d\u2019exercer cette exigence avec rigueur contre ceux qui tenteraient d\u2019emprunter en mettant en gage leur propres actions et obligations afin d\u2019en acheter davantage. On rappellerait avec force au public les risques inh\u00e9rents au fait d\u2019acheter des actions en visant leur plus\u2013value \u00bb (1954 : 198). Faut-il pr\u00e9ciser qu\u2019il n\u2019en a rien \u00e9t\u00e9 ? La pr\u00e9sence d\u2019Alan Greenspan \u00e0 la t\u00eate de la Fed, de 1987 \u00e0 2006 signifierait au contraire vingt ann\u00e9es sous la banni\u00e8re d\u2019une version extr\u00e9miste du laissez-faire, inspir\u00e9e du \u00ab libertarisme \u00bb militant d\u2019Ayn Rand, son mentor.<\/p>\n<p><em>La pr\u00e9vention des bulles financi\u00e8res<\/em><\/p>\n<p>Comme la bulle boursi\u00e8re des <em>start-ups<\/em> le d\u00e9montrerait au tournant du mill\u00e9naire, dans une bulle financi\u00e8re, le cours des actions s\u2019envole sans le moindre effort de la part des dirigeants d\u2019entreprises et des investisseurs qui en b\u00e9n\u00e9ficient, directement pour les investisseurs, et indirectement par l\u2019interm\u00e9diaire des <em>stock options<\/em> pour les patrons. Il n\u2019existe donc pour eux aucune incitation \u2013 bien au contraire \u2013 \u00e0 d\u00e9courager le d\u00e9veloppement d\u2019un tel ph\u00e9nom\u00e8ne. De m\u00eame, lors d\u2019une bulle immobili\u00e8re, si les propri\u00e9taires trouvent leur profit dans le fait que le prix de leur logement s\u2019envole, les bailleurs de fonds y d\u00e9couvrent aussi l\u2019occasion de pr\u00eater davantage, et les promoteurs de construire davantage. Alors \u00e0 qui revient la responsabilit\u00e9 d\u2019emp\u00eacher une bulle financi\u00e8re d\u2019appara\u00eetre et d\u2019enfler par la suite ?<\/p>\n<p>En fait, selon Alan Greenspan, aucune instance n\u2019en a la responsabilit\u00e9. Interrog\u00e9 \u00e0 ce sujet, il d\u00e9clarait en d\u00e9cembre 2007 : \u00ab Apr\u00e8s avoir observ\u00e9 durant un demi-si\u00e8cle de nombreuses bulles de prix se d\u00e9velopper et \u00e9clater, je suis arriv\u00e9 \u00e0 regret \u00e0 la conclusion que les bulles ne peuvent \u00eatre d\u00e9samorc\u00e9es sans danger par une politique mon\u00e9taire ou par d\u2019autres initiatives avant que la fi\u00e8vre sp\u00e9culative ne s\u2019\u00e9teigne d\u2019elle-m\u00eame. Il est clair qu\u2019il y avait tr\u00e8s peu que les banques centrales des diff\u00e9rents pays auraient pu faire pour temp\u00e9rer la manifestation la plus r\u00e9cente de cette disposition humaine \u00e0 l\u2019euphorie, rappelant d\u2019ailleurs par certains aspects la tulipomanie en Hollande au XVII\u00e8me si\u00e8cle ou la bulle des Mers du Sud au XVIII\u00e8me en Angleterre \u00bb (Greenspan 2007).<\/p>\n<p>A partir des ann\u00e9es 1970, la situation des salari\u00e9s am\u00e9ricains se d\u00e9grada lentement et si les effets de leur perte effective de pouvoir d\u2019achat furent partiellement masqu\u00e9s, c\u2019est uniquement du fait qu\u2019un syst\u00e8me complexe de cr\u00e9dit \u00e0 la consommation se mit en place, o\u00f9 l\u2019endettement personnel compensait la perte de pouvoir d\u2019achat fond\u00e9 sur les revenus, la bulle de l\u2019immobilier offrant, pour ceux d\u2019entre eux qui \u00e9taient propri\u00e9taires, la plus-value sans cesse croissante de leur logement comme collat\u00e9ral aux emprunts qu\u2019ils contractaient. Cette classe salariale, o\u00f9 l\u2019endettement des m\u00e9nages atteignait en 2004, 120 % de leurs revenus annuels bruts, devenait, au fil des ann\u00e9es, de plus en plus vuln\u00e9rable aux fluctuations de la conjoncture dans un pays \u00e0 la couverture sociale extr\u00eamement t\u00e9nue.<\/p>\n<p>En 2004, le budget des m\u00e9nages am\u00e9ricains entra en r\u00e9gime de \u00ab cavalerie \u00bb, d\u00e9pendant chaque jour davantage pour les d\u00e9penses de consommation, de la persistance de la bulle de l\u2019immobilier o\u00f9 seule l\u2019arriv\u00e9e constante de nouvelles recrues permettait \u00e0 ceux qui \u00e9taient d\u00e9j\u00e0 propri\u00e9taires de maintenir leur pr\u00e9sence. Tout ralentissement dans ce recrutement provoquerait une stagnation du prix de l\u2019immobilier qui conduirait l\u2019\u00e9difice \u00e0 s\u2019effondrer dans son ensemble. Lorsque ce ralentissement intervint, furent tout d\u2019abord entra\u00een\u00e9s dans la chute les m\u00e9nages dont la capacit\u00e9 \u00e0 payer leurs mensualit\u00e9s reposait sur le prix sans cesse croissant des maisons, des emprunts successifs leur permettant seuls de faire face \u00e0 leurs engagements. Furent ensuite atteints, les m\u00e9nages qui avaient sp\u00e9cul\u00e9 sur le gonflement de la bulle en s\u2019achetant plusieurs habitations ou en s\u2019\u00e9tant achet\u00e9 un logement trop vaste en vue de maximiser l\u2019effet de levier qu\u2019autorise l\u2019emprunt. L\u2019immobilier r\u00e9sidentiel, \u00e9branl\u00e9 par la remise sur le march\u00e9 d\u2019un nombre d\u2019habitations en hausse croissante, entra\u00eena enfin dans sa plong\u00e9e les m\u00e9nages qui avaient con\u00e7u leur logement comme la tirelire qui leur permettrait de jouir un jour d\u2019une retraite confortable.<\/p>\n<p><em>Le retour du m\u00eame<\/em><\/p>\n<p>Le rapprochement spontan\u00e9ment fait par les commentateurs entre 2007 et 1929 est donc amplement justifi\u00e9 : les manifestations des deux crises sont les m\u00eames et leurs causes sont pratiquement identiques. M\u00eame origine en effet dans une sp\u00e9culation immobili\u00e8re d\u00e9butant dans les deux cas en Floride. La sp\u00e9culation dans l\u2019immobilier et sur les march\u00e9s boursiers r\u00e9sultait d\u00e9j\u00e0 en 1929 d\u2019une disparit\u00e9 croissante des revenus et d\u2019une concentration de la richesse entre quelques mains. Les grandes fortunes \u00e9taient \u00e0 la recherche de rendements \u00e9lev\u00e9s pour leurs placements et d\u00e9l\u00e9guaient leurs efforts \u00e0 des \u00e9tablissements financiers dont le nom a simplement chang\u00e9 : appel\u00e9s \u00e0 l\u2019\u00e9poque \u00ab investment trusts \u00bb et \u00ab hedge funds \u00bb aujourd\u2019hui. Ces officines avaient alors trouv\u00e9 le moyen de d\u00e9coupler leurs op\u00e9rations de leur responsabilit\u00e9 financi\u00e8re et utilisaient massivement l\u2019effet de levier pour multiplier leurs chances de gain. Rien de nouveau donc sous le soleil : les m\u00eames causes engendr\u00e8rent les m\u00eames effets.<\/p>\n<p>Si le portrait dress\u00e9 par Galbraith en 1954 avait pr\u00e9valu, il aurait \u00e9t\u00e9 clair que les m\u00eames conditions \u00e9taient r\u00e9unies en 2007 qui avaient exist\u00e9 en 1929 et qu\u2019une crise similaire \u00e9tait donc sur le point d\u2019\u00e9clater. La substitution de th\u00e9ories fausses aux th\u00e9ories vraies n\u2019est pas innocente puisqu\u2019elle autorise le retour de crises qu\u2019une prise de conscience qu\u2019une configuration famili\u00e8re, pr\u00e9lude \u00e0 un d\u00e9sastre, s\u2019est reconstitu\u00e9e, permettrait au contraire d\u2019\u00e9viter.<\/p>\n<p>S\u2019il a \u00e9t\u00e9 possible \u00e0 la crise qui \u00e9clata en 2007 de reproduire celle de 1929, c\u2019est parce que la compr\u00e9hension de cette derni\u00e8re s\u2019est perdue \u00e0 l\u2019occasion d\u2019un processus de s\u00e9lection entre les diff\u00e9rentes explications qui en ont \u00e9t\u00e9 offertes et o\u00f9 la fausse a \u00e9limin\u00e9 la vraie gr\u00e2ce \u00e0 l\u2019investissement massif consenti dans l\u2019enseignement et dans la production de la \u00ab science \u00bb \u00e9conomique par ceux dont l\u2019int\u00e9r\u00eat est que ces th\u00e9ories fausses pr\u00e9valent.<\/p>\n<p>Avec le retour de la crise, la r\u00e9alit\u00e9 r\u00e9affirme bien entendu ses droits. La crise offre \u00e0 la th\u00e9orie vraie de son origine, l\u2019occasion pour elle aussi d\u2019un retour. Lorsque la stabilit\u00e9 se r\u00e9instaure provisoirement, les conditions se reconstituent cependant \u00e9galement qui conduiront tendanciellement au m\u00eame glissement progressif vers une repr\u00e9sentation fausse mais plus favorable aux int\u00e9r\u00eats des b\u00e9n\u00e9ficiaires des rapports de force existants au sein de l\u2019\u00e9conomie et de la finance. Une telle alternance dialectique est in\u00e9vitable tant que le cadre demeure identique. Des tentatives radicales de reb\u00e2tir l\u2019\u00e9conomie et la finance sur des bases enti\u00e8rement neuves ont eu lieu, il s\u2019est agi chaque fois de paris co\u00fbteux, prompts \u00e0 l\u2019aveuglement \u00e0 d\u2019\u00e9ventuelles cons\u00e9quences n\u00e9gatives, et pouvant par cons\u00e9quent \u2013 et comme l\u2019a tristement confirm\u00e9 l\u2019histoire \u2013 se r\u00e9v\u00e9ler d\u00e9sastreux.<\/p>\n<p>Un autre moyen de pr\u00e9venir le retour des crises \u2013 moins co\u00fbteux et mieux \u00e0 m\u00eame de se pr\u00eater \u00e0 des rectifications de tir \u2013 consisterait \u00e0 tenir pleinement compte du fait que l\u2019\u00e9conomie et la finance sont serties dans le fonctionnement des soci\u00e9t\u00e9s, et \u00e0 leur faire d\u00e9passer leur stade pr\u00e9sent, o\u00f9 leurs dispositions \u00e0 l\u2019auto-r\u00e9gulation et \u00e0 l\u2019auto-adaptation ne d\u00e9passent pas celles d\u2019un processus naturel laiss\u00e9 \u00e0 lui\u2013m\u00eame. Il convient de les faire b\u00e9n\u00e9ficier d\u2019un progr\u00e8s similaire \u00e0 celui qu\u2019a connu le politique avec l\u2019av\u00e8nement de la d\u00e9mocratie qui constitue elle une institution que les hommes se sont offerts \u00e0 eux\u2013m\u00eames gr\u00e2ce \u00e0 leur r\u00e9flexion propre et qu\u2019ils ont mise en \u0153uvre par leur industrie, en remplacement du processus naturel spontan\u00e9 qui la pr\u00e9c\u00e9dait : celui qui aboutit in\u00e9luctablement \u00e0 l\u2019\u00e9crasement des plus faibles par les plus forts.<\/p>\n<p>Si l\u2019on tire les le\u00e7ons de la crise actuelle, comme de toutes les pr\u00e9c\u00e9dentes, les mesures qu\u2019il conviendrait de prendre pour emp\u00eacher leur retour peuvent \u00eatre \u00e9lev\u00e9es au niveau de principes, et inscrites \u00e0 ce titre au sein d\u2019une constitution. Le seul obstacle \u00e0 proc\u00e9der de cette mani\u00e8re est l\u2019absence de volont\u00e9 : les causes de la crise actuelle sont connues, elles sont identiques \u00e0 celles de la crise pr\u00e9c\u00e9dente, dont les causes \u00e9taient d\u00e9j\u00e0 connues en son temps \u2013 m\u00eame si l\u2019oubli a \u00e9t\u00e9 impos\u00e9 \u00e0 ce savoir.<\/p>\n<p><em>R\u00e9f\u00e9rences bibliographiques :<\/em><\/p>\n<p>Ben S. Bernanke, <strong>Essays on the Great Depression<\/strong>, Princeton University Press, 2000<\/p>\n<p>John Kenneth Galbraith, <strong>The Great Crash \u2013 1929<\/strong>, Houghton Mifflin, 1954<\/p>\n<p>Susan George, \u00ab <a href=\"http:\/\/www.monde-diplomatique.fr\/1996\/08\/GEORGE\/5779 \">Mythologies \u00e9conomiques : Comment la pens\u00e9e devint unique<\/a> \u00bb, Le Monde Diplomatique, Ao\u00fbt 1996<\/p>\n<p>Alan Greenspan, \u00ab The Roots of the Mortgage Crisis \u00bb, <strong>The Wall Street Journal<\/strong>, le 12 d\u00e9cembre 2007<\/p>\n<p>Paul Jorion, <strong>L\u2019implosion. La finance contre l\u2019\u00e9conomie : ce que r\u00e9v\u00e8le et annonce \u00ab la crise des subprimes \u00bb<\/strong>, Fayard, 2008<\/p>\n<p>Robert A. Margo, <a href=\"http:\/\/www.h-net.org\/reviews\/showpdf.cgi?path=222963252660\">recension<\/a> de <strong>Ben S. Bernanke, Essays on the Great Depression<\/strong>, H-Net Reviews in the Humanities and Social Sciences, 2000<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un exercice int\u00e9ressant aura lieu demain : je serai interrog\u00e9 par la revue Savoir\/Agir sur mon article intitul\u00e9 La compr\u00e9hension des crises financi\u00e8res et de leur r\u00e9p\u00e9tition qui parut en juin 2008 dans le num\u00e9ro 4 de la revue (pages 11\u201318). Je vous en avais propos\u00e9 ici le texte complet, le 20 juin 2008. \u00ab\u00a0Juin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,1,307,2769,12],"tags":[383,61,1334,2022,4481,6902,613,4711,7693],"class_list":["post-127557","post","type-post","status-publish","format-standard","hentry","category-constitution-pour-leconomie","category-economie","category-finance","category-science-economique-2","category-subprime","tag-383","tag-ben-bernanke","tag-constitution-pour-leconomie","tag-crise-des-subprimes","tag-finance","tag-grande-crise","tag-john-kenneth-galbraith","tag-rapports-de-force","tag-sciences-economiques"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/127557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=127557"}],"version-history":[{"count":8,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/127557\/revisions"}],"predecessor-version":[{"id":127568,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/127557\/revisions\/127568"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=127557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=127557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=127557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}