{"id":129590,"date":"2021-09-04T17:12:42","date_gmt":"2021-09-04T15:12:42","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=129590"},"modified":"2021-09-04T17:12:42","modified_gmt":"2021-09-04T15:12:42","slug":"veille-effondrement-74-circonspection-renaturation-le-plan-z-1-2-par-jenesauraisvoir","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2021\/09\/04\/veille-effondrement-74-circonspection-renaturation-le-plan-z-1-2-par-jenesauraisvoir\/","title":{"rendered":"Veille effondrement #74 &#8211; <b>Circonspection &#038; renaturation, le plan Z\u00a0? #1\/2 par JeNeSauraisVoir<\/b>"},"content":{"rendered":"<p class=\"p2\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-126753\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Classe-vignette-150x150.png\" alt=\"\" width=\"150\" height=\"150\" \/>A force de lire des explications que je qualifierais de maladroitement sentencieuses sur les motifs du refus du pass sanitaire et plus profond\u00e9ment sur les raisons de la r\u00e9sistance \u00e0 la vaccination, je me suis demand\u00e9 s\u2019il ne serait pas int\u00e9ressant d\u2019essayer de formuler une explication ou tout au moins de poser la question d\u2019une autre mani\u00e8re\u00a0?<span class=\"Apple-converted-space\">\u00a0 <\/span>L\u2019exercice me parait d\u2019autant plus envisageable que j\u2019ai moi-m\u00eame un peu de mal \u00e0 adh\u00e9rer \u00e0 tout ce que l\u2019on d\u00e9cide dans la pr\u00e9cipitation. Et m\u00eame si ce n\u2019\u00e9tait pas le cas, partageant une part d\u2019humanit\u00e9 avec les anti-vax, il me semble possible d\u2019essayer de ressentir leurs motivations. Le refus du pass sanitaire et la r\u00e9sistance \u00e0 la vaccination sont, je crois, r\u00e9v\u00e9lateurs de bien des choses sur nous et sur notre soci\u00e9t\u00e9. Le pire serait que nous refusions \u00e0 regarder de pr\u00e8s sous le pr\u00e9texte sp\u00e9cieux que la maison est en feu et qu\u2019il n\u2019y a rien d\u2019autre \u00e0 faire que de courir droit devant. A ce train-l\u00e0 il y a toujours quelque chose qui brule (d\u2019autant que nous sommes entr\u00e9s en effondrement) alors sortirons-nous jamais de l\u2019auberge ?<\/p>\n<p><!--more--><\/p>\n<p class=\"p3\">Pour tenter de couper court \u00e0 toutes les supputations qui auraient pour effet de m\u2019\u00e9loigner de mon sujet principal, je pr\u00e9cise qu\u2019\u00e0 ce jour, je suis nanti d\u2019un pass sanitaire \u00e0 la suite d\u2019une vaccination unique justifi\u00e9e par le fait que j\u2019ai \u00e9t\u00e9 test\u00e9 positif dans le courant de la troisi\u00e8me vague, heureusement presque sans sympt\u00f4mes hormis d\u2019avoir transpir\u00e9 nuitamment, ce qui fut la raison pour laquelle j\u2019ai voulu faire un test. J\u2019ajoute qu\u2018avant ce test positif j\u2019\u00e9tais un peu h\u00e9sitant quoique assez dispos\u00e9 \u00e0 me pr\u00e9senter \u00e0 la vaccination quand mon tour arriverait. Mais apr\u00e8s avoir \u00e9t\u00e9 contamin\u00e9 et ayant constat\u00e9 que mon organisme a assez bien r\u00e9sist\u00e9, je me suis dit que je pouvais attendre un peu, que le virus disparaitrait peut-\u00eatre avant que mon immunit\u00e9 acquise ne s\u2019estompe ou que mon organisme r\u00e9sisterait de mieux en mieux. J\u2019\u00e9tais dans la situation d\u2019un supporteur qui a vu son idole de boxeur remporter un combat et qui est devenu presque plus confiant que le combattant.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">Mais revenons aux motifs du refus du pass et aux raisons de la r\u00e9sistance \u00e0 la vaccination. J\u2019ai organis\u00e9 mon exploration du sujet en deux volets.<\/p>\n<p class=\"p3\"><span class=\"s1\"><b>Premier volet\u00a0: de notre difficult\u00e9 \u00e0 g\u00e9rer la pluralit\u00e9<\/b><\/span><\/p>\n<p class=\"p3\">La s\u00e9quence des \u00e9v\u00e8nements que nous avons v\u00e9cus depuis le d\u00e9but de la crise sanitaire semble illustrer, une fois de plus, l\u2019incapacit\u00e9 de nos soci\u00e9t\u00e9s \u00e0 g\u00e9rer la pluralit\u00e9. Nous avons ainsi tendance \u00e0 transformer toute question en un affrontement entre le<span class=\"Apple-converted-space\">\u00a0 <\/span>vrai et le faux, en opposition entre le bien et le mal. Il faut toujours que tout se termine par la victoire d\u2019un camp sur l\u2019autre et nous poursuivons ce combat m\u00eame lorsqu\u2019il est devenu inutile quitte \u00e0 ressusciter la controverse sous d\u2019autres formes.<\/p>\n<p class=\"p3\">Peut-\u00eatre devrions-nous accepter de laisser s\u2019installer un peu de palabre dans nos soci\u00e9t\u00e9s\u00a0? Ce que je m\u2019appr\u00eate \u00e0 dire au sujet de la palabre, je le tiens d\u2019un de mes profs de lyc\u00e9e, un excellent homme d\u2019origine Suisse qui a pass\u00e9 sa vie active (soit plus de 40 ans) en Afrique. Mais j\u2019assume l\u2019enti\u00e8re responsabilit\u00e9 de la restitution que je fais ici. La palabre est habituellement d\u00e9daign\u00e9e parce qu\u2019elle consiste en un bavardage d\u2019apparence d\u00e9sorganis\u00e9 d\u2019o\u00f9 il ne ressort g\u00e9n\u00e9ralement aucune d\u00e9cision concr\u00e8te. Pour une soci\u00e9t\u00e9 habitu\u00e9e \u00e0 planifier, \u00e0 \u00e9crire des programmes puis \u00e0 les ex\u00e9cuter, la palabre est indubitablement une perte de temps.<\/p>\n<p class=\"p3\">En regardant de pr\u00e8s, il est toutefois possible d\u2019y reconnaitre un dispositif d\u2019\u00e9laboration de consensus social respectant la pluralit\u00e9. On ne s\u2019exprime pas dans une palabre pour gagner, pour l\u2019emporter sur l\u2019autre. Il ne s\u2019agit pas de faire triompher une opinion tenue pour vraie sur une autre qui serait fausse. La palabre est le lieu de rapporter des faits, d\u2019exprimer des id\u00e9es, de soutenir une opinion ou m\u00eame de tenter une mystification en convoquant les \u00e2mes des anc\u00eatres. Il est vrai que le cheminement de la parole peut rapidement tourner \u00e0 la r\u00e9citation de proverbes (comme il est dit dans un passage de \u00ab\u00a0<b><i>Comment la v\u00e9rit\u00e9 et la r\u00e9alit\u00e9 furent invent\u00e9es<\/i><\/b>\u00a0\u00bb). Chaque orateur prend la parole \u00e0 son tour sans forc\u00e9ment s\u2019exprimer en r\u00e9ponse aux locuteurs pr\u00e9c\u00e9dents, d\u2019o\u00f9 cette impression de d\u00e9cousu. On se croirait sur un blog tiens\u00a0! Au final une palabre offre \u00e0 l\u2019assembl\u00e9e des participants un \u00e9ventail assez complet des id\u00e9es et positions du moment. Et puis chacun repart avec ce qu\u2019il a entendu sans qu\u2019il lui soit enjoint d\u2019\u00e9pouser la position unique (ou unifi\u00e9e) que repr\u00e9senterait une synth\u00e8se, une opinion majoritaire ou un projet de plan d\u2019action.<\/p>\n<p class=\"p3\">C\u2019est \u00e0 partir de ce que chacun a entendu lors de la palabre que s\u2019\u00e9laborent les positions futures par glissement progressif quelquefois imperceptible. L\u2019on se rend compte alors que les crispations sont loin d\u2019\u00eatre d\u00e9finitives, que les antagonismes sont moins marqu\u00e9s qu\u2019il n\u2019y parait. C\u2019est ainsi que s\u2019installe un cours principal des \u00e9v\u00e8nements \u00e0 c\u00f4t\u00e9 duquel apparaissent ou subsistent quelques ruisseaux secondaires plus ou moins importants \u2013 en toute pluralit\u00e9 j\u2019allais dire\u00a0! Il me semble que le r\u00f4le d\u2019une collectivit\u00e9 un peu soucieuse du bien-\u00eatre de chacun de ses membres est de r\u00e9aliser et de prendre soin de la pluralit\u00e9 avec le plus de douceur possible \u00ab\u00a0quoi qu\u2019il en co\u00fbte\u00a0\u00bb et non d\u2019encourager ses repr\u00e9sentants \u00e0 jouer les p\u00e8res fouettards dans une sorte de c\u00e9l\u00e9bration paroxystique de la dictature de la majorit\u00e9 (d\u2019opinion \u2013 et encore).<\/p>\n<p class=\"p3\">D\u2019apr\u00e8s un raisonnement que j\u2019ai lu notamment sur ce blog (de Paul Jorion), nous serions dans une situation o\u00f9 l\u2019on demande \u00e0 des individualit\u00e9s de faire un effort pour le bien du collectif. Cela n\u2019implique-t-il pas que, dans le m\u00eame temps, le collectif prenne soin de m\u00e9nager les individualit\u00e9s surtout lorsqu\u2019elles h\u00e9sitent, y compris pour des raisons que l\u2019on jugerait irrationnelles<span class=\"Apple-converted-space\">\u00a0 <\/span>&#8211; mais notre vie est-elle uniquement rationnelle\u00a0? Notre soci\u00e9t\u00e9 agit souvent comme si quelques bergers connaissaient le chemin de sorte qu\u2019il leur revient, de plein droit, de mener le troupeau \u00e0 marche forc\u00e9e. Nous le faisons notamment dans le choix inconditionnel du capitalisme envers et contre tout. Nous le faisons pour bien d\u2019autres choses. C\u2019est devenu l\u2019unique mode de fonctionnement de nos soci\u00e9t\u00e9s. Qui sont-ils donc ceux qui pr\u00e9tendent conna\u00eetre le but de la vie et qu\u2019il faudrait suivre \u00e0 marche forc\u00e9e\u00a0?<\/p>\n<p class=\"p3\">Mon propos n\u2018est pas de faire dans le refus \u00e0 tous crins, en d\u00e9pit du bon sens, mais de nous inciter \u00e0 faire un peu plus attention aux h\u00e9sitants, \u00e0 nous m\u00e9fier des proclamations p\u00e9remptoires qui ne tiennent en g\u00e9n\u00e9ral qu\u2019un moment. Il me semble que l\u2019h\u00e9sitation n\u2019a pas toujours \u00e9t\u00e9 mal vue, tout particuli\u00e8rement en France. En d\u2019autres temps, nous avions d\u00e9cid\u00e9 qu\u2019il \u00e9tait urgent d\u2019attendre avant d\u2019accepter totalement les OGMs, que rien ne pressait vraiment en mati\u00e8re de clonage humain. Nous avons appel\u00e9 \u00e7a le principe de pr\u00e9caution et nous en \u00e9tions m\u00eame tr\u00e8s fiers. Certes les situations ne sont pas exactement comparables mais nous avons entendu faire de l\u2019h\u00e9sitation une vertu alors notre volte-face du moment devrait nous interpeller un peu. Et pendant que nous y sommes, les responsables politiques de premier plan qui se montrent si confiants sont-ils pr\u00eat \u00e0 prendre la responsabilit\u00e9 de sanctions personnelles<span class=\"Apple-converted-space\">\u00a0 <\/span>si demain ou apr\u00e8s-demain il apparaissait que nous aurions mieux fait d\u2019attendre avant de vacciner certaines populations notamment\u00a0? Ne s\u2019appr\u00eatent-ils pas plut\u00f4t \u00e0 nous resservir le couplet du scandale du sang contamin\u00e9 \u00ab\u00a0coupable mais pas responsable\u00a0\u00bb ou l\u2019inverse je ne sais plus\u00a0? Et que ferons-nous demain lorsque des industriels ou des apprentis sorciers d\u00e9cideront d\u2019activer la jurisprudence coronavirus que nous sommes en train de constituer\u00a0: d\u00e8s lors que les r\u00e9sultats de recherches en laboratoire et des premiers tests sur le terrain sont valid\u00e9s par un comit\u00e9 scientifique, cela vaut autorisation d\u2019exploiter l\u2019invention et gare au pays qui osera s\u2019y opposer\u00a0?<\/p>\n<p class=\"p3\">Au passage, vous aurez observ\u00e9 que je ne souhaite pas me lancer dans un d\u00e9bat sur la question de savoir si la vaccination serait ou non l\u2019unique solution dont nous disposions pour g\u00e9rer la crise du coronavirus. Je pense qu\u2019il y a une vraie inqui\u00e9tude dans le fait que nous soyons uniquement occup\u00e9s \u00e0 activer cette solution dans une sorte c\u00e9l\u00e9bration de la victoire du vrai sur le faux alors que pour la catastrophe annonc\u00e9e de l\u2019effondrement nous travaillons sur pas moins de trois plans. L\u2019on comprend bien que d\u2019autres possibilit\u00e9s seraient<span class=\"Apple-converted-space\">\u00a0 <\/span>envisageables mais que ce qui est v\u00e9ritablement en jeu c\u2019est une certaine hi\u00e9rarchie des co\u00fbts\/b\u00e9n\u00e9fices que nous opposons sans m\u00e9nagement \u00e0 la tranquillit\u00e9 de ceux qui h\u00e9sitent \u2013 mais de quel droit\u00a0? On pourra donc retenir que je d\u00e9plore dans cette affaire du pass sanitaire, dans ce refus du souhait de se soustraire \u00e0 la vaccination, un d\u00e9ficit assez fr\u00e9quent dans nos soci\u00e9t\u00e9s en mati\u00e8re de gestion de la pluralit\u00e9. Avec l\u2019effondrement, il sera de plus en plus compliqu\u00e9 d\u2019obtenir que l\u2019ensemble des citoyens se comportent comme un seul homme. Ce n\u2019\u00e9tait d\u00e9j\u00e0 pas le cas avant alors autant (r\u00e9)apprendre la pluralit\u00e9 sans d\u00e9lai.<\/p>\n<p>(\u00e0 suivre&#8230;)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A force de lire des explications que je qualifierais de maladroitement sentencieuses sur les motifs du refus du pass sanitaire et plus profond\u00e9ment sur les raisons de la r\u00e9sistance \u00e0 la vaccination, je me suis demand\u00e9 s\u2019il ne serait pas int\u00e9ressant d\u2019essayer de formuler une explication ou tout au moins de poser la question d\u2019une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8268,6301],"tags":[8267,7019,7072,7102,7494,8256],"class_list":["post-129590","post","type-post","status-publish","format-standard","hentry","category-veille-effondrement","category-epidemiologie","tag-antivax","tag-coronavirus","tag-covid-19","tag-pandemie","tag-vaccin-covid-19","tag-vaccination"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/129590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=129590"}],"version-history":[{"count":2,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/129590\/revisions"}],"predecessor-version":[{"id":129595,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/129590\/revisions\/129595"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=129590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=129590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=129590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}