{"id":130868,"date":"2021-12-11T19:25:26","date_gmt":"2021-12-11T18:25:26","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=130868"},"modified":"2021-12-11T19:25:26","modified_gmt":"2021-12-11T18:25:26","slug":"la-realite-depasse-la-fiction-trump-sa-tentative-de-coup-detat-par-cedric-chevalier","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2021\/12\/11\/la-realite-depasse-la-fiction-trump-sa-tentative-de-coup-detat-par-cedric-chevalier\/","title":{"rendered":"<b>La r\u00e9alit\u00e9 d\u00e9passe la fiction &#8211; Trump &#038; sa tentative de coup d&rsquo;\u00c9tat<\/b>, par C\u00e9dric Chevalier"},"content":{"rendered":"<p><a href=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Haute-trahison.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Haute-trahison-203x300.png\" alt=\"\" width=\"203\" height=\"300\" class=\"alignleft size-medium wp-image-123454\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Haute-trahison-203x300.png 203w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Haute-trahison.png 416w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/><\/a>Bonjour Paul,<\/p>\n<p><a href=\"https:\/\/www.theguardian.com\/us-news\/2021\/dec\/10\/trump-powerpoint-mark-meadows-capitol-attack\" rel=\"noopener\" target=\"_blank\">Capitol attack panel obtains PowerPoint that set out plan for Trump to stage coup | US Capitol attack | The Guardian<\/a><\/p>\n<p>vs<\/p>\n<p><a href=\"https:\/\/www.pauljorion.com\/blog\/2020\/09\/26\/si-lon-veut-eviter-le-coup-detat-aux-etats-unis\/\" rel=\"noopener\" target=\"_blank\">Si l\u2019on veut \u00e9viter le coup d\u2019\u00c9tat aux \u00c9tats-Unis\u2026 | Blog de Paul Jorion<\/a><\/p>\n<p>(Le blog est d\u00e9cid\u00e9ment une bonne source d&rsquo;information !)<\/p>\n<p>Et ce n&rsquo;est pas fini :<\/p>\n<p><a href=\"https:\/\/www.theguardian.com\/us-news\/2021\/nov\/14\/trump-president-2024-election-coup-republicans\" rel=\"noopener\" target=\"_blank\">\u2018Terrifying for American democracy\u2019: is Trump planning for a 2024 coup? | Donald Trump | The Guardian<\/a><br \/>\n<!--more--><br \/>\nJ&rsquo;ai un terrible sentiment que les Nazis avaient pratiquement la m\u00eame libert\u00e9 de man\u0153uvre fin des ann\u00e9es 20 et d\u00e9but des ann\u00e9es 30, lorsqu\u2019ils planifiaient tranquillement et ex\u00e9cutaient\u00a0paisiblement leurs plans pour d\u00e9truire la r\u00e9publique allemande&#8230; \u00e9tape par \u00e9tape, en opportunistes, avec un incroyable culot.<\/p>\n<p>Aujourd&rsquo;hui, Donald Trump est&#8230; en libert\u00e9 ! (sic)<\/p>\n<p>Je me souviens que tu disais que les rapports sur la \u00ab\u00a0haute trahison\u00a0\u00bb potentielle de Trump \u00e9taient con\u00e7us pour \u00ab\u00a0convaincre progressivement le peuple et les \u00e9lus r\u00e9publicains que Trump \u00e9tait un criminel\u00a0\u00bb afin de pouvoir l&#8217;emp\u00eacher sans provoquer une guerre civile (et des morts).<\/p>\n<p>Je me disais soudain hier : mais si on arr\u00eatait Trump aujourd&rsquo;hui pour haute trahison (tentative de coup d&rsquo;Etat), cela pourrait aussi provoquer une guerre civile aux USA (sortie en masse de ses supporters arm\u00e9s dans la rue). Il faudrait donc aussi \u00ab\u00a0d&rsquo;abord convaincre ses \u00e9lecteurs qu&rsquo;il est un criminel\u00a0\u00bb. Des juges et des procureurs pourraient \u00eatre assassin\u00e9s sinon et \u00e7a mettrait le feu aux poudres.<\/p>\n<p>\u00c7a me faisait penser aux man\u0153uvres entre C\u00e9sar, Pomp\u00e9e et Crassus \u00e0 Rome, o\u00f9 on sent que la situation peut basculer pour un oui ou pour un non. En fonction de quel message de qui arrive le premier au S\u00e9nat.<\/p>\n<p>Mais que faire alors ? Car on est au fondement de ce qui constitue une d\u00e9mocratie, le contrat social, la question du peuple souverain et du gouvernement l\u00e9gitime. Que faire quand une partie aussi \u00e9norme de la population pl\u00e9biscite un dictateur ? (cf. nombre d&rsquo;\u00e9lecteurs de Trump en 2020)\u00a0Voil\u00e0 ce qui s&rsquo;est produit en Allemagne dans les ann\u00e9es 1930 (et plus r\u00e9cemment en Turquie lors du putsch manqu\u00e9 contre Erdogan). Lorsque le peuple soutient ou du moins consent, le dictateur a le champ libre. La guerre civile ne survient que lorsqu&rsquo;il y a un \u00e9quilibre des forces (militaire). Sinon c&rsquo;est le coup d&rsquo;Etat, et m\u00eame une minorit\u00e9 peut suffire \u00e0 prendre le pouvoir, si le peuple reste passif. En plus si cette minorit\u00e9 ne recule pas devant l&rsquo;extermination des leaders de l&rsquo;autre camp (comme les Nazis)&#8230;<\/p>\n<p>Tout semble possible apr\u00e8s l&rsquo;invasion du Capitole (et l&rsquo;\u00e9lection de Trump en premier lieu en 2016).<\/p>\n<p>Cela me fait enfin penser au philosophe John Dewey, que je connais mal mais qui me semble-t-il, voyait le coeur de la d\u00e9mocratie non pas dans les institutions et les proc\u00e9dures ou les lois, mais bien dans une attitude, un comportement, une \u00e9thique quotidienne, de la vie de tous les jours, entre les citoyens eux-m\u00eames, une \u00ab\u00a0common decency\u00a0\u00bb entre les \u00ab\u00a0bonnes gens\u00a0\u00bb, o\u00f9 oui on n&rsquo;envisage pas d&rsquo;imposer ses vues par la force \u00e0 son semblable, o\u00f9 on discute entre voisins, et on essaie de trouver des solutions ensemble. L&rsquo;id\u00e9e d&rsquo;\u00e9galit\u00e9 et de citoyen.<\/p>\n<p>Bien \u00e0 toi,<\/p>\n<p>C\u00e9dric<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour Paul, Capitol attack panel obtains PowerPoint that set out plan for Trump to stage coup | US Capitol attack | The Guardian vs Si l\u2019on veut \u00e9viter le coup d\u2019\u00c9tat aux \u00c9tats-Unis\u2026 | Blog de Paul Jorion (Le blog est d\u00e9cid\u00e9ment une bonne source d&rsquo;information !) Et ce n&rsquo;est pas fini : \u2018Terrifying for [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6223,72,6093],"tags":[7803,4442,2626,8078],"class_list":["post-130868","post","type-post","status-publish","format-standard","hentry","category-la-chute-de-la-meteorite-trump","category-etats-unis","category-fascisme","tag-coup-detat-aux-etats-unis","tag-donald-trump","tag-fascisme","tag-prise-du-capitole-le-6-janvier-2021"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/130868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=130868"}],"version-history":[{"count":2,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/130868\/revisions"}],"predecessor-version":[{"id":130870,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/130868\/revisions\/130870"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=130868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=130868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=130868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}