{"id":133448,"date":"2022-08-06T18:51:53","date_gmt":"2022-08-06T16:51:53","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=133448"},"modified":"2022-08-06T19:44:34","modified_gmt":"2022-08-06T17:44:34","slug":"les-temps-difficiles","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2022\/08\/06\/les-temps-difficiles\/","title":{"rendered":"Veille effondrement #139 &#8211; <b>Les temps difficiles<\/b>"},"content":{"rendered":"<p>Dans <a href=\"https:\/\/en.wikipedia.org\/wiki\/First_inauguration_of_Franklin_D._Roosevelt#Inaugural_address\" rel=\"noopener\" target=\"_blank\">une fameuse allocution de 1933<\/a>, Franklin D. Roosevelt d\u00e9clarait : \u00ab\u00a0We have nothing to fear but fear itself\u00a0\u00bb, \u00ab\u00a0Nous ne devons avoir peur que de la peur elle-m\u00eame\u00a0\u00bb.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-133448-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/8_5_7_a_FDRFirstInaug_MSTR.mp3?_=1\" \/><a href=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/8_5_7_a_FDRFirstInaug_MSTR.mp3\">https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/8_5_7_a_FDRFirstInaug_MSTR.mp3<\/a><\/audio>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-133450\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Les-temps-difficiles.jpg\" alt=\"\" width=\"1024\" height=\"878\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Les-temps-difficiles.jpg 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Les-temps-difficiles-300x257.jpg 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Les-temps-difficiles-768x659.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>Conversation au coin du feu 2022<\/strong> \u00ab\u00a0Nous ne devons avoir peur que &#8230; des canicules, des feux incontr\u00f4l\u00e9s, de la s\u00e9cheresse, de la fonte des calottes polaires, de la mont\u00e9e du niveau des eaux des oc\u00e9ans, des inondations, des ouragans, de l&rsquo;extinction des esp\u00e8ces\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans <a href=\"https:\/\/en.wikipedia.org\/wiki\/First_inauguration_of_Franklin_D._Roosevelt#Inaugural_address\" rel=\"noopener\" target=\"_blank\">une fameuse allocution de 1933<\/a>, Franklin D. Roosevelt d\u00e9clarait : \u00ab\u00a0We have nothing to fear but fear itself\u00a0\u00bb, \u00ab\u00a0Nous ne devons avoir peur que de la peur elle-m\u00eame\u00a0\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-133450\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Les-temps-difficiles.jpg\" alt=\"\" width=\"1024\" height=\"878\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Les-temps-difficiles.jpg 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Les-temps-difficiles-300x257.jpg 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Les-temps-difficiles-768x659.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>Conversation au coin du feu 2022<\/strong> \u00ab\u00a0Nous ne devons avoir peur que &#8230; des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8268,6686,4390,7770,4494,5799],"tags":[4099,172,4295],"class_list":["post-133448","post","type-post","status-publish","format-standard","hentry","category-veille-effondrement","category-climat","category-collapsologie","category-effondrement","category-environnement","category-extinction","tag-effondrement","tag-rechauffement-climatique","tag-secheresse"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/133448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=133448"}],"version-history":[{"count":5,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/133448\/revisions"}],"predecessor-version":[{"id":133460,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/133448\/revisions\/133460"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=133448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=133448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=133448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}