{"id":134552,"date":"2022-11-26T10:38:49","date_gmt":"2022-11-26T09:38:49","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=134552"},"modified":"2022-11-26T11:18:38","modified_gmt":"2022-11-26T10:18:38","slug":"video-les-cryptomonnaies-ont-elles-un-avenir","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2022\/11\/26\/video-les-cryptomonnaies-ont-elles-un-avenir\/","title":{"rendered":"Vid\u00e9o &#8211; <b>Les cryptomonnaies ont-elles un avenir&nbsp;?<\/b>"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"700\" height=\"450\" class=\"aligncenter\" src=\"https:\/\/www.youtube.com\/embed\/96pa_dBKAQ8\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Pour la plupart des gens, le moyen de quitter leur condition n&rsquo;est offert que par des loteries.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><iframe loading=\"lazy\" width=\"700\" height=\"450\" class=\"aligncenter\" src=\"https:\/\/www.youtube.com\/embed\/96pa_dBKAQ8\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Pour la plupart des gens, le moyen de quitter leur condition n&rsquo;est offert que par des loteries.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4694,307,21],"tags":[8976,8974,8099,8975,678,8965,8977,8969],"class_list":["post-134552","post","type-post","status-publish","format-standard","hentry","category-bourse","category-finance","category-monnaie","tag-binance","tag-casino","tag-cryptomonnaie","tag-esperance","tag-espoir","tag-ftx","tag-pump-dump","tag-sam-bankman-fried"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/134552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=134552"}],"version-history":[{"count":4,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/134552\/revisions"}],"predecessor-version":[{"id":134556,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/134552\/revisions\/134556"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=134552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=134552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=134552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}