{"id":141952,"date":"2024-10-28T14:53:27","date_gmt":"2024-10-28T13:53:27","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=141952"},"modified":"2024-10-28T14:53:27","modified_gmt":"2024-10-28T13:53:27","slug":"afnor-se-preparer-pour-la-qse-de-demain-le-3-decembre-2024","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2024\/10\/28\/afnor-se-preparer-pour-la-qse-de-demain-le-3-decembre-2024\/","title":{"rendered":"Afnor, <b>Se pr\u00e9parer pour la QSE de demain<\/b>, le 3 d\u00e9cembre 2024"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-141953\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.43.17.png\" alt=\"\" width=\"2470\" height=\"1098\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.43.17.png 2470w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.43.17-300x133.png 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.43.17-1024x455.png 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.43.17-768x341.png 768w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.43.17-1536x683.png 1536w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.43.17-2048x910.png 2048w\" sizes=\"auto, (max-width: 2470px) 100vw, 2470px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-141954\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.03.png\" alt=\"\" width=\"2158\" height=\"1748\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.03.png 2158w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.03-300x243.png 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.03-1024x829.png 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.03-768x622.png 768w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.03-1536x1244.png 1536w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.03-2048x1659.png 2048w\" sizes=\"auto, (max-width: 2158px) 100vw, 2158px\" \/><br \/>\n<!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-141955\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.27.png\" alt=\"\" width=\"2148\" height=\"1478\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.27.png 2148w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.27-300x206.png 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.27-1024x705.png 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.27-768x528.png 768w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.27-1536x1057.png 1536w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.27-2048x1409.png 2048w\" sizes=\"auto, (max-width: 2148px) 100vw, 2148px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-141956\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.57.png\" alt=\"\" width=\"2154\" height=\"1762\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.57.png 2154w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.57-300x245.png 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.57-1024x838.png 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.57-768x628.png 768w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.57-1536x1256.png 1536w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-10-28-a\u0300-14.45.57-2048x1675.png 2048w\" sizes=\"auto, (max-width: 2154px) 100vw, 2154px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9204,13],"tags":[9839,9205,940],"class_list":["post-141952","post","type-post","status-publish","format-standard","hentry","category-grands-modeles-de-langage","category-intelligence-artificielle","tag-afnor","tag-grands-modeles-de-langage","tag-intelligence-artificielle-2"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/141952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=141952"}],"version-history":[{"count":1,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/141952\/revisions"}],"predecessor-version":[{"id":141957,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/141952\/revisions\/141957"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=141952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=141952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=141952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}