{"id":142321,"date":"2024-11-25T18:02:51","date_gmt":"2024-11-25T17:02:51","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=142321"},"modified":"2024-11-25T18:02:51","modified_gmt":"2024-11-25T17:02:51","slug":"le-mail-pour-signaler-une-panne-de-messagerie-bienvenue-en-absurdie-par-thombillabong","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2024\/11\/25\/le-mail-pour-signaler-une-panne-de-messagerie-bienvenue-en-absurdie-par-thombillabong\/","title":{"rendered":"<b>Le mail pour signaler une panne de messagerie (bienvenue en absurdie :-)&nbsp;!)<\/b>, par ThomBillabong"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-142323\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.30-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph.webp\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.30-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph.webp 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.30-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph-300x300.webp 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.30-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph-150x150.webp 150w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.30-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph-768x768.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<blockquote><p><em>Illustration par DALL\u00b7E (+PJ)<\/em><\/p><\/blockquote>\n<div>Ce matin, une panne mondiale sur Outlook affecte nombre d&rsquo;entreprises, dont la mienne.<\/div>\n<div>Les courriers affect\u00e9s le sont sur PC et t\u00e9l\u00e9phones mobiles, \u00e0 la r\u00e9ception&#8230; et n&rsquo;arrivent pas.<\/div>\n<div><\/div>\n<div>Bienvenue en absurdie \ud83d\ude42 :<\/div>\n<div>\n<ol>\n<li>En interne, dans ma soci\u00e9t\u00e9, l&rsquo;\u00e9quipe de support informatique envoie donc &#8230; un mail \u00e0 toute l&rsquo;entreprise pour pr\u00e9venir les salari\u00e9s qu&rsquo;ils ne recevront pas de mail ou qu&rsquo;il y a un risque qu&rsquo;ils ne re\u00e7oivent pas de mails &#8230;<\/li>\n<li>Je remonte au support &#8211; sur un outil de ticketing en ligne &#8211; l&rsquo;incongruit\u00e9 de la chose, parce que certains chanceux comme moi ont re\u00e7u le mail d&rsquo;information, et on me r\u00e9pond : \u00ab\u00a0nous sommes au courant du bug et nous avons pr\u00e9vu une proc\u00e9dure pour cela\u00a0\u00bb. Je r\u00e9ponds \u00e0 cela qu&rsquo;elle n&rsquo;est pas applicable en l&rsquo;occurrence et qu&rsquo;il convient d&rsquo;utiliser un autre canal que nous avons mis en place depuis 3 ans nomm\u00e9 Workplace (version payante et priv\u00e9e de Facebook pour les entreprises), et qu&rsquo;il est pr\u00e9f\u00e9rable dans de telles circonstances d&rsquo;utiliser la redondance pour que la transmission du message soit \u00ab\u00a0robuste\u00a0\u00bb, \u00e0 savoir que ce dernier arrive bien jusqu&rsquo;aux destinataires.<\/li>\n<li>On me r\u00e9pond sur l&rsquo;outil de ticketing que s&rsquo;il faut revoir la proc\u00e9dure, il faut faire un mail de demande sp\u00e9cifique en bonne et due forme ! Je r\u00e9ponds que ce n&rsquo;est pas d&rsquo;actualit\u00e9 vue la panne Outlook et que l&rsquo;application de proc\u00e9dure n&rsquo;interdit pas le bon sens. Pas de nouvelles du support depuis ma derni\u00e8re r\u00e9ponse.<\/li>\n<\/ol>\n<div><b>Pr\u00e9cision :<\/b> je travaille dans une entreprise priv\u00e9e familiale &#8211; un petit groupe d&rsquo;environ 800 personnes diss\u00e9min\u00e9es autour du globe pour \u00eatre exact &#8211; o\u00f9 la plupart de mes semblables sont persuad\u00e9s que le service public est une infamie synonyme de perte de temps et d&rsquo;efficacit\u00e9 qui gaspille nos imp\u00f4ts. Si j&rsquo;ose timidement souligner l&rsquo;incongruit\u00e9 de ce qui pr\u00e9c\u00e8de, on me r\u00e9pond \u00ab\u00a0Oui mais nous, c&rsquo;est du priv\u00e9 : \u00e7a concerne les actionnaires\u00a0\u00bb. Pas faux, me voil\u00e0 rassur\u00e9.<\/div>\n<div><\/div>\n<div>Bienvenue dans le monde orwellien.<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-142324\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.21-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph.webp\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.21-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph.webp 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.21-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph-300x300.webp 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.21-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph-150x150.webp 150w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/DALL\u00b7E-2024-11-25-17.52.21-A-surreal-depiction-of-a-world-turned-upside-down-where-people-are-seen-floating-or-standing-on-inverted-landscapes-sending-emails-through-holograph-768x768.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<blockquote><p><em>Illustration par DALL\u00b7E (+PJ)<\/em><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Illustration par DALL\u00b7E (+PJ) Ce matin, une panne mondiale sur Outlook affecte nombre d&rsquo;entreprises, dont la mienne. Les courriers affect\u00e9s le sont sur PC et t\u00e9l\u00e9phones mobiles, \u00e0 la r\u00e9ception&#8230; et n&rsquo;arrivent pas. Bienvenue en absurdie \ud83d\ude42 : En interne, dans ma soci\u00e9t\u00e9, l&rsquo;\u00e9quipe de support informatique envoie donc &#8230; un mail \u00e0 toute l&rsquo;entreprise [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[833],"tags":[9877,9878],"class_list":["post-142321","post","type-post","status-publish","format-standard","hentry","category-la-vie-de-tous-les-jours","tag-messageries","tag-outlook"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/142321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=142321"}],"version-history":[{"count":2,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/142321\/revisions"}],"predecessor-version":[{"id":142325,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/142321\/revisions\/142325"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=142321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=142321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=142321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}