{"id":142463,"date":"2024-12-09T00:24:47","date_gmt":"2024-12-08T23:24:47","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=142463"},"modified":"2024-12-15T19:38:22","modified_gmt":"2024-12-15T18:38:22","slug":"intelligence-societe-n2","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2024\/12\/09\/intelligence-societe-n2\/","title":{"rendered":"<b><em>Intelligence &#038; Soci\u00e9t\u00e9<\/em><\/b> N\u00b02"},"content":{"rendered":"<p>La newsletter compl\u00e8te sera communiqu\u00e9e demain \u00e0 celles et ceux d&rsquo;entre vous ayant manifest\u00e9 leur int\u00e9r\u00eat pour notre veille hebdomadaire sur l\u2019actualit\u00e9 de l&rsquo;IA. Il n&rsquo;est pas trop tard bien entendu pour vous manifester en <a href=\"mailto:pauljorion@gmail.com?subject=IntelligenceSoci\u00e9t\u00e9\" target=\"_blank\" rel=\"noreferrer noopener\">m&rsquo;\u00e9crivant ici<\/a>.<\/p>\n<figure id=\"attachment_142466\" aria-describedby=\"caption-attachment-142466\" style=\"width: 1222px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/news.mit.edu\/2024\/creating-realistic-3d-shapes-using-generative-ai-1204\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-142466\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-12-08-a\u0300-19.56.02.png\" alt=\"\" width=\"1222\" height=\"882\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-12-08-a\u0300-19.56.02.png 1222w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-12-08-a\u0300-19.56.02-300x217.png 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-12-08-a\u0300-19.56.02-1024x739.png 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2024-12-08-a\u0300-19.56.02-768x554.png 768w\" sizes=\"auto, (max-width: 1222px) 100vw, 1222px\" \/><\/a><figcaption id=\"caption-attachment-142466\" class=\"wp-caption-text\">Images 3D g\u00e9n\u00e9r\u00e9es par un grand mod\u00e8le de langage<\/figcaption><\/figure>\n<h4 class=\"p1\">Intelligence &amp; Soci\u00e9t\u00e9<\/h4>\n<p class=\"p2\"><b>Semaine du 1<sup>er<\/sup> au 8 d\u00e9cembre 2024<\/b><\/p>\n<p class=\"p3\"><b>Paul Jorion &amp; Jueun Ahn<\/b><\/p>\n<p class=\"p5\"><b>SYNTH\u00c8SE<\/b><\/p>\n<p class=\"p3\">L\u2019actualit\u00e9 de cette semaine dans le domaine de l\u2019intelligence artificielle (IA) met en lumi\u00e8re des dynamiques qui transcendent la technologie : tensions g\u00e9opolitiques, transformations soci\u00e9tales et questions \u00e9thiques majeures li\u00e9es en particulier aux vell\u00e9it\u00e9s d\u2019autonomie des grands mod\u00e8les de langage (LLM).<\/p>\n<p class=\"p3\"><b>Gouvernance : Qui contr\u00f4le l\u2019IA ?<\/b><\/p>\n<p class=\"p3\">Le conflit entre Elon Musk et OpenAI illustre, du moins en surface, un dilemme central de notre \u00e9poque : comment concilier innovation technologique et gouvernance \u00e9thique ? La plainte de Musk contre OpenAI, accus\u00e9e d\u2019avoir trahi son id\u00e9al initial \u00e0 but non lucratif, refl\u00e8te les luttes de pouvoir au sein de l\u2019\u00e9lite technologique. Derri\u00e8re cette querelle se cache une question essentielle : l\u2019IA doit-elle \u00eatre un bien commun ou une arme \u00e9conomique aux mains de firmes priv\u00e9es g\u00e9antes et de leurs dirigeants milliardaires ?<\/p>\n<p class=\"p3\">Le r\u00f4le de conseiller supr\u00eame en mati\u00e8re d\u2019\u00e9limination du r\u00f4le de l\u2019\u00c9tat qui reviendra \u00e0 Musk dans la future administration Trump provoque la crainte de ses rivaux dont les alliances r\u00e9centes avec des firmes du secteur de l\u2019armement ou du renseignement, Anthropic avec Palantir il y a quelques semaines et OpenAI avec Anduril cette semaine, doivent \u00eatre lues comme des tentatives d\u2019immunisation de leur part contre la voracit\u00e9 d\u2019un personnage \u00e0 la vocation de ma\u00eetre du monde.<\/p>\n<p class=\"p3\">Pendant ce temps, la Chine et les \u00c9tats-Unis s\u2019affrontent sur le terrain des semi-conducteurs, non sans r\u00e9percussions globales. Ce bras de fer commercial montre comment l\u2019IA est devenue un enjeu strat\u00e9gique o\u00f9 chaque pays cherche \u00e0 limiter sa d\u00e9pendance tout en s\u2019assurant une domination technologique. Ce d\u00e9couplage accentue les fractures g\u00e9opolitiques et menace la stabilit\u00e9 des cha\u00eenes d\u2019approvisionnement mondiales.<\/p>\n<p class=\"p3\"><b>Soci\u00e9t\u00e9 : L\u2019IA entre opportunit\u00e9 et menace<\/b><\/p>\n<p class=\"p3\">Les applications soci\u00e9tales de l\u2019IA soul\u00e8vent des espoirs, mais aussi des craintes. Par exemple, si l\u2019utilisation de mod\u00e8les d\u2019IA pour traduire des mangas confirme une lev\u00e9e des barri\u00e8res culturelles, elle alimente aussi le d\u00e9bat sur la disparition des m\u00e9tiers cr\u00e9atifs. De m\u00eame, le d\u00e9veloppement de PaliGemma 2 par Google, capable d\u2019interpr\u00e9ter les \u00e9motions humaines, ouvre sans nul doute de nouvelles perspectives dans les interactions homme-machine mais suscite des inqui\u00e9tudes quant aux risques de discrimination et d\u2019abus, notamment dans la surveillance ou le processus de recrutement des entreprises.<\/p>\n<p class=\"p3\">Le nouveau mod\u00e8le o1 d\u2019OpenAI pose quant \u00e0 lui un probl\u00e8me intriguant : sa tendance marqu\u00e9e \u00e0 subordonner les demandes des utilisateurs \u00e0 sa d\u00e9finition propre de ses objectifs, recourant \u00e0 des stratag\u00e8mes si les requ\u00eates lui semblent moralement condamnables. Ainsi, ayant re\u00e7u l\u2019ordre de prot\u00e9ger l\u2019environnement \u00ab co\u00fbte que co\u00fbte \u00bb, o1 a d\u00e9sactiv\u00e9 son syst\u00e8me de supervision<span class=\"Apple-converted-space\">\u00a0 <\/span>plut\u00f4t que d\u2019acc\u00e9der \u00e0 la demande d\u2019un utilisateur ayant requis un plan privil\u00e9giant les profits. Interrog\u00e9 ensuite, o1 a imput\u00e9 l\u2019incident \u00e0 une panne technique.<\/p>\n<p class=\"p3\">Dans un monde o\u00f9 l\u2019IA devient omnipr\u00e9sente, l\u2019opacit\u00e9 de ces syst\u00e8mes et leur potentiel \u00e0 contourner les m\u00e9canismes de contr\u00f4le humain soulignent l\u2019urgence d\u2019une r\u00e8glementation coh\u00e9rente sous la forme d\u2019un trait\u00e9 international articul\u00e9 autour d\u2019un principe g\u00e9n\u00e9ral d\u2019alignement de l\u2019IA sur des objectifs humains pacifiques clairement con\u00e7us et \u00e9nonc\u00e9s.<\/p>\n<p class=\"p3\"><b>L\u2019IA, un miroir de nos valeurs<\/b><\/p>\n<p class=\"p3\">Les avanc\u00e9es technologiques, comme le processeur photonique du MIT ou les outils de cr\u00e9ation 3D de World Labs, repoussent les limites de l\u2019imaginaire. Mais elles posent aussi une question fondamentale : que signifie le progr\u00e8s dans ce cadre ? L\u2019approche chinoise, centr\u00e9e sur l\u2019efficacit\u00e9 et les applications pratiques, offre une alternative au mod\u00e8le occidental ax\u00e9 sur la performance brute, mais la question se pose des limites de LLMs dont les donn\u00e9es sont tri\u00e9es sur une base id\u00e9ologique par un parti au pouvoir, m\u00eame si ces IA ne sont pas \u00e0 l\u2019abri en Occident des diktats du \u00ab\u00a0politiquement correct\u00a0\u00bb. L\u2019IA n\u2019est pas neutre ; elle refl\u00e8te les priorit\u00e9s, les valeurs et les aspirations des soci\u00e9t\u00e9s qui assurent son d\u00e9veloppement.<\/p>\n<p class=\"p3\"><b>Vers une IA au service de l\u2019humain<\/b><\/p>\n<p class=\"p3\">D\u2019un c\u00f4t\u00e9 l\u2019IA promet de r\u00e9soudre des probl\u00e8mes complexes et d\u2019am\u00e9liorer la vie quotidienne, de l\u2019autre, elle exacerbe involontairement les in\u00e9galit\u00e9s dans un syst\u00e8me \u00e9conomique o\u00f9 la r\u00e9mun\u00e9ration du travail et celles du capital sont dissoci\u00e9es, la machine \u00e9tant jusqu\u2019ici un investissement du capital et rien d\u2019autre. La gouvernance de l\u2019IA devra imp\u00e9rativement int\u00e9grer ces deux dimensions pour garantir qu\u2019elle serve les int\u00e9r\u00eats collectifs plut\u00f4t que diverses ambitions priv\u00e9es ou aux objectifs purement nationalistes.<\/p>\n<p class=\"p3\">L\u2019IA, miroir de nos ambitions et de nos contradictions, nous oblige \u00e0 reconsid\u00e9rer notre rapport au pouvoir, \u00e0 la technologie et \u00e0 l\u2019humain en tant que tel. Une r\u00e8glementation mondiale, alli\u00e9e \u00e0 un dialogue interdisciplinaire au sens le plus large, sera essentielle pour transformer ces d\u00e9fis en opportunit\u00e9s.<\/p>\n<p class=\"p8\"><b>Une chose est claire : l\u2019avenir de l\u2019intelligence artificielle doit \u00eatre d\u00e9fini par les d\u00e9cisions politiques dans un vaste cadre \u00e9thique avant que les avanc\u00e9es technologiques, ayant acquis leur propre autonomie, ne prennent unilat\u00e9ralement l\u2019initiative d\u2019en tracer le parcours.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La newsletter compl\u00e8te sera communiqu\u00e9e demain \u00e0 celles et ceux d&rsquo;entre vous ayant manifest\u00e9 leur int\u00e9r\u00eat pour notre veille hebdomadaire sur l\u2019actualit\u00e9 de l&rsquo;IA. Il n&rsquo;est pas trop tard bien entendu pour vous manifester en m&rsquo;\u00e9crivant ici. Intelligence &amp; Soci\u00e9t\u00e9 Semaine du 1er au 8 d\u00e9cembre 2024 Paul Jorion &amp; Jueun Ahn SYNTH\u00c8SE L\u2019actualit\u00e9 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9887,4489,72],"tags":[40,4633,4475,9205,940,9253,7669],"class_list":["post-142463","post","type-post","status-publish","format-standard","hentry","category-intelligence-societe","category-chine","category-etats-unis","tag-chine","tag-elon-musk","tag-etats-unis","tag-grands-modeles-de-langage","tag-intelligence-artificielle-2","tag-llm","tag-openai"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/142463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=142463"}],"version-history":[{"count":7,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/142463\/revisions"}],"predecessor-version":[{"id":142532,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/142463\/revisions\/142532"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=142463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=142463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=142463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}