{"id":143872,"date":"2025-04-11T14:53:24","date_gmt":"2025-04-11T12:53:24","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=143872"},"modified":"2025-04-11T14:53:24","modified_gmt":"2025-04-11T12:53:24","slug":"le-spectacle-de-la-prosperite-et-de-la-paix-que-lempire-chinois-offre-au-monde-va-convertir-tous-les-peuples-a-lharmonie-chinoise-par-pierre-guillemot","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2025\/04\/11\/le-spectacle-de-la-prosperite-et-de-la-paix-que-lempire-chinois-offre-au-monde-va-convertir-tous-les-peuples-a-lharmonie-chinoise-par-pierre-guillemot\/","title":{"rendered":"<b>Le spectacle de la prosp\u00e9rit\u00e9 et de la paix que l&#8217;empire chinois offre au monde va convertir tous les peuples \u00e0 l&rsquo;harmonie chinoise<\/b>, par Pierre Guillemot"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-143874\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_49_39-PM.png\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_49_39-PM.png 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_49_39-PM-300x300.png 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_49_39-PM-150x150.png 150w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_49_39-PM-768x768.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Illustration par ChatGPT 4o<\/em><\/p>\n<blockquote><p><strong>Billet invit\u00e9.<\/strong><\/p><\/blockquote>\n<p>La Chine ne sera pas le ma\u00eetre du monde au sens vulgaire du terme, avec des gouvernements ob\u00e9issants dans les autres pays, des garnisons chinoises partout dans le monde, un tribut vers\u00e9 en \u00e9change de la protection, et reconna\u00eetre la sup\u00e9riorit\u00e9 de la ville ensoleill\u00e9e en haut de la colline.<\/p>\n<p>La Chine a recommenc\u00e9 son r\u00f4le de dispensation des principes de gouvernement, la hi\u00e9rarchie des devoirs r\u00e9ciproques du haut en bas de la soci\u00e9t\u00e9, avec au sommet le gardien du bien commun. \u00ab\u00a0Le bon gouvernement, c&rsquo;est faire vivre dans l&rsquo;abondance un peuple nombreux.\u00a0\u00bb<\/p>\n<p>La d\u00e9mocratie telle qu&rsquo;on l&rsquo;entend en Occident, la loi produit du choix de la majorit\u00e9, les dirigeants choisis par une proc\u00e9dure de majorit\u00e9, la loi sup\u00e9rieure aux pouvoirs (\u00ab\u00a0Etat de droit\u00a0\u00bb), la \u00ab\u00a0concurrence libre et non fauss\u00e9e\u00a0\u00bb dans la production et la distribution des richesses, tout cela est contraire \u00e0 la raison. Les peuples ont maintenant vu ce que cela produit, combien ils sont opprim\u00e9s et spoli\u00e9s par ceux qui invoquent les principes d\u00e9mocratiques ; l&rsquo;Europe de Maastricht en est la caricature repoussante.<\/p>\n<p>Le spectacle de la prosp\u00e9rit\u00e9 et de la paix que l&#8217;empire chinois offre au monde, de nouveau apr\u00e8s un moment de faiblesse, va convertir tous les peuples \u00e0 l&rsquo;harmonie chinoise. La d\u00e9monstration des bienfaits \u00e9conomiques est d\u00e9j\u00e0 \u00e9clatante. La vision de s\u00e9curit\u00e9 et de propret\u00e9 qu&rsquo;en ram\u00e8nent tous les touristes et que racontent les \u00e9trangers qui y vivent contribue \u00e0 rendre sans objet la propagande malveillante qui essaie de faire durer l&rsquo;image de ce qui \u00e9tait presque vrai il y a quarante ans.<\/p>\n<p>Et les \u00e9colos illusionn\u00e9s voient dans l&rsquo;ordre hi\u00e9rarchique auquel ils n&rsquo;ont rien compris le moyen d&rsquo;imposer enfin leur r\u00eave de sauver le monde par l&rsquo;an\u00e9antissement des richesses et des hommes.<\/p>\n<p>Serons-nous bient\u00f4t tous Chinois ? Ou bien les id\u00e9es chinoises, dissoutes dans les chaudrons des autres civilisations, susciteront-elles de nouvelles temp\u00eates ?<\/p>\n<p>Il y a un pr\u00e9c\u00e9dent. En 1615 les gens instruits en Europe avaient trouv\u00e9 dans \u00ab\u00a0De Christiana expeditione apud Sinas\u00a0\u00bb la constatation extatique de Nicolas Trigault : \u00ab\u00a0Le plus instruit est le plus noble\u00a0\u00bb (ce n&rsquo;est pas la citation litt\u00e9rale, mais un r\u00e9sum\u00e9 de l&rsquo;expos\u00e9 sur la distinction sociale en Chine), et \u00e7a avait donn\u00e9, 174 ans apr\u00e8s, (en 1789 pour ceux qui ne souviendraient pas) \u00ab\u00a0Tous les Citoyens &#8230;. sont \u00e9galement admissibles \u00e0 toutes dignit\u00e9s, places et emplois publics, selon leur capacit\u00e9, et sans autre distinction que celle de leurs vertus et de leurs talents,\u00a0\u00bb n\u00e9gation de la naissance et de la faveur du roi qui fondaient la soci\u00e9t\u00e9 depuis des si\u00e8cles ; le principe est plus ou moins une d\u00e9rision dans la r\u00e9alit\u00e9, mais tout le monde y croit partout dans le monde, et ceux qui disent qu&rsquo;ils n&rsquo;y croient pas sont d\u00e9nonc\u00e9s.<\/p>\n<p>Et-ce que le message de la civilisation chinoise, aujourd&rsquo;hui relay\u00e9 par le Parti, r\u00e9ussira une nouvelle fois \u00e0 remodeler le monde ?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-143873\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_47_33-PM.png\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_47_33-PM.png 1024w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_47_33-PM-300x300.png 300w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_47_33-PM-150x150.png 150w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/ChatGPT-Image-Apr-11-2025-02_47_33-PM-768x768.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Illustration par ChatGPT 4o<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Illustration par ChatGPT 4o Billet invit\u00e9. La Chine ne sera pas le ma\u00eetre du monde au sens vulgaire du terme, avec des gouvernements ob\u00e9issants dans les autres pays, des garnisons chinoises partout dans le monde, un tribut vers\u00e9 en \u00e9change de la protection, et reconna\u00eetre la sup\u00e9riorit\u00e9 de la ville ensoleill\u00e9e en haut de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4489,2597],"tags":[40,10032],"class_list":["post-143872","post","type-post","status-publish","format-standard","hentry","category-chine","category-democratie-2","tag-chine","tag-nicolas-trigault"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/143872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=143872"}],"version-history":[{"count":3,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/143872\/revisions"}],"predecessor-version":[{"id":143877,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/143872\/revisions\/143877"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=143872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=143872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=143872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}