{"id":145746,"date":"2025-10-22T16:55:37","date_gmt":"2025-10-22T14:55:37","guid":{"rendered":"https:\/\/www.pauljorion.com\/blog\/?p=145746"},"modified":"2025-10-22T17:53:31","modified_gmt":"2025-10-22T15:53:31","slug":"nobodys-girl-a-memoir-of-surviving-abuse-and-fighting-for-justice-le-pouvoir-dun-livre","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2025\/10\/22\/nobodys-girl-a-memoir-of-surviving-abuse-and-fighting-for-justice-le-pouvoir-dun-livre\/","title":{"rendered":"<b><em>Nobody\u2019s Girl: A Memoir of Surviving Abuse and Fighting for Justice<\/em> &nbsp;: le pouvoir d&rsquo;un livre<\/b>"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-145749\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Nobodys-Girl.jpg\" alt=\"\" width=\"994\" height=\"1500\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Nobodys-Girl.jpg 994w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Nobodys-Girl-199x300.jpg 199w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Nobodys-Girl-679x1024.jpg 679w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Nobodys-Girl-768x1159.jpg 768w\" sizes=\"auto, (max-width: 994px) 100vw, 994px\" \/><\/p>\n<p>Virginia Roberts Giuffre fut l&rsquo;une des jeunes victimes du r\u00e9seau de trafic sexuel mis en place par Jeffrey Epstein et Ghislaine Maxwell &#8211; il est mort, elle est en prison (r\u00e9cemment d\u00e9plac\u00e9e &#8211; du fait de la g\u00e9n\u00e9rosit\u00e9 de l&rsquo;administration Trump &#8211; vers un \u00e9tablissement \u00ab\u00a0portes ouvertes\u00a0\u00bb).<\/p>\n<p>Hier a paru l&rsquo;autobiographie de Giuffre intitul\u00e9e <em>La fille \u00e0 personne : Le t\u00e9moignage d&rsquo;une survivante de s\u00e9vices et de son combat pour la justice<\/em><\/p>\n<p>\u2022 2011 : premi\u00e8res d\u00e9clarations publiques de Giuffre (<em>The Daily Mail<\/em>)<br \/>\n\u2022 2014-2015 : les pointill\u00e9s sont reli\u00e9s quand, \u00e0 l&rsquo;occasion d&rsquo;un proc\u00e8s, un t\u00e9moignage attribu\u00e9 \u00e0 \u00ab\u00a0Jane Doe #3\u00a0\u00bb (\u00ab Victime n\u00b0 3 \u00bb) reproduit des propos qu&rsquo;elle a d\u00e9j\u00e0 tenus<br \/>\n\u2022 2019 : regain d&rsquo;int\u00e9r\u00eat mondial apr\u00e8s l&rsquo;arrestation et la mort d&rsquo;Epstein, Giuffre met des noms sur certaines des personnes \u00e9voqu\u00e9es par elle, mais pas sur toutes &#8211; on croit comprendre que c&rsquo;est par peur de repr\u00e9sailles.<br \/>\n\u2022 2025 : Giuffre se suicide le 25 avril<\/p>\n<p>Le livre a donc paru hier.<\/p>\n<p>Le pouvoir d\u2019un livre : la royaut\u00e9 chancelle au Royaume-Uni, le prince Andrew est mouill\u00e9 jusqu\u2019au cou, il a vers\u00e9 la somme de 12 millions de livres sterling \u00e0 Giuffre comme prix de son silence, somme dont on s\u2019interroge quant \u00e0 l\u2019origine. Andrew a d\u00e9j\u00e0 renonc\u00e9 \u00e0 certains de ses privil\u00e8ges princiers, mais des parlementaires britanniques ne veulent pas s&rsquo;arr\u00eater l\u00e0.<\/p>\n<p>Andrew \u00e9tait un excellent ami d&rsquo;Epstein, mais son meilleur ami (jusqu&rsquo;\u00e0 un diff\u00e9rend relatif \u00e0 la vente d&rsquo;une maison) \u00e9tait, de notori\u00e9t\u00e9 publique, Donald Trump, lequel avait d&rsquo;ailleurs \u00e9crit dans le livre d&rsquo;Or \u00e0 l&rsquo;occasion des 50 ans d&rsquo;Epstein, entre autres, que \u00ab Nous avons certaines choses en commun, Jeffrey [&#8230;] Les \u00e9nigmes ne vieillissent jamais, l&rsquo;as-tu remarqu\u00e9 ? [&#8230;] Un pote, c&rsquo;est quelque chose de merveilleux. Joyeux anniversaire, et que chaque jour soit un nouveau merveilleux secret\u00a0\u00bb.<\/p>\n<p>Nous ne d\u00e9couvrons rien que nous ne sachions d\u00e9j\u00e0 quant \u00e0 la d\u00e9pravation d&rsquo;un certain <em>jet-set<\/em> et sa capacit\u00e9 \u00e0 passer entre les gouttes. Mais il n&rsquo;est jamais mauvais que le d\u00e9bat soit inlassablement remis \u00e0 l&rsquo;ordre du jour, sans fioritures et accompagn\u00e9 si n\u00e9cessaire, de l&rsquo;enti\u00e8ret\u00e9 des d\u00e9tails sordides, pour qu&rsquo;on saisisse bien la taille du scandale de l&rsquo;omerta institutionnelle.<\/p>\n<p>Si l&rsquo;on en croit Giuffre, le personnage le plus abject &#8211; qui la laissa couverte d&rsquo;ecchymoses et saignant de tous les orifices (des photos existent &#8211; Epstein lui dit : \u00ab\u00a0Ce sont des choses qui arrivent\u00a0\u00bb) &#8211; est un ministre dont le nom n&rsquo;appara\u00eet pas dans le livre, mais dont elle avait d\u00e9voil\u00e9 l&rsquo;identit\u00e9 lors d&rsquo;entretiens. Si l&rsquo;on relie ici les pointill\u00e9s, c&rsquo;est une autre facette du trafic sexuel international du <em>jet-set<\/em> qui est mise en lumi\u00e8re : sa dimension g\u00e9opolitique, ou \u00ab\u00a0Comment une grande nation peut \u00eatre forc\u00e9e de s&rsquo;aligner enti\u00e8rement sur la volont\u00e9 d&rsquo;une plus petite, parce qu&rsquo;un nombre suffisant de ses dirigeants se sont compromis dans l&rsquo;ombre d&rsquo;un pr\u00e9dateur sexuel \u00e0 l&rsquo;\u00e9chelle industrielle, et doivent d\u00e9sormais chanter\u00a0\u00bb.<\/p>\n<p>En ma\u00eetrisant sa souffrance, en r\u00e9digeant le r\u00e9cit de son calvaire et en mettant fin \u00e0 ses jours avant sa publication sous la forme d&rsquo;un livre &#8211; \u00e9chappant ainsi par la mort \u00e0 toutes les repr\u00e9sailles possibles (par exemple, Andrew d&rsquo;Angleterre ayant recrut\u00e9 des trolls professionnels pour la harceler) &#8211; Madame Virginia Roberts Giuffre a r\u00e9ussi le coup de ma\u00eetre de lancer une grenade d\u00e9goupill\u00e9e dans la fosse \u00e0 purin. Les retomb\u00e9es se feront sentir pendant des mois, sinon des ann\u00e9es. Il nous est ainsi rappel\u00e9 que si notre vie fut un g\u00e2chis sans nom, il nous est toujours possible de faire de notre mort, un chef-d&rsquo;\u0153uvre. Chapeau bas, bravo l&rsquo;Artiste !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-145750\" src=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2025-10-22-a\u0300-15.38.04.png\" alt=\"\" width=\"1086\" height=\"1446\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2025-10-22-a\u0300-15.38.04.png 1086w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2025-10-22-a\u0300-15.38.04-225x300.png 225w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2025-10-22-a\u0300-15.38.04-769x1024.png 769w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capture-de\u0301cran-2025-10-22-a\u0300-15.38.04-768x1023.png 768w\" sizes=\"auto, (max-width: 1086px) 100vw, 1086px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Virginia Roberts Giuffre fut l&rsquo;une des jeunes victimes du r\u00e9seau de trafic sexuel mis en place par Jeffrey Epstein et Ghislaine Maxwell &#8211; il est mort, elle est en prison (r\u00e9cemment d\u00e9plac\u00e9e &#8211; du fait de la g\u00e9n\u00e9rosit\u00e9 de l&rsquo;administration Trump &#8211; vers un \u00e9tablissement \u00ab\u00a0portes ouvertes\u00a0\u00bb). Hier a paru l&rsquo;autobiographie de Giuffre intitul\u00e9e La [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10412,10262,6476,72,10411],"tags":[10415,4442,10183,10184,10414,10413],"class_list":["post-145746","post","type-post","status-publish","format-standard","hentry","category-la-fille-a-personne","category-affaire-epstein","category-corruption","category-etats-unis","category-scandale","tag-nobodys-girl","tag-donald-trump","tag-ghislaine-maxwell","tag-jeffrey-epstein","tag-prince-andrew","tag-virginia-roberts-giuffre"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/145746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=145746"}],"version-history":[{"count":13,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/145746\/revisions"}],"predecessor-version":[{"id":145761,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/145746\/revisions\/145761"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=145746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=145746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=145746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}