{"id":204,"date":"2007-10-10T02:52:26","date_gmt":"2007-10-10T01:52:26","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=204"},"modified":"2013-01-02T00:21:33","modified_gmt":"2013-01-01T23:21:33","slug":"des-emprunteurs-dignes-de-confiance","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2007\/10\/10\/des-emprunteurs-dignes-de-confiance\/","title":{"rendered":"Des emprunteurs dignes de confiance"},"content":{"rendered":"<p>Tout ne va pas si mal dans le secteur du pr\u00eat au logement am\u00e9ricain : voici un cr\u00e9neau o\u00f9 les emprunteurs s\u2019acquittent d\u2019un taux d\u2019int\u00e9r\u00eat de pr\u00e8s de 10 % en moyenne et o\u00f9 les retards de paiement sont n\u00e9gligeables, n\u2019affectant qu\u2019un demi-pourcent des comptes. \u00ab Rien \u00e0 voir avec le secteur <em>subprime<\/em> \u00bb, d\u00e9clare au Wall Street Journal (*) Mr. Leonardo Simpser, le directeur g\u00e9n\u00e9ral de HNMA : la <em>Hispanic National Mortgage Association<\/em>, un organisme de pr\u00eat qui cible les \u00e9trangers latino\u2013am\u00e9ricains en situation irr\u00e9guli\u00e8re aux \u00c9tats-Unis. <\/p>\n<p>Le secret de la r\u00e9ussite ? Plusieurs \u00e9l\u00e9ments : une population tr\u00e8s motiv\u00e9e, des enqu\u00eates tr\u00e8s pointilleuses quant \u00e0 la solvabilit\u00e9 des candidats \u00e0 l\u2019accession \u00e0 la propri\u00e9t\u00e9, allant jusqu\u2019\u00e0 la v\u00e9rification de leur ardoise chez l\u2019\u00e9picier du coin ainsi qu\u2019une adaptation du processus de candidature aux sp\u00e9cificit\u00e9s culturelles : acceptation, par exemple, de preuves indirectes de revenus provenant du travail au noir, v\u00e9rifications du patrimoine au niveau de la famille \u00e9tendue plut\u00f4t qu\u2019au niveau du m\u00e9nage, etc.<\/p>\n<p>Qu\u2019en pensent les autorit\u00e9s ? La FDIC (<em>Federal Deposit Insurance Corporation<\/em>), un des organismes de tutelle des milieux financiers (celui qui garantit l\u2019ensemble des d\u00e9p\u00f4ts dans un \u00e9tablissement bancaire \u00e0 concurrence d\u2019un montant de cent mille dollars), est enthousiaste : elle encourage les pr\u00eats aux minorit\u00e9s, sans s\u2019attarder sur la l\u00e9galit\u00e9 ou non de leur pr\u00e9sence sur le territoire national am\u00e9ricain.<\/p>\n<p>Alors y a\u2013t\u2013il un probl\u00e8me ? Malheureusement oui : celui que j\u2019\u00e9voquais il y a une semaine dans <a href=\"http:\/\/www.pauljorion.com\/blog\/?p=195\">Le parti R\u00e9publicain d\u00e9chir\u00e9 par la lutte des classes<\/a> : les mesures de d\u00e9portations massives de travailleurs clandestins prises par le pr\u00e9sident pour donner des gages \u00e0 l\u2019extr\u00eame-droite, la seule fraction de l\u2019\u00e9lectorat qui lui demeure fid\u00e8le. Soucieux de se conserver une base, aussi \u00e9troite soit-elle, il a perdu de vue la devise de ceux qui l\u2019avaient pourtant port\u00e9 au pouvoir : \u00ab Business is business ! \u00bb <\/p>\n<p>(*) Miriam Jordan, \u00ab Unlikely Mortgage Winner \u00bb, Wall Street Journal, 9 octobre 2007.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tout ne va pas si mal dans le secteur du pr\u00eat au logement am\u00e9ricain : voici un cr\u00e9neau o\u00f9 les emprunteurs s\u2019acquittent d\u2019un taux d\u2019int\u00e9r\u00eat de pr\u00e8s de 10 % en moyenne et o\u00f9 les retards de paiement sont n\u00e9gligeables, n\u2019affectant qu\u2019un demi-pourcent des comptes. \u00ab Rien \u00e0 voir avec le secteur subprime \u00bb, d\u00e9clare [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,5,4,12],"tags":[],"class_list":["post-204","post","type-post","status-publish","format-standard","hentry","category-economie","category-sciences-cognitives","category-sociologie","category-subprime"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=204"}],"version-history":[{"count":1,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/204\/revisions"}],"predecessor-version":[{"id":45638,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/204\/revisions\/45638"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}