{"id":21871,"date":"2011-03-11T20:17:16","date_gmt":"2011-03-11T19:17:16","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=21871"},"modified":"2013-01-02T14:45:42","modified_gmt":"2013-01-02T13:45:42","slug":"la-grande-bretagne-a-lencan-par-emmanuel-quilgars","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2011\/03\/11\/la-grande-bretagne-a-lencan-par-emmanuel-quilgars\/","title":{"rendered":"<b>LA GRANDE BRETAGNE A L&rsquo;ENCAN ?<\/b>, par Emmanuel Quilgars"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9<\/p><\/blockquote>\n<p>Quand on n\u2019a plus d\u2019argent pour payer ses dettes, on vent les bijoux de famille, n\u2019est-ce pas\u00a0? Pourquoi alors l\u2019Etat britannique ne ferait-il pas ce que les particuliers font d\u2019eux-m\u00eames quand ils sont endett\u00e9s\u00a0? C\u2019est cette id\u00e9e simple que, le lundi 7 mars, la cha\u00eene publique Channel 4 a voulu exp\u00e9rimenter avec ses t\u00e9l\u00e9spectateurs, dans le cadre de l\u2019\u00e9mission Dispatches\u00a0: <em>\u00ab\u00a0Selling off Britain\u00a0\u00bb<\/em> (litt\u00e9ralement\u00a0: \u00ab\u00a0vendre\/liquider la Grande-Bretagne\u00a0\u00bb).<\/p>\n<p>Rappelons le contexte\u00a0: au mois de f\u00e9vrier dernier, le gouvernement Cameron a \u00e9t\u00e9 contraint de renoncer \u00e0 son projet de vendre au moins la moiti\u00e9 des 258\u00a0000 hectares de for\u00eats du pays. Un projet mal ficel\u00e9 (il est apparu que l\u2019op\u00e9ration ne serait pas rentable pour le Tr\u00e9sor, rien de garantissait l\u2019acc\u00e8s du public aux for\u00eats privatis\u00e9es, etc.), une mobilisation citoyenne massive (une p\u00e9tition de plus de 500\u00a0000 signatures, des manifestations ponctuelles) et une opinion largement hostile \u00e0 la vente du domaine forestier (84\u00a0% selon un sondage) ont eu raison de cette \u00ab\u00a0folie\u00a0\u00bb (selon le mot d\u2019Ed Miliband, le leader travailliste).<\/p>\n<p><!--more-->L\u2019id\u00e9e pourtant est dans l\u2019air du temps \u2013 l\u2019id\u00e9e que, pour r\u00e9tablir les comptes publics, le gouvernement pourrait vendre le patrimoine appartenant \u00e0 l\u2019Etat et aux collectivit\u00e9s locales. D\u2019o\u00f9 le programme <em>\u00ab\u00a0Selling off Britain\u00a0\u00bb<\/em> de Channel 4\u00a0: puisque les actifs publics sont estim\u00e9s \u00e0 337 milliards de livres (de Buckingham Palace \u00e0 Stonehenge en passant par les usines d\u2019uranium), pourquoi ne pas en c\u00e9der une partie pour r\u00e9duire la dette publique de 867\u00a0milliards\u00a0? Cela permettrait de r\u00e9duire les int\u00e9r\u00eats de cette dette et, par l\u00e0 m\u00eame, le d\u00e9ficit budg\u00e9taire (un peu comme \u00ab\u00a0r\u00e9duire le montant de son emprunt immobilier permet de r\u00e9duire son d\u00e9couvert\u00a0\u00bb, comme le pr\u00e9cisait avant l\u2019\u00e9mission le pr\u00e9sentateur<strong> Krishnan Guru-Murthy<\/strong> <strong>sur son blog<\/strong>). De nouvelles d\u00e9penses, plus propices \u00e0 la croissance, pourraient alors \u00eatre engag\u00e9es\u2026<\/p>\n<p>L\u2019\u00e9mission se voulait \u00e0 la fois ludique, p\u00e9dagogique et d\u00e9mocratique. Le dispositif \u00e9tait le suivant\u00a0: les personnes pr\u00e9sentes sur le plateau \u00e9taient invit\u00e9es \u00e0 se prononcer successivement sur la vente de quatre lots de biens publics\u00a0; apr\u00e8s un petit reportage sur le lot en question, un bref d\u00e9bat avait lieu entre partisans et adversaires de l\u2019op\u00e9ration, puis on passait au vote. Le premier lot regroupait les biens immobiliers de l\u2019Etat (\u00e0 titre d\u2019exemple\u00a0: des logements de fonction pour juges et le palais Saint James de Londres)\u00a0; le deuxi\u00e8me, les autoroutes\u00a0du pays\u00a0; le troisi\u00e8me, les biens sans affectation des municipalit\u00e9s (exemple\u00a0: Birmingham)\u00a0; le quatri\u00e8me, les \u00ab\u00a0forces arm\u00e9es\u00a0\u00bb. Chaque lot \u00e9tait \u00e9valu\u00e9 financi\u00e8rement (en centaines de millions ou en dizaines de milliards de livres), ce qui devait correspondre \u00e0 une r\u00e9duction d\u2019autant de la dette publique.<\/p>\n<p>Le moins que l\u2019on puisse dire, c\u2019est que le r\u00e9sultat a \u00e9t\u00e9 sans \u00e9quivoque\u00a0: \u00e0 chaque fois, le plateau a vot\u00e9 <em>contre<\/em> les ventes, \u00e0 une large majorit\u00e9 (de 58\u00a0% \u00e0 83\u00a0% selon les lots). Le pr\u00e9sentateur a m\u00eame eu l\u2019air un peu \u00e9tonn\u00e9 d\u2019un rejet si net. Quand \u00e0 la fin de l\u2019\u00e9mission est venu le moment des comptes, il a bien fallu se rendre \u00e0 l\u2019\u00e9vidence\u00a0: le Britannique ordinaire, dans sa grande sagesse, avait r\u00e9duit la dette du pays de 0 \u00a3.<\/p>\n<p>Quelle signification toutefois donner \u00e0 ce r\u00e9sultat\u00a0? D\u2019une certain mani\u00e8re, il ne nous apprend rien, il est conforme \u00e0 ce que l\u2019on sait d\u00e9j\u00e0 et que confirme la plupart des enqu\u00eates d\u2019opinion\u00a0: comme l\u2019a montr\u00e9 l\u2019affaire des for\u00eats, le pays dans sa grande majorit\u00e9 est\u00a0oppos\u00e9 \u00e0 la privatisation des biens publics, tout comme il est oppos\u00e9 \u2013 sur un autre plan \u2013 \u00e0 la privatisation des services publics tel le NHS (le service de sant\u00e9). En revanche, l\u2019\u00e9mission elle-m\u00eame nous en apprend beaucoup sur les m\u00e9canismes de la domination id\u00e9ologique : aussi bien dans son concept que dans son d\u00e9roulement, elle pr\u00e9sente un exemple arch\u00e9typique de la fa\u00e7on dans la pens\u00e9e n\u00e9olib\u00e9rale impr\u00e8gne la soci\u00e9t\u00e9 britannique.<\/p>\n<p>D\u2019abord, l\u2019\u00e9mission invite le t\u00e9l\u00e9spectateur \u00e0 se repr\u00e9senter le probl\u00e8me de la dette et du d\u00e9ficit sous un angle particulier\u00a0\u2013 sous l\u2019angle pr\u00e9cis\u00e9ment de la solution qui lui est propos\u00e9e\u00a0: la vente des biens publics, la privatisation (\u00e9ventuellement <em>totale<\/em>) du pays. A d\u00e9faut d\u2019\u00eatre souhaitable, cette privatisation est donc envisag\u00e9e d\u2019embl\u00e9e comme possible, en tout cas comme \u00e9tant une mesure digne d\u2019\u00eatre examin\u00e9e et discut\u00e9e. Cet \u00ab\u00a0effet de pr\u00e9supposition\u00a0\u00bb permet ainsi de circonscrire le cadre th\u00e9orique dans lequel le d\u00e9bat politique et \u00e9conomique doit avoir lieu. A contrario, on imagine mal Channel 4 organiser une \u00e9mission o\u00f9 les personnes pr\u00e9sentes sur le plateau devraient d\u00e9cider de nationaliser tel ou tel bien priv\u00e9, d\u2019augmenter tel ou tel imp\u00f4t, ou de renoncer \u00e0 rembourser tel ou tel cr\u00e9ancier\u00a0: ces cas de figure, par d\u00e9finition, sont exclus du dogme.<\/p>\n<p>Par ailleurs, le t\u00e9l\u00e9spectateur \u2013 dont est rappel\u00e9 sa qualit\u00e9 de \u00ab\u00a0copropri\u00e9taire\u00a0\u00bb des biens publics \u2013 est convi\u00e9 \u00e0 entrer dans la peau des gouvernants. Cette mise en situation sugg\u00e8re que le patrimoine d\u2019un Etat se g\u00e8re comme celui d\u2019un m\u00e9nage, qu\u2019une dette publique \u00e9quivaut \u00e0 un emprunt immobilier, et que le \u00ab\u00a0bon sens\u00a0\u00bb et quelques additions soustractions suffisent pour prendre les bonnes d\u00e9cisions. En fait, cette identification temporaire avec les agents du pouvoir est ce qui permet de construire \u00e0 terme, si ce n\u2019est une adh\u00e9sion explicite, du moins une acceptation r\u00e9sign\u00e9e \u00e0 la politique gouvernementale. L\u2019\u00e9mission pousse le t\u00e9l\u00e9spectateur \u00e0 subjectiviser une contrainte pos\u00e9e comme ext\u00e9rieure et irr\u00e9sistible (la dette, le d\u00e9ficit) et un moyen sp\u00e9cifique d\u2019y r\u00e9pondre (privatiser les biens publics)\u00a0: m\u00eame si, dans un premier temps, la solution propos\u00e9e est rejet\u00e9e, il est escompt\u00e9 que le Britannique moyen, qui aura partag\u00e9 quelques instants les affres du d\u00e9cideur devant une situation sans issue, saura se montrer raisonnable quand finalement c\u2019est cette solution-l\u00e0 qui sera retenue \u2013 plus raisonnable par exemple que le Grec qui, pareillement somm\u00e9 de vendre ses a\u00e9roports, ses plages voire ses \u00eeles, descend dans la rue et proteste.<\/p>\n<p>Pour que cette \u00ab\u00a0fabrique du consentement\u00a0\u00bb fonctionne au mieux, il faut bien s\u00fbr que soient \u00e9vacu\u00e9s du champ de la r\u00e9flexion les arguments susceptibles de remettre en cause la mani\u00e8re dont est pos\u00e9 le probl\u00e8me. A cet \u00e9gard, nous n\u2019avons pas \u00e9t\u00e9 surpris de la relative pauvret\u00e9 du d\u00e9bat qui a lieu au cours de l\u2019\u00e9mission. Les partisans de la vente des biens publics ont mis en avant l\u2019imp\u00e9rieuse n\u00e9cessit\u00e9 de r\u00e9duire la dette colossale du pays, la mauvaise utilisation que faisait l\u2019Etat des biens lui appartenant, la sup\u00e9riorit\u00e9 de la gestion priv\u00e9e sur la gestion publique, et les profits et revenus que pourraient g\u00e9n\u00e9rer les privatisations. En face, les opposants ont fait valoir des consid\u00e9rations politiques (le programme des Tories aux derni\u00e8res \u00e9lections ne pr\u00e9voyait pas de telles ventes) ou moralo-sentimentales (les biens publics appartiennent \u00e0 \u00ab\u00a0la communaut\u00e9\u00a0\u00bb, ils participent de l\u2019identit\u00e9 du pays, etc.). L\u2019opposant le plus \u00e9nergique a \u00e9t\u00e9 un \u00e9conomiste de Cambridge, Michael Kitson, qui a rappel\u00e9 que le meilleur moyen de lutter contre le d\u00e9ficit public \u00e9tait de favoriser la croissance et l\u2019emploi, qu\u2019une gestion priv\u00e9e n\u2019\u00e9tait pas en soi une garantie d\u2019efficacit\u00e9 (car soumise uniquement \u00e0 l\u2019exigence du profit) et que l\u2019Etat pouvait administrer ses biens d\u2019une fa\u00e7on tout \u00e0 fait satisfaisante du point de vue \u00e9conomique.<\/p>\n<p>Le plus \u00e9tonnant, toutefois, c\u2019est que jamais au cours de l\u2019\u00e9mission n\u2019a pas \u00e9t\u00e9 rappel\u00e9 ce fait pourtant fondamental \u2013 \u00e0 savoir que la forte augmentation de la dette publique et du d\u00e9ficit budg\u00e9taire \u00e9tait li\u00e9 directement au sauvetage des banques en 2008 et ne relevait pas d\u2019un d\u00e9faut inh\u00e9rent au fonctionnement de l\u2019Etat (\u00e0 supposer d\u2019ailleurs que la dette et le d\u00e9ficit soient toujours un d\u00e9faut). Par ailleurs, aucun intervenant n\u2019a soulev\u00e9 l\u2019une des questions suivantes\u00a0: <em>qui<\/em> allait acheter les biens publics, avec <em>quel argent<\/em>, en empruntant aupr\u00e8s de <em>qui<\/em>, etc.\u00a0? Un contradicteur habile et rigoureux aurait facilement pu d\u00e9montrer que les b\u00e9n\u00e9ficiaires de ces privatisations, si elles avaient lieu, seraient en dernier ressort ceux-l\u00e0 m\u00eame qui \u00e9taient responsable de l\u2019explosion de la dette et du d\u00e9ficit. Mais il aurait fallu alors \u00e9noncer quelques v\u00e9rit\u00e9s d\u00e9sagr\u00e9ables sur la nature de la dette publique, sur l\u2019identit\u00e9 des cr\u00e9anciers, sur la circulation mon\u00e9taire entre la Banque centrale, les banques priv\u00e9es et les riches particuliers, sur le r\u00f4le du pouvoir d\u2019Etat dans l\u2019organisation de ces flux, etc. \u2013 et tout cela aurait fatalement d\u00e9boucher sur la d\u00e9nonciation du fonctionnement oligarchique de la soci\u00e9t\u00e9 anglaise. Est-ce vraiment ce que souhaitaient les concepteurs de <em>\u00ab\u00a0Selling off Britain\u00a0\u00bb <\/em>?<\/p>\n<p>Une \u00e9mission de ce type, grand public et superficielle, laisse donc forc\u00e9ment perplexe. Elle t\u00e9moigne surtout du carcan id\u00e9ologique dans lequel est enferm\u00e9e la Grande-Bretagne. Un plateau TV cens\u00e9 repr\u00e9senter l\u2019opinion majoritaire se d\u00e9clare certes contre la privatisation rampante du pays, mais \u00e0 l\u2019int\u00e9rieur d\u2019un dispositif m\u00e9diatique biais\u00e9, au terme d\u2019un d\u00e9bat convenu, et sans que des arguments d\u00e9cisifs contre cette privatisation aient \u00e9t\u00e9 invoqu\u00e9s. Sans doute le public n\u2019a-t-il pas besoin d\u2019un long discours pour \u00eatre hostile \u00e0 ces ventes\u00a0: il sait d\u2019instinct que, d\u2019une mani\u00e8re ou d\u2019une autre, elles ne lui profiteront pas et permettront avant tout \u00e0 une poign\u00e9e de promoteurs et de financiers de s\u2019enrichir \u00e0 ses d\u00e9pends. Mais le sentiment et l\u2019instinct populaires gagnent toujours \u00e0 s\u2019appuyer sur une solide d\u00e9monstration \u2013 cela permet de couper court en particulier \u00e0 l\u2019argument selon lequel \u00ab\u00a0le peuple ne pense pas\u00a0\u00bb. On remarquera du reste que les partisans de la grande braderie du pays sont rest\u00e9s \u00e9trangement impassibles sur le plateau\u00a0: ils savent bien que, au fond, l\u2019opinion majoritaire \u2013 qu\u2019il faut bien laisser s\u2019exprimer, d\u00e9mocratie oblige \u2013 p\u00e8sera peu face \u00e0 l\u2019implacable logique du march\u00e9. Finalement, tout se passe comme si ni l\u2019un ni l\u2019autre des deux camps n\u2019avait explicit\u00e9 sa pens\u00e9e. Les formes du d\u00e9bat d\u00e9mocratique ont \u00e9t\u00e9 pr\u00e9serv\u00e9es, mais celui-ci a \u00e9t\u00e9 vid\u00e9 de sa substance\u00a0: <em>les choses essentielles n\u2019ont pas \u00e9t\u00e9 dites, les v\u00e9rit\u00e9s d\u00e9rangeantes ont \u00e9t\u00e9 refoul\u00e9es.<\/em><\/p>\n<p><em> <\/em><\/p>\n<p>Une escarmouche en fin d\u2019\u00e9mission a permis pourtant de lever un coin du voile. Invit\u00e9e \u00e0 commenter le vote du public, Edwina Currie, une d\u00e9put\u00e9e Tory, a object\u00e9 que le plateau n\u2019\u00e9tait pas \u00ab\u00a0repr\u00e9sentatif\u00a0\u00bb. Piqu\u00e9 au vif, le pr\u00e9sentateur a rappel\u00e9 la mobilisation contre la vente des for\u00eats et a trouv\u00e9 curieuse cette tendance des conservateurs \u00e0 toujours m\u00e9conna\u00eetre les sentiments du public (<em>\u201cmisjudge the public mood\u201d<\/em>). La d\u00e9put\u00e9e a alors op\u00e9r\u00e9 une retraite tactique en faisant un bref plaidoyer, non plus cette fois pour la vente pure et simple des biens de l\u2019Etat, mais pour leur location \u00e0 long terme. Il est peu dire que cet \u00e9change est embl\u00e9matique du dialogue \u00e0 trois temps qui, depuis pas mal de temps d\u00e9j\u00e0, structure la relation entre \u00ab\u00a0gouvernants\u00a0\u00bb et \u00ab\u00a0gouvern\u00e9s\u00a0\u00bb\u00a0: 1. Le pouvoir en place invoque sa l\u00e9gitimit\u00e9 \u00e9lectorale pour imposer ses choix \u00e9conomiques. 2. Le \u00ab\u00a0pays r\u00e9el\u00a0\u00bb manifeste son opposition aux mesures prises, <em>via<\/em> les sondages, les m\u00e9dias, les p\u00e9titions, les manifestations, etc. 3. Le pouvoir conc\u00e8de un faux compromis, qui permet de r\u00e9aliser tout de suite une partie du programme en reportant \u00e0 plus tard l\u2019ex\u00e9cution du reste.<\/p>\n<p>Nous avons l\u00e0 toutes les donn\u00e9es pour comprendre l\u2019impasse politique que conna\u00eet l\u2019Angleterre\u00a0: la gouvernance n\u00e9olib\u00e9rale du pays en est r\u00e9duite \u00e0 construire des \u00ab\u00a0repr\u00e9sentativit\u00e9s\u00a0\u00bb ad hoc pour justifier une politique \u00e9conomique qu\u2019une majorit\u00e9 de la population r\u00e9prouve\u00a0; les m\u00e9dias dominants donnent un large \u00e9cho \u00e0 la col\u00e8re publique \u2013 selon les canons du pluralisme d\u00e9mocratique dont ils pr\u00e9tendent \u00eatre les garants \u2013 mais, dans le m\u00eame temps, ils s\u2019av\u00e8rent incapables de diffuser et d\u2019articuler une critique radicale et coh\u00e9rente du syst\u00e8me\u00a0; le citoyen rumine sa frustration, et tire de son impuissance la conclusion que les \u00e9lections sont une farce n\u2019aboutissant qu\u2019\u00e0 une concentration accrue du pouvoir et des richesses. Nous sommes au point de rupture du l\u00e9gal et du l\u00e9gitime, mais sans discours alternatif audible. Bref, si le capitalisme anglo-saxon est \u00e0 l\u2019agonie, la d\u00e9mocratie britannique est \u00e9galement bien malade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9 Quand on n\u2019a plus d\u2019argent pour payer ses dettes, on vent les bijoux de famille, n\u2019est-ce pas\u00a0? Pourquoi alors l\u2019Etat britannique ne ferait-il pas ce que les particuliers font d\u2019eux-m\u00eames quand ils sont endett\u00e9s\u00a0? C\u2019est cette id\u00e9e simple que, le lundi 7 mars, la cha\u00eene publique Channel 4 a voulu exp\u00e9rimenter avec ses [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,17],"tags":[1236,224,74],"class_list":["post-21871","post","type-post","status-publish","format-standard","hentry","category-economie","category-politique","tag-biens-publics","tag-dette","tag-grande-bretagne"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/21871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=21871"}],"version-history":[{"count":4,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/21871\/revisions"}],"predecessor-version":[{"id":47630,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/21871\/revisions\/47630"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=21871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=21871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=21871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}