{"id":27864,"date":"2011-08-23T04:04:10","date_gmt":"2011-08-23T02:04:10","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=27864"},"modified":"2013-01-02T14:35:25","modified_gmt":"2013-01-02T13:35:25","slug":"slow-science-la-desexcellence-par-olivier-p-gosselain","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2011\/08\/23\/slow-science-la-desexcellence-par-olivier-p-gosselain\/","title":{"rendered":"<b>SLOW SCIENCE &#8211; LA D\u00c9SEXCELLENCE<\/b>, par  Olivier P. Gosselain*"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9<\/p><\/blockquote>\n<p>\u00c7a a commenc\u00e9 comme \u00e7a. Une poign\u00e9e de coll\u00e8gues issus de disciplines diff\u00e9rentes, l\u2019envie de travailler ensemble, un financement de cinq ans, des s\u00e9minaires r\u00e9guliers o\u00f9 le plaisir d\u2019\u00e9changer se m\u00ealait \u00e0 un sentiment grisant de progression et, au final, des objets d\u2019\u00e9tude, des rencontres et des r\u00e9sultats qui d\u00e9passaient de loin nos attentes initiales.<sup>1<\/sup> Une belle histoire de recherche, en somme, pour une petite communaut\u00e9 regroupant des acad\u00e9miques, des doctorants et des \u00e9tudiants.<\/p>\n<p>Le groupe n\u2019avait pas en commun que des objectifs scientifiques. Il partageait aussi une conception de la recherche et des relations entre chercheurs centr\u00e9e sur la convivialit\u00e9, l\u2019intelligibilit\u00e9, l\u2019\u00e9change et la volont\u00e9 de <em>bien faire<\/em> son travail. Rien de r\u00e9volutionnaire \u00e0 premi\u00e8re vue. Mais le d\u00e9calage avec les politiques de recherche d\u00e9velopp\u00e9es par nos institutions nationales et internationales \u00e9tait pourtant flagrant. Il y avait loin, en effet, entre ces valeurs et les injonctions de productivit\u00e9, de rentabilit\u00e9 et d\u2019imm\u00e9diatet\u00e9 inlassablement ressass\u00e9es par nos managers acad\u00e9miques.<\/p>\n<p>Frapp\u00e9s par ce d\u00e9calage et convaincus que notre fa\u00e7on de proc\u00e9der \u00e9tait humainement et scientifiquement plus satisfaisante, nous avons esquiss\u00e9 l\u2019id\u00e9e d\u2019un mouvement Slow Science \u2013 sorte de doigt d\u2019honneur acad\u00e9mique \u00e0 ce Nouvel Ordre de la recherche. La filiation avec Slow Food \u00e9tait d\u2019autant plus \u00e9vidente que deux des valeurs qui nous tenaient \u00e0 c\u0153ur \u00e9taient le <em>plaisir<\/em> et la <em>cr\u00e9ativit\u00e9<\/em>. Ici encore, rien de r\u00e9volutionnaire. Retirez \u00e7a de la recherche : que reste-t-il ?<\/p>\n<p><!--more-->Le hasard a fait que nous avons \u00e9t\u00e9 soumis quelques temps plus tard \u00e0 une \u00e9valuation de laboratoire. L\u2019outil destin\u00e9 \u00e0 mesurer nos performances \u00e9tait un formulaire standard, sorte de canif suisse du coaching en entreprise, avec son in\u00e9vitable analyse SWOT<sup>2<\/sup>. C\u2019\u00e9tait d\u00e9concertant de na\u00efvet\u00e9 et presque embarrassant \u00e0 remplir. Mais \u00e0 une question au moins, portant sur notre conception de la recherche, nous avions apport\u00e9 une r\u00e9ponse sinc\u00e8re : plaisir et cr\u00e9ativit\u00e9. Ce fut le point de rupture pour les duettistes en costume sombre qui pilotaient le groupe d\u2019\u00e9valuation. De tels termes, nous affirmaient-ils, \u00e9taient tout simplement inacceptables. Indignes de figurer sur un formulaire d\u2019\u00e9valuation et preuves \u00e9videntes de notre manque de s\u00e9rieux.<\/p>\n<p><strong><em>\u00c9mergence d\u2019une communaut\u00e9<\/em><\/strong><\/p>\n<p>Les \u00e9valuateurs et leur rapport sont sortis de notre vie aussi rapidement qu\u2019ils y \u00e9taient entr\u00e9s. L\u2019histoire serait donc sans cons\u00e9quence, si elle ne soulignait l\u2019\u00e9norme d\u00e9calage qui s\u2019est install\u00e9 entre une conception bureaucratique de la recherche, fond\u00e9e sur les pr\u00e9ceptes de l\u2019\u00e9conom\u00e9trie et de la communication d\u2019entreprise, et sa pratique concr\u00e8te, fond\u00e9e sur l\u2019engagement mutuel de chercheurs qui s\u2019efforcent avant tout de faire honn\u00eatement leur travail. Elle conduit \u00e9galement \u00e0 s\u2019interroger sur ce qu\u2019apporte cette \u00ab excellence \u00bb dont on nous rebat inlassablement les oreilles en termes de satisfaction et de r\u00e9alisation personnelles.<\/p>\n<p>Nous sommes manifestement nombreux \u00e0 nous poser la question. Une petite recherche sur le Net confirme d\u2019ailleurs que les bonnes id\u00e9es naissent rarement seules : la notion de \u00ab Slow Science \u00bb est dans l\u2019air depuis vingt ans au moins. Apparue tr\u00e8s paradoxalement sous la plume d\u2019Eugene Garfield<sup>3<\/sup>, le p\u00e8re de la bibliom\u00e9trie et de \u00ab l\u2019impact factor \u00bb<sup>4<\/sup>, elle a ensuite \u00e9t\u00e9 sporadiquement mentionn\u00e9e par des chimistes et physiciens am\u00e9ricains ou australiens, avant de faire son apparition en Europe dans l\u2019univers des sciences humaines. Ce passage des sciences de la Nature aux sciences de l\u2019Homme et du monde anglo-saxon \u00e0 l\u2019Europe (\u00e0 l\u2019exception notoire de l\u2019Angleterre) correspond grosso-modo \u00e0 la trajectoire historique des politiques de recherche centr\u00e9es sur la comp\u00e9titivit\u00e9 et la productivit\u00e9. Les occurrences du concept de Slow Science se lisent ainsi comme les sympt\u00f4mes d\u2019un malaise qui n\u2019a cess\u00e9 de s\u2019\u00e9tendre durant les derni\u00e8res d\u00e9cennies. Toutes apparaissent d\u2019ailleurs ind\u00e9pendamment les unes des autres, ce qui montre qu\u2019il ne s\u2019agit pas d\u2019un ph\u00e9nom\u00e8ne de mode, mais d\u2019un mouvement de fond, n\u00e9 de la prise de conscience d\u2019un probl\u00e8me par les acteurs eux m\u00eames, et d\u2019une tentative de r\u00e9ponse remarquablement convergente.<\/p>\n<p>Un aspect fondamental de cette convergence est qu\u2019elle nous pr\u00e9munit de toute tentative de confiscation du concept. Inutile de sombrer nous aussi dans la comp\u00e9tition et l\u2019enfermement. Si Slow Science peut devenir un mouvement permettant \u00e0 la fois de nous transformer nous m\u00eames et de transformer notre univers de travail, c\u2019est probablement \u00e0 la fa\u00e7on d\u2019un logiciel libre<sup>5<\/sup>. L\u2019approche classique \u2013 centralis\u00e9e et experte \u2013 devrait en effet c\u00e9der la place \u00e0 une construction collective, plus apte \u00e0 faire \u00e9merger une forme stable et coh\u00e9rente de r\u00e9sistance. Au lieu de <em>mouvement<\/em>, on parlera alors de <em>communaut\u00e9<\/em>.<\/p>\n<p><strong><em>Sympt\u00f4mes et solutions<\/em><\/strong><\/p>\n<p>Pour mieux cerner les termes de la r\u00e9flexion \u00e0 entreprendre, examinons bri\u00e8vement le contenu des quelques appels en faveur d\u2019une approche Slow Science. Le plus simple est de proc\u00e9der chronologiquement, en commen\u00e7ant par Eugene Garfield. Ce dernier fustige l\u2019image populaire d\u2019un progr\u00e8s scientifique essentiellement li\u00e9 \u00e0 une succession d\u2019\u00e9clairs de g\u00e9nie et de d\u00e9couvertes fortuites. Les perc\u00e9es importantes, \u00e9crit-il, sont plus souvent issues de d\u00e9cennies de travail. Elles proviennent d\u2019individus \u00ab qui labourent opini\u00e2trement un champ m\u00fbr pour une d\u00e9couverte, et qui sont pr\u00e9par\u00e9s intellectuellement \u00e0 reconna\u00eetre et exploiter des r\u00e9sultats inattendus \u00bb. En mati\u00e8re de recherche, la lenteur et la constance l\u2019emportent donc sur la vitesse et la versatilit\u00e9. Le danger vient de la pression exerc\u00e9e par l\u2019opinion publique sur les chercheurs \u2013 via les politiques de financement \u2013 dont on attend qu\u2019ils obtiennent des r\u00e9sultats imm\u00e9diats, dans des domaines qui changent sans cesse au gr\u00e9 de l\u2019actualit\u00e9. Ce que d\u00e9plore Garfield, en d\u00e9finitive, c\u2019est le d\u00e9s\u00e9quilibre actuel entre les recherches de type \u00ab <em>curiosity<\/em> <em>driven <\/em>\u00bb et \u00ab <em>objective driven <\/em>\u00bb.<\/p>\n<p>Dans un courrier adress\u00e9 \u00e0 <em>Nature<\/em><sup>6<\/sup>, Lisa Alleva (biochimiste) recentre la critique sur le comportement des scientifiques et particuli\u00e8rement celui de ses jeunes coll\u00e8gues, engag\u00e9s dans une course effr\u00e9n\u00e9e pour obtenir des financements, une direction de laboratoire ou une titularisation. Cette fr\u00e9n\u00e9sie finit par les \u00e9carter des fondements m\u00eames de la recherche. \u00ab En me d\u00e9tachant des ambitions de mes pairs \u00bb, \u00e9crit-elle, \u00ab j\u2019ai d\u00e9couvert un secret : la science, la slow science, est peut-\u00eatre le passe-temps le plus enrichissant et le plus agr\u00e9able que l\u2019on puisse avoir. \u00bb<sup>7 <\/sup>L\u2019origine de cette d\u00e9couverte ? Un petit laboratoire dans lequel les chercheurs ont toute libert\u00e9 de \u00ab lire la litt\u00e9rature, de formuler des id\u00e9es et de pr\u00e9parer soigneusement [leurs] exp\u00e9riences \u00bb, mettant en \u0153uvre des \u00ab strat\u00e9gies r\u00e9fl\u00e9chies. \u00bb<sup>8<\/sup><\/p>\n<p>Des id\u00e9es du m\u00eame ordre sont d\u00e9fendues par Dave Beacon, un physicien sp\u00e9cialis\u00e9 en informatique quantique.<sup>9<\/sup> S\u00e9duit par les appels au ralentissement dans de multiples domaines et soucieux de trouver un rythme de vie plus \u00e9quilibr\u00e9, il s\u2019interroge : \u00ab Quels changements faudrait-il pour faire advenir une \u201cscience plus lente\u201d ? Et que nous apporterait concr\u00e8tement ce ralentissement ? \u00bb En ligne de mire : la course folle qui conduit \u00e0 sacrifier la r\u00e9flexion sur l\u2019autel de d\u00e9lais toujours plus courts \u2013 appels \u00e0 projet, demandes de financement, publications, communications \u2013 ou l\u2019inqui\u00e9tude qui nous saisit lorsque nous voyons s\u2019\u00e9lever la pile des nouvelles publications sur le bureau d\u2019un coll\u00e8gue. Refuser cette course ne revient pas \u00e0 r\u00e9duire sa quantit\u00e9 de travail, mais \u00e0 transformer son rapport au travail. Et cela en s\u2019offrant notamment le \u00ab luxe \u00bb de s\u2019absorber tout entier dans un probl\u00e8me ou de fol\u00e2trer, courir ou bricoler pour nourrir sa r\u00e9flexion. En se donnant le droit de savourer et partager les contributions qui nous \u00e9merveillent, plut\u00f4t que de se sentir oblig\u00e9 de les critiquer ou d\u2019en produire une version l\u00e9g\u00e8rement alt\u00e9r\u00e9e. En trouvant le temps, au final, de s\u2019interroger sur ce que l\u2019on <em>recherche <\/em>vraiment dans la recherche. Le probl\u00e8me est qu\u2019il est tr\u00e8s difficile d\u2019atteindre des conditions propices \u00e0 un tel recentrage lorsque les financements de projet privil\u00e9gient syst\u00e9matiquement le court terme. Des programmes qui ne d\u00e9passent pas un horizon de quelques ann\u00e9es<sup>10<\/sup> ont pourtant peu de chances d\u2019engendrer des r\u00e9sultats satisfaisants, pour la simple raison qu\u2019une recherche s\u00e9rieuse impose souvent l\u2019exploration m\u00e9ticuleuse d\u2019innombrables culs-de-sac.<\/p>\n<p>Notons que cet imp\u00e9ratif du temps long est particuli\u00e8rement cruel pour les programmes interdisciplinaires qui s\u2019efforcent de d\u00e9passer la simple juxtaposition de domaines de recherche. Comme le constatent nos coll\u00e8gues F. Joulian, S. de Cheveign\u00e9 et J. Le Marec, \u00ab [l]es \u00e9quipes-projet qui font le pari de l\u2019interdisciplinarit\u00e9 se trouvent [&#8230;] dans la n\u00e9cessit\u00e9 de g\u00e9rer les contradictions entre les exigences de r\u00e9sultats et retomb\u00e9es rapides de la recherche par projet, et le besoin de dur\u00e9e longue et de marges d\u2019essais et d\u2019erreurs, pour construire v\u00e9ritablement les conditions de l\u2019interdisciplinarit\u00e9. \u00bb<sup>11<\/sup> Il en r\u00e9sulte une baisse marqu\u00e9e de la sp\u00e9culation intellectuelle et de la cr\u00e9ativit\u00e9. Le formatage des projets commence d\u2019ailleurs au niveau doctoral : pour esp\u00e9rer un financement, nos jeunes coll\u00e8gues se trouvent maintenant oblig\u00e9s de proposer des recherches balis\u00e9es, qui sortent aussi peu que possible des sentiers battus. Annon\u00e7ant pratiquement leurs r\u00e9sultats \u00e0 l\u2019avance, ils tentent ainsi de garantir le retour sur investissement. S\u2019il fallait \u00e9valuer les projets de la g\u00e9n\u00e9ration pr\u00e9c\u00e9dente sur de telles bases, la plupart seraient tout simplement refus\u00e9s. Quelle ironie, quand on pense que ses repr\u00e9sentants occupent aujourd\u2019hui les postes d\u2019\u00e9valuateurs.<\/p>\n<p>Toute recherche comporte donc sa part d\u2019incertitude et demande un temps consid\u00e9rable pour obtenir des r\u00e9sultats significatifs. C\u2019est le leitmotiv des initiateurs de la \u00ab Slow Science Academy \u00bb, qui a vu le jour \u00e0 Berlin en 2010.<sup>12<\/sup> Dans leur manifeste<sup>13<\/sup>, les auteurs se pr\u00e9sentent comme des scientifiques qui ne remettent pas en question le fonctionnement actuel de la science (auquel ils prennent tous part), mais refusent qu\u2019on la r\u00e9duise \u00e0 ces seules caract\u00e9ristiques.<sup>14<\/sup> La science, mart\u00e8lent-ils, requiert du temps. Pour lire, pour se tromper, pour d\u00e9couvrir la difficult\u00e9 de se comprendre \u2013 surtout entre sciences humaines et sciences de la nature \u2013, pour dig\u00e9rer les informations et pour progresser. Afin de pr\u00e9server ces bases, sur lesquelles s\u2019est fond\u00e9e la pratique scientifique durant des si\u00e8cles, nos coll\u00e8gues allemands proposent la cr\u00e9ation d\u2019un lieu inspir\u00e9 des anciennes Acad\u00e9mies, o\u00f9 se d\u00e9veloppait nagu\u00e8re le dialogue en face-\u00e0-face entre les scientifiques. Leur \u00ab Slow Science Academy \u00bb aura ainsi pour mission d\u2019offrir une possibilit\u00e9 de retraite aux chercheurs, leur fournissant \u00ab de l\u2019espace, du temps et par la suite des moyens, pour qu\u2019ils puissent mener leur job principal : discuter, s\u2019\u00e9merveiller, penser. \u00bb<sup>15<\/sup><\/p>\n<p>Le dernier plaidoyer en date est un <a href=\"http:\/\/slowscience.fr\/\">\u00ab Appel \u00e0 un mouvement Slow Science \u00bb<\/a><sup>16<\/sup> lanc\u00e9 par un anthropologue fran\u00e7ais, Jo\u00ebl Candau. Ses griefs ont une teneur famili\u00e8re : le temps n\u00e9cessaire \u00e0 la recherche manque de plus en plus dans le contexte actuel d\u2019imm\u00e9diatet\u00e9, d\u2019urgence, de flux tendus ; le fonctionnement des laboratoires impose la mise sur pied continue de projets que nous n\u2019avons jamais le temps de mener correctement ; le mode d\u2019\u00e9valuation des CV a entra\u00een\u00e9 une obsession de la quantit\u00e9 et la production de \u00ab milliers d\u2019articles dupliqu\u00e9s, saucissonn\u00e9s, reformat\u00e9s, quand ils ne sont pas plus ou moins \u201cemprunt\u00e9s\u201d \u00bb ; les injonctions \u00ab d\u2019innovation \u00bb et de \u00ab performance \u00bb poussent \u00e0 sauter sans cesse d\u2019un domaine \u00e0 l\u2019autre pour rester dans l\u2019air du temps (et dans la comp\u00e9tition acad\u00e9mique : c\u2019est ce que l\u2019Acad\u00e9mie des Sciences fran\u00e7aise nomme \u00ab la chasse aux domaines \u00e0 fort taux de citations et de publication \u00bb<sup>17<\/sup>). Quant \u00e0 la d\u00e9rive bureaucratique et la r\u00e9unionite, elles \u00ab font que plus personne n\u2019a de temps pour rien \u00bb : il faut se \u00ab prononcer sur des dossiers re\u00e7us le jour m\u00eame pour une mise en \u0153uvre le lendemain \u00bb. La fa\u00e7on de combattre cette d\u00e9rive ? Donner \u00ab la priorit\u00e9 \u00e0 des valeurs et principes fondamentaux \u00bb. Mais les propositions de Candau sont surtout d\u2019ordre logistique et administratif : r\u00e9\u00e9quilibrage des activit\u00e9s de recherche et d\u2019enseignement, octroi de p\u00e9riodes strictement consacr\u00e9es \u00e0 la recherche, abandon de la bibliom\u00e9trie dans les \u00e9valuations, r\u00e9duction drastique du temps consacr\u00e9 aux t\u00e2ches administratives, recentrage sur les questions de fond dans les activit\u00e9s de gestion.<\/p>\n<p><strong><em>Des VRP \u00e0 la peine<\/em><\/strong><\/p>\n<p>Outre la fr\u00e9n\u00e9sie, l\u2019urgence et la comp\u00e9tition qui r\u00e9gissent aujourd\u2019hui l\u2019agenda scientifique, il semble qu\u2019une cause majeure de la d\u00e9tresse du chercheur soit sa transformation en VRP. Inlassablement contraint de vendre ses comp\u00e9tences, ses id\u00e9es, ses projets, son CV ou son \u00e9quipe, c\u2019est sa dignit\u00e9 qu\u2019il finit par perdre peu \u00e0 peu. Or, que rapportent ces transactions ? Des cr\u00e9dits de plus en plus incertains et quelques galons acad\u00e9miques, qui permettent sans doute de se rapprocher des lieux de pouvoir, mais au prix d\u2019un \u00e9loignement des lieux de savoir. Du c\u00f4t\u00e9 institutionnel, le gain ne concerne pas la qualit\u00e9 du travail accompli mais l\u2019image de marque. Derri\u00e8re les incantations magiques glorifiant l\u2019excellence et la performance se cachent en effet des enjeux tr\u00e8s prosa\u00efques : accro\u00eetre son stock d\u2019\u00e9tudiants et gagner quelques places dans le Classement annuel des universit\u00e9s du monde<sup>18<\/sup>. Objectif d\u00e9risoire, ce dernier ferait sourire s\u2019il n\u2019\u00e9tait pas arbitr\u00e9, depuis Shanghai, par les repr\u00e9sentants d\u2019un \u00c9tat dont l\u2019id\u00e9ologie remet fondamentalement en cause un apport majeur de l\u2019\u00e9ducation : l\u2019\u00e9mancipation. Comme disent les anglo-saxons, on ajoute ici l\u2019insulte \u00e0 la blessure.<\/p>\n<p>Dans cette perspective, refuser l\u2019excellence c\u2019est refuser une politique scientifique qui nous condamne \u00e0 l\u2019\u00e9go\u00efsme, au calcul et \u00e0 la m\u00e9diocrit\u00e9. Qui nous oblige \u00e0 \u00eatre acteurs de notre propre destruction. Car ne nous y trompons pas : la bureaucratisation et la d\u00e9rive manag\u00e9riale du monde acad\u00e9mique ne sont pas le fait d\u2019acteurs externes. Comme le rappelle Yves Gingras, \u00ab [c]e sont [&#8230;] les scientifiques eux-m\u00eames qui succombent souvent aux usages anarchiques de la bibliom\u00e9trie individuelle et qui, si\u00e9geant parfois sur diff\u00e9rents comit\u00e9s et conseils d\u2019administration d\u2019organes d\u00e9cisionnels de la recherche, sugg\u00e8rent d\u2019en g\u00e9n\u00e9raliser l\u2019usage. Cela confirme que dans le champ scientifique, \u201cl\u2019ennemi\u201d est souvent moins le \u201cbureaucrate\u201d que le coll\u00e8gue&#8230; \u00bb.<sup>19<\/sup><\/p>\n<p>Comment en sortir ? Deux types de r\u00e9ponses sont apport\u00e9es par les d\u00e9fenseurs de la Slow Science. Il y a d\u2019abord des propositions d\u2019am\u00e9liorations ponctuelles, plus ou moins \u00e0 la marge du syst\u00e8me. L\u2019une d\u2019elles serait de repenser \u2013 ou \u00e0 tout le moins professionnaliser \u2013 l\u2019\u00e9valuation de la recherche. C\u2019est ce que pr\u00e9conisent \u00e9galement de nombreux autres coll\u00e8gues qui, il faut le souligner, ne remettent pas en cause le principe m\u00eame des \u00e9valuations de carri\u00e8re<sup>20<\/sup>. Autre proposition : mieux informer le public des r\u00e9alit\u00e9s de la recherche, afin d\u2019\u00e9viter la versatilit\u00e9 des politiques de financement. Ces financements devraient par ailleurs favoriser des projets \u00e0 long terme, pour assurer des r\u00e9sultats solides. Enfin, on pourrait transformer le contexte m\u00eame de l\u2019activit\u00e9 scientifique en cr\u00e9ant des \u00ab poches \u00bb de recherche sur d\u2019autres bases temporelles. Le lancement d\u2019une \u00ab Slow Science Academy \u00bb va tout \u00e0 fait dans ce sens, puisque celle-ci offre aux scientifiques une possibilit\u00e9 de repli temporaire dans une sorte de \u00ab tour d\u2019ivoire \u00bb (pour reprendre les termes de nos coll\u00e8gues allemands).<\/p>\n<p>\u00c0 c\u00f4t\u00e9 de ces r\u00e9ponses pratiques, il y a des propositions plus diffuses, mais peut-\u00eatre plus en accord avec l\u2019id\u00e9e d\u2019une Slow Science inspir\u00e9e du mouvement Slow Food. Ainsi, la finalit\u00e9 de ce dernier n\u2019est pas d\u2019am\u00e9liorer la qualit\u00e9 du menu des fast food \u2013 en y imposant par exemple un quota d\u2019aliments bio ou AOC \u2013, mais de promouvoir un rapport \u00e0 la nourriture centr\u00e9 sur le plaisir, le go\u00fbt et la convivialit\u00e9. Il s\u2019agit, en d\u2019autres termes, de transformer les valeurs sur lesquelles se fonde notre consommation alimentaire. Transpos\u00e9e \u00e0 l\u2019univers acad\u00e9mique, cette question de valeur semble surtout li\u00e9e \u00e0 l\u2019attitude adopt\u00e9e dans le travail. Or celle-ci retentit sur les r\u00e9sultats et les r\u00e9compenses qui en d\u00e9coulent, mais dans des termes pratiquement oppos\u00e9s \u00e0 ceux qu\u2019envisagent nos managers universitaires. Lisa Alleva et Dave Beacon vont clairement dans ce sens lorsqu\u2019ils invitent \u00e0 se d\u00e9tacher des ambitions de ses pairs, \u00e0 s\u2019absorber tout entier dans une activit\u00e9 de recherche ou \u00e0 savourer \u2013 plut\u00f4t que jalouser \u2013 la qualit\u00e9 d\u2019un travail bien fait. Une telle attitude ne favorise \u00e9videmment pas la course au ranking ou \u00e0 la carri\u00e8re acad\u00e9mique. Mais elle apporte une r\u00e9compense bien plus essentielle : la possibilit\u00e9 de tirer plaisir et fiert\u00e9 de son travail.<\/p>\n<p><strong><em>Figures d\u2019artisans<\/em><\/strong><\/p>\n<p>\u00c0 ce titre, adopter une d\u00e9marche Slow Science consiste moins \u00e0 d\u00e9velopper un univers parall\u00e8le ou \u00e0 bricoler dans les marges du syst\u00e8me, qu\u2019\u00e0 transformer nos pratiques scientifiques en y (r\u00e9)insufflant les valeurs qui font de notre vie une vie de qualit\u00e9. Deux ouvrages r\u00e9cents, remarquablement convergents, offrent \u00e0 cet \u00e9gard une figure de r\u00e9f\u00e9rence : celle de l\u2019artisan. Le premier est le fait d\u2019un universitaire am\u00e9ricain, Matthew Crawford<sup>21<\/sup>, titulaire d\u2019un doctorat en philosophie. Apr\u00e8s avoir fait l\u2019exp\u00e9rience de la d\u00e9rive actuelle du monde acad\u00e9mique, il l\u2019a abandonn\u00e9 pour ouvrir un atelier de r\u00e9paration de motos, dans lequel il m\u00e8ne une vie bien plus satisfaisante sur le plan intellectuel et moral. Le second ouvrage est du sociologue Richard Sennett<sup>22<\/sup>, qui poursuit une r\u00e9flexion historique sur l\u2019univers du travail. Tous deux partent d\u2019un constat devenu banal : la d\u00e9valorisation du travail manuel en milieu scolaire et professionnel est concomitante au d\u00e9veloppement d\u2019une \u00ab \u00e9conomie du savoir \u00bb caract\u00e9ris\u00e9e par un flux de connaissances de plus en plus superficielles et d\u00e9sincarn\u00e9es. Comme bien d\u2019autres, ils soulignent le caract\u00e8re id\u00e9ologique de cette s\u00e9paration entre la t\u00eate et les mains. \u00ab Faire \u00bb c\u2019est \u00ab penser \u00bb et r\u00e9ciproquement. Les aptitudes \u00e9l\u00e9mentaires sur lesquelles se fonde le travail artisanal \u2013 localiser, questionner, ouvrir<sup>23<\/sup> \u2013 sont d\u2019ailleurs identiques \u00e0 celles du travail de recherche. La premi\u00e8re implique en effet \u00ab de donner \u00e0 une chose un caract\u00e8re concret ; la deuxi\u00e8me, de r\u00e9fl\u00e9chir \u00e0 ses qualit\u00e9s ; la troisi\u00e8me, d\u2019en \u00e9tendre le sens. \u00bb<sup>24<\/sup><\/p>\n<p>Les pr\u00e9occupations de Crawford et Sennett rejoignent directement les n\u00f4tres lorsqu\u2019ils d\u00e9crivent les conditions n\u00e9cessaires \u00e0 la conduite d\u2019une activit\u00e9 manuelle qui engendre \u00e0 la fois de la qualit\u00e9 et de la satisfaction. De fa\u00e7on g\u00e9n\u00e9rale, l\u2019imp\u00e9ratif est de se soumettre aux exigences du m\u00e9tier, c\u2019est-\u00e0-dire aux limitations impos\u00e9es par la mati\u00e8re travaill\u00e9e et la t\u00e2che effectu\u00e9e. Ce sont en effet \u00ab les objectifs propres [de la t\u00e2che], en tant que biens en soi, qui font que je d\u00e9sire accomplir mon travail correctement \u00bb, rappelle Crawford<sup>25<\/sup>. \u00ab Ils r\u00e9gissent de fa\u00e7on tr\u00e8s stricte la \u201cqualit\u00e9\u201d d\u2019un produit, dimension quasi m\u00e9taphysique qui \u00e9chappe largement \u00e0 ceux qui se contentent de calculer leurs b\u00e9n\u00e9fices mais qui reste une pr\u00e9occupation centrale tant pour l\u2019usager que pour le producteur de l\u2019objet lui-m\u00eame. \u00bb<sup>26<\/sup> Accepter les exigences du m\u00e9tier implique \u00e9videmment de refuser les solutions de facilit\u00e9 ou les voies de contournement. Mais \u00e9galement de comprendre l\u2019importance des erreurs et de la r\u00e9p\u00e9tition, trop souvent envisag\u00e9es comme la marque d\u2019une absence de r\u00e9flexion et de cr\u00e9ativit\u00e9<sup>27<\/sup>. \u00ab [L]a v\u00e9ritable cr\u00e9ativit\u00e9 est le sous-produit d\u2019un type de ma\u00eetrise qui ne s\u2019obtient qu\u2019au terme de longues ann\u00e9es de pratique. [&#8230;] L\u2019identification entre cr\u00e9ativit\u00e9 et libert\u00e9 est typique du nouveau capitalisme ; dans cette culture, l\u2019imp\u00e9ratif de flexibilit\u00e9 exclut qu\u2019on s\u2019attarde sur une t\u00e2che sp\u00e9cifique suffisamment longtemps pour y acqu\u00e9rir une r\u00e9elle comp\u00e9tence. Or, ce type de comp\u00e9tence est la condition non seulement de la cr\u00e9ativit\u00e9 authentique, mais de l\u2019ind\u00e9pendance dont jouit l\u2019homme de m\u00e9tier. \u00bb<sup>28<\/sup> C\u2019est aussi la source de son autorit\u00e9 car, celle-ci ne revient pas \u00e0 \u00ab occuper une place d\u2019honneur dans un r\u00e9seau social. \u00bb<sup>29<\/sup><\/p>\n<p>Qualit\u00e9, cr\u00e9ativit\u00e9, ind\u00e9pendance, autorit\u00e9 : voil\u00e0 ce qu\u2019apporte, en plus des gains mat\u00e9riels, la poursuite honn\u00eate d\u2019un artisanat. \u00c0 ces b\u00e9n\u00e9fices s\u2019ajoute la fiert\u00e9 engendr\u00e9e par \u00ab l\u2019ex\u00e9cution int\u00e9grale d\u2019une t\u00e2che susceptible d\u2019\u00eatre anticip\u00e9e intellectuellement dans son ensemble et contempl\u00e9e comme un tout une fois achev\u00e9e. \u00bb<sup>30<\/sup> Comme le conclut Sennett \u2013 dans des termes qui pourraient figurer sur un manifeste Slow Science \u2013 \u00ab les artisans sont surtout fiers du savoir-faire qui m\u00fbrit. C\u2019est bien pourquoi la simple imitation ne procure pas une satisfaction durable ; la comp\u00e9tence doit \u00e9voluer. La lenteur m\u00eame du temps professionnel est une source de satisfaction ; la pratique s\u2019enracine et permet de s\u2019approprier un savoir-faire. La m\u00eame lenteur permet aussi le travail de r\u00e9flexion et d\u2019imagination \u2013 au contraire de la course aux r\u00e9sultats rapides. \u00bb<sup>31<\/sup><\/p>\n<p><strong><em>Des arbres et des herbes<\/em><\/strong><\/p>\n<p>Les r\u00e9flexions de Crawford et Sennett nous rappellent un fait essentiel : les vraies comp\u00e9tences, celles qui sont sources de progr\u00e8s, ont une dimension pratique et \u00e9thique (un terme malheureusement galvaud\u00e9 \u00e0 l\u2019heure actuelle). Elles s\u2019incarnent et m\u00fbrissent dans des activit\u00e9s orient\u00e9es vers la production de r\u00e9sultats tangibles, qui habilitent au plan aussi bien professionnel qu\u2019individuel. Il est bon de le garder \u00e0 l\u2019esprit, au moment o\u00f9 nos universit\u00e9s se lancent dans une nouvelle r\u00e9flexion sur les \u00ab r\u00e9f\u00e9rentiels de comp\u00e9tences \u00bb. Crawford et Sennett nous rappellent \u00e9galement que l\u2019\u00e9litisme intellectuel sur lequel se fonde le monde universitaire a entra\u00een\u00e9 une extraordinaire confusion des valeurs et affaibli notre capacit\u00e9 de r\u00e9sistance \u00e0 la d\u00e9rive manag\u00e9riale actuelle. Sur quels crit\u00e8res \u00e9valuer la qualit\u00e9 d\u2019une recherche ? Au nom de qui et \u00e0 quelles fins cette \u00e9valuation doit-elle se faire ? Qui fait figure d\u2019autorit\u00e9 ? \u00c0 ces questions viennent s\u2019ajouter d\u2019autres interrogations : sur la responsabilit\u00e9 professionnelle, l\u2019\u00e9quilibre entre passion et obsession, le rapport \u00e0 \u00e9tablir avec les pairs ou l\u2019engagement vis-\u00e0-vis de ceux que l\u2019on forme. L\u2019exemple de l\u2019artisanat ne nous offre pas seulement des pistes pour sortir de cette confusion ; il nous invite aussi \u00e0 une plus grande humilit\u00e9 par rapport \u00e0 d\u2019autres formes d\u2019exp\u00e9rience.<\/p>\n<p>Comme je l\u2019ai signal\u00e9 plus haut, la recherche d\u2019une forme stable et coh\u00e9rente de r\u00e9sistance devrait se concevoir dans la perspective d\u2019un logiciel libre, nourri et am\u00e9lior\u00e9 par ceux qui s\u2019en servent concr\u00e8tement. Si j\u2019ai r\u00e9sum\u00e9 et propos\u00e9 ici quelques pistes de r\u00e9flexion, le travail \u00e0 accomplir reste ph\u00e9nom\u00e9nal. Mais quelles que soient les solutions apport\u00e9es, la meilleure attitude est sans doute de plonger profond\u00e9ment nos racines dans les interstices du syst\u00e8me universitaire et de les cultiver, pour qu\u2019elles finissent par faire sauter la chape id\u00e9ologique qui le recouvre. On se souviendra \u00e0 cet \u00e9gard que les arbres \u00e0 croissance lente alt\u00e8rent plus durablement leur environnement que les herbes folles. L\u2019\u00e9clat de ces derni\u00e8res ne dure en effet qu\u2019un temps, celui d\u2019une saison&#8230;<\/p>\n<p><sup>1<\/sup> Voir Gosselain, O.P., R. Zeebroek et J.-M. Decroly (eds), 2008. Des choses, des gestes, des mots. Repenser les dynamiques culturelles. Paris : Editions de la MSH (Techniques et Culture 51).<\/p>\n<p><sup>2<\/sup>\u00ab Strenghts, Weaknesses, Opportunities, Threats \u00bb. C\u2019est sur cette base que s\u2019\u00e9laborent les plans strat\u00e9giques dans les milieux d\u2019affaire et, depuis quelques ann\u00e9es, dans les universit\u00e9s.<\/p>\n<p><sup>3<\/sup>Garfield, E., 1990. Fast Science vs. Slow Science, Or Slow and Steady Win the Race. The Scientist 4(18) :14.<\/p>\n<p><sup>4<\/sup> Outils statistiques servant de balises actuelles \u00e0 la gestion des carri\u00e8res scientifiques. Pour l\u2019Europe et dans le domaine des sciences humaines, le classement des revues (European Reference Index for the Humanities) a \u00e9t\u00e9 initi\u00e9 par la European Science Foundation au d\u00e9but des ann\u00e9es 2000 et concr\u00e9tis\u00e9 en 2007. Cet outil, qui n\u2019a fait qu\u2019accro\u00eetre la pression sur les chercheurs (particuli\u00e8rement les plus jeunes) et renforc\u00e9 la position h\u00e9g\u00e9monique de certaines universit\u00e9s, est pr\u00e9sent\u00e9 comme une progression favorable, \u00e9mancipatrice et garante de la diversit\u00e9 des cultures scientifiques europ\u00e9ennes. Les formules qui \u00e9gr\u00e8nent le texte de pr\u00e9sentation laissent en tout cas peu de doute sur la culture dans laquelle baignent ceux qui pilotent l\u2019initiative : \u00ab &#8230;how the community of European humanities researchers can best benchmark its outputs&#8230; \u00bb ; \u00ab &#8230; systematic turnover of panel membership was also implemented&#8230; \u00bb ; \u00ab &#8230; impact and&#8230; appropriate evaluation mechanisms for humanities research&#8230;\u00bb ; \u00ab &#8230; to raise the threshold of editorial standards&#8230; \u00bb ; \u00ab &#8230;to meet stringent benchmark standards&#8230; \u00bb (voir <a href=\"http:\/\/www.esf.org\/research-areas\/humanities\/erih-european-reference-index-for-the-humanities\/erih-foreword.html\">ce lien <\/a>, consult\u00e9 le 17 juin 2011).<\/p>\n<p><sup>5<\/sup> Du moins ceux qui se fondent, comme Linux, sur un style de d\u00e9veloppement de type \u00ab bazar \u00bb, pour reprendre la terminologie d\u2019Eric Raymond (voir <a href=\"http:\/\/www.linux-france.org\/article\/these\/cathedrale-bazar\/cathedrale-bazar-1.html\">ce lien<\/a>, consult\u00e9 le 15 juin 2011).<\/p>\n<p><sup>6<\/sup> Alleva, L., 2006. Taking time to savour the rewards of slow science. Nature 443, 21 September: 271.<\/p>\n<p><sup>7<\/sup> Ibid.<\/p>\n<p><sup>8<\/sup> Lisa Alleva est aujourd\u2019hui \u00e0 la t\u00eate de son propre (petit) laboratoire, poursuivant des travaux sur le traitement de certaines maladies virales (voir <a href=\"http:\/\/biology.anu.edu.au\/lisa_alleva\/\">ce lien<\/a>, consult\u00e9 le 17 juin 2011).<\/p>\n<p><sup>9<\/sup> Voir <a href=\"http:\/\/dabacon.org\/pontiff\/?p=2348\">ce lien<\/a> (consult\u00e9 le 15 juin 2011). <\/p>\n<p><sup>sup>\/sup>10 Dave Beacon fait r\u00e9f\u00e9rence aux programmes financ\u00e9s par la National Science Foundation (NSF).<\/p>\n<p><\/sup><sup>11<\/sup>Joulian, F., S. de Cheveign\u00e9 et J. Le Marec, 2005. \u00c9valuer les pratiques interdisciplinaires. Nature, Sciences, Soci\u00e9t\u00e9s 13 : 284-290 ; p. 286.<\/p>\n<p><sup>12<\/sup> <a href=\"http:\/\/slow-science.org\/\">Slow-science.org<\/a> (consult\u00e9 le 21 d\u00e9cembre 2010). Dommage que l\u2019anonymat et le mode de pr\u00e9sentation du site conf\u00e8rent \u00e0 cette \u00ab Acad\u00e9mie \u00bb une totale opacit\u00e9.<\/p>\n<p><sup>13<\/sup> <a href=\"http:\/\/slow-science.org\/slow-science-manifesto.pdf\">Slow science manifesto<\/a> (consult\u00e9 le 21 d\u00e9cembre 2010).<\/p>\n<p><sup>14<\/sup> Evaluation par les pairs et classement des publications en fonction de leur impact, importance accord\u00e9e aux m\u00e9dias et aux relations publiques, accroissement de la sp\u00e9cialisation et de la diversification dans toutes les disciplines, applications des recherches en vue d\u2019accro\u00eetre le bien-\u00eatre et la prosp\u00e9rit\u00e9 (ibid.).<\/p>\n<p><sup>15<\/sup> Ibid.<\/p>\n<p><sup>16<\/sup> Dat\u00e9 d\u2019octobre 2010, le document m\u2019a \u00e9t\u00e9 transmis par Agn\u00e8s Jeanjean, avec laquelle j\u2019ai souvent discut\u00e9 des probl\u00e8mes \u00e9voqu\u00e9s ici.<\/p>\n<p><sup>17 <\/sup>Du bon usage de la bibliom\u00e9trie pour l\u2019\u00e9valuation individuelle des chercheurs, Rapport de l\u2019Acad\u00e9mie des Sciences remis le 17 janvier 2011 \u00e0 Madame la Ministre de l&rsquo;Enseignement Sup\u00e9rieur et de la Recherche. Voir \u00ab Recommandation n\u00b03, p. 6 \u00bb (voir <a href=\"http:\/\/www.academie-sciences.fr\/activite\/rapport\/avis170111.pdf\">ce lien<\/a>, consult\u00e9 le 14 juin 2011). <\/p>\n<p><sup>18<\/sup> Pour un portrait r\u00e9aliste de ce classement, voir : Gingras, Y., 2008. La fi\u00e8vre de l\u2019\u00e9valuation de la recherche. Du mauvais usage de faux indicateurs. Montr\u00e9al : Centre Interuniversitaire de Recherche sur la Science et la Technologie (voir <a href=\"http:\/\/www.cirst.uqam.ca\/Portals\/0\/docs\/note_rech\/2008_05.pdf\">ce lien<\/a>).<\/p>\n<p><sup>19<\/sup> Ibid., p. 11. <\/p>\n<p><sup>20<\/sup> Voir, par exemple : Gingras 2008, op. cit. ; Servais, P. (Ed.), 2011. L&rsquo;\u00e9valuation de la recherche en sciences humaines et sociales : Regards de chercheurs. Louvain-la-Neuve : Editions Bruylant-Acad\u00e9mia.<\/p>\n<p><sup>21<\/sup> Crawford, M.B., 2010. \u00c9loge du carburateur. Essai sur le sens et la valeur du travail. Paris : Editions La D\u00e9couverte.<\/p>\n<p><sup>22<\/sup>Sennett, R., 2010. Ce que sait la main. La culture de l\u2019artisanat. Paris : Albin Michel.<\/p>\n<p><sup>23<\/sup> Ibid., p. 372.<\/p>\n<p><sup>24<\/sup> Ibid.<\/p>\n<p><sup>25<\/sup> Crawford, op. cit., p. 158.<\/p>\n<p><sup>26<\/sup> Ibid.<\/p>\n<p><sup>27<\/sup> \u00ab Le d\u00e9veloppement \u00e0 long terme des techniques manuelles montre [que la] facult\u00e9 de se concentrer durablement vient d\u2019abord ; c\u2019est ensuite seulement qu\u2019une personne pourra s\u2019impliquer \u00e9motionnellement ou intellectuellement. La concentration physique suit ses r\u00e8gles propres, fond\u00e9es sur la mani\u00e8re dont les gens apprennent \u00e0 pratiquer, \u00e0 r\u00e9p\u00e9ter ce qu\u2019ils font et \u00e0 tirer les le\u00e7ons de la r\u00e9p\u00e9tition. \u00bb (Sennett, op.cit., p. 236).<\/p>\n<p><sup>28<\/sup> Crawford, op. cit., p. 63.<\/p>\n<p><sup>29 <\/sup>Sennett, op. cit., p. 87.<\/p>\n<p><sup>30<\/sup> Crawford, op. cit. p. 179.<\/p>\n<p><sup>31<\/sup> Sennett, op. cit., p. 395.<\/p>\n<p>* Universit\u00e9 libre de Bruxelles \u2013 GAES, University of the Witwatersrand<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9 \u00c7a a commenc\u00e9 comme \u00e7a. Une poign\u00e9e de coll\u00e8gues issus de disciplines diff\u00e9rentes, l\u2019envie de travailler ensemble, un financement de cinq ans, des s\u00e9minaires r\u00e9guliers o\u00f9 le plaisir d\u2019\u00e9changer se m\u00ealait \u00e0 un sentiment grisant de progression et, au final, des objets d\u2019\u00e9tude, des rencontres et des r\u00e9sultats qui d\u00e9passaient de loin nos [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,171],"tags":[823,473,919,1473],"class_list":["post-27864","post","type-post","status-publish","format-standard","hentry","category-politique","category-sciences","tag-recherche","tag-rentabilite","tag-science","tag-universite"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/27864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=27864"}],"version-history":[{"count":17,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/27864\/revisions"}],"predecessor-version":[{"id":47128,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/27864\/revisions\/47128"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=27864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=27864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=27864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}