{"id":35925,"date":"2012-04-14T07:51:08","date_gmt":"2012-04-14T05:51:08","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=35925"},"modified":"2013-01-02T00:50:30","modified_gmt":"2013-01-01T23:50:30","slug":"leclatement-de-la-zone-euro-linstantane","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2012\/04\/14\/leclatement-de-la-zone-euro-linstantane\/","title":{"rendered":"<b>L\u2019\u00c9CLATEMENT DE LA ZONE EURO : L\u2019INSTANTAN\u00c9<\/b>"},"content":{"rendered":"<p>Ce que vous voyez sur ce <a href=\"http:\/\/www.bloomberg.com\/news\/2012-04-12\/europe-s-capital-flight-betrays-currency-s-fragility.html\">graphique produit par l\u2019agence de presse Bloomberg<\/a>, c\u2019est l\u2019\u00e9clatement de la zone euro. Sous la ligne horizontale, on voit les sommes qui quittent de mois en mois diff\u00e9rents pays tandis qu\u2019au-dessus de la ligne horizontale, on retrouve les m\u00eames sommes ventil\u00e9es par pays o\u00f9 ces sommes aboutissent.<\/p>\n<p>Les gagnants\u00a0:\u00a0 1. Allemagne, 2. Pays-Bas, 3. Luxembourg<\/p>\n<p>Les perdants (les plus tristes en premier)\u00a0: 1. Italie, 2. Espagne, 3. Irlande, 4. Gr\u00e8ce, 5. Portugal, 6. Belgique<\/p>\n<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capital-Flight-Bloomberg.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capital-Flight-Bloomberg.jpg\" alt=\"\" title=\"Bloomberg - fuite des capitaux au sein de la zone euro\" width=\"628\" height=\"491\" class=\"alignleft size-full wp-image-35926\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capital-Flight-Bloomberg.jpg 628w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Capital-Flight-Bloomberg-300x234.jpg 300w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/a><\/p>\n<p>\u00a9 Bloomberg<\/p>\n<p>Le graphique a \u00e9t\u00e9 produit par la r\u00e9daction de Bloomberg \u00e0 partir des donn\u00e9es fournies par les banques centrales des diff\u00e9rents pays de la zone euro. Un pays dont l\u2019argent sort, en signale les montants. De m\u00eame pour un pays qui le re\u00e7oit, la r\u00e9glementation int\u00e9rieure de la zone euro obligeant le pays receveur de pr\u00eater le m\u00eame montant au pays donneur.<\/p>\n<p>Si des sommes quittent un pays, c\u2019est bien s\u00fbr que leurs habitants (riches) craignent de se retrouver du jour au lendemain en possession de lires, pesetas, punts ou Irish pounds, drachmes, escudos, francs belges, d\u00e9valu\u00e9s.<\/p>\n<p>Pour donner un ordre de grandeur, en mars, par exemple, 65 milliards d\u2019euros ont quitt\u00e9 l\u2019Espagne.<\/p>\n<p>N.B. : La Suisse n&rsquo;\u00e9tant pas dans la zone euro, les mouvements de capitaux vers la Suisse n&rsquo;apparaissent pas sur le graphique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce que vous voyez sur ce graphique produit par l\u2019agence de presse Bloomberg, c\u2019est l\u2019\u00e9clatement de la zone euro. Sous la ligne horizontale, on voit les sommes qui quittent de mois en mois diff\u00e9rents pays tandis qu\u2019au-dessus de la ligne horizontale, on retrouve les m\u00eames sommes ventil\u00e9es par pays o\u00f9 ces sommes aboutissent. Les gagnants\u00a0:\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,204,21],"tags":[243],"class_list":["post-35925","post","type-post","status-publish","format-standard","hentry","category-economie","category-europe","category-monnaie","tag-zone-euro"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/35925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=35925"}],"version-history":[{"count":8,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/35925\/revisions"}],"predecessor-version":[{"id":46463,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/35925\/revisions\/46463"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=35925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=35925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=35925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}