{"id":38686,"date":"2012-06-25T01:23:49","date_gmt":"2012-06-24T23:23:49","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=38686"},"modified":"2013-01-02T00:45:36","modified_gmt":"2013-01-01T23:45:36","slug":"a-quoi-joue-der-spiegel","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2012\/06\/25\/a-quoi-joue-der-spiegel\/","title":{"rendered":"<b>\u00c0 QUOI JOUE <em>DER SPIEGEL<\/em> ?<\/b>"},"content":{"rendered":"<blockquote><p><strong>Ce texte est un \u00ab article presslib\u2019 \u00bb (*) <\/strong><\/p><\/blockquote>\n<p>C&rsquo;\u00e9tait un article du <em>Der Spiegel<\/em> qui avait r\u00e9v\u00e9l\u00e9 <a href=\"http:\/\/www.spiegel.de\/international\/europe\/greek-debt-crisis-how-goldman-sachs-helped-greece-to-mask-its-true-debt-a-676634.html\" target=\"_blank\">le 8 f\u00e9vrier 2010<\/a> le swap trafiqu\u00e9 mis au point par Goldman Sachs pour maquiller la situation de la dette grecque et permettre \u00e0 ce pays d&rsquo;entrer dans la zone euro en 2002. \u00c0 l&rsquo;\u00e9poque j&rsquo;interpr\u00e9tais cette \u00ab\u00a0fuite\u00a0\u00bb comme une mani\u00e8re pour quelqu&rsquo;un au minist\u00e8re des finances ou \u00e0 la Bundesbank d&rsquo;alerter les Allemands sur le fait qu&rsquo;un jour ou l&rsquo;autre et au bout du compte ce serait l&rsquo;Allemagne qui devrait r\u00e9gler l&rsquo;ardoise de l&rsquo;ensemble de la zone euro.<\/p>\n<p>Il y a un mois, <em>Der Spiegel<\/em> titrait <a href=\"http:\/\/www.spiegel.de\/spiegel\/print\/d-85734032.html\" target=\"_blank\">\u00ab\u00a0Akropolis adieu !\u00a0\u00bb<\/a>, pourquoi la Gr\u00e8ce doit quitter la zone euro. <\/p>\n<p>Tout cela allait dans le m\u00eame sens. Alors pourquoi mentionner <a href=\"http:\/\/www.spiegel.de\/wirtschaft\/soziales\/euro-krise-finanzministerium-zeichnet-duesteres-crash-szenario-a-840604.html\" target=\"_blank\">dans le num\u00e9ro qui sort aujourd&rsquo;hui<\/a>, comme le signale <a href=\"http:\/\/www.pauljorion.com\/blog\/?p=38677\" target=\"_blank\">Fran\u00e7ois Leclerc dans son dernier billet<\/a>, un rapport confidentiel du minist\u00e8re des finances pr\u00e9venant d&rsquo;une catastrophe si la zone euro devait s&rsquo;effondrer, la d\u00e9croissance pouvant atteindre 10% \u00e0 la fin de la premi\u00e8re ann\u00e9e de r\u00e9introduction du Deutsche Mark et le nombre de ch\u00f4meurs pouvant atteindre 5 millions, soit presque un doublement par rapport au chiffre actuel ? <\/p>\n<p>Veut-on simplement en Allemagne faire le tri entre les pays de la zone euro qui devraient avoir le chic de tirer leur r\u00e9v\u00e9rence d&rsquo;eux-m\u00eames (ceux qui auraient trich\u00e9 pour entrer dans la zone euro \u00e9tant des candidats de choix pour le d\u00e9part) et les \u00ab\u00a0bons\u00a0\u00bb, qui devraient eux serrer les rangs ? Distinction subtile et num\u00e9ro d&rsquo;\u00e9quilibriste car comment tracer maintenant une ligne de d\u00e9marcation claire entre les uns et les autres, alors qu&rsquo;on a laiss\u00e9 pourrir la situation pendant deux ans ? <\/p>\n<p>Autre hypoth\u00e8se envisageable : les journalistes de <em>Der Spiegel<\/em> font simplement leur m\u00e9tier de diffuser  l&rsquo;information.<\/p>\n<blockquote><p><strong>(*) Un \u00ab article presslib\u2019 \u00bb est libre de reproduction num\u00e9rique en tout ou en partie \u00e0 condition que le pr\u00e9sent alin\u00e9a soit reproduit \u00e0 sa suite. Paul Jorion est un \u00ab journaliste presslib\u2019 \u00bb qui vit exclusivement de ses droits d\u2019auteurs et de vos contributions. Il pourra continuer d\u2019\u00e9crire comme il le fait aujourd\u2019hui tant que vous l\u2019y aiderez. Votre soutien peut s\u2019exprimer <a href=\"http:\/\/www.pauljorion.com\/blog\/?page_id=647\"><em>ici<\/em><\/a>.<\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Ce texte est un \u00ab article presslib\u2019 \u00bb (*) C&rsquo;\u00e9tait un article du Der Spiegel qui avait r\u00e9v\u00e9l\u00e9 le 8 f\u00e9vrier 2010 le swap trafiqu\u00e9 mis au point par Goldman Sachs pour maquiller la situation de la dette grecque et permettre \u00e0 ce pays d&rsquo;entrer dans la zone euro en 2002. \u00c0 l&rsquo;\u00e9poque j&rsquo;interpr\u00e9tais cette [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,204],"tags":[94,1951,160,243],"class_list":["post-38686","post","type-post","status-publish","format-standard","hentry","category-economie","category-europe","tag-allemagne","tag-der-spiegel","tag-grece","tag-zone-euro"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/38686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=38686"}],"version-history":[{"count":9,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/38686\/revisions"}],"predecessor-version":[{"id":46216,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/38686\/revisions\/46216"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=38686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=38686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=38686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}