{"id":38783,"date":"2012-06-28T07:28:13","date_gmt":"2012-06-28T05:28:13","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=38783"},"modified":"2013-01-02T00:45:32","modified_gmt":"2013-01-01T23:45:32","slug":"chedd-les-chemins-de-la-transition-la-transition-rennes-le-3-juillet-a-14h15","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2012\/06\/28\/chedd-les-chemins-de-la-transition-la-transition-rennes-le-3-juillet-a-14h15\/","title":{"rendered":"<b>CHEDD, Les chemins de la transition, \u00ab\u00a0La transition&#8230;\u00a0\u00bb, Rennes, le 3 juillet \u00e0 14h15<\/b>"},"content":{"rendered":"<p>C&rsquo;est un colloque, qui a lieu \u00e0 Rennes, le 3 juillet, mon expos\u00e9 <strong>\u00ab\u00a0La transition&#8230; un \u00e9tat, une dynamique, un processus\u00a0\u00bb<\/strong>, en fait l&rsquo;ouverture \u00e0 14h15. \u00c0 17h40, je ferai l&rsquo;analyse de ce qui aura \u00e9t\u00e9 dit.<\/p>\n<p>Le <strong>CHEDD<\/strong>, c&rsquo;est le Coll\u00e8ge des Hautes \u00c9tudes de D\u00e9veloppement Durable. Et \u00e7a se tient aux <strong>Champs libres<\/strong>, 10 cours des Alli\u00e9s, 35000 Rennes, 02 23 40 66 00 M\u00e9tro : Charles de Gaulle<\/p>\n<p>C&rsquo;est gratuit mais il faut <a href=\"http:\/\/www.chedd-bretagne.eu\/index.php\/contact.html?view=ckforms&amp;id=1\" target=\"_blank\">s&rsquo;inscrire ici<\/a>.<\/p>\n<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Invitation-\u00e9lectronique-Colloque-interactif-les-chemins-de-la-transition.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-38784\" title=\"Invitation \u00e9lectronique - Colloque interactif - les chemins de la transition\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Invitation-\u00e9lectronique-Colloque-interactif-les-chemins-de-la-transition-768x1024.jpg\" alt=\"\" width=\"630\" height=\"900\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est un colloque, qui a lieu \u00e0 Rennes, le 3 juillet, mon expos\u00e9 \u00ab\u00a0La transition&#8230; un \u00e9tat, une dynamique, un processus\u00a0\u00bb, en fait l&rsquo;ouverture \u00e0 14h15. \u00c0 17h40, je ferai l&rsquo;analyse de ce qui aura \u00e9t\u00e9 dit. Le CHEDD, c&rsquo;est le Coll\u00e8ge des Hautes \u00c9tudes de D\u00e9veloppement Durable. Et \u00e7a se tient aux Champs libres, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,1],"tags":[26,93],"class_list":["post-38783","post","type-post","status-publish","format-standard","hentry","category-ecologie","category-economie","tag-capitalisme","tag-developpement-durable"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/38783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=38783"}],"version-history":[{"count":7,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/38783\/revisions"}],"predecessor-version":[{"id":46206,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/38783\/revisions\/46206"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=38783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=38783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=38783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}