{"id":42052,"date":"2012-10-02T12:11:21","date_gmt":"2012-10-02T10:11:21","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=42052"},"modified":"2013-01-02T00:28:32","modified_gmt":"2013-01-01T23:28:32","slug":"une-biere-avec-paul-jorion-par-un-belge","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2012\/10\/02\/une-biere-avec-paul-jorion-par-un-belge\/","title":{"rendered":"<b>UNE BI\u00c8RE AVEC PAUL JORION (1<sup>\u00e8re<\/sup> partie)<\/b>, par Un Belge"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9. La rencontre entre un fid\u00e8le du blog &#8211; \u00ab\u00a0Un Belge\u00a0\u00bb &#8211; et Paul Jorion, le 21 septembre dernier \u00e0 La Coupole<\/p><\/blockquote>\n<p><object height=\"81\" width=\"100%\"><param name=\"movie\" value=\"https:\/\/player.soundcloud.com\/player.swf?url=http%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F61920827&amp;show_comments=true&amp;auto_play=false&amp;color=74451d\"\/><param name=\"allowscriptaccess\" value=\"always\"\/><embed allowscriptaccess=\"always\" height=\"81\" src=\"https:\/\/player.soundcloud.com\/player.swf?url=http%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F61920827&amp;show_comments=true&amp;auto_play=false&amp;color=74451d\" type=\"application\/x-shockwave-flash\" width=\"100%\"\/><\/object> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. La rencontre entre un fid\u00e8le du blog &#8211; \u00ab\u00a0Un Belge\u00a0\u00bb &#8211; et Paul Jorion, le 21 septembre dernier \u00e0 La Coupole<\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-42052","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/42052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=42052"}],"version-history":[{"count":7,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/42052\/revisions"}],"predecessor-version":[{"id":45875,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/42052\/revisions\/45875"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=42052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=42052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=42052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}