{"id":42366,"date":"2012-10-15T10:18:26","date_gmt":"2012-10-15T08:18:26","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=42366"},"modified":"2013-01-02T00:28:05","modified_gmt":"2013-01-01T23:28:05","slug":"20-ans-de-marche-unique-ensemble-pour-une-nouvelle-croissance-i","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2012\/10\/15\/20-ans-de-marche-unique-ensemble-pour-une-nouvelle-croissance-i\/","title":{"rendered":"<b>20 ans de march\u00e9 unique : Ensemble pour une nouvelle croissance (I)<\/b>"},"content":{"rendered":"<p>Alors, ceci est potentiellement int\u00e9ressant. Je dis bien \u00ab\u00a0potentiellement\u00a0\u00bb. Je vais rendre compte en direct de l&rsquo;\u00e9v\u00e9nement sus-nomm\u00e9, auquel participeront (les autres me pardonneront s\u00fbrement) MM. Jos\u00e9 Manuel Barroso, Jacques Delors, Mario Monti et Michel Barnier.<\/p>\n<p>J&rsquo;avais re\u00e7u il y a quelques temps un courrier me disant que j&rsquo;\u00e9tais l&rsquo;une des trente \u00ab personnalit\u00e9s de la presse internationale \u00bb invit\u00e9es \u00e0 cet \u00e9v\u00e9nement. Bon, \u00e7a vous situe son homme, je suppose, et comme j&rsquo;\u00e9tais a Bruxelles de toute mani\u00e8re&#8230; <\/p>\n<p>Je vous ai d\u00e9j\u00e0 fait du direct, lors d&rsquo;auditions du Congr\u00e8s ou du S\u00e9nat am\u00e9ricain, mais c&rsquo;\u00e9tait diff\u00e9rent : il \u00e9tait trois heures du matin, et j&rsquo;\u00e9tais seul devant mon blog.<\/p>\n<p>\u00c7a a commenc\u00e9. Ce sont manifestement MM. Barroso et Barnier assis l\u00e0 devant moi, attendant qu&rsquo;on leur donne la parole. Il y a un monsieur qui nous explique que Jacques Delors est malade et qu&rsquo;on esp\u00e8re qu&rsquo;il regarde ce qui se passe ici en direct en streaming. Mario Monti est lui avec nous par le miracle de Skype. M. Barroso commence \u00e0 parler&#8230;<\/p>\n<p>(\u00e0 suivre&#8230;)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors, ceci est potentiellement int\u00e9ressant. Je dis bien \u00ab\u00a0potentiellement\u00a0\u00bb. Je vais rendre compte en direct de l&rsquo;\u00e9v\u00e9nement sus-nomm\u00e9, auquel participeront (les autres me pardonneront s\u00fbrement) MM. Jos\u00e9 Manuel Barroso, Jacques Delors, Mario Monti et Michel Barnier. J&rsquo;avais re\u00e7u il y a quelques temps un courrier me disant que j&rsquo;\u00e9tais l&rsquo;une des trente \u00ab personnalit\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,204],"tags":[],"class_list":["post-42366","post","type-post","status-publish","format-standard","hentry","category-blog","category-europe"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/42366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=42366"}],"version-history":[{"count":6,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/42366\/revisions"}],"predecessor-version":[{"id":45847,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/42366\/revisions\/45847"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=42366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=42366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=42366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}