{"id":43496,"date":"2012-11-11T17:27:13","date_gmt":"2012-11-11T16:27:13","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=43496"},"modified":"2013-01-02T00:19:34","modified_gmt":"2013-01-01T23:19:34","slug":"la-semaine-qui-vient-du-12-au-18-novembre","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2012\/11\/11\/la-semaine-qui-vient-du-12-au-18-novembre\/","title":{"rendered":"<b>LA SEMAINE QUI VIENT, du 12 au 18 novembre<\/b>"},"content":{"rendered":"<p>Le mercredi 14 novembre, je participerai \u00e0 Paris \u00e0 la <a href=\"http:\/\/www.icp.fr\/fr\/Organismes\/Faculte-de-Sciences-Sociales-et-Economiques-FASSE\/Actualites\/Ethique-et-mathematiques-financieres\" target=\"_blank\">Table ronde \u00ab\u00a0\u00c9thique et math\u00e9matiques financi\u00e8res\u00a0\u00bb<\/a> organis\u00e9e par la <em>Chaire \u00c9thique et finance de l\u2019Institut Catholique de Paris<\/em> (ICP) et la <em>Fondation Maison des sciences de l\u2019homme<\/em> (FMSH), de14h30 \u00e0 18h.<\/p>\n<p>Les intervenants : <\/p>\n<p>&#8211;  Christian Walter, professeur associ\u00e9 \u00e0 l\u2019IAE de l\u2019universit\u00e9 Paris 1 Panth\u00e9on-Sorbonne, directeur de la chaire Ethique et finance de l\u2019Institut Catholique de Paris, \u201cEthique et finance : le tournant performatif\u201d<\/p>\n<p>&#8211;  Jean-Philippe Bouchaud, Fondateur et pr\u00e9sident de Capital Fund Management, professeur \u00e0<br \/>\nl\u2019Ecole polytechnique, \u201cMod\u00e9lisations toxiques en \u00e9conomie et en finance: pourquoi les th\u00e9ories alternatives peinent \u00e0 s\u2019imposer\u201d [Si vous avez eu l&rsquo;occasion de voir sur France 2, l&rsquo;\u00e9mission de <em>Cash Investigation<\/em> intitul\u00e9e : \u00ab\u00a0Finance folle : l&rsquo;attaque des robots-traders\u00a0\u00bb, vous vous souvenez peut-\u00eatre de la s\u00e9quence o\u00f9 \u00c9lise Lucet interroge Jean-Philippe Bouchaud].<\/p>\n<p>&#8211;  Paul Jorion, titulaire de la Chaire Stewardship of Finance de la Vrije Universiteit Brussel<\/p>\n<p>&#8211;  Sylvain Piron, directeur d\u2019\u00e9tudes \u00e0 l\u2019Ecole des hautes \u00e9tudes en sciences sociales (EHESS) [Il a \u00e9t\u00e9 question des travaux de Sylvain Piron dans <a href=\"http:\/\/www.pauljorion.com\/blog\/?p=21729\" target=\"_blank\">un billet de Z\u00e9bu<\/a>. C&rsquo;est lui qui, en particulier, a su dater l&rsquo;apparition du mot \u00ab\u00a0valeur\u00a0\u00bb dans les textes d&rsquo;Aristote : la traduction de l&rsquo;<em>\u00c9thique \u00e0 Nicomaque<\/em> par le scolastique Albert le Grand]. <\/p>\n<p>Le 14 toujours, Gr\u00e9gory Makl\u00e8s et moi serons de 18h20 \u00e0 19h sur <em>France inter<\/em> pour pr\u00e9senter <em><a href=\"http:\/\/www.amazon.fr\/La-survie-lesp%C3%A8ce-Paul-Jorion\/dp\/275480725X\/ref=pd_sim_sbs_b_3\">La survie de l\u2019esp\u00e8ce<\/a><\/em> dans le cadre de l\u2019\u00e9mission <a href=\"http:\/\/www.franceinter.fr\/emission-downtown\" target=\"_blank\"><em>Downtown<\/em><\/a>.<\/p>\n<p>Le 17, je serai \u00e0 Brest, au festival <a href=\"http:\/\/www.economer.fr\/\" target=\"_blank\"><em>Econo&rsquo;mer<\/em><\/a>, je serai l\u00e0 pour promouvoir la r\u00e9\u00e9dition de <em><a href=\"http:\/\/www.amazon.fr\/p%C3%AAcheurs-dHouat-Paul-Jorion\/dp\/2365120091\/ref=sr_1_10?s=books&amp;ie=UTF8&amp;qid=1351718789&amp;sr=1-10\">Les p\u00eacheurs d\u2019Houat<\/a><\/em> (Le Croquant) dans la cat\u00e9gorie Livres de la mer, <em><a href=\"http:\/\/www.amazon.fr\/La-survie-lesp%C3%A8ce-Paul-Jorion\/dp\/275480725X\/ref=pd_sim_b_1\">La survie de l\u2019esp\u00e8ce<\/a><\/em> dans la cat\u00e9gorie BD, et je participerai de 11h \u00e0 12h30 \u00e0 une table-ronde sur la sp\u00e9culation dans la cat\u00e9gorie <em>\u00e9co caf\u00e9<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mercredi 14 novembre, je participerai \u00e0 Paris \u00e0 la Table ronde \u00ab\u00a0\u00c9thique et math\u00e9matiques financi\u00e8res\u00a0\u00bb organis\u00e9e par la Chaire \u00c9thique et finance de l\u2019Institut Catholique de Paris (ICP) et la Fondation Maison des sciences de l\u2019homme (FMSH), de14h30 \u00e0 18h. Les intervenants : &#8211; Christian Walter, professeur associ\u00e9 \u00e0 l\u2019IAE de l\u2019universit\u00e9 Paris 1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-43496","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/43496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=43496"}],"version-history":[{"count":7,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/43496\/revisions"}],"predecessor-version":[{"id":45547,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/43496\/revisions\/45547"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=43496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=43496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=43496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}