{"id":48459,"date":"2013-01-02T22:01:30","date_gmt":"2013-01-02T21:01:30","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=48459"},"modified":"2013-01-15T12:31:41","modified_gmt":"2013-01-15T11:31:41","slug":"enron-revisite-i-il-y-a-nous-dun-cote-et-puis-tous-les-autres","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2013\/01\/02\/enron-revisite-i-il-y-a-nous-dun-cote-et-puis-tous-les-autres\/","title":{"rendered":"<b>ENRON REVISIT\u00c9 (I) \u00ab IL Y A NOUS, D\u2019UN C\u00d4T\u00c9\u2026 ET PUIS TOUS LES AUTRES\u2026 \u00bb<\/b>"},"content":{"rendered":"<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Post-Enron-World.png\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Post-Enron-World.png\" alt=\"Post-Enron World\" width=\"160\" height=\"245\" class=\"alignleft size-full wp-image-49045\" \/><\/a><br \/>\nEn vue d\u2019y consacrer l\u2019une des le\u00e7ons de la chaire \u00ab\u00a0Stewardship of Finance\u00a0\u00bb, je me suis replong\u00e9 dans la litt\u00e9rature relative \u00e0 la chute de la compagnie am\u00e9ricaine Enron \u00e0 l\u2019automne 2001. Parmi les textes que j\u2019ai relus\u00a0: le livre que j\u2019avais personnellement consacr\u00e9 \u00e0 l\u2019affaire\u00a0: <i><a href=\"http:\/\/www.amazon.fr\/Investing-Post-Enron-World-Paul-Jorion\/dp\/0071409386\/ref=sr_1_2?s=english-books&amp;ie=UTF8&amp;qid=1357151999&amp;sr=1-2\">Investing in a Post-Enron World<\/a><\/i> (McGraw-Hill 2003), et avec un int\u00e9r\u00eat plus particulier encore, les deux chapitres qui n\u2019avaient pas \u00e9t\u00e9 int\u00e9gr\u00e9s \u00e0 l\u2019ouvrage en raison de leur technicit\u00e9 jug\u00e9e excessive par l\u2019\u00e9diteur\u00a0: l\u2019un, relatif \u00e0 l\u2019utilisation par le vendeur d\u2019\u00e9nergie texan des produits financiers d\u00e9riv\u00e9s, l\u2019autre, portant sur les nombreux S.P.V. (<i>Special Purpose Vehicles<\/i>) qu\u2019il avait cr\u00e9\u00e9s afin de mettre hors-bilan, et donc relativement \u00e0 l\u2019abri du regard indiscret de ses actionnaires, certaines de ses dettes les plus inqui\u00e9tantes.<\/p>\n<p>En revisitant Enron, j\u2019esp\u00e9rais qu\u2019un certain nombre d\u2019\u00e9l\u00e9ments m\u2019appara\u00eetraient en lesquels je pourrais reconna\u00eetre les pr\u00e9curseurs de la crise actuelle. Sur ce plan-l\u00e0, j\u2019ai \u00e9t\u00e9 d\u00e9\u00e7u puisqu\u2019une loi\u00a0: le <i>Sarbanes-Oxley Act<\/i>, fut promulgu\u00e9e en 2002 en vue de prohiber un certain nombre de pratiques apparues en surface \u00e0 l\u2019occasion de l\u2019affaire Enron, et cette loi remplit sa t\u00e2che depuis \u00e0 la satisfaction g\u00e9n\u00e9rale (les firmes am\u00e9ricaines pouss\u00e8rent bien entendu des cris de putois, mais qu\u2019attendait-on d\u2019autre de leur part\u00a0?). L\u2019exigence la plus symbolique de ce corps de lois fut l\u2019obligation faite au P-DG d\u2019une entreprise am\u00e9ricaine d\u2019engager sa responsabilit\u00e9 personnelle dans la publication des bilans trimestriels et annuels de sa firme. L\u2019objectif \u00e9tait de contrer une fois pour toutes la strat\u00e9gie qu\u2019avait adopt\u00e9e pour sa d\u00e9fense Jeff Skilling &#8211; qui avait \u00e9t\u00e9 P-DG d\u2019Enron peu avant sa chute \u2013 \u00e0 savoir, r\u00e9p\u00e9ter inlassablement, aussi bien lors des auditions parlementaires portant sur l\u2019affaire que lors du proc\u00e8s qui lui fut intent\u00e9 ensuite \u00e0 titre personnel\u00a0: \u00ab\u00a0Qu\u2019est-ce que j\u2019en sais\u00a0? je ne suis pas comptable\u00a0!\u00a0\u00bb, rejetant par l\u00e0 enti\u00e8rement la responsabilit\u00e9 de la chute de sa compagnie sur la firme charg\u00e9e de son audit\u00a0: Arthur Andersen, laquelle fut effectivement balay\u00e9e par les retomb\u00e9es de l\u2019affaire, et disparut \u00e0 jamais.<\/p>\n<p>Qu\u2019est-ce qui provoqua alors la chute d\u2019Enron qui, six mois seulement avant sa faillite, se vantait d\u2019\u00eatre en taille la 7<sup>\u00e8me<\/sup> entreprise des \u00c9tats-Unis ? Le fait, pour commencer, qu\u2019elle n\u2019\u00e9tait en r\u00e9alit\u00e9 pas la 7<sup>\u00e8me<\/sup> mais la 287<sup>\u00e8me<\/sup>, comme le mit en \u00e9vidence Robert McCullough, un ancien partenaire d\u2019Arthur Andersen pr\u00e9cis\u00e9ment, quand il d\u00e9couvrit que le rang flatteur de 7<sup>\u00e8me<\/sup> lui avait \u00e9t\u00e9 attribu\u00e9e sur la base de calculs douteux fond\u00e9s sur la valeur \u00ab\u00a0notionnelle\u00a0\u00bb de certains produits d\u00e9riv\u00e9s dans son portefeuille plut\u00f4t que sur leur gain probable qui, dans le cas des produits d\u00e9riv\u00e9s, ne repr\u00e9sente en g\u00e9n\u00e9ral qu\u2019une fraction du montant du <i>notionnel<\/i>. La compagnie Enron \u00e9tait donc, en r\u00e9alit\u00e9, beaucoup moins importante qu\u2019on ne l\u2019imaginait \u00e0 la veille de sa chute.<\/p>\n<p>Comment une telle erreur d\u2019appr\u00e9ciation avait-elle \u00e9t\u00e9 possible\u00a0? Essentiellement parce qu\u2019en raison de leur complexit\u00e9, la compr\u00e9hension du fonctionnement des produits d\u00e9riv\u00e9s est le plus souvent tr\u00e8s approximative, m\u00eame dans les milieux financiers. Il m\u2019a par exemple \u00e9t\u00e9 donn\u00e9, lors d\u2019une r\u00e9union \u00e0 la Communaut\u00e9 Europ\u00e9enne, d\u2019entendre un des principaux \u00e9conomistes de l\u2019OCDE, faire la m\u00eame erreur exactement lors de son expos\u00e9 et la soutenir\u2026 graphiques \u00e0 l\u2019appui\u00a0!<\/p>\n<p>Est-ce \u00e0 dire que l\u2019erreur d\u2019Enron avait \u00e9t\u00e9 commise de bonne foi\u00a0? Je n\u2019en jurerais pas pour autant\u00a0: les compagnies de ce type recrutent un personnel fort comp\u00e9tent, et il s\u2019est s\u00fbrement trouv\u00e9 au sein de celui-ci certains pour se dire que, vu que sont tr\u00e8s rares ceux qui s\u2019y retrouvent, on n\u2019y verrait probablement que du feu. Ce que les faits devaient en effet confirmer.<\/p>\n<p>Et en disant cela, nous nous rapprochons d\u00e9j\u00e0 davantage d\u2019une v\u00e9ritable explication du cas Enron\u00a0: celui de firmes qui, comme elle, en viennent \u00e0 consid\u00e9rer que le monde entier \u00e0 l\u2019exception de ses propres dirigeants (et de ceux de quelques-unes de leurs cons\u0153urs susceptibles \u00e9galement de les employer) est constitu\u00e9 essentiellement d\u2019imb\u00e9ciles\u00a0; celui de firmes qui se conduisent en cons\u00e9quence, et qui, mis \u00e0 part quelques rares accidents comme la chute d\u2019Enron pr\u00e9cis\u00e9ment, celle de Bernard Madoff, et quelques autres exemples, voient \u00e0 tout moment confirm\u00e9e la plausibilit\u00e9 de leur hypoth\u00e8se.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En vue d\u2019y consacrer l\u2019une des le\u00e7ons de la chaire \u00ab\u00a0Stewardship of Finance\u00a0\u00bb, je me suis replong\u00e9 dans la litt\u00e9rature relative \u00e0 la chute de la compagnie am\u00e9ricaine Enron \u00e0 l\u2019automne 2001. Parmi les textes que j\u2019ai relus\u00a0: le livre que j\u2019avais personnellement consacr\u00e9 \u00e0 l\u2019affaire\u00a0: Investing in a Post-Enron World (McGraw-Hill 2003), et avec [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[307,18],"tags":[1683,393],"class_list":["post-48459","post","type-post","status-publish","format-standard","hentry","category-finance","category-monde-financier","tag-investing-in-a-post-enron-world","tag-enron"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/48459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=48459"}],"version-history":[{"count":9,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/48459\/revisions"}],"predecessor-version":[{"id":49046,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/48459\/revisions\/49046"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=48459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=48459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=48459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}