{"id":53235,"date":"2013-05-15T14:50:42","date_gmt":"2013-05-15T12:50:42","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=53235"},"modified":"2013-05-16T16:52:17","modified_gmt":"2013-05-16T14:52:17","slug":"le-monde-le-moins-disant-salarial-en-accusation-lundi-13-mardi-14-mai-2013","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2013\/05\/15\/le-monde-le-moins-disant-salarial-en-accusation-lundi-13-mardi-14-mai-2013\/","title":{"rendered":"<b>LE MONDE, Le moins-disant salarial en accusation<\/b>, lundi 13 &#8211; mardi 14 mai 2013"},"content":{"rendered":"<p><b>Sur la page \u00ab\u00a0Les d\u00e9bats\u00a0\u00bb : \u00ab\u00a0Aligner les salaires fran\u00e7ais sur ceux du Bangladesh\u00a0\u00bb : le sc\u00e9nario du pire, mercredi 15 mai de 15h \u00e0 16h30. <a href=\"http:\/\/www.pauljorion.com\/les_debats\/?p=193\" target=\"_blank\">Ce fut ici<\/a>. <strong>C&rsquo;EST TERMIN\u00c9 ! <\/strong><\/b><\/p>\n<blockquote><p>Le Monde a eu l&rsquo;amabilit\u00e9 de mettre ma chronique en \u00ab\u00a0une\u00a0\u00bb de l&rsquo;\u00e9dition en ligne, non sans en avoir modifi\u00e9 le titre, qui est devenu <a href=\"http:\/\/www.lemonde.fr\/economie\/article\/2013\/05\/13\/le-moins-disant-salarial-en-accusation_3175394_3234.html\" target=\"_blank\">\u00ab\u00a0Aligner les salaires fran\u00e7ais sur ceux du Bangladesh\u00a0\u00bb : le sc\u00e9nario du pire<\/a>.<\/p><\/blockquote>\n<p>Parler de \u00ab\u00a0r\u00e9formes structurelles de comp\u00e9titivit\u00e9\u00a0\u00bb c\u2019est accepter le principe d\u2019un <i>moins-disant<\/i> salarial au plan international\u00a0: c\u2019est admettre qu\u2019il existe un pays o\u00f9 le niveau du salaire de subsistance est le plus bas, et que ce salaire de subsistance du travailleur le plus mis\u00e9rable de la plan\u00e8te doit jouer le r\u00f4le d\u2019un \u00ab\u00a0attracteur\u00a0\u00bb pour l\u2019ensemble des salaires \u00e0 la surface du globe.<\/p>\n<p>Le salaire moyen au Bangladesh \u00e9tant aujourd\u2019hui cinq fois plus faible qu\u2019en Chine, j\u2019ai choisi de traduire dans mes conf\u00e9rences l\u2019expression obscure \u00ab\u00a0r\u00e9formes structurelles de comp\u00e9titivit\u00e9\u00a0\u00bb par \u00ab\u00a0aligner les salaires fran\u00e7ais sur ceux du Bangladesh\u00a0\u00bb, une phrase dont la signification est identique mais pr\u00e9sente l\u2019avantage d\u2019\u00eatre comprise ais\u00e9ment par tous mes auditeurs. En utilisant cette expression pol\u00e9mique, je ne pensais cependant pas qu\u2019une actualit\u00e9 tragique en ferait \u00e0 ce point r\u00e9sonner la pertinence.<\/p>\n<p>Le 24 avril, l\u2019effondrement \u00e0 Savar, un faubourg de Dacca, du Rana Plaza, un immeuble de huit \u00e9tages rassemblant un grand nombre d\u2019ateliers de confection aux conditions de travail dickensiennes, a caus\u00e9 la mort de plus de onze cents personnes, des femmes essentiellement.<\/p>\n<p>\u00c0 la vue d\u2019\u00e9tiquettes de marques famili\u00e8res m\u00eal\u00e9es aux corps sans vie au milieu des gravats, l\u2019indignation est \u00e0 son comble. La presse financi\u00e8re internationale n\u2019est pas en reste\u00a0: \u00e0 de telles situations o\u00f9 des ouvri\u00e8res et des ouvriers sont renvoy\u00e9s dans des locaux en voie d\u2019effondrement et aux issues de secours bloqu\u00e9es par une \u00ab\u00a0police industrielle\u00a0\u00bb, elle conna\u00eet la r\u00e9ponse. Son nom, affirme le Financial Times, c\u2019est la syndicalisation, qui permet aux travailleurs de faire valoir leurs droits. Tout occup\u00e9s \u00e0 \u00e9chapper \u00e0 l\u2019enfer du monde rural pour d\u00e9couvrir la paix relative des ateliers urbains (migration qui en vingt ans a fait baisser la pauvret\u00e9 de moiti\u00e9), les Bengladeshis auraient n\u00e9glig\u00e9 la protection qu\u2019offrent les syndicats. Sans doute, mais peut-\u00eatre ont-ils en m\u00e9moire le syndicaliste Aminul Islam, dont le cadavre portant les marques de s\u00e9vices fut retrouv\u00e9 l\u2019ann\u00e9e derni\u00e8re abandonn\u00e9 sur une autoroute.<\/p>\n<p>La r\u00e9v\u00e9lation spectaculaire des conditions dans lesquelles est produit dans le tiers-monde notre <i>low-cost<\/i> occidental modifiera-t-elle la philosophie de nos dirigeants\u00a0? Il en faudrait certainement plus\u00a0car nous vivons dans un monde o\u00f9, si les individus sont encore ancr\u00e9s dans une logique territoriale, les entreprises ont cess\u00e9 de l\u2019\u00eatre depuis plus d\u2019un si\u00e8cle. Par le biais de l\u2019instrument juridique qu\u2019est le \u00ab\u00a0trust\u00a0\u00bb anglo-saxon, les individus les plus fortun\u00e9s, gr\u00e2ce \u00e0 des montages fond\u00e9s sur l\u2019anonymat qu\u2019autorisent les havres fiscaux, ont le moyen d\u2019acc\u00e9der \u00e0 titre personnel au pouvoir dont disposent les transnationales\u00a0: pouvoir \u00e9conomique mais aussi pouvoir politique en raison du poids que l\u2019argent permet d\u2019exercer sur le m\u00e9canisme d\u00e9mocratique. Dans le cadre actuel, la logique du <i>moins-disant salarial<\/i> est l\u2019un des principes de base de l\u2019\u00e9conomie de march\u00e9, \u00e0 preuve l\u2019indiff\u00e9rence des populations \u00e0 l\u2019annonce de ces \u00ab\u00a0r\u00e9formes structurelles de comp\u00e9titivit\u00e9\u00a0\u00bb.<\/p>\n<p>L\u2019horreur de Rana Plaza restera-t-elle sans cons\u00e9quences\u00a0? Rien n\u2019est moins s\u00fbr cependant, car c\u2019est la philosophie du \u00ab\u00a0moins-disant\u00a0\u00bb sous toutes ses formes qui se retrouve aujourd\u2019hui sur la d\u00e9fensive\u00a0depuis que l\u2019affaire Cahuzac a mis sur la sellette le <i>moins-disant juridique<\/i> et <i>fiscal<\/i> des havres fiscaux, et que l\u2019inviolabilit\u00e9 qui faisait leur force s\u2019est vue compromise dans la r\u00e9solution de l\u2019affaire de Chypre.\u00a0Si en effet les sommes d\u00e9pos\u00e9es sur un compte dans un havre fiscal ont cess\u00e9 d\u2019y \u00eatre en s\u00e9curit\u00e9, c\u2019est l\u2019\u00e9difice entier qui s\u2019effondre.<\/p>\n<p>Et c\u2019est l\u00e0 que se situe le talon d\u2019Achille du <i>moins-disant salarial<\/i>\u00a0: dans le fait que les opinions publiques sont d\u00e9sormais en r\u00e9bellion ouverte contre la philosophie du <i>moins-disant<\/i> dans toutes ses manifestations. Ce ne sont pas les dirigeants eux-m\u00eames qui ont mis le hol\u00e0 mais la r\u00e9probation g\u00e9n\u00e9rale les a oblig\u00e9s d\u2019installer des coupe-feu dans l\u2019urgence pour contenir la vague d\u2019indignation. Qu\u2019on pense \u00e0 la promptitude de la r\u00e9ponse, m\u00eame si ce n\u2019\u00e9tait pas une transparence voyeuriste que r\u00e9clamait de la classe politique, l\u2019opinion, mais bien plus banalement, des gages d\u2019honn\u00eatet\u00e9.<\/p>\n<p>Le <i>moins-disant juridique<\/i> et <i>fiscal<\/i> a atteint le seuil de l\u2019intol\u00e9rable parce qu\u2019il instaure en r\u00e9gime id\u00e9al la piraterie que les grosses entreprises &#8211; transnationales de fait &#8211; exercent sur l\u2019\u00e9conomie mondiale\u00a0: pr\u00e9dation par elles des entreprises plus petites, confin\u00e9es quant \u00e0 elles de par leur taille sur le territoire national et contribuant seules par le versement de l\u2019imp\u00f4t aux frais de maintien de l\u2019ordre commercial, ordre dont les transnationales b\u00e9n\u00e9ficient sinon gratuitement, du moins avec un rabais consid\u00e9rable. Ces transnationales n\u2019en voient pas moins le contribuable voler \u00e0 leur secours en p\u00e9riode de vaches maigres, pour r\u00e9gler non seulement leurs pertes \u00e9conomiques r\u00e9elles mais \u00e9galement leurs paris sp\u00e9culatifs perdus, illustration tragique du principe de \u00ab\u00a0privatisation des profits, socialisation des pertes\u00a0\u00bb.<\/p>\n<p>Le <i>moins-disant salarial<\/i> des \u00ab\u00a0r\u00e9formes structurelles de comp\u00e9titivit\u00e9\u00a0\u00bb rel\u00e8ve de la m\u00eame logique exactement que le <i>moins-disant fiscal<\/i>\u00a0: il s\u2019agit l\u00e0 aussi, par la baisse des salaires, de maximiser la part de la richesse cr\u00e9\u00e9e qui passera en dividendes et en bonus extravagants que les dirigeants des plus grosses entreprises s\u2019octroient \u00e0 eux-m\u00eames.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur la page \u00ab\u00a0Les d\u00e9bats\u00a0\u00bb : \u00ab\u00a0Aligner les salaires fran\u00e7ais sur ceux du Bangladesh\u00a0\u00bb : le sc\u00e9nario du pire, mercredi 15 mai de 15h \u00e0 16h30. Ce fut ici. C&rsquo;EST TERMIN\u00c9 ! Le Monde a eu l&rsquo;amabilit\u00e9 de mettre ma chronique en \u00ab\u00a0une\u00a0\u00bb de l&rsquo;\u00e9dition en ligne, non sans en avoir modifi\u00e9 le titre, qui [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2597,1,204],"tags":[2600,2599,2106],"class_list":["post-53235","post","type-post","status-publish","format-standard","hentry","category-democratie-2","category-economie","category-europe","tag-bengladesh","tag-rana-plaza","tag-reformes-structurelles"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/53235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=53235"}],"version-history":[{"count":14,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/53235\/revisions"}],"predecessor-version":[{"id":53525,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/53235\/revisions\/53525"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=53235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=53235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=53235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}