{"id":56401,"date":"2013-07-15T14:02:33","date_gmt":"2013-07-15T12:02:33","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=56401"},"modified":"2013-07-15T14:02:33","modified_gmt":"2013-07-15T12:02:33","slug":"lactualite-de-demain-en-troikaland-la-crise-politique-bat-son-plein-par-francois-leclerc","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2013\/07\/15\/lactualite-de-demain-en-troikaland-la-crise-politique-bat-son-plein-par-francois-leclerc\/","title":{"rendered":"<i>L&rsquo;actualit\u00e9 de demain<\/i> : <b>EN TRO\u00cfKALAND, LA CRISE POLITIQUE BAT SON PLEIN<\/b>, par Fran\u00e7ois Leclerc"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9<\/p><\/blockquote>\n<p>La crise politique est d\u00e9sormais g\u00e9n\u00e9rale dans le <i>Tro\u00efkaland<\/i>, devenue un facteur aggravant de la dynamique de la crise europ\u00e9enne. Des gouvernements pr\u00e9caires de circonstance ne parviennent dans aucun de ces pays \u2013 Espagne, Gr\u00e8ce, Italie et Portugal &#8211; \u00e0 ma\u00eetriser la d\u00e9gradation de la situation \u00e9conomique et sociale qui se poursuit, ne se maintenant au pouvoir que par d\u00e9faut. <\/p>\n<p>Au Portugal, les deux partis de la coalition gouvernementale \u2013 le PSD et le CDS-PP \u2013 entament \u00e0 la demande du Pr\u00e9sident de la R\u00e9publique des n\u00e9gociations avec le PS en vue d\u2019adopter un accord improbable de \u00ab\u00a0salut national\u00a0\u00bb (en attendant un gouvernement du m\u00eame nom, tout aussi improbable). Mais les socialistes annoncent voter une motion de censure d\u00e9pos\u00e9e par les Verts et conditionnent tout accord \u00e0 la ren\u00e9gociation du <i>plan de sauvetage<\/i> de la Tro\u00efka \u2013 qu\u2019ils ont \u00e0 l\u2019\u00e9poque initi\u00e9 &#8211; afin d\u2019ent\u00e9riner des objectifs de r\u00e9duction de la dette prenant en compte la croissance \u00e9conomique. La crise politique est d\u00e9sormais permanente. <\/p>\n<p><!--more-->En Espagne, le PSOE demande la d\u00e9mission imm\u00e9diate de Mariano Rajoy, le premier ministre, les \u00e9l\u00e9ments \u00e0 charge s\u2019accumulant \u00e0 propos des enveloppes qu\u2019il aurait mensuellement re\u00e7ues avec d\u2019autres dirigeants du Partido Popular (PP). Derniers en date, des \u00e9changes de SMS du premier ministre avec l\u2019ancien tr\u00e9sorier du PP depuis sa prison, impliquant entre eux une n\u00e9gociation \u00e0 propos du silence de ce dernier, ce que Mariano Rajoy d\u00e9ment. \u00c9galement contre toute \u00e9vidence, mais sur un autre terrain, le ministre de l\u2019\u00e9conomie Luis de Guindos annonce que \u00ab la r\u00e9cession est pass\u00e9e, la question porte d\u00e9sormais sur la vigueur de la reprise \u00bb et que l\u2019Espagne ne songe plus \u00e0 demander des fonds. Les banques nationales n\u00e9gocient cependant la transformation de 30 milliards d\u2019euros d\u2019imp\u00f4ts diff\u00e9r\u00e9s en cr\u00e9dit d\u2019imp\u00f4t afin de renforcer leurs fonds propres, ce qui devrait peser d\u2019autant sur le d\u00e9ficit public&#8230;<\/p>\n<p>En Gr\u00e8ce, la coalition form\u00e9e par Nouvelle D\u00e9mocratie et le Pasok survit au d\u00e9part du petit parti de gauche Dimar et doit honorer ses nouveaux engagements vis-\u00e0-vis de la <i>Tro\u00efka<\/i>, afin de recevoir en partie une nouvelle tranche d\u2019aide financi\u00e8re \u00e9vitant de faire d\u00e9faut sur le remboursement d\u2019aides pr\u00e9c\u00e9dentes. Les deux partis sont condamn\u00e9s \u00e0 s\u2019entendre afin d\u2019\u00e9viter des \u00e9lections dont le r\u00e9sultat serait pour eux d\u00e9sastreux, Syriza talonnant de peu Nouvelle D\u00e9mocratie dans les sondages et devan\u00e7ant le Pasok. Le parlement est dans l\u2019imm\u00e9diat appel\u00e9 \u00e0 voter une loi portant sur la r\u00e9forme du secteur public, avec pour objectif de supprimer 4.000 emplois d\u2019ici la fin de l\u2019ann\u00e9e et d\u2019imposer des mutations, pouvant \u00eatre le pr\u00e9lude \u00e0 leur licenciement, \u00e0 12.500 fonctionnaires. On ne parle plus du programme de privatisation, qui connait \u00e9chec sur \u00e9chec&#8230; <\/p>\n<p>La coalition PD-PdL italienne dirig\u00e9e par Enrico Letta survit suspendue \u00e0 la d\u00e9cision de Silvio Berlusconi de la faire chuter quand il le jugera opportun, tandis que Beppe Grillo, le leader du Mouvement 5 \u00e9toiles, appelle le Pr\u00e9sident de la R\u00e9publique a convoquer de nouvelles \u00e9lections dans un climat politique d\u00e9liquescent. Standard &#038; Poor\u2019s vient de d\u00e9grader de BBB+ \u00e0 BBB la note de l\u2019Italie et le FMI pr\u00e9voit une r\u00e9cession de -1,8 % du PIB cette ann\u00e9e, ce qui n\u2019emp\u00eache pas Fabrizio Saccomanni, le ministre de l&rsquo;\u00e9conomie, d&rsquo;apercevoir \u00ab les premiers signes de la croissance \u00bb. Le FMI pr\u00e9f\u00e8re pour sa part voir \u00ab des signes de stabilisation mais de forts vents contraires [qui] continuent de freiner la reprise \u00bb. Enrico Letta man\u0153uvre en permanence entre les engagements de rigueur europ\u00e9ens et les exigences de baisse des imp\u00f4ts de Silvio Berlusconi, avec en fin d\u2019ann\u00e9e un trou budg\u00e9taire de 12 milliards d\u2019euros selon des sources gouvernementales cit\u00e9es par le quotidien \u00ab La Repubblica \u00bb.<\/p>\n<p>En Gr\u00e8ce et en Italie, la formation de coalitions bancales a \u00e9t\u00e9 une solution de derni\u00e8re extr\u00e9mit\u00e9 permettant de conserver un interlocuteur auquel imposer les recettes du d\u00e9sendettement, car il en faut un afin de respecter la souverainet\u00e9 et les r\u00e8gles de la d\u00e9mocratie repr\u00e9sentative ! Cela reste \u00e0 construire au Portugal, si cela ne se pose pas encore en Espagne, o\u00f9 toutefois le scandale touchant le PP ne peut plus \u00eatre contenu, les prochaines \u00e9lections n\u2019\u00e9tant pour l\u2019instant pr\u00e9vues qu\u2019en 2015 et le PSOE ne souhaitant pas qu\u2019elles soient anticip\u00e9es en raison du score que les instituts de sondage lui pr\u00e9disent. <\/p>\n<p>Trouver une majorit\u00e9 dans cette crise politique g\u00e9n\u00e9ralis\u00e9e semble partout n\u00e9cessiter le m\u00eame exp\u00e9dient, \u00e0 chaque fois au nom d\u2019un \u00ab salut national \u00bb qui n\u2019a de salut que le nom. Mais comment cette fiction pourra-t-elle tenir les dix ann\u00e9es qui sont annonc\u00e9es comme allant \u00eatre n\u00e9cessaires pour conclure le d\u00e9sendettement et ce qui l\u2019accompagne ?  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9 La crise politique est d\u00e9sormais g\u00e9n\u00e9rale dans le Tro\u00efkaland, devenue un facteur aggravant de la dynamique de la crise europ\u00e9enne. Des gouvernements pr\u00e9caires de circonstance ne parviennent dans aucun de ces pays \u2013 Espagne, Gr\u00e8ce, Italie et Portugal &#8211; \u00e0 ma\u00eetriser la d\u00e9gradation de la situation \u00e9conomique et sociale qui se poursuit, ne [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[204],"tags":[75,160,78,264,2800],"class_list":["post-56401","post","type-post","status-publish","format-standard","hentry","category-europe","tag-espagne","tag-grece","tag-italie","tag-portugal","tag-troikaland"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/56401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=56401"}],"version-history":[{"count":7,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/56401\/revisions"}],"predecessor-version":[{"id":56408,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/56401\/revisions\/56408"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=56401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=56401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=56401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}