{"id":58837,"date":"2013-10-04T13:52:23","date_gmt":"2013-10-04T11:52:23","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=58837"},"modified":"2013-10-04T14:23:48","modified_gmt":"2013-10-04T12:23:48","slug":"lactualite-de-demain-un-tres-gros-vilain-defaut-par-francois-leclerc","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2013\/10\/04\/lactualite-de-demain-un-tres-gros-vilain-defaut-par-francois-leclerc\/","title":{"rendered":"<i>L&rsquo;actualit\u00e9 de demain<\/i> : <b>UN TR\u00c8S GROS VILAIN D\u00c9FAUT<\/b>, par Fran\u00e7ois Leclerc"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9<\/p><\/blockquote>\n<p>Un d\u00e9faut sur la dette am\u00e9ricaine ? Vous n\u2019y pensez pas ! Il reste cependant treize jours pour que le Congr\u00e8s d\u00e9cide d\u2019\u00e9lever le plafond de la dette des \u00c9tats-Unis, faute de quoi ils devraient se trouver en situation de cessation de paiement. \u00c0 moins que de petites r\u00e9serves \u2013 dont l\u2019existence est ni\u00e9e par le secr\u00e9taire d\u2019\u00e9tat au Tr\u00e9sor \u2013 ne permettent de faire durer un tout petit peu le plaisir. <\/p>\n<p>Les d\u00e9clarations alarmistes pleuvent de partout, exprimant une inqui\u00e9tude montante au fur et \u00e0 mesure que l\u2019\u00e9ch\u00e9ance se rapproche, chacun ne pouvant s\u2019emp\u00eacher de penser qu\u2019un accord de derni\u00e8re minute interviendra, quand la tension sera au paroxysme et l\u2019obstacle devant le nez. Mais le doute s\u2019insinue : \u00ab et si le sc\u00e9nario des fois pr\u00e9c\u00e9dentes ne se r\u00e9p\u00e9tait pas ? \u00bb. Inutile d\u2019\u00e9piloguer \u00e0 ce sujet, m\u00eame si, <a href=\"http:\/\/www.pauljorion.com\/blog\/?p=58798\">comme le rappelle Paul Jorion<\/a>, la polarisation politique s\u2019accentue aux \u00c9tats-Unis, rendant les compromis de plus en plus difficiles. Renouant dans un contexte fort diff\u00e9rent avec le d\u00e9lire maccarthyste d\u2019hier, les libertariens font \u00e0 leur tour croisade contre le \u00ab socialisme \u00bb que repr\u00e9sente l\u2019assurance-sant\u00e9, et pensent le moment propice pour faire reculer Barack Obama sur sa r\u00e9forme.<\/p>\n<p><!--more-->Envisager les cons\u00e9quences d\u2019un d\u00e9faut n\u2019est pas superflu dans ces conditions. Sans omettre de le faire aussi si le plafond d\u2019une dette de 16.700 milliards de dollars devait \u00e0 nouveau \u00eatre rehauss\u00e9, en se demandant jusqu\u2019\u00e0 quel niveau \u2013 et avec quelle contribution de la Fed \u2013 il sera possible de continuer \u00e0 la financer. Les fuites en avant ne manquent pas, mais celle-ci est de taille, comme son bilan !<\/p>\n<p>L\u2019augmentation du taux de la dette cons\u00e9cutive \u00e0 l\u2019annonce que la banque centrale pourrait d\u00e9c\u00e9l\u00e9rer ses achats de titres a donn\u00e9 un avant-go\u00fbt de ce qui pourrait se passer en cas de d\u00e9faut. Une augmentation importante des taux serait difficilement supportable en raison de ses r\u00e9percussions sur le march\u00e9 obligataire mondial, augmentant les taux de la dette souveraine et des entreprises. Mais elle ne le serait pas davantage pour le syst\u00e8me financier dans son ensemble, et pour les banques en particulier. La dette am\u00e9ricaine est le pilier sur lequel le premier repose car ses titres sont jusqu\u2019\u00e0 maintenant r\u00e9put\u00e9s \u00e0 risque z\u00e9ro. Les secondes devraient enregistrer des pertes importantes, afin de prendre en compte la d\u00e9valorisation qui r\u00e9sulterait d\u2019une hausse des taux des bons du Tr\u00e9sor qu\u2019elles d\u00e9tiennent. Enfin, le dollar chuterait brutalement, faisant monter l\u2019euro et les autres monnaies dans un contexte o\u00f9 il reste la principale monnaie dans les \u00e9changes commerciaux internationaux, p\u00e9nalisant les exportations des pays dont la croissance en d\u00e9pend. <\/p>\n<p>La crise a d\u00e9but\u00e9 comme une crise de la dette, elle pourrait se poursuivre comme une crise des taux. C\u2019est une des raisons pour lesquelles Jens Weidmann, le patron de la Bundesbank, a soulign\u00e9, comme <a href=\"http:\/\/www.pauljorion.com\/blog\/?p=58775\" target=\"_blank\">l&rsquo;a expliqu\u00e9 ici Pierre Sarton du Jonchay<\/a>, le danger qu\u2019il y a \u00e0 ce que les banques centrales financent les achats de titres souverains des banques, en r\u00e9clamant que cela cesse (en s&rsquo;opposant aux op\u00e9rations du type LTRO). Ces titres n\u2019offrent plus les garanties d\u2019avant et sont au contraire susceptibles de pr\u00e9cipiter une nouvelle crise bancaire. On a \u00e9galement vu comment la demande de collat\u00e9ral de qualit\u00e9 grandissait sur <i>les march\u00e9s<\/i>, notant que la d\u00e9gradation de l&rsquo;offre en la mati\u00e8re ne pourrait qu\u2019accentuer la p\u00e9nurie redout\u00e9e. Mais si Jens Weidmann a raison de mettre en \u00e9vidence ce dangereux m\u00e9canisme, il n\u2019explique pas comment les \u00c9tats vont pouvoir continuer \u00e0 financer leur dette sans le soutien des banques centrales et des banques, sauf \u00e0 amplifier la politique de <i>d\u00e9valuation interne<\/i> qui est actuellement suivie, accompagn\u00e9e le cas \u00e9ch\u00e9ant par un <i>choc de l\u2019offre<\/i> se concr\u00e9tisant par des transferts financiers en faveur des entreprises et au d\u00e9triment des particuliers, polarisant les diff\u00e9renciations sociales. <\/p>\n<p>Le syst\u00e8me financier fait face \u00e0 une augmentation globale du risque, \u00e0 laquelle il contribue en contournant une r\u00e9gulation n\u2019allant pas au c\u0153ur des choses, tentant de limiter la baisse des rendements auquel il \u00e9tait accoutum\u00e9. Cela se traduit par une hausse des taux qui cr\u00e9e autant de probl\u00e8mes que leur bas niveau pr\u00e9c\u00e9dent en a g\u00e9n\u00e9r\u00e9s. C\u2019est en ce sens que la crise est mont\u00e9e d\u2019un cran et pourrait le faire de plusieurs d&rsquo;un coup si les \u00c9tats-Unis faisaient d\u2019aventure d\u00e9faut. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9 Un d\u00e9faut sur la dette am\u00e9ricaine ? Vous n\u2019y pensez pas ! Il reste cependant treize jours pour que le Congr\u00e8s d\u00e9cide d\u2019\u00e9lever le plafond de la dette des \u00c9tats-Unis, faute de quoi ils devraient se trouver en situation de cessation de paiement. \u00c0 moins que de petites r\u00e9serves \u2013 dont l\u2019existence est [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[2007,2253],"class_list":["post-58837","post","type-post","status-publish","format-standard","hentry","category-monde-financier","tag-jens-weidmann","tag-plafond-de-la-dette"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/58837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=58837"}],"version-history":[{"count":5,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/58837\/revisions"}],"predecessor-version":[{"id":58843,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/58837\/revisions\/58843"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=58837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=58837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=58837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}