{"id":59163,"date":"2013-10-19T16:16:44","date_gmt":"2013-10-19T14:16:44","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=59163"},"modified":"2013-10-20T15:50:11","modified_gmt":"2013-10-20T13:50:11","slug":"la-cote-dalerte-est-depassee-par-jean-pierre-page","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2013\/10\/19\/la-cote-dalerte-est-depassee-par-jean-pierre-page\/","title":{"rendered":"<b>LA COTE D&rsquo;ALERTE EST D\u00c9PASS\u00c9E<\/b>, par Jean-Pierre Pag\u00e9"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9.<\/p><\/blockquote>\n<p>Cela a retenti comme un coup de tonnerre !  un sondage concernant les \u00e9lections europ\u00e9ennes, le Front National devancerait l\u2019UMP et le Parti Socialiste arriverait en troisi\u00e8me position.<\/p>\n<p>Et ce ph\u00e9nom\u00e8ne n\u2019est pas sp\u00e9cifique \u00e0 la France. L\u2019hypoth\u00e8se selon laquelle le regroupement des partis \u00ab populistes \u00bb dans l\u2019Union europ\u00e9enne obtiendrait la majorit\u00e9 relative au Parlement europ\u00e9en l\u2019an prochain ne saurait \u00eatre \u00e9cart\u00e9e.<\/p>\n<p>Voil\u00e0 \u00e0 quoi ont men\u00e9 bient\u00f4t quatre ans de politiques suicidaires en Europe. Et ceci ne peut pas \u00eatre imput\u00e9 uniquement \u00e0 l\u2019aveuglement n\u00e9o-lib\u00e9ral des eurocrates de Bruxelles, mais r\u00e9sulte de la d\u00e9cision des chefs d\u2019Etats et de Gouvernements r\u00e9unis en Conseil.<\/p>\n<p><!--more-->Comment, en effet, s\u2019\u00e9tonner de ce que quatre ans de politiques d\u2019aust\u00e9rit\u00e9, qui n\u2019ont laiss\u00e9 aucun espoir aux populations, aient r\u00e9ussi \u00e0 tuer l\u2019id\u00e9e noble et g\u00e9n\u00e9reuse de l\u2019Europe !<\/p>\n<p>N\u2019est-il pas surr\u00e9aliste et impudent d\u2019entendre les dirigeants de la Gr\u00e8ce se f\u00e9liciter de ce qu\u2019ils peuvent envisager une \u00ab reprise de la croissance \u00bb de 0,6% en 2014, apr\u00e8s que le PIB de leur pays ait chut\u00e9 de plus de 25% depuis le d\u00e9but de la crise, et que le taux de ch\u00f4mage des jeunes ait atteint le chiffre record de 50% ! Et l\u2019on pourrait citer d\u2019autres exemples de cet acabit en Espagne et au Portugal. Non seulement, \u00ab la crise n\u2019est pas finie \u00bb et l\u2019Europe n\u2019est pas r\u00e9ellement assainie comme on voudrait nous le faire croire et comme en t\u00e9moignent les niveaux toujours tr\u00e8s \u00e9lev\u00e9s de la dette, mais elle sort de cette \u00ab cure \u00bb an\u00e9mi\u00e9e et aigrie, en quelque sorte \u00ab rapetiss\u00e9e \u00bb dans son essence. Dans ces conditions, il n\u2019est pas \u00e9tonnant qu\u2019elle ne suscite aucun enthousiasme de la part de ses citoyens (en particulier des plus jeunes) et soit, au contraire, l\u2019objet d\u2019un rejet de plus en plus g\u00e9n\u00e9ralis\u00e9. Ses dirigeants portent une lourde responsabilit\u00e9 \u00e0 cet \u00e9gard, eux qui ont pr\u00e9f\u00e9r\u00e9 les palliatifs et les recettes \u00e0 courte vue, les \u00ab petits pas \u00bb, quand il ne s\u2019est pas agi de reculs (cf : le budget europ\u00e9en), au lieu  d\u2019affronter franchement les d\u00e9fis de la construction europ\u00e9enne.<br \/>\nCeci nous rapproche f\u00e2cheusement de la politique de la \u00ab table rase \u00bb, mise en \u00e9vidence par Naomi Klein, visant \u00e0 remplacer les services et entreprises publiques, quasi d\u00e9truites, par des entreprises priv\u00e9es, qui a eu son heure de gloire lors du passage des pays de l\u2019Europe de l\u2019Est \u00e0 l\u2019\u00e9conomie de march\u00e9.<\/p>\n<p>Il est temps de sonner le tocsin. Le d\u00e9mant\u00e8lement de la zone euro et, au-del\u00e0, le retour aux vieux clivages nationalistes en Europe sont \u00e0 nos portes.<\/p>\n<p>Il est plus que temps de r\u00e9agir en changeant de politique \u00e9conomique et sociale en donnant une nouvelle et vigoureuse impulsion \u00e0 la construction d\u2019une Europe r\u00e9ellement unie (et non la parodie que l\u2019on nous en pr\u00e9sente), gr\u00e2ce \u00e0 une d\u00e9marche hardie fond\u00e9e sur la r\u00e9novation des infrastructures, des innovations, une transition \u00e9nerg\u00e9tique justifiant les investissements porteurs du renouveau futur de l\u2019activit\u00e9 \u00e9conomique et la cr\u00e9ation des institutions le permettant.<\/p>\n<p>Mais, en premier lieu et d\u00e8s maintenant, il appartient aux gouvernants des pays de l\u2019Union de mobiliser par leur parole les citoyens de ces pays en leur montrant ce que peut leur apporter une union bien pens\u00e9e et bien construite, au lieu de s\u2019en remettre \u00e0 des propos nationalo-centr\u00e9s. Il leur appartient de le faire avant les \u00e9lections europ\u00e9ennes, faute de quoi celles-ci risquent de conduire \u00e0 un Parlement europ\u00e9en incapable de jouer le r\u00f4le novateur que l\u2019on attend de lui ou, pire, ferment de d\u00e9liquescence de l\u2019Europe. Adieu alors le r\u00eave de voir ce Parlement \u00e9lire un Pr\u00e9sident de l\u2019Europe capable de conduire celle-ci et prenant la mesure des enjeux ! Et ceci vaut d\u2019abord pour notre pays o\u00f9 tout est fait pour \u00e9viter un d\u00e9bat public sur l\u2019Europe de crainte qu\u2019il ne r\u00e9veille les vieux d\u00e9mons de la campagne pour la ratification du Trait\u00e9 Constitutionnel.<\/p>\n<p>La cote d\u2019alerte est d\u00e9pass\u00e9e. Le risque est grand de voir l\u2019Europe redevenir une \u00ab mosa\u00efque \u00bb de petits Etats \u00e0 l\u2019\u00e9chelle de la mondialisation, une \u00ab grande Suisse \u00bb, comme l\u2019a dit Hubert V\u00e9drine. Ce qui plairait sans doute \u00e0 beaucoup de ses citoyens, mais signerait son arr\u00eat de mort, au milieu des empires qui se constituent ailleurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. Cela a retenti comme un coup de tonnerre ! un sondage concernant les \u00e9lections europ\u00e9ennes, le Front National devancerait l\u2019UMP et le Parti Socialiste arriverait en troisi\u00e8me position. Et ce ph\u00e9nom\u00e8ne n\u2019est pas sp\u00e9cifique \u00e0 la France. L\u2019hypoth\u00e8se selon laquelle le regroupement des partis \u00ab populistes \u00bb dans l\u2019Union europ\u00e9enne obtiendrait la majorit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,204],"tags":[553,311,243],"class_list":["post-59163","post","type-post","status-publish","format-standard","hentry","category-economie","category-europe","tag-austerite","tag-france","tag-zone-euro"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/59163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=59163"}],"version-history":[{"count":3,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/59163\/revisions"}],"predecessor-version":[{"id":59165,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/59163\/revisions\/59165"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=59163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=59163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=59163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}