{"id":6998,"date":"2010-01-21T22:32:43","date_gmt":"2010-01-21T21:32:43","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=6998"},"modified":"2010-01-22T10:44:14","modified_gmt":"2010-01-22T09:44:14","slug":"%c2%ab-va-y-avoir-de-la-bagarre-%c2%bb","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2010\/01\/21\/%c2%ab-va-y-avoir-de-la-bagarre-%c2%bb\/","title":{"rendered":"\u00ab Va y avoir de la bagarre ! \u00bb"},"content":{"rendered":"<blockquote><p><strong>Ce texte est un \u00ab article presslib\u2019 \u00bb (*) <\/strong><\/p><\/blockquote>\n<p>Donc ce matin dans <a href=\"http:\/\/www.pauljorion.com\/blog\/?p=6989\">\u00ab Pour qui sonne le glas \u00bb<\/a> j\u2019expliquais qu\u2019Obama disposait au d\u00e9but de son mandat d\u2019une super-majorit\u00e9 pour mettre au pas Wall Street et qu\u2019au lieu d\u2019en tirer parti, il avait tergivers\u00e9, entour\u00e9 de conseillers et de ministres copains comme cochon avec la finance, et que \u2013 comme il \u00e9tait hautement pr\u00e9visible du coup \u2013 l\u2019opinion se retournait maintenant contre lui. <\/p>\n<p>Il a entendu le message (pas le mien mais celui de la rue dont je synth\u00e9tisais le sentiment) et on apprenait donc cet apr\u00e8s-midi qu\u2019il passait enfin aux actes avec l\u2019intention de faire rentrer Wall Street dans le rang : r\u00e9tablissement (\u00e0 peu de choses pr\u00e8s) du Glass-Steagall Act  qui s\u00e9pare l\u2019activit\u00e9 d\u2019interm\u00e9diation des banques (mettre en contact ceux qui peuvent pr\u00eater et ceux qui veulent emprunter) des \u00ab op\u00e9rations sur fonds propres \u00bb (sp\u00e9culation des salles de march\u00e9 et investissement dans les fonds d\u2019investissement sp\u00e9culatifs), d\u00e9mant\u00e8lement des \u00e9tablissements financiers Trop Gros pour Faire D\u00e9faut, etc. On passait enfin aux choses s\u00e9rieuses !<\/p>\n<p>Je me souviens d\u2019un Laurel et Hardy vu \u00e9tant gosse o\u00f9 Hardy se disputait avec un voisin de palier au sommet d\u2019un immeuble, les deux bellig\u00e9rants d\u00e9cidaient d\u2019aller r\u00e9gler l\u2019affaire sur le trottoir et, pendant qu\u2019ils descendaient des \u00e9tages, Laurel frappait aux portes \u00e0 chaque palier pour alerter les locataires : \u00ab Va y avoir de la bagarre ! \u00bb Arriv\u00e9s en bas, le combat tournait court : le voisin irascible allongeait Hardy d\u2019un direct bien ass\u00e9n\u00e9. <\/p>\n<p>Si je vous raconte \u00e7a, c\u2019est que c\u2019est exactement ce qui s\u2019est pass\u00e9 aujourd\u2019hui : Obama avait \u00e0 peine dirig\u00e9 son coup du droit, qu\u2019un uppercut \u00e0 la m\u00e2choire le mettait K.O.<\/p>\n<p>Dans ma petite discussion avec Jean-Claude Casanova le mois dernier sur <a href=\"http:\/\/www.pauljorion.com\/blog\/?p=6023\">France Culture<\/a>, au moment o\u00f9 il m\u2019objectait que le New Deal rooseveltien avait capot\u00e9 en 1937, je lui avais demand\u00e9 s\u2019il avait entendu parler de l\u2019action de sape men\u00e9e \u00e0 l\u2019\u00e9poque par la Chambre de Commerce am\u00e9ricaine (j\u2019\u00e9voquais une \u00ab Chambre de Commerce\u2026 toujours aussi nuisible qu\u2019elle l\u2019\u00e9tait autrefois\u2026 \u00bb), et par la Cour Supr\u00eame (\u00ab Une Cour Supr\u00eame d\u2019extr\u00eame-droite comme elles le sont toujours aux Etats-Unis\u2026 \u00bb).<\/p>\n<p>Encore une fois, il ne s\u2019agit pas d\u2019une digression : on apprenait aujourd\u2019hui que la Cour Supr\u00eame avait lev\u00e9 toute restriction quant au montant des contributions financi\u00e8res que peuvent apporter les personnes morales (soci\u00e9t\u00e9s et organisations) aux campagnes \u00e9lectorales (invalidant une r\u00e9glementation qui avait \u00e9t\u00e9 introduite par \u2013 devinez qui ? John McCain !) et ceci au nom du Premier Amendement \u00e0 la constitution qui prot\u00e8ge le droit d\u2019expression (sic). <\/p>\n<p>Obama se rebelle contre ses \u00ab protecteurs \u00bb de Wall Street et leur r\u00e9ponse ne se fait pas attendre : \u00ab Tiens, prends \u00e7a dans les gencives ! T\u2019es pas pr\u00e8s de te relever ! \u00bb<\/p>\n<p>Et la Chambre de Commerce dans tout \u00e7a ? Elle a fait savoir par la voix de son porte-parole, Robin Conrad, que \u00ab La d\u00e9cision prise aujourd\u2019hui prot\u00e8ge le droit au Premier Amendement des organisations appartenant \u00e0 l\u2019ensemble de l\u2019\u00e9ventail politique et constitue une \u00e9volution positive pour le processus politique et la libert\u00e9 d\u2019entreprendre \u00bb. Quand je vous disais.        <\/p>\n<blockquote><p><strong>(*) Un \u00ab article presslib\u2019 \u00bb est libre de reproduction en tout ou en partie \u00e0 condition que le pr\u00e9sent alin\u00e9a soit reproduit \u00e0 sa suite. Paul Jorion est un \u00ab journaliste presslib\u2019 \u00bb qui vit exclusivement de ses droits d\u2019auteurs et de vos contributions. Il pourra continuer d\u2019\u00e9crire comme il le fait aujourd\u2019hui tant que vous l\u2019y aiderez. Votre soutien peut s\u2019exprimer <a href=\"http:\/\/www.pauljorion.com\/blog\/?page_id=647\">ici<\/a>.<\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Ce texte est un \u00ab article presslib\u2019 \u00bb (*) Donc ce matin dans \u00ab Pour qui sonne le glas \u00bb j\u2019expliquais qu\u2019Obama disposait au d\u00e9but de son mandat d\u2019une super-majorit\u00e9 pour mettre au pas Wall Street et qu\u2019au lieu d\u2019en tirer parti, il avait tergivers\u00e9, entour\u00e9 de conseillers et de ministres copains comme cochon avec [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,18,17],"tags":[98,279,278,99,100],"class_list":["post-6998","post","type-post","status-publish","format-standard","hentry","category-economie","category-monde-financier","category-politique","tag-barack-obama","tag-chamber-of-commerce","tag-cour-supreme","tag-john-mccain","tag-wall-street"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/6998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=6998"}],"version-history":[{"count":6,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/6998\/revisions"}],"predecessor-version":[{"id":7049,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/6998\/revisions\/7049"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=6998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=6998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=6998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}