{"id":70735,"date":"2014-11-10T11:42:53","date_gmt":"2014-11-10T10:42:53","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=70735"},"modified":"2014-11-10T11:51:10","modified_gmt":"2014-11-10T10:51:10","slug":"productivite-competitivite-emploi-et-etat-social-i-par-michel-leis","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2014\/11\/10\/productivite-competitivite-emploi-et-etat-social-i-par-michel-leis\/","title":{"rendered":"<b>Productivit\u00e9, comp\u00e9titivit\u00e9, emploi et \u00c9tat social (I)<\/b>, par Michel Leis"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9<\/p><\/blockquote>\n<p>Les discours officiels justifient l\u2019\u00e9rosion progressive de l\u2019\u00c9tat social par la contrainte que font peser les d\u00e9ficits budg\u00e9taires. Dans le m\u00eame temps, ils font de la comp\u00e9titivit\u00e9 des entreprises le credo et le seul horizon de la politique \u00e9conomique. Ces deux aspects d\u2019un discours gestionnaire et dogmatique qui est devenu la norme politique d\u2019aujourd\u2019hui ne sont pas aussi ind\u00e9pendants qu\u2019il n\u2019y para\u00eet au premier abord. Le monde \u00e9conomique proclame \u00e0 longueur de journ\u00e9e qu\u2019il est impossible d\u2019augmenter les imp\u00f4ts au nom d\u2019une comp\u00e9titivit\u00e9 insuffisante. Pour seul substitut, l\u2019\u00c9tat r\u00eave du retour de la croissance, potion miracle qui permettrait \u00e0 la fois d\u2019augmenter les recettes fiscales et l\u2019emploi. Illusion dangereuse qui ignore les \u00e9volutions longues de la productivit\u00e9 et de l\u2019emploi. Pour autant, il faut regarder la situation actuelle dans toute sa complexit\u00e9 et ce long billet est en partie une r\u00e9ponse et un compl\u00e9ment \u00e0 deux billets d\u00e9j\u00e0 anciens de Z\u00e9bu (<a href=\"http:\/\/www.pauljorion.com\/blog\/2014\/10\/27\/la-robotisation-stade-ultime-du-capitalisme-par-zebu\/\">27 octobre<\/a> et <a href=\"http:\/\/www.pauljorion.com\/blog\/2014\/10\/30\/le-capitalisme-un-bref-resume-par-zebu\/\">30 octobre<\/a>) sur la productivit\u00e9 et la robotisation.<\/p>\n<p>Je voudrais montrer dans cette s\u00e9rie de billets l\u2019impossibilit\u00e9 de concilier dans le contexte qui est le n\u00f4tre deux types d\u2019action politique. D\u2019un c\u00f4t\u00e9, celle qui serait d\u00e9di\u00e9e aux \u00ab\u00a0imp\u00e9ratifs\u00a0\u00bb de productivit\u00e9 et comp\u00e9titivit\u00e9, au nom des bienfaits suppos\u00e9s d\u2019une \u00e9conomie florissante, leitmotiv du gouvernement et des organisations patronales. De l\u2019autre, une politique qui affirme vouloir d\u00e9fendre la solidarit\u00e9 nationale, les sacrifices consentis ne le seraient que pour pr\u00e9server l\u2019essentiel, autrement dit, se couper le petit doigt plut\u00f4t qu\u2019\u00eatre victime de la gangr\u00e8ne qui semble pourtant in\u00e9vitable. Depuis plusieurs ann\u00e9es, les compromis qui sont pr\u00e9sent\u00e9s par le pouvoir politique refl\u00e8tent au mieux une absence de choix, au pire un cynisme sans limites.<\/p>\n<p><!--more-->Dans le contexte actuel des rapports de forces, c\u2019est une illusion d\u2019imaginer que l\u2019on peut se passer de choix radicaux, les citoyens en ont parfaitement conscience. C\u2019est ce qui profite entre autres \u00e0 certains partis populistes de droite, l\u2019habilit\u00e9 tactique consiste \u00e0 pr\u00e9senter pour ces partis une radicalit\u00e9 qui ne s\u2019adresse qu\u2019\u00e0 l\u2019autre. Pour autant, la strat\u00e9gie du bouc \u00e9missaire comme celle du compromis ont leurs limites puisqu\u2019elles ne s\u2019adressent jamais au fond du probl\u00e8me. Il faut rappeler les concepts fondamentaux qui sont au c\u0153ur du d\u00e9bat pour comprendre cette incompatibilit\u00e9 croissante et \u00e9clairer les alternatives politiques.<\/p>\n<p><strong>Productivit\u00e9<\/strong><\/p>\n<p>La productivit\u00e9 est l\u2019une des notions dont on parle le plus, sans jamais s\u2019interroger sur sa mesure. La productivit\u00e9 est un ratio d\u2019efficacit\u00e9 qui est cens\u00e9 \u00e9valuer la contribution d\u2019un facteur (le travail ou le capital) \u00e0 la production de l\u2019entreprise. S\u2019agissant d\u2019efficacit\u00e9, elle devrait se mesurer dans un rapport purement mat\u00e9riel, par exemple entre le nombre d\u2019unit\u00e9s produites et le nombre d\u2019employ\u00e9s, de machines, ou la quantit\u00e9 d\u2019heures travaill\u00e9es. Une telle mesure ne permet malheureusement aucune comparaison entre secteurs d\u2019activit\u00e9. M\u00eame entre entreprises produisant des biens similaires, la comparaison reste malais\u00e9e, tant la quantit\u00e9 totale de travail (de l\u2019homme ou de la machine) incorpor\u00e9e dans le bien produit peut varier d\u2019un objet \u00e0 l\u2019autre et entre les usines. Mesurer l\u2019efficacit\u00e9 d\u2019une machine ne dit rien non plus de son co\u00fbt\u00a0: une machine extraordinairement efficace qui co\u00fbterait des millions d\u2019Euros pour produire des biens tr\u00e8s bon march\u00e9 et \u00e0 faible marge unitaire n\u2019a pas grand sens du point de vue de la gestion des entreprises. La productivit\u00e9 ne peut donc pas \u00eatre consid\u00e9r\u00e9e comme l\u2019alpha et l\u2019om\u00e9ga du processus de production, ce point sera discut\u00e9 plus en d\u00e9tail dans la partie consacr\u00e9e \u00e0 la comp\u00e9titivit\u00e9.<\/p>\n<p>Pour obtenir des mesures comparables, la mesure de la productivit\u00e9 du travail<a href=\"#_edn1\" name=\"_ednref\">[i]<\/a> m\u00e9lange donc des choux et des carottes en rapportant la valeur ajout\u00e9e (une valeur mon\u00e9taire) \u00e0 la quantit\u00e9 d\u2019heures travaill\u00e9es qui mesure une donn\u00e9e \u00ab\u00a0physique\u00a0\u00bb. La productivit\u00e9 du capital est quant \u00e0 elle plus coh\u00e9rente, elle consiste \u00e0 rapporter la valeur ajout\u00e9e produite au volume de capital utilis\u00e9, les deux \u00e9tant mesur\u00e9s par une valeur mon\u00e9taire. Pourtant, dans le monde r\u00e9el, \u00e0 partir du moment o\u00f9 interviennent des prix (de vente, d\u2019achat) et la monnaie, un certain nombre de rapports de forces sont \u00e0 l\u2019\u0153uvre qui biaisent la mesure, j\u2019y reviendrai ult\u00e9rieurement.<\/p>\n<p>Si l\u2019on prend par exemple la valeur ajout\u00e9e, celle-ci est en premi\u00e8re approximation la mesure mon\u00e9taire d\u2019un surplus, celui qui serait g\u00e9n\u00e9r\u00e9 par l\u2019incorporation du travail de l\u2019homme et de la machine<a href=\"#_edn2\" name=\"_ednref\">[ii]<\/a> aux biens ou prestations achet\u00e9s pour produire un bien ou offrir un service. Il faut entendre ici le terme \u00ab\u00a0d\u2019incorporation\u00a0\u00bb au sens large. Il repr\u00e9sente non seulement un pur travail de production et de transformation, mais aussi un travail logistique et commercial, par exemple celui qui consiste \u00e0 apporter le produit dans un point de vente \u00e0 proximit\u00e9 du consommateur, et \u00e0 r\u00e9aliser la vente. De m\u00eame on peut mesurer comptablement une valeur ajout\u00e9e dans le travail d\u2019interm\u00e9diation bancaire\u00a0r\u00e9alis\u00e9 par les machines ou les traders: emprunter aupr\u00e8s d\u2019une banque centrale ou d\u2019autres \u00e9tablissements financiers \u00e0 un certain taux d\u2019int\u00e9r\u00eat et \u00e0 vendre des cr\u00e9dits \u00e0 un taux sup\u00e9rieur.<\/p>\n<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-011.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-70736\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-011.png\" alt=\"Michel 01\" width=\"716\" height=\"94\" \/><\/a><\/p>\n<p>Si la mesure de la productivit\u00e9 du travail en partant de la Valeur ajout\u00e9e a un sens, c\u2019est celui de la qu\u00eate du profit. Une partie de la Valeur ajout\u00e9e sert \u00e0 r\u00e9mun\u00e9rer d\u2019un c\u00f4t\u00e9 le travail des hommes sous forme de salaire et de l\u2019autre les avances en capital sous toutes leurs formes (cr\u00e9dit, actions), la productivit\u00e9 est donc un enjeu majeur. Plus un processus de production est efficace, c\u2019est-\u00e0-dire moins il n\u00e9cessite de travail humain, et plus il reste une fraction importante pour r\u00e9mun\u00e9rer le capital. Encore faut-il que les produits et les services offerts trouvent preneurs. La recherche des gains de productivit\u00e9 est donc un des plus puissants moteurs de l\u2019\u00e9conomie capitaliste depuis ses origines. Je voudrais rappeler dans ce premier billet les diff\u00e9rentes strat\u00e9gies \u00e0 l\u2019\u0153uvre pour obtenir un tel r\u00e9sultat.<\/p>\n<p>La combinaison initiale entre capital et travail donne un certain niveau de productivit\u00e9, elle refl\u00e8te en g\u00e9n\u00e9ral l\u2019\u00e9tat de la technique au moment o\u00f9 l\u2019outil de production est mis en \u0153uvre ainsi que les standards de la profession. Pourtant cette combinaison n\u2019est id\u00e9ale que le jour o\u00f9 la production d\u00e9marre (ou le service est lanc\u00e9). Il est probable que les outils mis en \u0153uvre quelques mois plus tard seront plus efficaces, car les standards \u00e9voluent constamment.<\/p>\n<p>On peut illustrer cette id\u00e9e par quelques chiffres th\u00e9oriques dont les variations nous permettront de comprendre comment des actions portant sur l\u2019organisation, l\u2019automatisation ou la relation avec les clients ou les fournisseurs permettent d\u2019obtenir des gains de productivit\u00e9.<\/p>\n<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-021.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-70737\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-021.png\" alt=\"Michel 02\" width=\"700\" height=\"60\" \/><\/a><\/p>\n<p><em>La Valeur ajout\u00e9e est la diff\u00e9rence entre le chiffre d\u2019affaires et les consommations interm\u00e9diaires (y compris les variations de stock) et achats externes, ici, 100\u00a0000 et 40\u00a0000<\/em><\/p>\n<p>Je vais me focaliser dans la suite de ce billet sur la productivit\u00e9 horaire apparente. Quatre strat\u00e9gies de base permettent d\u2019obtenir des gains de productivit\u00e9.<\/p>\n<p>La strat\u00e9gie historique du capitalisme en mati\u00e8re de gains de productivit\u00e9, c\u2019est la division du travail en t\u00e2ches \u00e9l\u00e9mentaires, c\u2019est celle qui fonde entre autres le passage de l\u2019artisanat \u00e0 l\u2019industrie. C\u2019est une approche bien ant\u00e9rieure aux \u00e9crits de Charles Taylor. On trouve ainsi des processus de production sp\u00e9cialis\u00e9e d\u00e8s l\u2019antiquit\u00e9 en Chine<a href=\"#_edn3\" name=\"_ednref\">[iii]<\/a>. Le Taylorisme et le Fordisme sont en r\u00e9alit\u00e9 une \u00ab\u00a0mise \u00e0 plat\u00a0\u00bb au sens propre du terme de cette sp\u00e9cialisation des t\u00e2ches. Celles-ci sont juxtapos\u00e9es dans un encha\u00eenement logique, dont l\u2019aboutissement industriel est la cha\u00eene de production qui combine la parcellisation du travail et la minimisation de la logistique interne. Une telle division existe aussi dans la bureaucratie. Plus on d\u00e9compose la fabrication d\u2019un objet ou la cr\u00e9ation d\u2019un service en processus \u00e9l\u00e9mentaire, moins il y a de temps pass\u00e9 sur chacun des processus. On peut essayer d\u2019acc\u00e9l\u00e9rer la cadence, mais on bute alors sur des limites de faisabilit\u00e9 pour chaque op\u00e9ration \u00e9l\u00e9mentaire qui n\u00e9cessite une quantit\u00e9 de temps incompressible. Outre l\u2019automatisation sur laquelle je reviendrais, une d\u00e9composition encore plus fine du travail permet d\u2019obtenir un tel r\u00e9sultat, ce qui revient \u00e0 ajouter des postes de production sur la cha\u00eene de montage pour pouvoir r\u00e9duire le temps pass\u00e9 sur chaque poste de travail. Cette d\u00e9composition a toutefois des limites d\u00e8s qu\u2019il est n\u00e9cessaire d\u2019introduire une certaine flexibilit\u00e9 sur les cha\u00eenes de production. Une d\u00e9composition trop fine devient alors contre-productive, car certaines t\u00e2ches ne sont pas effectu\u00e9es syst\u00e9matiquement, ce qui pourrait conduire \u00e0 des personnes ou des machines partiellement inoccup\u00e9es dans le processus. Il faut noter que du point de vue industriel, l\u2019op\u00e9ration est r\u00e9versible, la r\u00e9duction du volume s\u2019accompagne de la r\u00e9duction du nombre de postes sur la cha\u00eene, car les cadences varient dans des fourchettes \u00e9troites, une d\u00e9gradation de la productivit\u00e9 est synonyme d\u2019une r\u00e9mun\u00e9ration moindre des avances en capital.<\/p>\n<p>C\u2019est la logique \u00ab\u00a0des temps modernes\u00a0\u00bb de Charlie Chaplin, celle qui pr\u00e9side aux processus de production qui repr\u00e9sente un certain volume. Par rapport \u00e0 notre exemple initial on peut repr\u00e9senter la variation de productivit\u00e9 obtenue en suivant ce type de strat\u00e9gie comme suit\u00a0:<\/p>\n<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-031.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-70738\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-031.png\" alt=\"Michel 03\" width=\"700\" height=\"64\" \/><\/a><\/p>\n<p>Le gain de productivit\u00e9 r\u00e9sulte de l\u2019augmentation de la quantit\u00e9 produite sans changement du nombre d\u2019heures travaill\u00e9es (cela pourrait \u00eatre une m\u00eame quantit\u00e9 produite en utilisant moins de travail), les consommations interm\u00e9diaires et achats externes augmentent en simple proportion du nombre d\u2019unit\u00e9s produites.<\/p>\n<p>La deuxi\u00e8me strat\u00e9gie possible consiste \u00e0 substituer le facteur capital, r\u00e9put\u00e9 plus efficace, au facteur travail. En r\u00e9alit\u00e9, cette possibilit\u00e9 de substitution est largement d\u00e9pendante de l\u2019\u00e9tat de la technique et de la division du travail qui est une condition pr\u00e9alable \u00e0 remplir pour pouvoir automatiser les t\u00e2ches. C\u2019est l\u2019autre vision classique que nous avons \u00e0 l\u2019esprit des gains de productivit\u00e9. Pourtant, l\u2019arbitrage entre robots et ouvriers dans un processus de production est un exercice d\u00e9licat. Dans certains domaines, en particulier ceux qui impliquent la manipulation et la transformation de pi\u00e8ces lourdes, le robot est infiniment sup\u00e9rieur \u00e0 l\u2019homme. Cependant, malgr\u00e9 l\u2019augmentation de performance exponentielle des logiciels, il existe un certain nombre de limites physique \u00e0 l\u2019automatisation des t\u00e2ches dans le domaine industriel. La robotique n\u2019est pas seulement une question de software, mais aussi une question de physique et de m\u00e9canique. Un processus complexe ou pas suffisamment d\u00e9compos\u00e9 en processus \u00e9l\u00e9mentaires est extr\u00eamement on\u00e9reux \u00e0 mettre en \u0153uvre, le prix des robots croit exponentiellement avec le nombre d\u2019axes de rotation mis en \u0153uvre pour r\u00e9aliser un processus. Le degr\u00e9 de pr\u00e9cision des v\u00e9rins, des roulements et des moteurs n\u00e9cessaires gr\u00e8vent les co\u00fbts de production de telles machines. Mais si l\u2019on s\u2019oriente vers une d\u00e9composition de la production en processus plus \u00e9l\u00e9mentaire, celle-ci a un impact sur l\u2019organisation enti\u00e8re de la cha\u00eene de montage, en particulier sur la flexibilit\u00e9 requise sur les cha\u00eenes. Du point de vue de la gestion d\u2019entreprise, le transfert vers du capital fixe n\u2019offre pas non plus la m\u00eame flexibilit\u00e9 en cas de variation de l\u2019output, c\u2019est donc une d\u00e9cision qui doit montrer un b\u00e9n\u00e9fice tangible. La machine doit pouvoir remplacer un certain nombre d\u2019ouvriers pour justifier sa place, les cadences restent gouvern\u00e9es par le point le plus lent de la cha\u00eene, sauf quand l\u2019ensemble du processus peut \u00eatre automatis\u00e9. En mati\u00e8re de service, de traitement de l\u2019information ou d\u2019assistance \u00e0 la d\u00e9cision, la part de manipulation physique est souvent r\u00e9duite \u00e0 la portion congrue, ce qui permet une automatisation plus facile. Des \u00e9tapes interm\u00e9diaires ou des m\u00e9tiers ont ainsi totalement disparu, car devenu inutile\u00a0: c\u2019est le cas des st\u00e9nos dactylos, mais aussi des m\u00e9caniciens navigants dans les avions.<\/p>\n<p>Pour revenir \u00e0 l\u2019exemple initial, la variation de productivit\u00e9 obtenue dans ce cas se pr\u00e9sente comme suit\u00a0:<\/p>\n<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-04.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-70739\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-04.png\" alt=\"Michel 04\" width=\"700\" height=\"61\" \/><\/a><\/p>\n<p>Le gain de productivit\u00e9 r\u00e9sulte ici de la diminution de la quantit\u00e9 d\u2019heures travaill\u00e9es pour produire une m\u00eame quantit\u00e9 de biens, toutes les autres valeurs restent identiques. Ce peut \u00eatre aussi une augmentation de l\u2019output avec la m\u00eame quantit\u00e9 de travail, comme dans le cas pr\u00e9c\u00e9dent. Cet exemple th\u00e9orique illustre bien la puissance des gains de productivit\u00e9 que l\u2019on peut obtenir par l\u2019automatisation, les limites en ce domaine r\u00e9sident bien dans le rapport entre le co\u00fbt de l\u2019investissement et sa valeur ajout\u00e9e. Dans le monde r\u00e9el, ces deux premi\u00e8res strat\u00e9gies, division du travail et automatisation, sont \u00e9videmment utilis\u00e9es conjointement.<\/p>\n<p>La troisi\u00e8me strat\u00e9gie est celle de l\u2019externalisation. Il s\u2019agit de sous-traiter une part de l\u2019activit\u00e9 qui n\u2019est pas \u00ab\u00a0core business\u00a0\u00bb \u00e0 une entreprise pour qui c\u2019est le c\u0153ur de m\u00e9tier. Dans les comptes nationaux, cela ne devrait repr\u00e9senter qu\u2019un gain de productivit\u00e9 minime, s\u2019agissant de l\u2019ex\u00e9cution d\u2019un m\u00eame travail par une autre soci\u00e9t\u00e9. Pourtant, il n\u2019en est rien pour plusieurs raisons. Ce qui n\u2019est qu\u2019une activit\u00e9 accessoire pour la soci\u00e9t\u00e9 donneuse d\u2019ordre peut constituer l\u2019activit\u00e9 centrale pour l\u2019entreprise sous-traitante. Celle-ci peut se r\u00e9v\u00e9ler beaucoup plus efficace en la mati\u00e8re, surtout si elle a plusieurs clients pour des produits similaires, ce qui lui permet d\u2019allonger les s\u00e9ries et d\u2019optimiser la division du travail et l\u2019automatisation. C\u2019est ce diff\u00e9rentiel de productivit\u00e9 qui se retrouve en tant que gain dans les comptes nationaux. Ensuite, cette t\u00e2che peut \u00eatre r\u00e9alis\u00e9e \u00e0 l\u2019\u00e9tranger dans des r\u00e9gions o\u00f9 la main d\u2019\u0153uvre est meilleur march\u00e9. Le b\u00e9n\u00e9fice est double\u00a0: l\u2019augmentation du poste achat est moindre, ce qui pr\u00e9serva plus de Valeur ajout\u00e9e alors que le m\u00e9canisme des prix de transfert et les facturations par l\u2019interm\u00e9diaire de filiales offshore facilitent l\u2019\u00e9vasion fiscale.<\/p>\n<p>Cette strat\u00e9gie se retranscrit comme suit par rapport \u00e0 notre exemple initial\u00a0:<\/p>\n<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-05.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-70740\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-05.png\" alt=\"Michel 05\" width=\"700\" height=\"61\" \/><\/a><\/p>\n<p>Le montant des achats externes augmente puisque ce qui n\u2019est pas produit sur place devient un achat, ce qui entra\u00eene la diminution de la valeur ajout\u00e9e, mais si le nombre d\u2019heures travaill\u00e9es diminue plus que proportionnellement, on obtient un gain de productivit\u00e9. Bien \u00e9videmment, si les rapports de forces ou la production \u00e0 l\u2019\u00e9tranger permettent d\u2019obtenir un prix d\u2019achat encore plus bas, le gain de productivit\u00e9 apparent est encore plus important.<\/p>\n<p>Enfin, il reste une strat\u00e9gie qui ne vise pas \u00e0 proprement parler \u00e0 l\u2019augmentation de la productivit\u00e9, mais dont l\u2019effet est directement visible sur la mesure de celle-ci\u00a0: si l\u2019entreprise arrive \u00e0 augmenter par la gr\u00e2ce du marketing, de l\u2019image de marque ou toute autre approche visant \u00e0 valoriser le prix de vente sans changer massivement la quantit\u00e9 de travail n\u00e9cessaire \u00e0 la production ou alors les achats, alors il y aussi gain de productivit\u00e9 par simple augmentation de la valeur ajout\u00e9e. Il ne faut pas n\u00e9gliger ce type de strat\u00e9gie qui compte pour beaucoup dans la hausse de la productivit\u00e9 apparente que l\u2019on a pu observer ces derni\u00e8res ann\u00e9es.<\/p>\n<p>C\u2019est ce que refl\u00e8te la derni\u00e8re variation de notre exemple th\u00e9orique\u00a0:<\/p>\n<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-06.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-70741\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Michel-06.png\" alt=\"Michel 06\" width=\"700\" height=\"61\" \/><\/a><\/p>\n<p>Ici, beaucoup de postes augmentent\u00a0\u00e0 commencer par le prix de vente. Mais il existe des co\u00fbts de nature diverse qui viennent s\u2019ajouter, \u00e0 commencer par des co\u00fbts marketing, sans compter un contenu qu\u2019il faut donner au produit pour justifier cette diff\u00e9rence de prix et qui se traduisent probablement par l\u2019ajout de nouvelles fonctionnalit\u00e9s ou des performances accrues.<\/p>\n<p>Bien entendu, les strat\u00e9gies expliqu\u00e9es ci-dessus et les exemples th\u00e9oriques qui l\u2019accompagnent ne se retrouvent jamais utilis\u00e9s seuls, mais bien en combinaisons extr\u00eamement complexes. Chaque secteur a sa propre combinaison en \u00e9volution permanente que l\u2019on peut d\u00e9finir comme la norme de production du secteur. L\u2019imbrication entre les entreprises et les processus rend difficilement discernable l\u2019origine du gain de productivit\u00e9. L\u2019effet des gains de productivit\u00e9 au niveau de l\u2019emploi est quant \u00e0 lui une fonction directe de la combinaison propre \u00e0 chaque secteur, mais aussi des d\u00e9bouch\u00e9s que celui-ci peut trouver aupr\u00e8s des clients. L\u2019\u00e9tape suivante est de mettre en perspective sur une longue p\u00e9riode les gains de productivit\u00e9, mais aussi les facteurs qui ont pr\u00e9sid\u00e9 \u00e0 cette hausse par grands secteurs d\u2019activit\u00e9 pour comprendre les impacts pass\u00e9s et futurs sur l\u2019emploi.<\/p>\n<p>_____________<\/p>\n<p><a href=\"#_ednref\" name=\"_edn1\">[i]<\/a> Il s\u2019agit ici de la productivit\u00e9 horaire apparente du travail sur laquelle il existe de larges bases statistiques.<\/p>\n<p><a href=\"#_ednref\" name=\"_edn2\">[ii]<\/a> Il existe bien \u00e9videmment des \u00e9l\u00e9ments qui vont faire varier la Valeur ajout\u00e9e, par exemple, la variation de stock ou tout ce qui r\u00e9sultent des produits et des charges exceptionnelles, ou des produits financiers dans le cas ou ceux-ci seraient sup\u00e9rieurs aux charges financi\u00e8res. On est \u00e0 ce niveau dans une logique d\u2019analyse \u00e9conomique, pas une logique comptable.<\/p>\n<p><a href=\"#_ednref\" name=\"_edn3\">[iii]<\/a> La c\u00e9l\u00e8bre arm\u00e9e en terre cuite de Xian est r\u00e9alis\u00e9e en s\u00e9rie \u00e0 partir d\u2019\u00e9l\u00e9ments s\u00e9par\u00e9s fabriqu\u00e9s par des artisans sp\u00e9cialis\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9 Les discours officiels justifient l\u2019\u00e9rosion progressive de l\u2019\u00c9tat social par la contrainte que font peser les d\u00e9ficits budg\u00e9taires. Dans le m\u00eame temps, ils font de la comp\u00e9titivit\u00e9 des entreprises le credo et le seul horizon de la politique \u00e9conomique. Ces deux aspects d\u2019un discours gestionnaire et dogmatique qui est devenu la norme politique [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,102],"tags":[],"class_list":["post-70735","post","type-post","status-publish","format-standard","hentry","category-economie","category-travail"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/70735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=70735"}],"version-history":[{"count":5,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/70735\/revisions"}],"predecessor-version":[{"id":70746,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/70735\/revisions\/70746"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=70735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=70735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=70735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}