{"id":71035,"date":"2014-11-23T17:51:58","date_gmt":"2014-11-23T16:51:58","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=71035"},"modified":"2014-11-23T17:51:58","modified_gmt":"2014-11-23T16:51:58","slug":"musee-dorsay-attaquer-le-soleil-annie-le-brun-et-laurence-des-cars-le-17-octobre-2014","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2014\/11\/23\/musee-dorsay-attaquer-le-soleil-annie-le-brun-et-laurence-des-cars-le-17-octobre-2014\/","title":{"rendered":"<b>Mus\u00e9e d&rsquo;Orsay, \u00ab\u00a0Attaquer le soleil\u00a0\u00bb, Annie Le Brun et Laurence des Cars<\/b>, le 17 octobre 2014"},"content":{"rendered":"<p><iframe loading=\"lazy\" frameborder=\"0\" width=\"610\" height=\"345\" src=\"\/\/www.dailymotion.com\/embed\/video\/x28ylyg\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p><iframe loading=\"lazy\" frameborder=\"0\" width=\"610\" height=\"345\" src=\"\/\/www.dailymotion.com\/embed\/video\/x28ylyg\" allowfullscreen><\/iframe><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,20],"tags":[1963,732],"class_list":["post-71035","post","type-post","status-publish","format-standard","hentry","category-arts","category-philosophie","tag-annie-le-brun","tag-marquis-de-sade"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/71035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=71035"}],"version-history":[{"count":3,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/71035\/revisions"}],"predecessor-version":[{"id":71038,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/71035\/revisions\/71038"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=71035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=71035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=71035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}