{"id":732,"date":"2008-09-03T05:37:46","date_gmt":"2008-09-03T04:37:46","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=732"},"modified":"2018-08-05T17:11:09","modified_gmt":"2018-08-05T15:11:09","slug":"mendocino-hotel","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2008\/09\/03\/mendocino-hotel\/","title":{"rendered":"Mendocino Hotel"},"content":{"rendered":"<blockquote><p><strong>Ce texte est un \u00ab article presslib\u2019 \u00bb (*) <\/strong><\/p><\/blockquote>\n<p><i>A l\u2019Est d\u2019Eden<\/i> d\u2019Elia Kazan, d\u2019apr\u00e8s le roman de John Steinbeck est, avec <i>G\u00e9ant<\/i> de George Stevens, l\u2019un des grands films qui consacr\u00e8rent James Dean.<\/p>\n<p>L\u2019action d\u2019<i>A l\u2019Est d\u2019Eden<\/i> se passe \u00e0 Salinas et Monterey, \u00e0 200 km au Sud de San Francisco. Quand le film fut r\u00e9alis\u00e9 en 1954, Monterey avait trop chang\u00e9 par rapport \u00e0 1917 \u2013 l\u2019\u00e9poque o\u00f9 se situe le film, \u00e9tant devenu entre-temps un grand port industriel. Mendocino, \u00e0 300 km au Nord de San Francisco, sur un bout de c\u00f4te d\u00e9sol\u00e9, avait conserv\u00e9 son cachet d\u00e9suet. Certaines sc\u00e8nes du film furent tourn\u00e9es au Mendocino Hotel o\u00f9 nous avons log\u00e9 dimanche soir. <\/p>\n<p><a href='http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/mendocino-082.jpg'><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/mendocino-082.jpg\" alt=\"\" title=\"Mendocino Hotel\" width=\"700\" height=\"466\" class=\"aligncenter size-full wp-image-733\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/mendocino-082.jpg 3888w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/mendocino-082-300x200.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>Mendocino est tr\u00e8s beau.<\/p>\n<p><a href='http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/mendocino-116.jpg'><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/mendocino-116.jpg\" alt=\"\" title=\"Mendocino Le village vu de la falaise\" width=\"700\" height=\"466\" class=\"aligncenter size-full wp-image-734\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/mendocino-116.jpg 3888w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/mendocino-116-300x200.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><strong>(*) Un \u00ab article presslib\u2019 \u00bb est libre de reproduction en tout ou en partie \u00e0 condition que le pr\u00e9sent alin\u00e9a soit reproduit \u00e0 sa suite. Paul Jorion est un \u00ab journaliste presslib\u2019 \u00bb qui vit exclusivement de ses droits d\u2019auteurs et de vos contributions. Il pourra continuer d\u2019\u00e9crire comme il le fait aujourd\u2019hui tant que vous l\u2019y aiderez. Votre soutien peut s\u2019exprimer <a href=\"http:\/\/www.pauljorion.com\/blog\/?page_id=647\"><em>ici<\/em><\/a>.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce texte est un \u00ab article presslib\u2019 \u00bb (*) A l\u2019Est d\u2019Eden d\u2019Elia Kazan, d\u2019apr\u00e8s le roman de John Steinbeck est, avec G\u00e9ant de George Stevens, l\u2019un des grands films qui consacr\u00e8rent James Dean. L\u2019action d\u2019A l\u2019Est d\u2019Eden se passe \u00e0 Salinas et Monterey, \u00e0 200 km au Sud de San Francisco. Quand le film [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-732","post","type-post","status-publish","format-standard","hentry","category-arts"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=732"}],"version-history":[{"count":5,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/732\/revisions"}],"predecessor-version":[{"id":105779,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/732\/revisions\/105779"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}