{"id":75603,"date":"2015-06-01T00:07:39","date_gmt":"2015-05-31T22:07:39","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=75603"},"modified":"2015-06-01T09:39:41","modified_gmt":"2015-06-01T07:39:41","slug":"california-nightmare-petit-etat-des-lieux-de-la-secheresse-en-californie-les-phenomenes-climatiques-critiques-sont-complexes-par-francois-corre","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2015\/06\/01\/california-nightmare-petit-etat-des-lieux-de-la-secheresse-en-californie-les-phenomenes-climatiques-critiques-sont-complexes-par-francois-corre\/","title":{"rendered":"<b>California nightmare&#8230;\u00a0(*) Petit \u00e9tat des lieux de la s\u00e9cheresse en Californie. Les ph\u00e9nom\u00e8nes climatiques &lsquo;critiques&rsquo; sont complexes<\/b>, par Fran\u00e7ois Corre"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9. Ouvert aux commentaires.<\/p><\/blockquote>\n<p>Les p\u00e9riodes de s\u00e9cheresse ne sont a\u00a0priori pas anormales dans des r\u00e9gions \u00e0 dominante semi-arides ou semi-d\u00e9sertiques, dans les territoires de l&rsquo;Ouest ou du Sud des \u00c9tats-Unis, ou m\u00eame parfois dans les &lsquo;High Plains&rsquo; ou le &lsquo;Middle West&rsquo;.\u00a0On peut facilement observer les quinze derni\u00e8res ann\u00e9es via le site \u00ab\u00a0<a href=\"http:\/\/droughtmonitor.unl.edu\/Home.aspx\" target=\"_blank\">United States Drought Monitor\u00a0\u00bb<\/a> ou pour les amateurs d&rsquo;archives, sur un si\u00e8cle via le site \u00ab\u00a0<a href=\"http:\/\/www.ncdc.noaa.gov\/temp-and-precip\/drought\/historical-palmers\/psi\/201201-201504\" target=\"_blank\">Historical Palmer Drought Indices\u00a0\u00bb<\/a>.<\/p>\n<p><!--more--><\/p>\n<p>Bien que la Californie soit globalement plus proche d&rsquo;un climat de type m\u00e9diterran\u00e9en, les \u00e9pisodes de s\u00e9cheresse y sont connus\u00a0<a href=\"http:\/\/droughtmonitor.unl.edu\/data\/pdfs\/20150526\/20150526_west_trd.pdf\" target=\"_blank\">mais l&rsquo;actuelle<\/a>, touchant \u00e9galement le Nevada et l&rsquo;Oregon, ressentie d\u00e8s 2012 et pr\u00e9c\u00e9d\u00e9e d&rsquo;une p\u00e9riode d\u00e9j\u00e0 difficile (2007\/2009), semble cumuler tous les param\u00e8tres.<\/p>\n<p>D\u00e9ficit pluviom\u00e9trique, temp\u00e9ratures au-dessus des moyennes, faibles chutes de neige dans la\u00a0<a href=\"http:\/\/climate.nasa.gov\/state_of_flux#Drought_California_930x308.jpg\" target=\"_blank\">Sierra Nevada<\/a>, gaspillage et pompage excessif pour l&rsquo;agriculture intensive (environ 75% de la consommation totale) d\u00e9pendante de l&rsquo;irrigation, l&rsquo;\u00e9levage bovin, l&rsquo;industrie p\u00e9troli\u00e8re et agroalimentaire (Nestl\u00e9, Coca cola) ; conflits sur le partage des eaux du fleuve Colorado, sans oublier les\u00a0<a href=\"http:\/\/static01.nyt.com\/images\/2015\/04\/05\/us\/05DROUGHT5websub\/05DROUGHT5websub-superJumbo.jpg\" target=\"_blank\">golfs<\/a>, ou les\u00a0<a href=\"http:\/\/static01.nyt.com\/images\/2015\/04\/05\/us\/05DROUGHTtop\/05DROUGHTtop-superJumbo.jpg\" target=\"_blank\">piscines et pelouses<\/a> &#8230;\u00a0La s\u00e9cheresse s\u00e9v\u00e8re ou extr\u00eame ainsi que l&rsquo;\u00e9puisement des r\u00e9serves dans l&rsquo;\u00c9tat le plus peupl\u00e9 des USA (39 millions d&rsquo;habitants) ont donc des origines climatiques, \u00e9conomiques et politiques.<\/p>\n<p>Des groupements agriculteurs, principalement de grandes exploitations, prennent les devants en annon\u00e7ant la\u00a0r\u00e9duction de leur consommation d&rsquo;eau de 25%, esp\u00e9rant ainsi \u00e9viter des restrictions plus importantes impos\u00e9es par les autorit\u00e9s de l&rsquo;\u00c9tat, d&rsquo;autres ont mis une partie de leurs terres en jach\u00e8re ou ont proc\u00e9d\u00e9\u00a0\u00e0 l&rsquo;arrachage d&rsquo;amandiers, pourtant r\u00e9sistants au manque d&rsquo;eau.<\/p>\n<p>L&rsquo;exploitation du p\u00e9trole de schiste consomme \u00e9galement beaucoup d&rsquo;eau, et les compagnies rejettent\u00a0leurs eaux us\u00e9es (la partie r\u00e9cup\u00e9r\u00e9e) dans certaines nappes phr\u00e9atiques, ou bien m\u00eame peuvent les vendre\u00a0\u00e0 des agriculteurs, sans r\u00e9els contr\u00f4les pr\u00e9alables.<\/p>\n<p>Plusieurs projets de constructions de nouvelles usines de d\u00e9salinisation sont en cours en Californie, celle\u00a0de Carlsbad pr\u00e8s de San Diego sera la plus importante des \u00c9tats-Unis, et en service d\u00e8s 2016.\u00a0Si la technologie peut aider \u00e0 mieux g\u00e9rer et \u00e9conomiser les ressources, le co\u00fbt \u00e9nerg\u00e9tique et l&rsquo;impact\u00a0\u00e9cologique des centrales de d\u00e9salinisation sont loin d&rsquo;\u00eatre n\u00e9gligeables&#8230;<\/p>\n<p>Le manque d&rsquo;eau ne s&rsquo;arr\u00eate pas aux fronti\u00e8res, et la majeure partie du nord du Mexique est \u00e9galement tr\u00e8s\u00a0affect\u00e9e depuis 2011, tout comme le sud du Br\u00e9sil ou encore de l&rsquo;Australie depuis 2013 environ.<\/p>\n<p>Reverrons-nous ces impressionnantes s\u00e9ries de temp\u00eates de poussi\u00e8res des ann\u00e9es 30 dans la r\u00e9gion des\u00a0&lsquo;Great Plains&rsquo;,\u00a0les <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Dust_Bowl\" target=\"_blank\">dust bowl<\/a>, qui existent ponctuellement en Arizona\u00a0par exemple, jusqu&rsquo;\u00e0 devenir chroniques comme dans le sc\u00e9nario de\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=fUEGdBbtSG4\" target=\"_blank\">Interstellar<\/a> &#8230;?<\/p>\n<p>Pendant ce temps, 2000 kilom\u00e8tres plus \u00e0 l&rsquo;est, plusieurs comt\u00e9s du Texas et de l&rsquo;Oklahoma viennent de\u00a0subir des inondations suite \u00e0 des cumuls de pluies parfois record pour un mois de mai.<\/p>\n<p>Vous avez dit changement climatique ?<\/p>\n<p>(*) <a href=\"https:\/\/www.youtube.com\/watch?v=dN3GbF9Bx6E\" target=\"_blank\">The Mamas and the Papas : California Dreamin&rsquo;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. Ouvert aux commentaires. Les p\u00e9riodes de s\u00e9cheresse ne sont a\u00a0priori pas anormales dans des r\u00e9gions \u00e0 dominante semi-arides ou semi-d\u00e9sertiques, dans les territoires de l&rsquo;Ouest ou du Sud des \u00c9tats-Unis, ou m\u00eame parfois dans les &lsquo;High Plains&rsquo; ou le &lsquo;Middle West&rsquo;.\u00a0On peut facilement observer les quinze derni\u00e8res ann\u00e9es via le site \u00ab\u00a0United States [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[77,4294,3931,4295],"class_list":["post-75603","post","type-post","status-publish","format-standard","hentry","category-ecologie","tag-californie","tag-dust-bowl","tag-interstellar","tag-secheresse"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/75603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=75603"}],"version-history":[{"count":9,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/75603\/revisions"}],"predecessor-version":[{"id":75616,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/75603\/revisions\/75616"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=75603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=75603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=75603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}