{"id":7775,"date":"2010-02-08T10:54:42","date_gmt":"2010-02-08T09:54:42","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=7775"},"modified":"2012-10-31T09:21:58","modified_gmt":"2012-10-31T08:21:58","slug":"bfm-radio-lundi-8-fevrier-a-10h46","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2010\/02\/08\/bfm-radio-lundi-8-fevrier-a-10h46\/","title":{"rendered":"<b>Cronos d\u00e9vorant l\u2019un de ses enfants<\/b>, BFM Radio, lundi 8 f\u00e9vrier \u00e0 10h46"},"content":{"rendered":"<p><strong>Cronos d\u00e9vorant l\u2019un de ses enfants<\/strong><\/p>\n<p>Le tableau de Goya, \u00ab Cronos d\u00e9vorant l\u2019un de ses enfants \u00bb m\u2019est venu \u00e0 l\u2019esprit la semaine derni\u00e8re quand on a commenc\u00e9 \u00e0 parler des d\u00e9boires de la Gr\u00e8ce d\u2019abord, puis du Portugal et de l\u2019Espagne.<\/p>\n<p>Les noms de Bear Stearns, Lehman Brothers et Merrill Lynch vous rappellent peut-\u00eatre quelque chose. Elles furent autrefois \u2013 jusqu\u2019en 2008 \u2013, les fleurons de Wall Street : trois des cinq grandes banques d\u2019investissement qui faisaient sa gloire. Les deux autres, Goldman Sachs et Morgan Stanley existent toujours mais elles ont eu chaud : le 17 septembre 2008 le cours de Goldman Sachs perdait 20 % de sa valeur, celui de Morgan Stanley, 28 %. Elles se sont alors transform\u00e9es pr\u00e9cipitamment en banques commerciales pour pouvoir b\u00e9n\u00e9ficier des fonds de sauvetage distribu\u00e9s par la Federal Reserve. <\/p>\n<p>Ce n\u2019est plus un myst\u00e8re aujourd\u2019hui qu\u2019elles ont chacune pari\u00e9 des sommes colossales sur la chute de leurs concurrentes. Le moyen qu\u2019elles utilis\u00e8rent furent les fameux CDS, les <i>Credit-Default Swaps<\/i>. Je rappelle en deux mots que les CDS jouent pour quelqu\u2019un qui d\u00e9tient un instrument de dette, le r\u00f4le d\u2019une assurance, en lui garantissant que toute perte qu\u2019il pourrait subir en raison du d\u00e9faut de l\u2019emprunteur lui sera rembours\u00e9e. Mais le CDS permet aussi \u2013 et c\u2019est l\u00e0 que la bombe \u00e0 retardement se niche \u2013 \u00e0 quelqu\u2019un qui n\u2019est pas expos\u00e9 \u00e0 un risque particulier de \u00ab s\u2019assurer quand m\u00eame \u00bb. Dans ce cas-l\u00e0, le CDS \u00e9quivaut \u00e0 un simple pari pris sur la chute de celui qui fait l\u2019objet du contrat. <\/p>\n<p>Pourquoi est-ce que le fait de prendre un CDS sur un \u00e9metteur de dette peut pr\u00e9cipiter sa chute ? Parce que la prime (de risque) du CDS est consid\u00e9r\u00e9e par le march\u00e9 comme une \u00e9valuation objective du risque de non-remboursement et que le taux qui est exig\u00e9 de l\u2019emprunteur va s\u2019y ajuster. Si une foule d\u2019acheteurs de CDS appara\u00eet, elle peut provoquer la perte d\u2019un emprunteur. En principe, le m\u00e9canisme n\u2019a rien d\u2019automatique. Mais on a affaire ici au m\u00eame ph\u00e9nom\u00e8ne que sur les march\u00e9s \u00e0 terme : il n\u2019y a <i>aucune raison<\/i> pour que les prix spot s\u2019alignent sur les prix \u00e0 terme mais c\u2019est pourtant ce qui se passe. Tout simplement parce que les op\u00e9rateurs sur ces march\u00e9s consid\u00e8rent que le prix \u00e0 terme est une \u00e9valuation objective du prix futur et qu\u2019il est plus prudent de s\u2019aligner imm\u00e9diatement sur lui.<\/p>\n<p>Alors, les firmes de Wall Street se sont mang\u00e9es les unes les autres parce que, comme pour Cronos et ses fils, il valait mieux d\u00e9vorer qu\u2019\u00eatre d\u00e9vor\u00e9 soi-m\u00eame. Comme il n\u2019en reste plus beaucoup, elles s\u2019en prennent maintenant, avec l\u2019aide des <i>hedge funds<\/i>, aux \u00c9tats. Certaines de ces firmes s\u2019assurent contre un risque qu\u2019elles courent r\u00e9ellement si elles poss\u00e8dent de la dette souveraine de la Gr\u00e8ce, du Portugal ou de l\u2019Espagne. Mais d\u2019autres ont une position \u00ab nue \u00bb sur des CDS et parient cyniquement sur leur perte. Elles ne s\u2019arr\u00eateront pas l\u00e0 : la Grande-Bretagne et les Etats-Unis suivront. Ces pays conna\u00eetront le sort que Mr. George Soros avait fait subir en 1992 \u00e0 la livre sterling.<\/p>\n<p>Seulement, les \u00c9tats ne sont pas de simples firmes, et si les banques et compagnie, entrent en guerre avec eux, ils ne se laisseront peut-\u00eatre pas faire. Une telle guerre serait alors sans merci. <\/p>\n<p><a href=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Chronos.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Chronos.jpg\" alt=\"Cronos d\u00e9vorant ses enfants\" title=\"Cronos d\u00e9vorant ses enfants\" width=\"619\" height=\"1085\" class=\"alignnone size-full wp-image-7705\" srcset=\"https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Chronos.jpg 619w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Chronos-171x300.jpg 171w, https:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Chronos-584x1024.jpg 584w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cronos d\u00e9vorant l\u2019un de ses enfants<\/strong><\/p>\n<p>Le tableau de Goya, \u00ab Cronos d\u00e9vorant l\u2019un de ses enfants \u00bb m\u2019est venu \u00e0 l\u2019esprit la semaine derni\u00e8re quand on a commenc\u00e9 \u00e0 parler des d\u00e9boires de la Gr\u00e8ce d\u2019abord, puis du Portugal et de l\u2019Espagne.<\/p>\n<p>Les noms de Bear Stearns, Lehman Brothers et Merrill Lynch vous rappellent [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,1,307,18],"tags":[56,160,42],"class_list":["post-7775","post","type-post","status-publish","format-standard","hentry","category-constitution-pour-leconomie","category-economie","category-finance","category-monde-financier","tag-cds","tag-grece","tag-speculation"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/7775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=7775"}],"version-history":[{"count":5,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/7775\/revisions"}],"predecessor-version":[{"id":12246,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/7775\/revisions\/12246"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=7775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=7775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=7775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}