{"id":77854,"date":"2015-08-11T11:28:11","date_gmt":"2015-08-11T09:28:11","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=77854"},"modified":"2015-08-11T11:28:11","modified_gmt":"2015-08-11T09:28:11","slug":"un-pansement-de-fortune-par-francois-leclerc","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2015\/08\/11\/un-pansement-de-fortune-par-francois-leclerc\/","title":{"rendered":"<b>UN PANSEMENT DE FORTUNE<\/b>, par Fran\u00e7ois Leclerc"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9.<\/p><\/blockquote>\n<p>Un accord \u00ab\u00a0\u00e0 quelques d\u00e9tails pr\u00e8s\u00a0\u00bb, selon un n\u00e9gociateur grec, a \u00e9t\u00e9 trouv\u00e9 dans la nuit, les cr\u00e9anciers annon\u00e7ant pour leur part un communiqu\u00e9 pour la mi-journ\u00e9e. Les modalit\u00e9s n\u2019en sont pas encore connues, mais des enseignements peuvent d\u00e9j\u00e0 \u00eatre tir\u00e9s de ce que l\u2019on en sait. Il devra \u00eatre act\u00e9 par l\u2019Eurogroupe, un examen de passage dont le statut n\u2019est plus clairement d\u00e9fini. <\/p>\n<p><!--more--><\/p>\n<p>1. Afin de tenir compte de la d\u00e9t\u00e9rioration de la situation \u00e9conomique &#8211; une baisse de 2,1% \u00e0 2,3% du PIB est attendue cette ann\u00e9e &#8211; les pr\u00e9visions d\u2019exc\u00e9dent budg\u00e9taire de ce plan de trois ans ont \u00e9t\u00e9 revues \u00e0 la baisse, m\u00eame s\u2019il a \u00e9t\u00e9 sacrifi\u00e9 \u00e0 un p\u00each\u00e9 mignon : elles sont rest\u00e9es identiques aux pr\u00e9c\u00e9dentes en troisi\u00e8me ann\u00e9e (3,5%), et \u00e0 cet \u00e9gard peu cr\u00e9dibles.<\/p>\n<p>2. Le gouvernement grec se serait engag\u00e9 \u00e0 faire adopter par le Parlement une liste h\u00e9t\u00e9roclite de 35 mesures prioritaires avant toute lib\u00e9ration de fonds : ce nouvel accord continue de concevoir l\u2019encadrement financier du pays comme sa mise sous r\u00e9gime de tutelle, posant d\u2019ind\u00e9niables questions de fond \u00e0 propos de l\u2019exercice de la d\u00e9mocratie au sein de la zone euro. <\/p>\n<p>3. Le montant du plan reste affich\u00e9 \u00e0 un minimum de 82 milliards d\u2019euros mais son financement n\u2019est pas boucl\u00e9, \u00e0 moins que le MES n\u2019augmente sa mise initiale de 50 milliards d\u2019euros, le FMI ne pouvant combler \u00e0 lui seul la diff\u00e9rence une fois un accord sur la dette intervenu. L\u2019impasse financi\u00e8re finale pourra-t-elle \u00eatre r\u00e9solue par le seul programme de privatisation ? Si c&rsquo;est pr\u00e9sent\u00e9 ainsi, ce sera sur le papier !<\/p>\n<p>4. Le tribut que les Grecs vont devoir payer pour rembourser la BCE et le FMI ne pourra \u00eatre appr\u00e9ci\u00e9 qu\u2019une fois connu l\u2019int\u00e9gralit\u00e9 de l\u2019accord. <\/p>\n<p>5. L&rsquo;offensive de Wolfgang Sch\u00e4uble visant \u00e0 couper une premi\u00e8re branche morte au sein de la zone euro a provisoirement \u00e9chou\u00e9. <\/p>\n","protected":false},"excerpt":{"rendered":"<blockquote>\n<p>Billet invit\u00e9.<\/p>\n<\/blockquote>\n<p>Un accord \u00ab\u00a0\u00e0 quelques d\u00e9tails pr\u00e8s\u00a0\u00bb, selon un n\u00e9gociateur grec, a \u00e9t\u00e9 trouv\u00e9 dans la nuit, les cr\u00e9anciers annon\u00e7ant pour leur part un communiqu\u00e9 pour la mi-journ\u00e9e. Les modalit\u00e9s n\u2019en sont pas encore connues, mais des enseignements peuvent d\u00e9j\u00e0 \u00eatre tir\u00e9s de ce que l\u2019on en sait. Il devra \u00eatre act\u00e9 par l\u2019Eurogroupe, [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,204],"tags":[160,985],"class_list":["post-77854","post","type-post","status-publish","format-standard","hentry","category-economie","category-europe","tag-grece","tag-wolfgang-schauble"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/77854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=77854"}],"version-history":[{"count":9,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/77854\/revisions"}],"predecessor-version":[{"id":77869,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/77854\/revisions\/77869"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=77854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=77854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=77854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}