{"id":78423,"date":"2015-09-03T11:26:20","date_gmt":"2015-09-03T09:26:20","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=78423"},"modified":"2015-09-03T11:26:20","modified_gmt":"2015-09-03T09:26:20","slug":"drame-des-refugies-syriens-tous-responsables-par-cedric-mas","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2015\/09\/03\/drame-des-refugies-syriens-tous-responsables-par-cedric-mas\/","title":{"rendered":"Drame des r\u00e9fugi\u00e9s syriens : tous responsables, par C\u00e9dric Mas"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9<\/p><\/blockquote>\n<p>Que fuient les r\u00e9fugi\u00e9s syriens qui affluent vers l&rsquo;Europe ?<\/p>\n<p>Leur pays devenu un enfer, du fait de la guerre civile que nous laissons se d\u00e9rouler sans r\u00e9agir, malgr\u00e9 les horreurs et les crimes.<\/p>\n<p>Cette guerre civile oppose plusieurs factions, mais celles qui motivent la fuite des Syriens sont les factions islamistes (dont certaines milices jihadistes qui n&rsquo;ont rien de \u00ab\u00a0mod\u00e9r\u00e9es\u00a0\u00bb), l&rsquo;\u00c9tat islamique (qui menace aujourd&rsquo;hui Alep et s&rsquo;approche dangereusement de Damas et de Homs) et la dictature d&rsquo;Assad, dont les troupes bombardent aveugl\u00e9ment (et desesp\u00e9r\u00e8ment) les civils (avec l&rsquo;aide mat\u00e9rielle de la Russie, comme \u00e0 Idlib)<\/p>\n<p><!--more-->Le drame se joue donc \u00e0 plusieurs endroits :<\/p>\n<p>&#8211; en Syrie<\/p>\n<p>&#8211; sur le trajet vers l&rsquo;Europe<\/p>\n<p>&#8211; et en Europe.<\/p>\n<p>Notre responsabilit\u00e9 (nous europ\u00e9ens) est enti\u00e8re sur ces trois lieux du drame :<\/p>\n<p>&#8211; en Syrie en laissant les factions les plus terribles r\u00e9gner (\u00c9tat Islamique, JAN et Assad), commettre leurs crimes en toute impunit\u00e9, s&rsquo;\u00e9tendre et aggraver le chaos et l&rsquo;enfer, ce qui va multiplier le nombre de r\u00e9fugi\u00e9s.<\/p>\n<p>&#8211; sur le trajet, en fermant toute possibilit\u00e9 de visa, ce qui am\u00e8ne ces populations desesp\u00e9r\u00e9es \u00e0 confier leur vie \u00e0 des passeurs mafieux, et \u00e0 prendre tous les risques.<\/p>\n<p>&#8211; en Europe en refusant de les accueillir et de les aider (rappelons que la prochaine r\u00e9union \u00ab\u00a0d&rsquo;urgence\u00a0\u00bb de l&rsquo;Union europ\u00e9enne sur le sujet aura lieu le 12 septembre&#8230;, combien de morts encore ? Et combien de r\u00e9unions \u00ab\u00a0urgentes\u00a0\u00bb avant de r\u00e9agir ?), et restant indiff\u00e9rents \u00e0 leur appel \u00e0 l&rsquo;aide (et ils demandent d&rsquo;abord de stopper la guerre dans leur pays, puis \u00e0 d\u00e9faut de les accueillir).<\/p>\n<p>Un exemple de notre indiff\u00e9rence coupable :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/CN9XvjPUcAA50k4.jpg\" width=\"599\" height=\"459\" class=\"alignnone\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/CN9XvjTUEAA5N3S.jpg\" width=\"600\" height=\"800\" class=\"alignnone\" \/><\/p>\n<p><em>Comparaison des couvertures des journaux fran\u00e7ais et UK ce matin<\/em><\/p>\n<p>Notre responsabilit\u00e9 est enti\u00e8re, mais il ne faut pas oublier aussi la responsabilit\u00e9 des factions les plus violentes qui alimentent cette guerre civile, n\u00e9e de la r\u00e9pression violente et aveugle des forces de s\u00e9curit\u00e9 baassistes de manifestations demandant seulement une \u00ab\u00a0d\u00e9mocratisation\u00a0\u00bb.<\/p>\n<p>Il est ainsi \u00e9vident que l&rsquo;\u00c9tat islamique, toujours en progression, est l&rsquo;ennemi principal, et participent par ses exactions quotidiennes \u00e0 la fuite des Syriens. Il en est de m\u00eame de certaines milices jihadistes engag\u00e9es dans les zones qualifi\u00e9es de \u00ab\u00a0rebelles mod\u00e9r\u00e9s\u00a0\u00bb (je rappelle qu&rsquo;il y a eu plusieurs manifestations, y compris r\u00e9centes, \u00e0 Alep, Idlib et dans le sud, des populations demandant leur d\u00e9part, ou le passage sous une administration plus \u00ab\u00a0mod\u00e9r\u00e9e\u00a0\u00bb).<\/p>\n<p>Mais il ne faut pas nier aussi que les bombardements et les crimes des milices d&rsquo;Assad, sont aussi responsables de cet exode massif.<\/p>\n<p>Par les bombardements aveugles des zones civiles rebelles, par les enl\u00e8vements, tortures et disparitions de tout opposant, la dictature d&rsquo;Assad porte m\u00eame une incontestable responsabilit\u00e9 dans ces drames, n\u00e9 d&rsquo;une guerre civile qu&rsquo;elle a provoqu\u00e9 et qu&rsquo;elle alimente (concentrant ses coups contre les milices mod\u00e9r\u00e9es, et \u00e9pargnant autant que possible l&rsquo;\u00c9tat islamique). Et ne parlons m\u00eame pas des milices chiites iraniennes ou du Hezbollah, peu \u00e9conome de la vie des civils syriens (majoritairement sunnites).<\/p>\n<p>Vouloir d\u00e9douaner Assad de sa responsabilit\u00e9 dans le drame v\u00e9cu par les civils syriens, pour ne voir que les Jihadistes, c&rsquo;est comme nier la responsabilit\u00e9 d&rsquo;Isra\u00ebl dans le drame des civils de Gaza (pour ne voir que le Hamas).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9 Que fuient les r\u00e9fugi\u00e9s syriens qui affluent vers l&rsquo;Europe ? Leur pays devenu un enfer, du fait de la guerre civile que nous laissons se d\u00e9rouler sans r\u00e9agir, malgr\u00e9 les horreurs et les crimes. Cette guerre civile oppose plusieurs factions, mais celles qui motivent la fuite des Syriens sont les factions islamistes (dont [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1627,3001,4440],"tags":[],"class_list":["post-78423","post","type-post","status-publish","format-standard","hentry","category-geopolitique-2","category-guerre-2","category-migrations"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/78423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=78423"}],"version-history":[{"count":1,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/78423\/revisions"}],"predecessor-version":[{"id":78424,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/78423\/revisions\/78424"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=78423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=78423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=78423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}