{"id":80281,"date":"2015-11-18T15:46:42","date_gmt":"2015-11-18T14:46:42","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=80281"},"modified":"2015-11-21T12:00:47","modified_gmt":"2015-11-21T11:00:47","slug":"les-classes-moyennes-une-supercherie-politique-par-andre-fontaine","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2015\/11\/18\/les-classes-moyennes-une-supercherie-politique-par-andre-fontaine\/","title":{"rendered":"Les classes moyennes, une supercherie politique, par Andr\u00e9 Fontaine"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9.<\/p><\/blockquote>\n<p>Les \u00ab\u00a0classes moyennes\u00a0\u00bb sont actuellement la tarte \u00e0 la cr\u00e8me des journalistes, des politiques et des sociologues. Les derniers, plus cons\u00e9quents, s\u2019efforcent d\u2019en donner des d\u00e9finitions dont ils reconnaissent eux-m\u00eames l\u2019\u00e9quivoque. On se demande donc \u00e0 quel objectif peut bien correspondre l\u2019engouement pr\u00e9sent.<\/p>\n<p><!--more--><\/p>\n<p>On commence par poser les questions\u00a0: comment aujourd\u2019hui d\u00e9finir les \u00ab\u00a0classes sociales\u00a0\u00bb et \u00e0 la moyenne de quoi faut-il se r\u00e9f\u00e9rer? Apr\u00e8s avoir examin\u00e9 certaines r\u00e9ponses de sociologues, on essayera, suivant une remarque de Pierre Bourdieu, d\u2019envisager le probl\u00e8me sous l\u2019angle politique. Apr\u00e8s un aper\u00e7u historique, on analysera la nouvelle division sociale qui a pris son \u00e9lan en France \u00e0 la fin de la Deuxi\u00e8me guerre mondiale et on constatera que, les sociologues, en n\u2019int\u00e9grant pas ces changements, se condamnent \u00e0 en rester \u00e0 l\u2019\u00e9dredon des classes moyennes\u00a0 pour couvrir leur c\u00e9cit\u00e9 et les enjeux politiciens.<\/p>\n<p><strong>Les \u00ab\u00a0classes moyennes\u00a0\u00bb\u00a0?<\/strong><\/p>\n<p>Si le mot classe est d\u00e9j\u00e0 sujet \u00e0 discussion, il n\u2019est gu\u00e8re \u00e9tonnant que les \u00ab\u00a0classes moyennes\u00a0\u00bb aient pris, au long de l\u2019histoire, un visage sans cesse remodel\u00e9 et sujet \u00e0 une grande diversit\u00e9 de points de vue. Ce concept a re\u00e7u tant de d\u00e9finitions variables suivant la personnalit\u00e9 de l\u2019analyste qu\u2019il en a perdu toute efficacit\u00e9 pour la compr\u00e9hension de la soci\u00e9t\u00e9 actuelle et des forces politiques. On ne reviendra pas sur les \u00ab\u00a0classes moyennes\u00a0\u00bb\u00a0distingu\u00e9es par le pass\u00e9 et on examinera rapidement la fa\u00e7on dont elles sont aujourd\u2019hui envisag\u00e9es.<\/p>\n<p>Il est certain que le mot classe, qui indique la recherche de regroupements homog\u00e8nes d\u2019objets en fonction d\u2019une ou plusieurs caract\u00e9ristiques, se pr\u00eate \u00e0 une grande g\u00e9n\u00e9ralit\u00e9 d\u2019emploi. Pour les politiques ou les sociologues, la classification porte sur le r\u00f4le des individus dans la soci\u00e9t\u00e9 \u00e0 laquelle ils appartiennent. Mais tout homme est un microcosme dont les actions ob\u00e9issent \u00e0 un nombre consid\u00e9rable de param\u00e8tres ; il faut donc les condenser et les hi\u00e9rarchiser pour s\u2019en tenir \u00e0 ceux qu\u2019on d\u00e9clare primordiaux.<\/p>\n<p>Comme on le sait, Adam Smith fut un des premiers \u00e0 remarquer qu\u2019au sein des entreprises industrielles naissantes, le patron, pour augmenter la \u00ab\u00a0rente\u00a0\u00bb, s\u2019efforce de remplacer dans le processus de fabrication certains ouvriers par des machines ou par d\u2019autres ouvriers plus comp\u00e9titifs, engendrant ainsi une nouvelle division du travail. Marx a g\u00e9n\u00e9ralis\u00e9 cette analyse en liant chaque type de soci\u00e9t\u00e9 \u00e0 un mode de production caract\u00e9ris\u00e9 par une division sociale au sein de laquelle la classe qui organise la production domine la soci\u00e9t\u00e9 toute enti\u00e8re. Chacune cherchant \u00e0 maintenir ou am\u00e9liorer sa position, il en r\u00e9sulte des luttes des classes qui sont le moteur de l\u2019Histoire. On sait combien cette philosophie a impr\u00e9gn\u00e9 le mouvement social sous la forme simplifi\u00e9e de la Doctrine communiste au point que beaucoup d\u2019analystes se croient toujours oblig\u00e9s de se pr\u00e9senter comme d\u00e9tach\u00e9s du marxisme.<\/p>\n<p>Dans son long article <em>Le retour des classes sociales <\/em>(D\u00e9partement des \u00e9tudes de l\u2019OFCE, cellule de sociologie IEP et OSC . Octobre 2001), Louis Chauvel, pour s\u2019opposer au nouvel air ambiant, essaye de donner une d\u00e9finition telle qu\u2019elle puisse englober celle de la plupart des analystes et il distingue deux approches possibles des classes :<\/p>\n<p>&#8211; l\u2019une qualifi\u00e9e de marxienne (\u00ab<em>\u201dMarxien\u201d qualifie ici une tradition intellectuelle marqu\u00e9e par l\u2019\u00e9valuation critique<\/em>\u00bb), adjectif qui lui \u00e9vite d\u2019\u00eatre trait\u00e9 de \u00ab\u00a0marxiste\u00a0\u00bb, dans le sens d\u2019adepte de la Doctrine communiste ,<\/p>\n<p>&#8211; l\u2019autre de weberienne.<\/p>\n<p>La premi\u00e8re \u00ab\u00a0<em>est parfois qualifi\u00e9e de <\/em>holiste (<em>holos = tout) parce qu\u2019ici, la totalit\u00e9 est plus que la somme des individus\u00a0<\/em>\u00bb. La seconde \u00ab<em> suppose que les classes sociales sont des groupes d\u2019individus semblables partageant une dynamique probable similaire \u00bb.<\/em><\/p>\n<p>Imm\u00e9diatement, Chauvel ajoute \u00ab\u00a0<em>Une d\u00e9finition <\/em>(des classes)<em>, implicitement pr\u00e9sente chez les sociologues souhaitant disposer de crit\u00e8res empiriques, peut \u00eatre explicit\u00e9e, d\u00e9finition qui pr\u00e9sente l\u2019int\u00e9r\u00eat de sortir de nombreuses apories.<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1) in\u00e9galement situ\u00e9es &#8211; et dot\u00e9es &#8211; dans le syst\u00e8me productif<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2) marqu\u00e9es par une forte <\/em>identit\u00e9 de classe<em>, dont trois modalit\u00e9s peuvent \u00eatre sp\u00e9cifi\u00e9es :<\/em><\/p>\n<p><em>\u00a0\u00a0 &#8211; <\/em>l\u2019identit\u00e9 temporelle &#8230;<\/p>\n<p>&#8211; l\u2019identit\u00e9 culturelle &#8230;<\/p>\n<p>&#8211; l\u2019identit\u00e9 collective &#8230; \u00bb<\/p>\n<p>Comme le dit l\u2019auteur lui-m\u00eame : cette d\u00e9finition est \u00e0 la fois marxienne et weberienne. Elle ouvre la porte \u00e0 tous les d\u00e9veloppements imaginables et couvre les sociologues dans leur d\u00e9marche tous azimuts. Qu\u2019importe ! La v\u00e9ritable pr\u00e9occupation est de \u00ab\u00a0<em>disposer de crit\u00e8res empiriques\u00a0\u00bb<\/em>\u00a0et, \u00e0 partir de l\u00e0, de pouvoir proposer des hypoth\u00e8ses, d\u00e9rouler des consid\u00e9rations en utilisant et, au besoin, en inventant des types d\u2019ensembles sociaux, susceptibles d\u2019\u00eatre soumis \u00e0 des statistiques. Les discussions se concentrent alors sur d\u2019innombrables pourcentages.<\/p>\n<p>Dans son article, Louis Chauvel s\u2019appuie en premier lieu sur les cat\u00e9gories socioprofessionnelles de l\u2019INSEE\u00a0 qui, pour lui, satisfont \u00e0 son premier point : la place dans le syst\u00e8me productif. Ensuite, m\u00eame si, dans un titre, il s\u2019interroge sur \u00ab\u00a0<em>les ind\u00e9finissables \u201cclasses moyennes\u201d?\u00a0<\/em>\u00bb, il multiplie les analyses de r\u00e9sultats statistiques de diff\u00e9rents crit\u00e8res. La r\u00e9partition des revenus est largement comment\u00e9e, mais bien d\u2019autres sujets (par exemple l\u2019homogamie) sont explor\u00e9s pour \u00e9tayer la th\u00e8se de l\u2019article : si les Trente glorieuses \u00ab\u00a0<em>ont vu l\u2019effacement d\u2019une partie du contenu objectif des classes sociales &#8230; depuis, au contraire des in\u00e9galit\u00e9s structur\u00e9es se reconstituent &#8230; \u00bb<\/em><\/p>\n<p>Les r\u00e9ticences n\u2019emp\u00eachent pas la diffusion accrue du concept de \u00ab\u00a0classe moyenne\u00a0\u00bb, par exemple Chauvel lui-m\u00eame publie <em>La d\u00e9rive des classes moyennes\u00a0<\/em>(2006) et plus r\u00e9cemment Serge Bosc <em>Sociologie des classes moyennes<\/em> (2008).\u00a0 Tous deux s\u2019inscrivent dans la continuit\u00e9 d\u2019un courant de pens\u00e9e ancien qui porte sur le probl\u00e8me de l\u2019existence \u00e9ventuelle de classes au sein des ensembles salari\u00e9s<\/p>\n<p>Pourquoi donc se polariser sur des\u00a0\u00bbclasse moyennes\u00a0\u00bb qui suivant leur d\u00e9nomination partagent des caract\u00e8res communs avec les classes inf\u00e9rieures ou sup\u00e9rieures qui les encadrent? Mais, c\u2019est l\u00e0 tout l\u2019int\u00e9r\u00eat du concept : il est tellement flou qu\u2019il englobe de multiples<em> \u00ab caract\u00e8res empiriques \u00bb <\/em>faisant l\u2019objet de statistiques dont l&rsquo;int\u00e9r\u00eat principal est de proposer des nombres pour \u00e9tayer des hypoth\u00e8ses ou des qualit\u00e9s aussi peu quantifiables que, par exemples : la \u00ab\u00a0conscience de classe\u00a0\u00bb ou \u00ab\u00a0l\u2019identit\u00e9 culturelle\u00a0\u00bb. La sociologie qui se veut science, certes sociale mais science, ne peut exister sans se donner une aur\u00e9ole qui la valorise\u00a0; elle se croit oblig\u00e9e de s\u2019appuyer sur un d\u00e9luge de nombres dont la seule vertu est d\u2019\u00eatre des nombres. Les sociologues n\u2019\u00e9chappent pas \u00e0 leur \u00e9poque et \u00e0 la ferveur num\u00e9rique qui autorise tout un chacun \u00e0 se penser savant.<\/p>\n<p>\u00ab\u00a0<em>Le commencement de toutes les sciences, c&rsquo;est l&rsquo;\u00e9tonnement de ce que les choses sont ce qu&rsquo;elles sont.\u00a0<\/em>\u00bb (Aristote &#8211;\u00a0<em>M\u00e9taphysique<\/em>). Or, le propre du sociologue est bien d\u2019\u00e9liminer son \u00ab\u00a0\u00e9tonnement\u00a0\u00bb devant la r\u00e9alit\u00e9 sociale qu\u2019il \u00e9tudie pour en donner une appr\u00e9ciation la plus tangible possible. Il serait temps d\u2019en finir avec cette propension \u00e0 \u00e9riger tout domaine en science : histoire, sociologie, \u00e9conomie &#8230; Les sociologues devraient \u00eatre les premiers \u00e0 s\u2019engager dans cette croisade pour un retour \u00e0 un rationalisme raisonnable. Ces pr\u00e9tendues sciences sociales ne font qu\u2019apporter un obscurantisme de type religieux \u00e0 des consid\u00e9rations qui pourraient \u00eatre pertinentes, si elles restaient dans des d\u00e9bats nuanc\u00e9s au lieu d\u2019\u00eatre ass\u00e9n\u00e9es comme v\u00e9rit\u00e9s indiscutables puisque scientifiques. Comme pour l\u2019\u00e9conomie, on est en pr\u00e9sence d\u2019un domaine qui veut se pr\u00e9senter sous un jour d\u2019objectivit\u00e9 gr\u00e2ce \u00e0 des statistiques.<\/p>\n<p>Sans doute peut-on faire des statistiques en distribuant les \u00e9l\u00e9ments d\u2019un ensemble dans diff\u00e9rentes bo\u00eetes dont une, appel\u00e9e \u00ab\u00a0moyenne\u00a0\u00bb, regroupe les \u00e9l\u00e9ments dont les caract\u00e8res ne sont pas suffisamment affirm\u00e9s. Mais lorsque cette bo\u00eete moyenne est la plus importante ou seulement une des plus copieuses, on en d\u00e9duit que les caract\u00e8res choisis pour l\u2019analyse sont mal adapt\u00e9s \u00e0 l\u2019obtention d\u2019une classification pertinente. Qui plus est, quand cette bo\u00eete porte une d\u00e9nomination plurielle (les classes moyennes) qui signifie le regroupement de plusieurs classes mal d\u00e9finies, on n\u2019en voit plus l\u2019int\u00e9r\u00eat et on pense \u00e0 la formule de Coluche : \u00ab\u00a0<em>Les statistiques, c&rsquo;est comme le bikini : \u00e7a donne des id\u00e9es mais \u00e7a cache l&rsquo;essentiel !\u00a0<\/em>\u00bb Que cachent \u00ab\u00a0les classes moyennes\u00a0\u00bb ? Essentiellement ce qu\u2019elles ne disent pas : quelles sont leurs limites sup\u00e9rieures ou inf\u00e9rieures ? Extensibles \u00e0 volont\u00e9, elles envahissent toute la sph\u00e8re sociale ; les classes qui les entourent sont r\u00e9duites \u00e0 leur plus simple expression. Parfois m\u00eame le concept de classe, \u00e0 proprement parler, est abandonn\u00e9. Comme conclut Xavier Mol\u00e9nat dans son article \u201c<em>Les classes moyennes<\/em>\u201d (n\u00b0188 -d\u00e9cembre 2007 du magazine Sciences Humaines) : \u00ab\u00a0<em>&#8230; mais d\u2019une certaine mani\u00e8re\u00a0 tout le monde est un peu \u201cmoyen\u201d- donc plus personne ne l\u2019est.\u00a0<\/em>\u00bb<\/p>\n<p>Plut\u00f4t que de savoir s\u2019il existe des \u00ab\u00a0classe moyennes\u00a0\u00bb, ne serait-il pas plus sens\u00e9 de se tourner vers la classe dominante, puisque c\u2019est elle qui r\u00e9v\u00e8le la nature du mode de production dominant ? Rien n\u2019a-t-il vraiment chang\u00e9 depuis\u00a0 au moins deux si\u00e8cles dans la soci\u00e9t\u00e9, pour qu\u2019on continue de la d\u00e9crire avec les m\u00eames vocables : capitalisme, bourgeoisie, certes parfois compl\u00e9t\u00e9s par des adjectifs comme dans \u00ab\u00a0capitalisme financier\u00a0\u00bb\u00a0\u00ab\u00a0haute bourgeoisie\u00a0\u00bb. Mais o\u00f9 placer ces salari\u00e9s grassement r\u00e9mun\u00e9r\u00e9s qui font partie des directions des entreprises ou des services ? Et pour ceux qui se situent en dessous\u00a0 des \u00ab\u00a0classes moyennes\u00a0\u00bb, faut-il parler de prol\u00e9taires ou de \u00ab\u00a0classes populaires\u00a0\u00bb ? Personne ne veut plus \u00eatre tax\u00e9 de marxiste, mais tous reviennent au vocabulaire \u00e9cul\u00e9 de la Doctrine communiste en intercalant entre bourgeois et prol\u00e9taires ceux qu\u2019ils d\u00e9nomment les \u00ab\u00a0moyens\u00a0\u00bb. Comme le remarquait Pierre Bourdieu : \u00ab <em>&#8230; l\u2019enjeu des d\u00e9bats autour de la notion de classe sociale est en effet d\u2019ordre politique, l\u2019h\u00e9t\u00e9ronomie du champ des sciences sociales ayant pour cons\u00e9quence que la recherche en sciences sociales reste enferm\u00e9e dans une retraduction pseudo-savante de probl\u00e8mes et de divisions politiques. <\/em>\u00bb (Propos sur le champ politique. Presses universitaire de Lyon 2000 &#8211; p. 94)<\/p>\n<p>La critique est s\u00e9v\u00e8re et oriente la r\u00e9flexion, non sur la d\u00e9finition des \u00ab\u00a0classes moyennes\u00a0\u00bb, mais sur l\u2019\u00e9tude, l\u2019analyse, la compr\u00e9hension, la d\u00e9finition du champ politique de notre \u00e9poque, champ qui porte l\u2019empreinte de l\u2019actuelle division sociale, mais aussi de relents de la Doctrine communiste, m\u00eame si cette derni\u00e8re est discr\u00e9dit\u00e9e et amplement d\u00e9cri\u00e9e.<\/p>\n<p><strong>Au c\u0153ur du probl\u00e8me<\/strong><\/p>\n<p>Le <em>Manifeste du Parti communiste<\/em> est un des textes les plus importants qui ait fond\u00e9 les objectifs d\u2019un parti sur une analyse sociale, \u00e9tay\u00e9e par une philosophie de l\u2019Histoire con\u00e7ue comme une succession de modes de production mue par les luttes des classes et le d\u00e9veloppement des forces productives. Mais la philosophie rel\u00e9gu\u00e9e dans l\u2019ombre, la perspective politique est devenue une \u00ab\u00a0Doctrine\u00a0\u00bb futuriste, \u00e9cran sur lequel fut projet\u00e9 le film d\u2019un avenir radieux, dont les machinistes allaient tirer avantage. L\u2019histoire en a montr\u00e9 la temporalit\u00e9 et la nuisance<\/p>\n<p>Au moment de sa parution, en 1848, dans une industrie compos\u00e9e pour l\u2019essentiel de fabriques, la relation patron-ouvrier illustrait sans ambigu\u00eft\u00e9 la contradiction bourgeoisie-classe ouvri\u00e8re et n\u2019avait pas lieu d\u2019\u00eatre contest\u00e9e. Elle \u00e9tait au centre des relations sociales induites par les forces productives de l\u2019\u00e9poque. On voulait croire que ces forces productives allaient cro\u00eetre inchang\u00e9es jusqu\u2019\u00e0 englober le monde entier ; personne ne pouvait pr\u00e9voir les perturbations que des progr\u00e8s techniques insoup\u00e7onn\u00e9s apporteraient aux relations sociales elles-m\u00eames.<\/p>\n<p>Aujourd\u2019hui, il est facile de suivre les \u00e9volutions qui ont conduit \u00e0 mettre en \u00e9vidence certaines r\u00e9alit\u00e9s, occult\u00e9es ou minimis\u00e9es. Dans le <em>Manifeste<\/em>, \u00a0le mod\u00e8le social \u00a0est \u00a0r\u00e9duit \u00a0\u00e0 \u00a0son\u00a0 squelette \u00a0par \u00a0le \u00a0mot \u00a0\u201cprol\u00e9taires\u201d \u00a0qui englobe tous les exploit\u00e9s et les rassemble gr\u00e2ce au vocabulaire dans le combat antibourgeois, alors que beaucoup ne sont que les r\u00e9sidus des classes domin\u00e9es des modes de production ant\u00e9rieurs et ne participent pas directement \u00e0 la contradiction bourgeoisie-classe ouvri\u00e8re, comme le montrera le r\u00f4le de la paysannerie dans l\u2019accession au pouvoir de Napol\u00e9on III. De m\u00eame, sans nier le r\u00f4le des ing\u00e9nieurs et cadres, l\u2019analyse de la fabrique dans le <em>Capital<\/em>, n\u2019en montre pas le caract\u00e8re crucial qui fit que le pouvoir de cette couche ira augmentant avec le volume des usines m\u00e9caniques.<\/p>\n<p>D\u00e9s 1880, dans <em>Socialisme utopique, socialisme scientifique<\/em>, Engels relevait\u00a0: \u00ab\u00a0<em>Appropriation des grands organismes de production et de communication, d\u2019abord par des soci\u00e9t\u00e9s par actions, puis par des trusts, ensuite\u00a0 par l\u2019\u00c9tat. La bourgeoisie s\u2019av\u00e8re comme une classe superflue\u00a0; toutes ses fonctions sociales sont maintenant remplies par des employ\u00e9s r\u00e9mun\u00e9r\u00e9s. \u00bb<\/em> Pour lui, cette constatation ne faisait que conforter la Doctrine et rendre plus urgente la deuxi\u00e8me partie du texte fondateur, intitul\u00e9e \u00ab prol\u00e9taires et communistes \u00bb, qui soulignait le r\u00f4le essentiel des communistes comme \u00e9tant \u00ab<em> la fraction la plus r\u00e9solue des partis ouvriers de tous les pays, la fraction qui entra\u00eene toutes les autres ; sur le plan de la th\u00e9orie, ils ont sur le reste du prol\u00e9tariat l\u2019avantage d\u2019une intelligence claire des conditions, de la marche et des r\u00e9sultats g\u00e9n\u00e9raux du mouvement prol\u00e9tarien.\u00a0<\/em>\u00bb.<\/p>\n<p>Si la classe dominante \u00e9tait devenue superflue, toutes les relations sociales auraient dues \u00eatre chamboul\u00e9es. Quelques doutes se firent jour : est-on vraiment sur les rails d\u2019un socialisme conduisant au communisme ? Les fondateurs disparus, il revint \u00e0 L\u00e9nine d\u2019institutionnaliser la Doctrine en organisant son \u00e9glise : le Parti. Dans le contexte particulier de la Russie de 1917, il r\u00e9ussira \u00e0 installer les bolcheviks au pouvoir. Sans entrer dans les d\u00e9tails d\u2019une histoire bien connue, on peut cependant remarquer que, d\u00e8s les ann\u00e9es 30 comme l\u2019\u00e9crit Anton Ciligua (in L\u00e9nine et la r\u00e9volution, Spartacus 1978), \u00ab\u00a0<em>Staline d\u00e9clara que les sp\u00e9cialistes sans parti et l\u2019intelligentzia en g\u00e9n\u00e9ral \u00e9taient des \u201cbolcheviks sans parti\u201c.\u00a0<\/em>\u00bb L\u2019auteur souligne ce retour aux r\u00e9alit\u00e9s de la division sociale, car il pensait que les sp\u00e9cialistes \u00e9limineraient du pouvoir le Parti communiste. Il n\u2019en fut rien, la stasicratie (mot forg\u00e9 par moi pour signifier \u00ab\u00a0pouvoir du Parti\u00a0\u00bb) subsista en URSS gr\u00e2ce au primat de l\u2019industrie lourde jusqu\u2019\u00e0 ce que l\u2019organisation de la production mise en place ait fait la preuve de son inefficacit\u00e9.<\/p>\n<p>Malgr\u00e9 l\u2019\u00e9branlement de la R\u00e9volution russe et le coup d\u2019acc\u00e9l\u00e9ration donn\u00e9 aux forces productives par la Grande guerre, la bourgeoisie affaiblie et d\u00e9nonc\u00e9e dans la Doctrine r\u00e9sista encore face au Parti. La division sociale continua \u00e0 s\u2019approfondir, notamment en raison de \u00e0 la large diffusion de l\u2019\u00e9nergie gr\u00e2ce aux r\u00e9seaux \u00e9lectriques et au moteur \u00e0 explosion, cr\u00e9ant les conditions d\u2019une nouvelle classe dominante.<\/p>\n<p>\u00ab\u00a0<em>Une araign\u00e9e fait des op\u00e9rations qui ressemblent \u00e0 celles du tisserand, et l\u2019abeille confond par ses cellules de cire l\u2019habilet\u00e9 de plus d\u2019un architecte. Mais ce qui distingue d\u00e8s l\u2019abord le plus mauvais architecte de l\u2019abeille la plus experte, c\u2019est qu\u2019il a construit la cellule dans sa t\u00eate avant de la construire dans la ruche. Le r\u00e9sultat auquel le travail aboutit pr\u00e9existe id\u00e9alement dans l\u2019imagination du travailleur. Ce n\u2019est pas qu\u2019il op\u00e8re seulement un changement de forme dans les mati\u00e8res naturelles ; il y r\u00e9alise du m\u00eame coup son propre but dont il a conscience, qui d\u00e9termine comme loi son mode d\u2019action, et auquel il doit subordonner sa volont\u00e9.\u00a0<\/em>\u00bb <em>(<\/em>Karl Marx, La production de valeurs d\u2019usage, in <em>Le Capital<\/em>, livre 1,\u00a0 chap. VII)<\/p>\n<p>De cette c\u00e9l\u00e8bre citation, il ressort que l\u2019essence de l\u2019ali\u00e9nation produite par la division du travail commence par le fait que le but de la production et la loi de son mode d\u2019action n\u2019appartiennent plus au travailleur. Dans la course \u00e0 la productivit\u00e9, on en vint \u00e0 tron\u00e7onner la fabrication au point d\u2019en arriver dans l\u2019industrie m\u00e9canique tayloris\u00e9e \u00e0 des ouvriers sp\u00e9cialis\u00e9s dans un seul geste. En contrepartie, ceux qui d\u00e9cident des buts et des modes d\u2019action concentrent de plus en plus de pouvoirs. Dans la manufacture et la fabrique, ce furent les possesseurs des moyens de production. Dans les grandes entreprises de l\u2019industrie m\u00e9canique, les propri\u00e9taires sont peu \u00e0 peu dessaisis de ce pouvoir par les ing\u00e9nieurs et cadres.<\/p>\n<p>Les processus s\u2019amplifient et se g\u00e9n\u00e9ralisent. Des machines automatiques s\u2019ins\u00e8rent de plus en plus au sein de la production. Les ouvriers perdent la sp\u00e9cificit\u00e9 de leur travail et, avec elle, leur possibilit\u00e9 de r\u00e9sistance. Un nouveau mode de production se met en place caract\u00e9ris\u00e9 par la contradiction entre la classe comp\u00e9tente, apte \u00e0 d\u00e9cider de la loi et du mode d\u2019action, et la classe ex\u00e9cutante, vou\u00e9e \u00e0 des t\u00e2ches d\u00e9pourvues d\u2019initiative.<\/p>\n<p>Les premi\u00e8res analyses vinrent des Etats-Unis, pays le plus avanc\u00e9 dans la nouvelle organisation du travail. D\u00e8s 1941, J. Burnham publiait\u00a0 <em>L\u2019\u00e8re des organisateurs<\/em> o\u00f9, pour ainsi dire, l\u2019essentiel \u00e9tait analys\u00e9 : naissance d\u2019une nouvelle classe dirigeante. JK Galbraith n\u2019est pas aussi explicite mais sa notion de technostructure (1961) se place dans la m\u00eame vision. Suite \u00e0 sa victoire de 1945, l\u2019imp\u00e9rialisme \u00e9tats-uniens exporte son syst\u00e8me au del\u00e0 des fronti\u00e8res. D\u00e8s 1967, Guy Debord publie <em>La\u00a0 soci\u00e9t\u00e9 du spectacle<\/em>. D\u2019autres, comme Serge Mallet parlent de\u00a0<em>Nouvelle classe ouvri\u00e8re<\/em> (1969) ou comme Nico Poulantzas de<em> nouvelle petite bourgeoisie<\/em> (1974). Au PSU, \u00e0 partir de 1975, le courant C tente sans grand succ\u00e8s de rallier les militants \u00e0 son analyse des classes comp\u00e9tente et ex\u00e9cutante. Les nouvelles relations sociales sont au c\u0153ur des d\u00e9bats politiques.<\/p>\n<p>Cependant, leur \u00e9tude est vite d\u00e9laiss\u00e9e et les cent fleurs des \u00ab\u00a0classes moyennes\u00a0\u00bb vont fleurir avec toutes les couleurs qu\u2019elles peuvent prendre, alors que d\u2019importants \u00e9v\u00e9nements politiques ponctuent les mutations sociales. La IV<sup>e\u00a0<\/sup>R\u00e9publique, est renvers\u00e9e par le coup d\u2019\u00c9tat du g\u00e9n\u00e9ral de Gaulle, la France entre dans un \u201ccapitalisme d\u2019organisation\u201d, suivant l\u2019expression de Marcuse. En 1964, la CFDT est cr\u00e9\u00e9e. En mai 1968, la r\u00e9volte \u00e9tudiante jette dans les rues des foules consid\u00e9rables et d\u00e9clenche la plus grande gr\u00e8ve g\u00e9n\u00e9rale que le pays ait jamais connue. Beaucoup ne veulent y voir qu\u2019une exigence de lib\u00e9ralisation des m\u0153urs alors que les gr\u00e9vistes visaient l\u2019organisation du travail et des rapports sociaux dans les entreprises au nom de l\u2019autogestion, car, comme l\u2019\u00e9crivit plus tard la CFDT (1972 &#8211; Syndicalisme Magazine n\u00b01415) : \u00ab\u00a0<em>Dans une soci\u00e9t\u00e9 autog\u00e9r\u00e9e, ils (<\/em>les travailleurs<em>) retrouveront leur v\u00e9ritable dignit\u00e9 bas\u00e9e sur la comp\u00e9tence.\u00a0<\/em>\u00bb L\u2019id\u00e9al d\u2019autogestion s\u2019\u00e9vanouira. Mais, le mot avait son importance, il traduisait l\u2019intuition que le probl\u00e8me n\u2019\u00e9tait plus de produire mais de g\u00e9rer, il portait l\u2019espoir que chaque individu y gagnerait une part de souverainet\u00e9.<\/p>\n<p>Depuis lors, les entreprises continuent \u00e0 s\u2019automatiser. Les ouvriers voient leur qualification effac\u00e9e par des machines aux performances sup\u00e9rieures en pr\u00e9cision et en rapidit\u00e9, ils ne sont plus que des ex\u00e9cutants vou\u00e9s \u00e0 les surveiller, \u00e0 les alimenter en mati\u00e8res premi\u00e8res et \u00e0 en \u00e9vacuer les produits. Les possesseurs des grands moyens de production, actionnaires de soci\u00e9t\u00e9s anonymes, sont sans pouvoir r\u00e9el sur l\u2019organisation et laissent la gestion aux mains des comp\u00e9tents. Les progr\u00e8s de l\u2019informatique accentuent la division du travail qui se propage dans les soci\u00e9t\u00e9s de service o\u00f9 le travail intellectuel se borne \u00e0 des op\u00e9rations standardis\u00e9es exig\u00e9es par les logiciels vendus avec les ordinateurs. Les employ\u00e9s ne sont plus que des ex\u00e9cutants ali\u00e9n\u00e9s par les comp\u00e9tents, concepteurs des logiciels.<\/p>\n<p>Toutes les classes sont sous la domination comp\u00e9tente, l\u2019air du temps\u00a0est \u00e0 la gestion, \u00e0 l\u2019\u00e9conomisme et \u00e0 l\u2019individualisme.<\/p>\n<p>Comme l\u2019avait analys\u00e9 JK Galbraith (<em>La soci\u00e9t\u00e9 \u00e9conomique et l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral<\/em>, NRF, Gallimard 1974 et <em>Les mensonges de l\u2019\u00e9conomie<\/em>, Grasset et Fasquelle, 2004), les grandes entreprises sont devenues des soci\u00e9t\u00e9s anonymes o\u00f9 les productions mat\u00e9rielles, non encore automatis\u00e9es, sont confi\u00e9es \u00e0 des sous-traitants. Pour l\u2019\u00e9conomiste am\u00e9ricain, les pays d\u00e9velopp\u00e9s se scindent en un secteur planificateur form\u00e9 de multinationales et en un secteur de march\u00e9 laiss\u00e9 \u00e0 de petits producteurs. Les mots parlent d\u2019eux-m\u00eames : le secteur de march\u00e9 est soumis \u00e0 la concurrence, tandis que le secteur planificateur gr\u00e2ce \u00e0 sa puissance et sa connivence avec l\u2019\u00c9tat planifie la production et les \u00e9changes \u00e0 son profit. Les grandes entreprises ne tirent plus directement leurs b\u00e9n\u00e9fices de la plus value sur le travail, mais de contrats l\u00e9onins pass\u00e9s avec les sous-traitants.<\/p>\n<p><strong>O\u00f9 en est-on ?<\/strong><\/p>\n<p>Ce court panorama historique depuis le <em>Manifeste<\/em> relate un changement de mode de production n\u00e9 du d\u00e9veloppement des forces productives, avec lequel interf\u00e8re le changement de mode de production d\u00e9coulant de la Doctrine. R\u00e9sumons\u00a0:<\/p>\n<p>&#8211; &#8211; \u00a0depuis la R\u00e9volution fran\u00e7aise, le mode de production bourgeois domine. \u00c0\u00a0la fin du 19\u00e8me si\u00e8cle, il atteint son apog\u00e9e et ouvre la voie \u00e0 ses concurrents, en faisant de la bourgeoisie une classe superflue.<\/p>\n<p>&#8211; &#8211; \u00a0dans les conditions particuli\u00e8res de la Russie de 1917, le mode de production stasicratique se met en place impos\u00e9 d\u2019une main de fer par Lenine et Staline, le Parti devient la classe dominante de l\u2019Union sovi\u00e9tique.<\/p>\n<p>&#8211; &#8211;\u00a0 au 20\u00e8me si\u00e8cle, les trois modes de production bourgeois, stasicratique et comp\u00e9tent coexistent chacun s\u2019effor\u00e7ant d\u2019\u00e9liminer les deux autres,<\/p>\n<p>&#8211;\u00a0 pendant la premi\u00e8re moiti\u00e9 du si\u00e8cle, la bourgeoisie nationale fran\u00e7aise se maintient face au Parti moyennant des avantages sociaux octroy\u00e9s aux travailleurs, comme par exemple lors du Front populaire et de la Lib\u00e9ration,<\/p>\n<p>&#8211;\u00a0 apr\u00e8s la Deuxi\u00e8me guerre mondiale, le mode de production comp\u00e9tent entre en lice. Le combat comprend alors trois protagonistes qui se r\u00e9v\u00e8lent dans les affrontements de mai 68. Ces \u00c9v\u00e9nements sont le fait politique majeur du 20\u00e8me si\u00e8cle. Ce furent de belles empoignades entre les manifestants, le gouvernement et le Parti. Sur le plan politique, la bourgeoisie nationale gaulliste et le Parti se r\u00e9tablirent, mais sur le plan id\u00e9ologique, ils ont perdu la bataille.<\/p>\n<p>&#8211;\u00a0 peu \u00e0 peu, le mode de production comp\u00e9tent \u00e9limine en quelques d\u00e9cennies ses concurrents en les utilisant eux-m\u00eames pour d\u00e9truire leurs propres valeurs\u00a0: l\u2019humanisme et le marxisme.<\/p>\n<p>D\u00e8s 1968, Edgar Faure s\u2019attaque \u00e0 l\u2019\u00e9ducation nationale, cr\u00e9ant l\u2019Universit\u00e9 de Vincennes et am\u00e9ricanisant les m\u00e9thodes p\u00e9dagogiques. Pompidou fait entrer la Grande-Bretagne dans le March\u00e9 Commun et Chirac porte sur les fonds baptismaux l\u2019Europe de Maastricht. Trahie par ses repr\u00e9sentants, la bourgeoisie nationale a perdu le rempart de la nation et laisse le champ libre aux multinationales.<\/p>\n<p>Le Parti Communiste s\u2019accroche bec et ongles \u00e0 la Doctrine. Il n\u2019abandonne la \u201cdictature du prol\u00e9tariat\u201d que contraint par le grand fr\u00e8re sovi\u00e9tique. Las, ce dernier, entr\u00e9 en p\u00e9restro\u00efka, d\u00e9nonce la Doctrine. Le Parti Communiste perd sa raison d\u2019\u00eatre et entra\u00eene dans sa d\u00e9confiture le mat\u00e9rialisme historique : plus personne ne pourra momentan\u00e9ment se recommander du marxisme.<\/p>\n<p>La Section Ouvri\u00e8re de l\u2019Internationale Socialiste meurt de sa belle mort, faute de classe ouvri\u00e8re. Un nouveau parti est cr\u00e9\u00e9 en 1969, on lui donne le nom de socialiste. Mitterrand en devient secr\u00e9taire g\u00e9n\u00e9ral et, par l\u00e0, lui-m\u00eame socialiste. En 1974, la \u201cdeuxi\u00e8me gauche\u201d rejoint le PS\u00a0; issue des rangs de mai\u00a068, elle l\u2019impr\u00e8gne de l\u2019id\u00e9ologie comp\u00e9tente et en fait le parti de la classe de m\u00eame nom. Vivent le lib\u00e9ralisme et le trait\u00e9 de Maastricht\u00a0! Les gouvernements socialistes vendent les services publics et d\u00e9mant\u00e8lent l\u2019\u00e9cole \u201cbourgeoise\u201d : J.\u00a0Lang introduit \u00a0l\u2019anglais \u00e0 l\u2019\u00e9cole \u00a0primaire, Mme Fiorazo \u00a0l\u00e9galise l\u2019universit\u00e9 fran\u00e7aise anglophone, Mme Vallaud-Belkacem supprime le latin au coll\u00e8ge. Le Parti Socialiste, parti de la classe dirigeante, se rallie \u00e0 M. Valls pour s\u2019\u00e9crier\u00a0: \u00ab\u00a0<em>J\u2019aime l\u2019entreprise\u00a0<\/em>\u00bb.<\/p>\n<p>Notre mode de production est un mode de production comp\u00e9tent o\u00f9 les petites entreprises capitalistes sont sous tutelle de grandes soci\u00e9t\u00e9s anonymes. \u00c0\u00a0force de se cacher cette r\u00e9alit\u00e9 sociale, d\u00e9bats, projets, analyses politiciennes n\u2019ont plus de sens. Le champ politique est la proie de tous les obscurantismes. Tel Diog\u00e8ne cherchant un homme, les sociologues errent \u00e0 la recherche des classes d\u2019antan.<\/p>\n<p>Pourtant des faits concrets et visibles ont jalonn\u00e9 les 19\u00e8me et 20\u00e8me si\u00e8cles. Autour des ann\u00e9es 1900, les d\u00e9couvertes scientifiques ont compl\u00e8tement boulevers\u00e9 notre vision de la nature et ont \u00e9t\u00e9 suivies de r\u00e9alisations techniques qui ont chang\u00e9 nos conditions de vie et de penser. Qui ne sait pas que les mines de charbons et de fer ont \u00e9t\u00e9 ferm\u00e9es en France, que d\u2019\u00e9normes barrages ont ma\u00eetris\u00e9 le Rh\u00f4ne, que le territoire s\u2019est couvert de centrales nucl\u00e9aires, que la paysannerie a fondu, que l\u2019industrie est en voie de d\u00e9mant\u00e8lement, que le secteur tertiaire est en expansion, que la num\u00e9risation atteint toutes les activit\u00e9s \u2026\u00a0? Qui ne sait pas que la stasicratie sovi\u00e9tique a jet\u00e9 l\u2019\u00e9ponge !<\/p>\n<p>Tout le monde le sait, personne ne cherche \u00e0 comprendre. Une contradiction philosophique traverse l\u2019id\u00e9ologie\u00a0actuelle. D\u2019un cot\u00e9, le marxisme est marginalis\u00e9\u00a0et on oublie les luttes des classe\u00a0; d\u2019un autre il est, pour ainsi dire, approuv\u00e9 dans sa d\u00e9viance doctrinaire et la soci\u00e9t\u00e9 est envahie par un \u00e9conomisme sans r\u00e9plique. Sans doute, Marx et Engels avaient-ils qualifi\u00e9 l\u2019\u00e9conomie politique de scientifique, donnant ainsi, dans une \u00e9poque positiviste, une valeur incontournable aux perspectives politiques du prol\u00e9tariat, mais, le v\u00e9ritable triomphe \u00e9clate quand, comme il est \u00e9crit dans le Larousse illustr\u00e9 de 1973 :\u00a0\u00ab\u00a0<em>les \u00e9conomistes ont r\u00e9cemment substitu\u00e9 \u00e0 l\u2019expression<\/em> ECONOMIE POLITIQUE <em>celle de\u00a0<\/em>SCIENCE ECONOMIQUE\u00a0\u00bb.<\/p>\n<p>La classe comp\u00e9tente dispose l\u00e0 de l\u2019outil qui ferme la bouche \u00e0 toutes les critiques, qui justifie sa domination et ses privil\u00e8ges. Aux objections du peuple,\u00a0 on r\u00e9pond, comme dans Tartuffe, \u00ab\u00a0et l\u2019\u00e9conomie\u00a0?\u00a0\u00bb. Ce dieu nouveau est l\u2019objet d\u2019une v\u00e9n\u00e9ration quasi religieuse. Il engloutit des sommes \u00e9normes pour l\u2019honorer, dans l\u2019\u00e9ducation nationale, dans les universit\u00e9s, dans de grandes \u00e9coles, dans les m\u00e9dias, dans les soci\u00e9t\u00e9s de conseil\u00a0&#8230; On accepte que la classe dirigeante s\u2019attribue des r\u00e9mun\u00e9rations de 1000 fois le SMIC. La raison s\u2019incline devant une idole\u00a0: la science \u00e9conomique. Les pages des medias sont pleines de ses oracles.<\/p>\n<p>La formule de Protagoras \u00ab\u00a0<em>L\u2019homme est la mesure de toute chose\u00a0<\/em>\u00bb n\u2019a plus cours. On est entr\u00e9 dans l\u2019\u00e8re d\u2019un obscurantisme engendr\u00e9 par la foi en une science qui n\u2019est pas scientifique.<\/p>\n<p>Si on revient \u00e0 l\u2019article de Louis Chauvel, on constate qu\u2019il est sensible \u00e0 l\u2019\u00e9volution g\u00e9n\u00e9rale\u00a0: les Trente glorieuses <em>ont vu l\u2019effacement d\u2019une partie du contenu objectif des classes sociales &#8230; depuis, au contraire des in\u00e9galit\u00e9s structur\u00e9es se reconstituent ..<\/em><\/p>\n<p>En effet, un nouveau mode de production affaiblit les classes anciennes dont les limites sont de moins en moins claires, puis son empreinte s\u2019accroissant, il fait appara\u00eetre les in\u00e9galit\u00e9s propres \u00e0 la nouvelle contradiction. Louis Chauvel ajoute : \u00ab\u00a0<em>Lorsque sera trouv\u00e9e la synth\u00e8se entre les deux fractions des classes populaires que sont les ouvriers et les employ\u00e9s, ce discours de classe pourrait avoir un impact important. En attendant, des d\u00e9cennies peuvent aussi bien passer dans un contexte de r\u00e9activation de la pens\u00e9e n\u00e9o-conservatrice populaire, ou dans l\u2019abstention \u00e9lectorale massive du peuple<\/em>. \u00bb (p.\u00a0356). Que ne se tourne-t-il vers l\u2019automatisation de toutes les activit\u00e9s, qui engendre une forme de travail identique chez les ouvriers et les employ\u00e9s, les r\u00e9unissant dans la classe des ex\u00e9cutants ?<\/p>\n<p>Pourtant, il ne peut ignorer que Marx a \u00e9crit\u00a0: <em>\u00ab\u00a0Mais l\u2019essence humaine n\u2019est pas une abstraction inh\u00e9rente \u00e0 l\u2019individu singulier. Dans sa r\u00e9alit\u00e9, c\u2019est l\u2019ensemble des rapports sociaux.<\/em>\u00a0\u00bb (6<sup>\u00e8me<\/sup> th\u00e8se sur Feuerbach,) et a soulign\u00e9, tout au long de son \u0153uvre, la subordination des concepts de l\u2019\u00e9conomie politique aux rapports sociaux. \u00ab\u00a0<em>Dans toutes les formes de soci\u00e9t\u00e9, c\u2019est une production d\u00e9termin\u00e9e et les rapports de cette derni\u00e8re qui assignent \u00e0 toutes les autres productions et \u00e0 tous les autres rapports leur rang et influence.<\/em>\u00a0\u00bb (Karl Marx \u2013 <em>Contribution \u00e0 la critique de l\u2019\u00e9conomie politique <\/em>&#8211; Les \u00e9ditions sociales, 2014, p. 53 ). Mais Louis Chauvel pr\u00e9f\u00e8re rester dans le champ politique habituel, aussi d\u00e9pass\u00e9 soit-il. Il se condamne \u00e0 ne pas discerner le mode de production dominant, \u00e0 recourir aux classes moyennes, concept sans pertinence, fourre tout o\u00f9 disparaissent les v\u00e9ritables questions.<\/p>\n<p>La soumission du sociologique au politique, comme l\u2019a not\u00e9 Pierre Bourdieu, transpara\u00eet dans cette c\u00e9cit\u00e9. Les classes moyennes ne sont mises \u00e0 toutes les sauces que pour \u00e9viter de r\u00e9v\u00e9ler ce qui pourrait f\u00e2cher la classe au pouvoir : l\u2019analyse de son existence et la d\u00e9signation de son soutien politicien, le Parti socialiste. Comment sortir de cet engrenage social o\u00f9 perdurent non autonomes les classes du\u00a0<em>Manifeste<\/em> dans un syst\u00e8me de march\u00e9 esclave d\u2019un syst\u00e8me planificateur dans lequel la classe comp\u00e9tente justifie ses privil\u00e8ges au nom de l\u2019\u00e9conomisme et de l\u2019individualisme\u00a0? Toute r\u00e9flexion est vici\u00e9e par la pression de la classe dominante que les sociologues se gardent de d\u00e9finir. La raison reprendra-t-elle des couleurs\u00a0?<\/p>\n<p>D\u2019apr\u00e8s Guillaume Fondu, une lueur d\u2019espoir appara\u00eet.<\/p>\n<p>\u00ab\u00a0 <em>Ainsi, les sciences sociales contemporaines, apr\u00e8s des ann\u00e9es de vide th\u00e9orique assum\u00e9, semblent s\u2019interroger de nouveau sur les concepts qu\u2019elles mobilisent et par lequel elles mod\u00e9lisent leur objet. Dans la plupart des disciplines, il semble en effet que l\u2019imp\u00e9rialisme de la formalisation math\u00e9matique par exemple, qu\u2019il soit install\u00e9 de longue date (comme en \u00e9conomie) ou fraye encore sa route vers l\u2019h\u00e9g\u00e9monie (comme par exemple dans certains pans de la sociologie), soit contest\u00e9 et ce du point de vue de la th\u00e9orie elle-m\u00eame<\/em>.\u00a0\u00bb (Postface de\u00a0<em>Contribution \u00e0 la critique de l\u2019\u00e9conomie politique, K. Marx<\/em>, Les \u00e9ditions sociales, 2014, p.\u00a0246)<\/p>\n<p><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Andr%C3%A9_Fontaine_(g%C3%A9ographe)\" target=\"_blank\">Andr\u00e9 Fontaine<\/a>, auteur de <em>Les socialismes\u00a0: l\u2019Histoire sans fin<\/em>, Spartacus, 1992, <em>Mai 68 dans l\u2019Histoire<\/em>, L\u2019Harmattan, 2010<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. Les \u00ab\u00a0classes moyennes\u00a0\u00bb sont actuellement la tarte \u00e0 la cr\u00e8me des journalistes, des politiques et des sociologues. Les derniers, plus cons\u00e9quents, s\u2019efforcent d\u2019en donner des d\u00e9finitions dont ils reconnaissent eux-m\u00eames l\u2019\u00e9quivoque. On se demande donc \u00e0 quel objectif peut bien correspondre l\u2019engouement pr\u00e9sent.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[421,4566,1391,45],"class_list":["post-80281","post","type-post","status-publish","format-standard","hentry","category-sociologie","tag-adam-smith","tag-autogestion","tag-classes-moyennes","tag-karl-marx"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/80281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=80281"}],"version-history":[{"count":8,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/80281\/revisions"}],"predecessor-version":[{"id":80323,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/80281\/revisions\/80323"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=80281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=80281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=80281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}