{"id":82163,"date":"2016-02-03T23:59:46","date_gmt":"2016-02-03T22:59:46","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=82163"},"modified":"2016-02-04T00:03:52","modified_gmt":"2016-02-03T23:03:52","slug":"lurgence-de-refonder-la-gauche-en-theorie-comme-en-pratique-par-david-dahomay","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2016\/02\/03\/lurgence-de-refonder-la-gauche-en-theorie-comme-en-pratique-par-david-dahomay\/","title":{"rendered":"L\u2019urgence de refonder la gauche, en th\u00e9orie comme en pratique, par David Dahomay"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9. \u00c9galement sur <a href=\"https:\/\/blogs.mediapart.fr\/david-dahomay\/blog\/020216\/lurgence-de-refonder-la-gauche-en-theorie-comme-en-pratique\" target=\"_blank\">son blog<\/a>. Ouvert aux commentaires.<\/p><\/blockquote>\n<p>L\u2019urgence de r\u00e9fl\u00e9chir, de comprendre. L\u2019urgence de \u00ab\u00a0penser o\u00f9 \u00e7a fait mal\u00a0\u00bb, de penser au bord de l\u2019ab\u00eeme (ab\u00eeme politique, moral, voire m\u00eame civilisationnel). L\u2019urgence de mettre des mots sur des maux. L\u2019urgence et le devoir imp\u00e9ratif de nous ressaisir, de r\u00e9sister, et de refonder la politique et la d\u00e9mocratie, en th\u00e9orie comme en pratique (\u00ab\u00a0<em>r\u00e9sister, c\u2019est cr\u00e9er<\/em>\u00a0\u00bb, St\u00e9phane Hessel).<\/p>\n<p><!--more--><\/p>\n<p>Telle est la t\u00e2che qui nous incombe d\u00e9sormais, nous citoyens de gauche en particulier, et citoyens \u00e9pris de libert\u00e9, d\u2019\u00e9galit\u00e9, de justice, d\u2019\u00e9cologie, et d\u2019humanisme en g\u00e9n\u00e9ral.<\/p>\n<p>\u00ab\u00a0La gauche peut mourir\u00a0\u00bb d\u00e9clarait en juin 2014 Manuel Valls. Quelle affligeante ironie. Cette phrase r\u00e9sonnerait-elle comme le d\u00e9sir (inconscient ?) d\u2019une proph\u00e9tie auto-r\u00e9alisatrice ? La question se pose en effet, tant Fran\u00e7ois Hollande et l\u2019actuel chef du Gouvernement n\u2019ont eu de cesse depuis 2012 de mettre \u00e0 mal, dans les mots et dans les actes, toutes les aspirations et les esp\u00e9rances individuelles et collectives de nombre de nos concitoyens. Jusqu\u2019\u00e0 tourner le dos, tout r\u00e9cemment, \u00e0 certains de nos grands principes d\u00e9mocratiques et r\u00e9publicains (je veux bien entendu parler de \u00ab\u00a0l\u2019\u00e9tat d\u2019exception permanent\u00a0\u00bb et de la d\u00e9ch\u00e9ance de la nationalit\u00e9 pour les binationaux, qu\u2019ils souhaitent, droits dans leurs bottes, inscrire dans la Constitution).<\/p>\n<p>Ils se sont ainsi appliqu\u00e9s \u00e0 mettre en \u0153uvre, nonobstant quelques d\u00e9cisions et r\u00e9formes pertinentes, \u00e0 peu pr\u00e8s tout le contraire de leurs engagements forts pris devant les Fran\u00e7ais durant la campagne pr\u00e9sidentielle, et tout particuli\u00e8rement en mati\u00e8re de politique \u00e9conomique.<\/p>\n<p>\u00ab\u00a0Mon v\u00e9ritable adversaire n\u2019a pas de nom, pas de visage, pas de parti. Il ne pr\u00e9sentera jamais sa candidature, il ne sera donc pas \u00e9lu. Et pourtant, il gouverne. Cet adversaire, c\u2019est le monde de la finance\u00a0\u00bb (Fran\u00e7ois Hollande au Bourget, le 22 janvier 2012). Ce jour-l\u00e0, certains d\u2019entre nous y ont cru, nous y avons honn\u00eatement cru, d\u2019autant plus qu\u2019il nous apparaissait que c\u2019\u00e9tait la premi\u00e8re fois en France qu\u2019un candidat \u00e0 la pr\u00e9sidentielle affirmait vouloir r\u00e9solument s\u2019attaquer \u00e0 \u00ab\u00a0l\u2019hydre mondiale\u00a0\u00bb incarn\u00e9e dans l\u2019oligopole bancaire mondial\u00a0; oligopole au c\u0153ur de la financiarisation globalitaire et \u00f4 combien mortif\u00e8re de l\u2019\u00e9conomie (la crise financi\u00e8re syst\u00e9mique de 2008 \u00e9tant de ce point de vue tr\u00e8s \u00e9difiante). Mais l\u2019orateur du Bourget y croyait-il vraiment\u00a0? Il est aujourd\u2019hui permis d\u2019en douter tr\u00e8s s\u00e9rieusement.<\/p>\n<p>Fran\u00e7ois Hollande ou la chronique \u00ab\u00a0d\u2019une \u00e9trange capitulation\u00a0\u00bb annonc\u00e9e\u00a0: celle de l\u2019abdication h\u00e2tive face \u00e0 l\u2019Allemagne, en renon\u00e7ant \u00e0 \u00ab\u00a0ren\u00e9gocier\u00a0\u00bb le pacte budg\u00e9taire europ\u00e9en, ratifi\u00e9 par la France d\u00e8s octobre 2012, et qui fut tr\u00e8s lourd de cons\u00e9quences pour notre pays en termes de politiques funestes d\u2019aust\u00e9rit\u00e9 (dont nous ne sommes toujours pas sortis, mais finirons-nous un jour par en sortir\u00a0?). Il aurait sans aucun doute fallu, de l\u2019avis \u00e9clair\u00e9 de nombreux \u00e9conomistes, mener une politique de relance de l\u2019activit\u00e9 \u00e9conomique, tant \u00e0 l\u2019\u00e9chelle europ\u00e9enne qu\u2019en France (\u00e0 l\u2019instar de celle men\u00e9e aux Etats-Unis).<\/p>\n<p>Celle de la capitulation devant les seuls int\u00e9r\u00eats du grand capitalisme mondial, sur l\u2019autel de nombreux ouvriers de l\u2019industrie, et ceux des hauts-fourneaux de Florange en particulier, malgr\u00e9 toutes les promesses ass\u00e9n\u00e9es \u2013 avec des tr\u00e9molos dans la voix \u2013 devant ces ouvriers durant la campagne pr\u00e9sidentielle. La proposition de l\u2019ex-ministre du Redressement productif, Arnaud Montebourg, qui consistait en\u00a0une nationalisation temporaire du site, \u00e9tait \u00e0 l\u2019\u00e9vidence la plus pertinente, mais c\u2019e\u00fbt \u00e9t\u00e9 symboliquement, pour Fran\u00e7ois Hollande et les quelques sociaux-lib\u00e9raux du Gouvernement (qui n\u2019ont de social que le nom), d\u00e9plaire trop fortement \u00e0 la doxa n\u00e9olib\u00e9rale.<\/p>\n<p>Celle du renoncement \u00e0 s\u00e9parer de fa\u00e7on efficiente les activit\u00e9s de banque de d\u00e9p\u00f4ts et de banque d\u2019investissement, sous la pression du lobby bancaire fran\u00e7ais (si tant est qu\u2019il y e\u00fbt vraiment pression), et de l\u2019adoption au final d\u2019une r\u00e9forme bancaire assez d\u00e9cevante au regard de ses grandes ambitions initiales. Et que dire en outre des n\u00e9gociations europ\u00e9ennes relatives \u00e0 la taxe sur les transactions financi\u00e8res (dite taxe Tobin), d\u00e9marr\u00e9es en 2011 et dont l\u2019entr\u00e9e en vigueur est sans cesse repouss\u00e9e aux calendes grecques (2017, nous dit-on), l\u00e0 encore pour ne pas d\u00e9plaire aux banques (et avec l\u2019\u00e9tonnante complaisance de Paris \u00e0 l\u2019\u00e9gard du lobby bancaire)\u00a0?<\/p>\n<p>Celle de l\u2019abandon de la grande r\u00e9forme fiscale (avec comme mesure phare la fusion de l\u2019imp\u00f4t sur le revenu et de la CSG), pourtant promise par Fran\u00e7ois Hollande avant la pr\u00e9sidentielle, annonc\u00e9e par l\u2019ex-Premier ministre Jean-Marc Ayrault en novembre 2013 (et qui avait fait rena\u00eetre une lueur d\u2019espoir parmi certains d\u2019entre nous), mais qu\u2019il n\u2019aura finalement pas l\u2019occasion de mettre en \u0153uvre (d\u00e9savou\u00e9 par l\u2019Elys\u00e9e, Ayrault quitte Matignon quelques mois plus tard). Face \u00e0 l\u2019explosion des in\u00e9galit\u00e9s en France, comme en Europe et dans le monde, et une r\u00e9partition toujours plus in\u00e9galitaire entre les revenus du travail et ceux du capital, c\u2019est pourtant une vraie \u00ab\u00a0r\u00e9volution fiscale\u00a0\u00bb qu\u2019il faudrait imp\u00e9rativement engager (voir sur ce point les propositions fort pertinentes port\u00e9es depuis tant\u00f4t par l\u2019\u00e9conomiste renomm\u00e9 Thomas Piketty), en vue d\u2019une v\u00e9ritable politique \u00ab\u00a0redistributive\u00a0\u00bb, seule \u00e0 m\u00eame de corriger ces criantes in\u00e9galit\u00e9s, autant insupportables socialement qu\u2019inacceptables moralement.<\/p>\n<p>Fran\u00e7ois Hollande s\u2019\u00e9tait engag\u00e9 durant la campagne pr\u00e9sidentielle \u00e0 taxer jusqu\u2019\u00e0 75 % les revenus sup\u00e9rieurs \u00e0 1 million d\u2019euro, \u00e0 supprimer les stock-options, \u00e0 encadrer les bonus des grands patrons, et \u00e0 limiter la r\u00e9mun\u00e9ration des dirigeants des grandes entreprises publiques de 1 \u00e0 20. Toutes ces promesses abandonn\u00e9es, et l\u2019ex-ministre de l\u2019Economie Pierre Moscovici d\u2019enfoncer le clou en mai 2013\u00a0: \u00ab Il n&rsquo;y aura pas de projet de loi sp\u00e9cifique sur la gouvernance d&rsquo;entreprise\u2026Nous pr\u00e9f\u00e9rons miser sur une autor\u00e9gulation exigeante\u00a0\u00bb. La messe est dite, dormez tranquille braves gens\u00a0!<\/p>\n<p>Celle enfin de la trahison face \u00e0 notre appartenance commune au socialisme et \u00e0 la gauche, sans nier pour autant la palette de nuances id\u00e9ologiques au sein de la famille socialiste\u00a0; trahison \u00e9tal\u00e9e au grand jour avec tambours et trompettes lors de la fameuse conf\u00e9rence de presse du 14 janvier 2014\u00a0: l\u2019annonce du Pacte de responsabilit\u00e9 et de la politique de l\u2019offre d\u00e9sormais ouvertement assum\u00e9e (\u00ab\u00a0l\u2019offre cr\u00e9e la demande\u00a0\u00bb, dixit Fran\u00e7ois Hollande, en r\u00e9f\u00e9rence \u00e0 l\u2019\u00e9conomiste du 18<sup>e<\/sup> si\u00e8cle Jean-Baptiste Say, dont les th\u00e8ses sont aujourd\u2019hui largement battues en br\u00e8che). Le prix Nobel d\u2019\u00e9conomie Paul Krugman n\u2019h\u00e9sita pas \u00e0 qualifier, \u00e0 juste titre, de \u00ab\u00a0scandaleux\u00a0\u00bb ce tournant assum\u00e9 par l\u2019ex\u00e9cutif fran\u00e7ais, avec la complicit\u00e9 passive (ou active) d\u2019une majorit\u00e9 de parlementaires de gauche.<\/p>\n<p>Un tournant qui avait en r\u00e9alit\u00e9 commenc\u00e9 d\u00e8s novembre 2012 avec la mise en place du CICE (cr\u00e9dit d\u2019imp\u00f4t pour la comp\u00e9titivit\u00e9 et l\u2019emploi), et dont le vice fondateur semble \u00eatre l\u2019absence de conditionnalit\u00e9 probante impos\u00e9e aux entreprises, en contrepartie des 20 milliards d\u2019euros par an consentis par l\u2019Etat pour baisser leurs charges. Et d\u2019autant que le bilan \u00e0 ce jour du CICE est pour le moins d\u00e9cevant au regard des objectifs initiaux d\u2019am\u00e9lioration de la comp\u00e9titivit\u00e9 des entreprises, en vue <em>in fine<\/em> de cr\u00e9er de l\u2019emploi (c\u2019est d\u2019abord le secteur de la restauration et de l\u2019h\u00f4tellerie qui en a b\u00e9n\u00e9fici\u00e9, alors qu\u2019il e\u00fbt sans doute fallu cibler essentiellement les secteurs et les cat\u00e9gories d\u2019entreprises r\u00e9ellement soumises \u00e0 la concurrence ext\u00e9rieure).<\/p>\n<p>Cette politique de l\u2019offre, tout enti\u00e8re arcbout\u00e9e sur la baisse du co\u00fbt du travail et sa flexibilit\u00e9 (facilit\u00e9 des licenciements et souplesse de la dur\u00e9e l\u00e9gale du travail avec la baisse de majoration des heures suppl\u00e9mentaires, envisag\u00e9s dans la r\u00e9forme \u00e0 venir du Code du travail) \u2013 politique n\u00e9olib\u00e9rale, dangereuse \u00e9conomiquement et socialement, et d\u2019un dogmatisme \u00e9cul\u00e9 \u2013, appara\u00eet d\u2019ores et d\u00e9j\u00e0 comme l\u2019oraison fun\u00e8bre de ce gouvernement de gauche (dont il est permis d\u2019ailleurs d\u2019\u00e9mettre les plus grandes r\u00e9serves quant \u00e0 sa r\u00e9elle appartenance aux valeurs de la gauche, et celles notamment de l\u2019aspiration au bien-\u00eatre pour tous).<\/p>\n<p>La droite dite r\u00e9publicaine, qui dans le fond n\u2019a pas grand-chose \u00e0 redire de cette politique n\u00e9olib\u00e9rale mise en place (et dont le renouvellement des id\u00e9es en son sein p\u00e2tit s\u00e9rieusement de ce triomphe du n\u00e9olib\u00e9ralisme pr\u00e9sent\u00e9, \u00e0 grands renforts m\u00e9diatiques, comme la seule alternative), aurait assur\u00e9ment appliqu\u00e9, \u00e0 peu de choses pr\u00e8s, la m\u00eame politique \u00e9conomique si elle avait \u00e9t\u00e9 au pouvoir. Comment d\u00e8s lors s\u2019\u00e9tonner du d\u00e9sarroi des citoyens qui, de plus en plus nombreux, n\u2019ont plus confiance en la politique (dans le sens o\u00f9 ils n\u2019en attendent plus rien), ne vont plus voter, ou plus inqui\u00e9tant encore, sont s\u00e9duits par les id\u00e9es de l\u2019extr\u00eame-droite\u00a0?<\/p>\n<p>A court terme, notamment pour relancer l\u2019activit\u00e9 \u00e9conomique int\u00e9rieure, tout porte \u00e0 croire que c\u2019est d\u2019abord une politique de la demande qu\u2019il faudrait privil\u00e9gier (revalorisations salariales, en particulier les bas salaires via l\u2019augmentation sensible du SMIC, baisse de la TVA, \u2026), tout en investissant beaucoup plus massivement dans l\u2019enseignement sup\u00e9rieur, la recherche et l\u2019innovation, pour ensemencer de nouveaux gisements d\u2019emplois \u00e0 moyen et long terme (et tout particuli\u00e8rement les \u00ab\u00a0emplois verts\u00a0\u00bb).<\/p>\n<p>Sous l\u2019effet conjugu\u00e9 de la lib\u00e9ralisation tous azimuts de l\u2019\u00e9conomie globalis\u00e9e et de l\u2019accumulation et de la concentration du capital dans les mains (ou plut\u00f4t les coffres-forts) des 1% les plus riches de la plan\u00e8te \u2013 et alors m\u00eame que jamais autant de richesses n\u2019avaient \u00e9t\u00e9 produites auparavant dans toute l\u2019histoire de l\u2019humanit\u00e9 \u2013, les in\u00e9galit\u00e9s sociales, la pr\u00e9carit\u00e9, et la pauvret\u00e9 explosent dans tous les pays industrialis\u00e9s (Thomas Piketty a parfaitement d\u00e9montr\u00e9 cela dans son livre <em>Le Capital au XXIe si\u00e8cle\u00a0<\/em>; voir aussi le rapport de l\u2019OCDE de 2015 mettant en avant le niveau sans pr\u00e9c\u00e9dent des in\u00e9galit\u00e9s qui, selon cette organisation, nuisent \u00e0 la croissance). Sans compter les souffrances et le mal-\u00eatre au travail, d\u2019une ampleur in\u00e9dite, et qui pourtant ne semblent pas \u00e9mouvoir, outre mesure, nos d\u00e9cideurs politiques.<\/p>\n<p>Or seule une politique volontariste de l\u00e9gif\u00e9ration, de r\u00e9gulation et de redistribution (notamment par la fiscalit\u00e9, on l\u2019a dit), permettrait d\u2019enrayer la mont\u00e9e de ces in\u00e9galit\u00e9s en France, en Europe, et dans le monde. Au lieu de cela, le gouvernement Hollande s\u2019ent\u00eate dans l\u2019erreur, autiste aux maux dont souffre le peuple fran\u00e7ais dans son immense majorit\u00e9, et s\u2019acharne \u00e0 vouloir baisser le co\u00fbt du travail (aux cons\u00e9quences sociales d\u00e9sastreuses), pour pr\u00e9tendument rendre la France plus comp\u00e9titive sur le march\u00e9 europ\u00e9en et international concurrentiel (comme si la concurrence entre \u00c9tats au sein de la zone euro \u00e9tait souhaitable, voire m\u00eame \u00e9conomiquement pertinente. C\u2019est une politique de coop\u00e9ration et de solidarit\u00e9 qu\u2019il faudrait sans tarder op\u00e9rer en Europe, mais au lieu de cela, nous laissons l\u2019Allemagne poursuivre sa politique d\u2019exc\u00e9dents commerciaux aux d\u00e9pens de tous, y compris d\u2019elle-m\u00eame, du moins \u00e0 long terme). En outre, comment pourrions-nous une seconde envisager un jour d\u2019avoir une main-d\u2019\u0153uvre en France, aussi \u00ab\u00a0comp\u00e9titive\u00a0\u00bb que celle des pays \u00e9mergents tels que la Chine et l\u2019Inde, si ce n\u2019est en g\u00e9n\u00e9ralisant, <em>manu militari <\/em>(car cela ne serait r\u00e9alisable qu\u2019\u00ab\u00a0apr\u00e8s la d\u00e9mocratie\u00a0\u00bb), une baisse massive des salaires et en produisant une arm\u00e9e de sous-prol\u00e9taires ? Ce \u00e0 quoi r\u00eave bien entendu le grand capitalisme mondial (en attendant que la machine ne remplace d\u00e9finitivement l\u2019Homme, et dont l\u2019existence deviendra alors totalement superflue).<\/p>\n<p>C\u2019est pourquoi Emmanuel Todd et d\u2019autres ont raison de pr\u00f4ner un certain \u00ab\u00a0protectionnisme europ\u00e9en\u00a0\u00bb, sans qu\u2019ils ne soient d\u2019embl\u00e9e tax\u00e9s de dangereux nationalistes. Ce serait \u00e0 l\u2019\u00e9vidence une erreur de laisser \u00e0 l\u2019extr\u00eame-droite le monopole de ces probl\u00e9matiques, tellement importantes si l\u2019on souhaite r\u00e9ellement retrouver une certaine prosp\u00e9rit\u00e9 en Europe et en France. De m\u00eame, la question du maintien de la France au sein de la zone euro m\u00e9rite plus que jamais d\u2019\u00eatre d\u00e9battue \u00e0 gauche, tant les bases id\u00e9ologiques \u2013 <em>l\u2019ordolib\u00e9ralisme<\/em>\u00a0 allemand \u2013 qui ont pr\u00e9sid\u00e9 \u00e0 la construction de l\u2019euro (et en particulier l\u2019ind\u00e9pendance totale de la Banque centrale europ\u00e9enne (BCE), hors de toute volont\u00e9 et de tout contr\u00f4le d\u00e9mocratiques) semblent de plus en plus incompatibles avec une prosp\u00e9rit\u00e9 \u00e9conomique et sociale en Europe, et dont tout porte \u00e0 croire qu\u2019elles servent avant tout les int\u00e9r\u00eats allemands, au d\u00e9triment de toute solidarit\u00e9 europ\u00e9enne. Aussi, force est d\u2019admettre que Jean-Luc M\u00e9lenchon a raison de poser la question du \u00ab\u00a0plan B\u00a0\u00bb, dans le cas o\u00f9 la \u00ab\u00a0nouvelle gauche fran\u00e7aise\u00a0\u00bb (ni social-lib\u00e9rale, ni \u00e0 l\u2019extr\u00eame-gauche marxiste) que nous appelons de nos v\u0153ux, prendrait le pouvoir en 2017, avec pour mandat explicite de ren\u00e9gocier les trait\u00e9s europ\u00e9ens (et d\u2019envisager le \u00ab\u00a0plan B\u00a0\u00bb \u2013 la sortie de la zone euro \u2013 en cas d\u2019\u00e9chec des n\u00e9gociations, et le passage alors \u00e0 une monnaie commune en lieu et place d\u2019une monnaie unique\u00a0; voir sur ce point les propositions pertinentes de l\u2019\u00e9conomiste Jacques Sapir).<\/p>\n<p>Mais \u00e0 y regarder de plus pr\u00e8s, ce que nous vivons actuellement, c\u2019est une crise syst\u00e9mique majeure, mise \u00e0 nu avec la crise financi\u00e8re et \u00e9conomique de 2008, et qui ne serait autre que la crise cr\u00e9pusculaire du capitalisme lui-m\u00eame (ce que semblent ne pas voir ou comprendre la plupart de nos dirigeants actuels, malgr\u00e9 toutes les alertes lanc\u00e9es par nombre d\u2019intellectuels, d\u2019\u00e9conomistes, de scientifiques, de philosophes, d\u2019historiens, ou de citoyens clairvoyants et engag\u00e9s). Un capitalisme d\u00e9sormais enti\u00e8rement financiaris\u00e9 et sp\u00e9culatif (une \u00ab\u00a0\u00e9conomie-casino\u00a0\u00bb), totalement d\u00e9connect\u00e9 de l\u2019\u00e9conomie r\u00e9elle et des besoins sociaux et soci\u00e9taux. \u00ab Un capitalisme mis \u00e0 mort par ses sp\u00e9culateurs m\u00eames \u00bb (Marcel Duchamp, <em>La Mari\u00e9e mise \u00e0 nu par ses c\u00e9libataires, m\u00eame<\/em>). Sans doute que m\u00eame Marx n\u2019y retrouverait pas ses petits.<\/p>\n<p>C\u2019est peut-\u00eatre aussi autant une crise syst\u00e9mique qu\u2019une v\u00e9ritable \u00ab\u00a0mutation civilisationnelle\u00a0\u00bb, et dont il convient co\u00fbte que co\u00fbte d\u2019en prendre toute la mesure et de s\u2019y pr\u00e9parer (visiblement sans l\u2019aide de nos d\u00e9cideurs, dont c\u2019est pourtant avant tout l\u2019imp\u00e9rieuse responsabilit\u00e9). La nouvelle crise financi\u00e8re et \u00e9conomique qui est d\u00e9sormais \u00e0 nos portes, pourrait bien \u00eatre pire que celle de 1929 (voir sur ce point l\u2019analyse de plusieurs \u00e9conomistes \u00e9clair\u00e9s, notamment l\u2019\u00e9conomiste-sociologue Paul Jorion, et qui pr\u00e9conise l\u2019interdiction de la sp\u00e9culation\u00a0; mesure qui nous semble au final des plus pertinentes, eu \u00e9gard aux p\u00e9rils qui menacent nos soci\u00e9t\u00e9s humaines).<\/p>\n<p>D\u00e9j\u00e0 en 1972, des chercheurs am\u00e9ricains du MIT, sous la direction de Dennis Meadows, avaient publi\u00e9 un rapport rendu c\u00e9l\u00e8bre, <em>The Limits to Growth <\/em>(Les Limites \u00e0 la Croissance), command\u00e9 par le fameux Club de Rome, et qui pr\u00e9disait ni plus ni moins qu\u2019un \u00ab\u00a0effondrement\u00a0\u00bb \u00e9conomique et social g\u00e9n\u00e9ralis\u00e9 \u00e0 l\u2019\u00e9chelle plan\u00e9taire (pronostics obtenus par des simulations math\u00e9matiques et informatiques complexes \u00e0 partir de variables rendant compte des activit\u00e9s humaines et de l\u2019\u00e9volution d\u00e9mographique, et r\u00e9\u00e9valu\u00e9s par diff\u00e9rents chercheurs \u00e0 plusieurs reprises depuis). Ce rapport concluait sur l\u2019urgence de changer de mod\u00e8le de d\u00e9veloppement pour \u00e9viter le pire, et notamment des d\u00e9sastres \u00e9cologiques irr\u00e9parables (nous connaissons la suite, ce rapport fut accueilli \u00e0 l\u2019\u00e9poque avec scepticisme par nos dirigeants).<\/p>\n<p>De nombreux \u00e9conomistes de renom n\u2019ont cess\u00e9 de nous mettre en garde sur les limites de la croissance, et sur le fait qu\u2019il serait illusoire et m\u00eame dangereux d\u2019esp\u00e9rer revenir \u00e0 des niveaux de croissance dans les pays industrialis\u00e9s (aujourd\u2019hui post-industriels), comparables \u00e0 ceux que nous avons connus durant les Trente Glorieuses (p\u00e9riode que nous pourrions consid\u00e9rer comme le \u00ab\u00a0rattrapage\u00a0\u00bb des destructions massives survenues durant la Seconde Guerre mondiale et des sauts technologiques op\u00e9r\u00e9s). Nous pourrions ainsi citer p\u00eale-m\u00eale Robert J. Gordon, Thomas Piketty, Daniel Cohen, Jean Gadrey, Dominique M\u00e9da, Olivier Berruyer, et bien d\u2019autres. La plupart pr\u00e9voient pour les ann\u00e9es \u00e0 venir des taux moyens de croissance de 0,5 \u00e0 1% (en \u00e9tant optimistes), bien loin des 3% qui seraient n\u00e9cessaires pour significativement inverser la courbe du ch\u00f4mage.<\/p>\n<p>Nous sommes devant une aporie inou\u00efe\u00a0: \u00ab\u00a0Le monde est clos et le d\u00e9sir infini\u00a0\u00bb (Daniel Cohen). Il va pourtant bien falloir s\u2019atteler \u00e0 la r\u00e9soudre, et il y a urgence car notre maison plan\u00e9taire commence \u00e0 l\u2019\u00e9vidence \u00e0 s\u2019embraser, et nous n\u2019aurons pas le temps de d\u00e9velopper la technologie nous permettant de coloniser Mars. Voil\u00e0 ce \u00e0 quoi doit sans tarder se d\u00e9vouer la \u00ab\u00a0nouvelle gauche fran\u00e7aise\u00a0\u00bb, et des pistes existent d\u2019ores et d\u00e9j\u00e0.<\/p>\n<p>La fin de la \u00ab\u00a0glorieuse croissance\u00a0\u00bb et les progr\u00e8s technologiques consid\u00e9rables cumul\u00e9s (l\u2019intelligence artificielle, la robotisation, l\u2019imprimante 3D, le \u00ab\u00a0Tout-num\u00e9rique\u00a0\u00bb et Internet), ont produit un monde de raret\u00e9 du travail, dont nous n\u2019avons pas encore pris toute la mesure (il faut bien admettre aujourd\u2019hui que d\u00e9j\u00e0 en 1995, J\u00e9r\u00e9my Rifkin avait vu juste, dans son livre <em>La fin du travail<\/em>, pr\u00e9fac\u00e9 dans sa traduction fran\u00e7aise par Michel Rocard). D\u2019ailleurs, les \u00ab\u00a0hollandistes\u00a0\u00bb sociaux-lib\u00e9raux s\u2019\u00e9vertuent, tels des h\u00e9r\u00e9tiques, \u00e0 croire \u2013 et \u00e0 nous faire croire \u2013 qu\u2019ils feront revenir la croissance \u00e0 des niveaux suffisants permettant d\u2019enrayer la mont\u00e9e inexorable du ch\u00f4mage.<\/p>\n<p>La croissance ne reviendra pas \u2013 du moins pas \u00e0 des niveaux suffisants, et d\u2019ailleurs il ne serait pas sain pour l\u2019\u00e9cologie qu\u2019elle revienne \u2013, et le travail se fera de plus en plus rare (difficile en effet de lutter contre les progr\u00e8s technologiques, qui sont d\u2019ailleurs cens\u00e9s nous \u00e9manciper des activit\u00e9s \u00e9prouvantes). Qu\u2019on se le dise, une bonne fois pour toute\u00a0!<\/p>\n<p>D\u00e8s lors, que faire\u00a0? Si le travail est rare, nous devons \u00e0 l\u2019\u00e9vidence commencer par le partager. C\u2019\u00e9tait toute la vertu originelle des \u00ab\u00a035 heures\u00a0\u00bb mises en place sous le gouvernement Jospin, et qu\u2019aujourd\u2019hui Manuel Valls et surtout Emmanuel Macron, s\u2019acharnent \u00e0 vouloir d\u00e9truire, au nom de la doxa n\u00e9olib\u00e9rale. Contrairement \u00e0 une propagande savamment orchestr\u00e9e par un certain grand patronat, les \u00ab\u00a035 heures\u00a0\u00bb ont, non seulement contribu\u00e9 \u00e0 am\u00e9liorer la productivit\u00e9 horaire en France (l\u2019une des plus \u00e9lev\u00e9es d\u2019Europe), mais ont aussi et surtout permis de cr\u00e9er un nombre significatif d\u2019emplois. Il faut souhaiter qu\u2019un rapport d\u2019\u00e9valuation objectif et ind\u00e9pendant sur ce dispositif, voie enfin le jour.<\/p>\n<p>Michel Rocard et Pierre Larrouturou pr\u00e9conisent m\u00eame la semaine \u00e0 4 jours. Cela nous semble une avanc\u00e9e et une piste int\u00e9ressantes, que la gauche (ou les gauches) devrai(en)t d\u00e9battre sans tarder. Concomitamment, il conviendrait aussi sans doute de r\u00e9fl\u00e9chir \u00e0 l\u2019id\u00e9e d\u2019un \u00ab\u00a0revenu universel\u00a0\u00bb, mis en \u0153uvre \u00e0 l\u2019aune de \u00ab\u00a0la troisi\u00e8me r\u00e9volution industrielle\u00a0\u00bb et de \u00ab\u00a0la nouvelle soci\u00e9t\u00e9 du co\u00fbt marginal z\u00e9ro\u00a0\u00bb pr\u00e9conis\u00e9es par J\u00e9r\u00e9my Rifkin, et que certains auraient sans doute tort de prendre pour un na\u00eff utopique. \u00ab\u00a0Revenu universel\u00a0\u00bb que le Conseil national du num\u00e9rique pr\u00e9conise dans un r\u00e9cent rapport, et que la Finlande s\u2019appr\u00eaterait \u00e0 exp\u00e9rimenter.<\/p>\n<p>Il conviendrait en outre de d\u00e9battre d\u2019une nouvelle gouvernance d\u2019entreprise (fin des stock-options, limitation des r\u00e9mun\u00e9rations des dirigeants, r\u00e8glementations pour un actionnariat responsable, \u2026), et d\u2019une nouvelle \u00e9thique de l\u2019entrepreneuriat et du capitalisme, bas\u00e9e notamment sur les principes de l\u2019\u00e9conomie sociale et solidaire. L\u2019\u00e9conomie collaborative \u2013 et l\u2019av\u00e8nement des plateformes num\u00e9riques \u2013, devraient \u00e0 l\u2019\u00e9vidence \u00eatre davantage \u00e9tudi\u00e9es et explor\u00e9es, tout en \u00e9vitant les \u00e9cueils de \u00ab\u00a0l\u2019ub\u00e9risation\u00a0\u00bb.<\/p>\n<p>Nous ne sommes pas de dangereux r\u00e9volutionnaires robespierristes, mais au vu de l\u2019urgence sociale, \u00e9cologique, \u00e9conomique, et d\u00e9mocratique, il est l\u2019heure d\u2019\u00eatre radical (\u00ab\u00a0\u00e0 vouloir \u00e9touffer les r\u00e9volutions pacifiques, on rend in\u00e9vitables les r\u00e9volutions violentes\u00a0\u00bb, J. F. Kennedy). L\u2019heure d\u2019une r\u00e9volution d\u00e9mocratique a d\u00e9sormais sonn\u00e9 (celle de l\u2019av\u00e8nement de la <em>d\u00e9mocratie d\u2019exercice<\/em> (repenser les relations gouvernants-gouvern\u00e9s), telle que brillamment expos\u00e9e par l\u2019historien-sociologue Pierre Rosanvallon, dans son livre <em>Le Bon Gouvernement<\/em>).<\/p>\n<p>Le temps est sans doute aussi venu de retrouver \u00ab\u00a0le sens de la R\u00e9publique\u00a0\u00bb et d\u2019invoquer l\u2019h\u00e9ritage des Lumi\u00e8res, en ces temps consum\u00e9ristes, troubl\u00e9s et obscurs, o\u00f9 nous perdons peu \u00e0 peu le sens de toute chose, et tout particuli\u00e8rement le sens moral (\u00ab\u00a0Kant, \u00f4 Kant, pourquoi nous as-tu abandonn\u00e9s\u00a0?\u00a0\u00bb).<\/p>\n<p>Un Dennis Meadows, un Yanis Varoufakis, ou un Pierre Rabhi, sont susceptibles d\u2019\u00e9branler la marche ubuesque du monde, bien plus que ne le pourront jamais Fran\u00e7ois Hollande, Manuel Valls, et Emmanuel Macron (ce \u00ab\u00a0golden boy [m\u00e9diatique] du hollandisme cr\u00e9pusculaire\u00a0\u00bb).<\/p>\n<p>N\u2019en d\u00e9plaise \u00e0 Manuel Valls, la gauche n\u2019est pas morte. \u00ab\u00a0Elle est m\u00eame bien vivante la gauche\u00a0!\u00a0\u00bb (Pierre Joxe). Par contre, il se pourrait que le Parti socialiste ne survive pas \u00e0 ce hollandisme finissant. Serait-il m\u00eame souhaitable qu\u2019il survive\u00a0? La question reste enti\u00e8re.<\/p>\n<p>En tout cas, d\u00e9sormais, le Parti socialiste, ce sera sans moi. Et mes amis et mes camarades du PS qui croient encore, vaille que vaille, pouvoir r\u00e9former ce parti de l\u2019int\u00e9rieur, seraient bien avis\u00e9s d\u2019y renoncer \u2013 c\u2019est peine perdue \u2013, et de mobiliser leur \u00e9nergie pour refonder une nouvelle gauche fran\u00e7aise, r\u00e9publicaine, sociale, et \u00e9cologiste.<\/p>\n<p>L\u2019urgence absolue, ce n\u2019est donc pas de savoir si Hollande et le PS accepteront d\u2019organiser des primaires \u00e0 gauche pour la pr\u00e9sidentielle de 2017. L\u2019urgence absolue, c\u2019est de cr\u00e9er de toutes pi\u00e8ces un nouveau parti politique, d\u2019ici cet \u00e9t\u00e9, et issu tr\u00e8s largement de la soci\u00e9t\u00e9 civile (dans toutes ses composantes). Parti qui rassemblerait, si possible, les diff\u00e9rentes sensibilit\u00e9s de la gauche fran\u00e7aise et des \u00e9cologistes, sur des bases th\u00e9oriques et id\u00e9ologiques commun\u00e9ment partag\u00e9es.<\/p>\n<p>Et seulement \u00e0 partir de l\u00e0, nous pourrions envisager des primaires \u00e0 gauche, une fois rassembl\u00e9s autour de valeurs communes, et de ce nouveau parti politique. Nous voyons poindre d\u00e9j\u00e0 de nombreux candidats potentiels et talentueux\u00a0: Arnaud Montebourg, Christiane Taubira, Jean-Luc M\u00e9lenchon, C\u00e9cile Duflot, Marie-No\u00eblle Linemann, Barbara Romagnan, Christian Paul, et bien d\u2019autres. Avec le risque in\u00e9vitable d\u2019une bataille d\u2019\u00e9go d\u00e9mobilisatrice, au d\u00e9triment des id\u00e9es et d\u2019une vraie refondation de la gauche.<\/p>\n<p>C\u2019est pourquoi pour ma part, j\u2019aurais plut\u00f4t pl\u00e9biscit\u00e9 une personnalit\u00e9 neuve, \u00ab\u00a0anti-syst\u00e8me\u00a0\u00bb, et issue de la soci\u00e9t\u00e9 civile. Apr\u00e8s m\u00fbre r\u00e9flexion, il est probable que Paul Jorion ait vu juste\u00a0: l\u2019\u00e9conomiste Thomas Piketty serait sans doute le mieux \u00e0 m\u00eame de f\u00e9d\u00e9rer toutes ces personnalit\u00e9s, et toutes les sensibilit\u00e9s autour de sa personne. Il incarnerait \u00e0 l\u2019\u00e9vidence, une nouvelle esp\u00e9rance pour la gauche, pour la France, pour l\u2019Europe, et pour le monde.<\/p>\n<p>Quant \u00e0 Fran\u00e7ois Hollande, sa proposition d\u2019inscrire dans la Constitution \u00ab\u00a0l\u2019\u00e9tat d\u2019urgence\u00a0\u00bb ainsi que la d\u00e9ch\u00e9ance de la nationalit\u00e9 pour les binationaux (quand bien m\u00eame cette r\u00e9f\u00e9rence aux binationaux ne serait plus explicite mais implicite), constitue \u00e0 l\u2019\u00e9vidence \u00ab\u00a0l\u2019infamie\u00a0\u00bb de trop, \u00ab\u00a0l\u2019ultime rupture\u00a0\u00bb. Tout a \u00e9t\u00e9 dit sur cette \u00ab\u00a0lep\u00e9nisation\u00a0des esprits \u00bb, qui a fini m\u00eame par corrompre le c\u0153ur du pouvoir \u00ab\u00a0socialiste\u00a0\u00bb. Je citerai n\u00e9anmoins cette phrase magnifique de l\u2019\u00e9crivain Patrick Chamoiseau\u00a0:<\/p>\n<p>\u00ab\u00a0<em>Les nationalit\u00e9s r\u00e9vocables dessinent en France un effondrement \u00e9thique d\u2019une ampleur sid\u00e9rante. Une ind\u00e9cence majeure qu\u2019aucun b\u00e9n\u00e9fice politicien ne saurait justifier. De tr\u00e8s vieilles ombres sont de retour et nous fixent sans trembler.<\/em> \u00bb<\/p>\n<p>Et comme en \u00e9cho \u00e0 Christiane Taubira\u00a0: \u00ab\u00a0<em>Il n\u2019est pas question de livrer le monde aux assassins d\u2019aube<\/em>\u00a0\u00bb\u00a0! (Aim\u00e9 C\u00e9saire).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. \u00c9galement sur son blog. Ouvert aux commentaires. L\u2019urgence de r\u00e9fl\u00e9chir, de comprendre. L\u2019urgence de \u00ab\u00a0penser o\u00f9 \u00e7a fait mal\u00a0\u00bb, de penser au bord de l\u2019ab\u00eeme (ab\u00eeme politique, moral, voire m\u00eame civilisationnel). L\u2019urgence de mettre des mots sur des maux. L\u2019urgence et le devoir imp\u00e9ratif de nous ressaisir, de r\u00e9sister, et de refonder la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2597,17],"tags":[1715,3084,4671,1360,1789,1263],"class_list":["post-82163","post","type-post","status-publish","format-standard","hentry","category-democratie-2","category-politique","tag-francois-hollande","tag-manuel-valls","tag-primaire-a-gauche","tag-ps","tag-socialisme","tag-thomas-piketty"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/82163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=82163"}],"version-history":[{"count":3,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/82163\/revisions"}],"predecessor-version":[{"id":82166,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/82163\/revisions\/82166"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=82163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=82163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=82163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}