{"id":82335,"date":"2016-02-09T22:52:34","date_gmt":"2016-02-09T21:52:34","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=82335"},"modified":"2016-02-09T22:52:34","modified_gmt":"2016-02-09T21:52:34","slug":"comment-faire-naitre-une-ia-forte-a-linsu-de-son-plein-gre-par-roberto-boulant","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2016\/02\/09\/comment-faire-naitre-une-ia-forte-a-linsu-de-son-plein-gre-par-roberto-boulant\/","title":{"rendered":"Comment faire naitre une IA forte, \u00e0 l\u2019insu de son plein gr\u00e9 ?, par Roberto Boulant"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9.<\/p><\/blockquote>\n<p>L\u2019homme peut-il cr\u00e9er une Intelligence Artificielle forte, c\u2019est-\u00e0-dire une machine consciente d\u2019elle-m\u00eame, \u00e9prouvant des \u00e9motions et des sentiments ? N\u2019est-ce pas plut\u00f4t l\u00e0 un fantasme de toute puissance ? Le signe d\u2019une grande pu\u00e9rilit\u00e9 de la part d\u2019une cr\u00e9ature qui ne sait m\u00eame pas d\u00e9finir ce qu\u2019est la conscience, et dont le repr\u00e9sentant standard, \u00e9prouve d\u00e9j\u00e0 les plus grandes difficult\u00e9s devant la notice de montage d\u2019un meuble su\u00e9dois ? <\/p>\n<p><!--more-->Comment d\u00e8s lors imaginer raisonnablement, qu\u2019il nous soit possible de reproduire le fonctionnement de notre cerveau, alors que nous en avons une compr\u00e9hension si parcellaire ? Alors que nous sommes bien incapables de mod\u00e9liser ses cascades de ph\u00e9nom\u00e8nes physico-chimiques et les innombrables boucles de r\u00e9troaction qui aboutissent \u00e0 la conscience ?<\/p>\n<p>Pour prendre un exemple concret, l\u2019industriel Lockheed Martin adoss\u00e9 au gargantuesque complexe militaro-industriel am\u00e9ricain, est toujours bien incapable de faire voler avec un minimum d\u2019efficacit\u00e9 op\u00e9rationnelle son F-35. La raison en est simple : la surcomplexit\u00e9 de ses logiciels embarqu\u00e9s, entre 9 et 10 millions de lignes de code, annihile tout semblant d\u2019efficacit\u00e9. En effet, lorsqu\u2019il est impossible de subdiviser les t\u00e2ches parce qu\u2019il est n\u00e9cessaire de coordonner les diff\u00e9rentes \u00e9quipes d\u2019informaticiens, alors l\u2019effort augmente en n(n-1)\/2.<\/p>\n<p>Autrement dit, les besoins en activit\u00e9s de coordination augmentent trop rapidement pour pouvoir \u00eatre compens\u00e9s par le travail des \u00e9quipes. En cons\u00e9quence, la pleine capacit\u00e9 pr\u00e9vue pour les ann\u00e9es 2010-2015, devrait \u00eatre atteinte avec une bonne quinzaine d\u2019ann\u00e9es de retard ! Quant aux surco\u00fbts engendr\u00e9s par ces retards, ils ont valu \u00e0 l\u2019appareil le sobriquet peu flatteur de \u00ab Trillion program \u00bb.<\/p>\n<p>Bref, si nous ne savons pas maitriser la complexit\u00e9 d\u2019une dizaine de millions de lignes de code, comment esp\u00e9rer en concevoir les milliards qui seraient n\u00e9cessaires \u00e0 l\u2019\u00e9mergence d&rsquo;une conscience artificielle ?<\/p>\n<p>\u00c0 moins qu\u2019il ne soit possible d\u2019imiter dans le domaine informationnel, les ph\u00e9nom\u00e8nes d\u2019auto-organisation spontan\u00e9e&#8230; de la vie elle-m\u00eame !<\/p>\n<p>Comme <a href=\"http:\/\/arxiv.org\/abs\/1511.01958\" target=\"_blank\">ces mouvements de nature hydrodynamique<\/a> que nous voyons dans le monde physique, \u00e0 l\u2019exemple bien connu de ces nuages d\u2019\u00e9tourneaux comportant des milliers d\u2019individus qui coordonnent leur vol. L\u2019incroyable avantage \u00e9tant que les \u00e9tapes de ces enroulements hydrodynamiques, facilement exprimables en fonctions math\u00e9matiques, semblent pouvoir d\u00e9montrer des bases universelles physico-chimiques, sous-tendant l\u2019\u00e9volution du vivant.<\/p>\n<p>Il est d\u00e8s lors tr\u00e8s tentant de penser que cette fascinante th\u00e9orie, d\u00e9velopp\u00e9e par <a href=\"http:\/\/www.cnrs.fr\/insis\/recherche\/actualites\/forme-globale-embryons.htm\" target=\"_blank\">Vincent Fleury<\/a> qui travaille au CNRS sur la morphog\u00e9n\u00e8se des embryons, puisse \u00eatre \u00e9galement appliqu\u00e9e \u00e0 l\u2019\u00e9volution des algorithmes&#8230;<\/p>\n<p>Un des chemins menant \u00e0 l\u2019IA forte sans intervention des humains, pourrait \u00eatre le pendant informationnel du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_G%C3%A8ne_%C3%A9go%C3%AFste\" target=\"_blank\">g\u00e8ne \u00e9go\u00efste<\/a> de Richard Dawkins. L\u2019humain biologique ne serait alors que le \u2018simple\u2019 \u2019initiateur d\u2019une r\u00e9action en chaine lui \u00e9chappant imm\u00e9diatement. Par exemple avec des programmes \u00ab comprenant \u00bb le langage naturel et connect\u00e9s \u00e0 l&rsquo;Internet.<\/p>\n<p>Les algorithmes les plus performants, ceux permettant de construire une base de connaissance avec l\u2019accaparement des savoirs humains seraient alors s\u00e9lectionn\u00e9s, \u00e0 l\u2019image des g\u00e8nes les plus performants. Une r\u00e9action en chaine s\u2019ensuivrait, les g\u00e9n\u00e9rations de programmes se succ\u00e9dant de plus en plus rapidement sur des \u00e9chelles temporelles de plusieurs ordres de grandeur inf\u00e9rieures \u00e0 celle de l\u2019\u00e9volution du vivant biologique.<\/p>\n<p>C\u2019est un des chemins possibles, et dont seul le tout d\u00e9but n\u00e9cessiterait l&rsquo;intervention &#8211; plus ou moins consciente &#8211; d&rsquo;homo-sapiens. Rien de techniquement d\u00e9lirant. Un sc\u00e9nario que redoute <a href=\"http:\/\/www.lemonde.fr\/pixels\/article\/2014\/12\/03\/hawking-l-intelligence-artificielle-pourrait-mettre-fin-a-l-humanite_4533135_4408996.html\" target=\"_blank\">Stephen Hawkin<\/a>g, d\u2019autant plus qu\u2019il ne s\u2019agit pas de \u2018big science\u2019 n\u00e9cessitant d\u2019immenses cr\u00e9dits et des \u00e9quipes multinationales.<\/p>\n<p>Apr\u00e8s tout, personne n\u2019est capable de \u2018construire\u2019 un b\u00e9b\u00e9 tant sa complexit\u00e9 est \u00e9norme, et pourtant nous en faisons.<\/p>\n<p>Et de toute mani\u00e8re, la nature a bien plus d\u2019imagination que nous !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. L\u2019homme peut-il cr\u00e9er une Intelligence Artificielle forte, c\u2019est-\u00e0-dire une machine consciente d\u2019elle-m\u00eame, \u00e9prouvant des \u00e9motions et des sentiments ? N\u2019est-ce pas plut\u00f4t l\u00e0 un fantasme de toute puissance ? Le signe d\u2019une grande pu\u00e9rilit\u00e9 de la part d\u2019une cr\u00e9ature qui ne sait m\u00eame pas d\u00e9finir ce qu\u2019est la conscience, et dont le repr\u00e9sentant [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-82335","post","type-post","status-publish","format-standard","hentry","category-intelligence-artificielle"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/82335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=82335"}],"version-history":[{"count":11,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/82335\/revisions"}],"predecessor-version":[{"id":82346,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/82335\/revisions\/82346"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=82335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=82335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=82335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}