{"id":83297,"date":"2016-03-10T09:00:39","date_gmt":"2016-03-10T08:00:39","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=83297"},"modified":"2016-03-10T09:31:22","modified_gmt":"2016-03-10T08:31:22","slug":"vos-guerres-sont-nos-benefices-par-roberto-boulant","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2016\/03\/10\/vos-guerres-sont-nos-benefices-par-roberto-boulant\/","title":{"rendered":"\u00ab\u00a0Vos guerres sont nos b\u00e9n\u00e9fices !\u00a0\u00bb, par Roberto Boulant"},"content":{"rendered":"<blockquote><p>Billet invit\u00e9.<\/p><\/blockquote>\n<p>\u00c0 l\u2019heure o\u00f9 le projet de loi El Khomri d\u00e9truit les acquis sociaux pour mieux les prot\u00e9ger, force est de constater qu\u2019il n\u2019y a pas que sur la sc\u00e8ne politique int\u00e9rieure que l\u2019\u00e9cart entre les paroles et les actes devient abyssal, c\u2019est \u00e9galement le cas dans le monde merveilleux des ventes d\u2019armes. Je dis merveilleux, parce que notre pays a ratifi\u00e9 pratiquement tous les trait\u00e9s et accords internationaux encadrant ce commerce, m\u00eame ceux aux crit\u00e8res les plus restrictifs.<\/p>\n<p><!--more--><\/p>\n<p>Officiellement les choses sont donc d\u2019une limpidit\u00e9 aveuglante : <strong>les armes n\u2019\u00e9tant pas des marchandises comme les autres<\/strong>, leurs exportations sont soumises aux crit\u00e8res les plus drastiques.<!--more--><\/p>\n<p>&#8211; Dans le cadre national, la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Commission_interminist%C3%A9rielle_pour_l'%C3%A9tude_des_exportations_de_mat%C3%A9riel_de_guerre\">CIEEMG<\/a> (Commission interminist\u00e9rielle pour l&rsquo;\u00e9tude des exportations de mat\u00e9riel de guerre) donne, ou non, son accord apr\u00e8s le vote des repr\u00e9sentants de trois minist\u00e8res r\u00e9galiens (Affaires \u00e9trang\u00e8res, D\u00e9fense, \u00c9conomie et finances), et apr\u00e8s consultation des repr\u00e9sentants du minist\u00e8re de l&rsquo;Enseignement sup\u00e9rieur et de la Recherche, de l&rsquo;Int\u00e9rieur, des services de renseignement, du cabinet du Premier ministre, et enfin de l&rsquo;\u00c9tat-major particulier du pr\u00e9sident de la R\u00e9publique. Fermez le ban ! Le tout conform\u00e9ment \u00e0 <a href=\"https:\/\/www.legifrance.gouv.fr\/affichTexte.do?cidTexte=JORFTEXT000026088164&amp;categorieLien=id\">l\u2019arr\u00eat\u00e9 du 27\/06\/2012<\/a> d\u00e9finissant tr\u00e8s pr\u00e9cis\u00e9ment la liste des mat\u00e9riels de guerre et assimil\u00e9s, soumis \u00e0 autorisation d\u2019exportation.<\/p>\n<p>&#8211; Dans le cadre europ\u00e9en, la France est signataire de la position commune prise par l\u2019UE en 2008 (<a href=\"http:\/\/eur-lex.europa.eu\/LexUriServ\/LexUriServ.do?uri=OJ:L:2008:335:0099:0103:FR:PDF\">2008\/944\/PESC<\/a>) et d\u00e9finissant les r\u00e8gles r\u00e9gissant le contr\u00f4le des exportations de technologie et d\u2019\u00e9quipements militaires. Outre le pr\u00e9ambule dithyrambique o\u00f9 l\u2019UE se pare des plus hautes et nobles ambitions, le document pr\u00e9cise tr\u00e8s clairement que ses signataires s\u2019engagent \u00e0 n\u2019exporter que dans le cas o\u00f9 le pays destinataire :<br \/>\n\u2022 respecte les obligations internationales,<br \/>\n\u2022 respecte les droits de l\u2019homme et le droit humanitaire international,<br \/>\n\u2022 ne connait pas de situation de tension ou de conflit susceptible de s\u2019aggraver,<br \/>\n\u2022 \u0153uvre \u00e0 pr\u00e9server la paix, la stabilit\u00e9 et la s\u00e9curit\u00e9 r\u00e9gionale,<br \/>\n\u2022 ne remet pas en cause la s\u00e9curit\u00e9 nationale des \u00c9tats signataires ou celle de leurs alli\u00e9s,<br \/>\n\u2022 ne soutient ou n\u2019encourage en aucune mani\u00e8re le terrorisme,<br \/>\n\u2022 ne comporte pas de risque de voir un d\u00e9tournement de la technologie ou des \u00e9quipements militaires dans le pays acheteur, ou de r\u00e9exportation de ceux-ci dans des conditions non souhait\u00e9es.<\/p>\n<p>&#8211; Enfin, sous l\u2019\u00e9gide de l\u2019ONU, notre pays a sign\u00e9 et ratifi\u00e9 le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Trait%C3%A9_sur_le_commerce_des_armes\">TCA<\/a> (Trait\u00e9 sur le commerce des armes), qui interdit toute transaction s\u2019il existe un risque s\u00e9rieux pour que les armes ou syst\u00e8mes livr\u00e9s, soient utilis\u00e9s de mani\u00e8re abusive pour perp\u00e9trer des <a href=\"https:\/\/www.oxfam.org\/fr\/campagnes\/droits-en-situation-de-crise\/le-traite-sur-le-commerce-des-armes-en-questions\">violations des droits humains ou des crimes de guerre<\/a>.<\/p>\n<p>Il ressort de ce rapide survol que nous conformant \u00e0 ces diff\u00e9rents cadres, nous devrions parvenir \u00e0 livrer une ou deux caisses de r\u00e9volvers \u00e0 grenaille aux gardes suisses du Vatican, mais gu\u00e8re plus.<\/p>\n<p>Or chose curieuse, et pour ne prendre qu\u2019une actualit\u00e9 r\u00e9cente, nous vendons des armes et des syst\u00e8mes de haute-technologie \u00e0 :<\/p>\n<p>1- la junte militaire \u00e9gyptienne parvenue au pouvoir apr\u00e8s un coup d\u2019\u00e9tat qui a destitu\u00e9 un gouvernement d\u00e9mocratiquement \u00e9lu,<\/p>\n<p>2- plus haut dans l\u2019horreur, plus loin dans le double langage, et d\u00e9n\u00e9gation absolue de l\u2019esprit et de la lettre de tous les trait\u00e9s et accords internationaux sign\u00e9s et ratifi\u00e9s par l\u2019auto-proclam\u00e9e Patrie des droits de l\u2019homme, nous commer\u00e7ons avec\u2026 l\u2019Arabie Saoudite !<\/p>\n<p>Difficile de faire pire que de vendre des armes \u00e0 une th\u00e9ocratie pratiquant ouvertement <a href=\"http:\/\/tempsreel.nouvelobs.com\/monde\/20150729.OBS3326\/plusieurs-centaines-de-mauritaniennes-destinees-a-l-esclavage-en-arabie-saoudite.html\">l\u2019esclavage<\/a>, pr\u00e9datrice des <a href=\"http:\/\/info.arte.tv\/fr\/larabie-saoudite-ce-pays-qui-decapite-les-droits-de-lhomme\">libert\u00e9s fondamentales<\/a>, et attribuant aux femmes un <a href=\"http:\/\/info.arte.tv\/fr\/arabie-saoudite-les-femmes-vont-enfin-pouvoir-voter\">statut d\u2019objets mobiliers<\/a> ?<\/p>\n<p>Eh bien si !<\/p>\n<p>S\u2019en f\u00e9liciter comme l\u2019a fait Manuel Valls, \u00e0 l\u2019heure m\u00eame o\u00f9 ces armes aidaient tr\u00e8s probablement \u00e0 perp\u00e9trer des <a href=\"http:\/\/www.lefigaro.fr\/international\/2015\/10\/13\/01003-20151013ARTFIG00176-au-yemen-des-crimes-de-guerre-dans-l-indifference.php\">crimes de guerre au Y\u00e9men<\/a>, il est vrai dans l\u2019indiff\u00e9rence g\u00e9n\u00e9rale et un quasi-silence m\u00e9diatique, suivant le bon vieil adage \u00ab pas d\u2019images, pas de probl\u00e8mes \u00bb. Serait-ce que les m\u00e9dias <em>mainstream<\/em> ont \u00e0 c\u0153ur de ne pas indisposer les industriels fran\u00e7ais de l\u2019armement ? On n\u2019ose le croire, peut-\u00eatre un oubli ?<\/p>\n<p>Cependant ce qui risque de ne pas \u00eatre oubli\u00e9, c\u2019est le message sans ambig\u00fcit\u00e9 que nous adressons \u00e0 la jeunesse du Moyen-Orient : si vos bourreaux ont le bon go\u00fbt d\u2019acheter nos mat\u00e9riels et de nous vendre vos richesses, nous les soutiendrons, m\u00eame s\u2019ils vous massacrent. Il en r\u00e9sulte une politique \u00e9trang\u00e8re totalement schizophr\u00e8ne, o\u00f9 nous combattons le terrorisme islamiste\u2026 tout en l\u2019alimentant !<\/p>\n<p>Mais sans doute ne sommes-nous pas assez instruits pour comprendre la subtilit\u00e9 de la politique \u00e9trang\u00e8re de &lsquo;notre&rsquo; gouvernement. Alors pour tous ceux et celles qui trop mal-comprenant(e)s n\u2019ont pas fait l\u2019ENA, voici un petit tableau explicatif pour nous permettre, \u00f4 peuple ignorant, de faire la distinction entre les gentils alli\u00e9s que nous d\u00e9corons (quoique on ne peut plus <a href=\"http:\/\/www.liberation.fr\/planete\/2016\/03\/07\/arabie-saoudite-les-revers-d-une-legion-d-honneur_1438066\">discr\u00e8tement<\/a>), et les barbares sanguinaires que nous combattons:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-83300 aligncenter\" src=\"http:\/\/www.pauljorion.com\/blog\/wp-content\/uploads\/Publicit\u00e9-comparative.jpeg.jpg\" alt=\"Publicit\u00e9 comparative.jpeg\" width=\"700\" height=\"1400\" \/><\/p>\n<p>En r\u00e9sum\u00e9, puisqu&rsquo;il a \u00e9t\u00e9 commis l&rsquo;idiotie d&rsquo;instruire les peuples, l\u2019oligarchie leur a \u00e9crit des trait\u00e9s et des constitutions prouvant noir sur blanc qu\u2019ils vivent en d\u00e9mocratie. Dormez en paix, braves gens, tout ce qu&rsquo;il est bon pour vous de savoir continuera de vous \u00eatre communiqu\u00e9\u00a0<a href=\"http:\/\/www.pauljorion.com\/blog\/2016\/03\/09\/modernite-sociale-et-journaux-televises-par-michel-leis\/#more-83293\">au 20h<\/a> !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. \u00c0 l\u2019heure o\u00f9 le projet de loi El Khomri d\u00e9truit les acquis sociaux pour mieux les prot\u00e9ger, force est de constater qu\u2019il n\u2019y a pas que sur la sc\u00e8ne politique int\u00e9rieure que l\u2019\u00e9cart entre les paroles et les actes devient abyssal, c\u2019est \u00e9galement le cas dans le monde merveilleux des ventes d\u2019armes. Je [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2597,3594,4454,1627,3001],"tags":[],"class_list":["post-83297","post","type-post","status-publish","format-standard","hentry","category-democratie-2","category-ethique-2","category-france","category-geopolitique-2","category-guerre-2"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/83297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=83297"}],"version-history":[{"count":15,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/83297\/revisions"}],"predecessor-version":[{"id":83317,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/83297\/revisions\/83317"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=83297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=83297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=83297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}