{"id":85908,"date":"2016-05-25T12:00:24","date_gmt":"2016-05-25T10:00:24","guid":{"rendered":"http:\/\/www.pauljorion.com\/blog\/?p=85908"},"modified":"2016-05-25T10:11:30","modified_gmt":"2016-05-25T08:11:30","slug":"mao-en-continuateur-de-formes-de-pensee-chinoises-plurimillenaires-par-dd-dh","status":"publish","type":"post","link":"https:\/\/www.pauljorion.com\/blog\/2016\/05\/25\/mao-en-continuateur-de-formes-de-pensee-chinoises-plurimillenaires-par-dd-dh\/","title":{"rendered":"Mao en continuateur de formes de pens\u00e9e chinoises plurimill\u00e9naires, par DD &#038; DH"},"content":{"rendered":"<blockquote>\n<p style=\"text-align: left;\">Billet invit\u00e9.<\/p>\n<\/blockquote>\n<p>Nous ne ferons ici que reprendre les th\u00e8ses brillamment d\u00e9velopp\u00e9es, et d&rsquo;une extraordinaire clairvoyance, d\u00e8s les ann\u00e9es 70 (en pleine R\u00e9volution culturelle), par Pierre Ryckmans (alias Simon Leys) et Ren\u00e9 Etiemble. <!--more-->A savoir que la Chine de Mao, qu&rsquo;on exhibait si volontiers sous nos cieux comme un parangon de marxisme-l\u00e9ninisme, n&rsquo;\u00e9tait qu&rsquo;un leurre et un genre de contrefa\u00e7on. Combien de beaux esprits, et des mieux form\u00e9s, de chez nous s&rsquo;y laiss\u00e8rent prendre ? Il leur aurait suffi, pour \u00e9viter le pi\u00e8ge o\u00f9 ils se sont jet\u00e9s, d&rsquo;avoir un peu de curiosit\u00e9 pour la Chine d&rsquo;avant 1921 (puisque c&rsquo;\u00e9tait, fondation du PCC oblige, la date inaugurale au-del\u00e0 de laquelle ils auraient jug\u00e9 inconvenant et m\u00eame h\u00e9r\u00e9tique de remonter !).<br \/>\nSoit dit en passant, l&rsquo;histoire de nos \u00ab\u00a0mao\u00efstes\u00a0\u00bb est tout \u00e0 fait semblable \u00e0 celle que nous conte Fontenelle \u00e0 propos de \u00ab\u00a0la dent d&rsquo;or\u00a0\u00bb : le bruit ayant couru qu&rsquo;\u00e0 un enfant de Sil\u00e9sie une dent d&rsquo;or avait pouss\u00e9 en remplacement d&rsquo;une dent naturelle, tous les savants, th\u00e9ologiens et autres sommit\u00e9s acad\u00e9miques du moment s&rsquo;adonn\u00e8rent \u00e0 son propos \u00e0 une foule de commentaires qui donn\u00e8rent bient\u00f4t naissance \u00e0 autant de th\u00e8ses et contre-th\u00e8ses aussi doctes que fumeuses. Lesquelles furent bien s\u00fbr consign\u00e9es pour la post\u00e9rit\u00e9 dans une grande quantit\u00e9 d&rsquo;\u00e9pais et pontifiants volumes. Jusqu&rsquo;au jour o\u00f9 un orf\u00e8vre eut l&rsquo;id\u00e9e d&rsquo;examiner la dent et qu&rsquo;il s&rsquo;av\u00e9ra qu&rsquo;on avait affaire \u00e0 une supercherie : une simple feuille d&rsquo;or avait \u00e9t\u00e9 habilement appliqu\u00e9e sur une dent parfaitement naturelle ! Mais, comme dit Fontenelle,\u00a0\u00bb on commen\u00e7a par faire des livres\u00a0\u00bb&#8230;\u00a0Le marxisme chinois a exist\u00e9, c&rsquo;est ind\u00e9niable, mais au m\u00eame titre que cette feuille d&rsquo;or !<\/p>\n<p>C&rsquo;est donc, \u00e0 c\u00f4t\u00e9 de Marx et L\u00e9nine, aussi du c\u00f4t\u00e9 des fondements de la pens\u00e9e chinoise sous ses trois formes majeures qu&rsquo;il faut diriger le faisceau de notre lampe de poche pour repenser \u00e0 nouveaux frais la Chine contemporaine.<\/p>\n<p>&#8212; Le tao\u00efsme (tel qu&rsquo;il s&rsquo;exprime \u00e0 travers Laozi et Zhuangzi) qu&rsquo;on peut coupler ici \u00e0 l&rsquo;Ecole du Yin-yang alimente, sous une forme plut\u00f4t souterraine, \u00e0 la mani\u00e8re d&rsquo;une source, et non dite (parce que le besoin de se dire tao\u00efste n&rsquo;est pas \u00e9prouv\u00e9), tous les aspects de la vie chinoise au quotidien. Il impr\u00e8gne en particulier la vie des campagnes et Mao en a \u00e9t\u00e9 imbib\u00e9, comme tous les paysans, dans son Hunan natal. On peut donc le consid\u00e9rer, pour aller vite, comme la matrice plus ou moins inconsciente de la pens\u00e9e chinoise et le substrat non formalis\u00e9 de toute lecture chinoise du monde tel qu&rsquo;il va. Les Chinois sont tao\u00efstes comme M. Jourdain faisait de la prose. Sans le savoir.<\/p>\n<p>&#8212; Le confucianisme. L&rsquo;av\u00e8nement de la RPC n&rsquo;a pas ouvert une page blanche dans l&rsquo;histoire de la Chine. L&rsquo;h\u00e9ritage confuc\u00e9en (\u00e0 travers les confuc\u00e9ens \u00ab\u00a0orthodoxes\u00a0\u00bb que sont Confucius lui-m\u00eame et Mencius) est tout \u00e0 fait pr\u00e9sent chez les fondateurs de la \u00ab\u00a0Nouvelle Chine\u00a0\u00bb. Le postulat d&rsquo;une nature humaine fondamentalement bonne y entra\u00eene la conviction que toute d\u00e9viation, faute ou sortie de route ne peut \u00eatre due qu&rsquo;\u00e0 un d\u00e9faut d&rsquo;\u00e9ducation. Par cette \u00e9ducation, si elle est bien men\u00e9e, la nature humaine peut m\u00eame \u00eatre constamment am\u00e9lior\u00e9e. Le confucianisme suppose une foi profonde dans le toujours possible perfectionnement de l&rsquo;homme. L&rsquo;apport marxiste vient pr\u00e9cis\u00e9ment renforcer cette confiance : c&rsquo;est le mythe de \u00ab\u00a0l&rsquo;Homme nouveau dont accouchera la Chine nouvelle\u00a0\u00bb ! Mao est le \u00ab\u00a0Grand Instituteur\u00a0\u00bb en m\u00eame temps que le \u00ab\u00a0Grand Timonier\u00a0\u00bb. Cette volont\u00e9 d&rsquo;\u00e9duquer \u00e0 marches forc\u00e9es s&rsquo;est tout de suite manifest\u00e9e par l&rsquo;alphab\u00e9tisation (si on peut user de ce mot pour une langue non alphab\u00e9tique) g\u00e9n\u00e9ralis\u00e9e et la multiplication des \u00e9coles sur tout le territoire. Mais elle s&rsquo;est aussi traduite par les innombrables \u00ab\u00a0mouvements\u00a0\u00bb (\u00ab\u00a0yundong\u00a0\u00bb en chinois) qui ont jalonn\u00e9 le \u00ab\u00a0r\u00e8gne\u00a0\u00bb de Mao et \u00e9taient autant de \u00ab\u00a0le\u00e7ons\u00a0\u00bb en m\u00eame temps que des offensives mobilisatrices permanentes destin\u00e9es \u00e0 augmenter le niveau de conscience des \u00ab\u00a0masses\u00a0\u00bb : par exemple (il y en eut des centaines !) \u00ab\u00a0contre les mauvais penchants\u00a0\u00bb, \u00ab\u00a0contre les vieilles id\u00e9es f\u00e9odales\u00a0\u00bb&#8230; En th\u00e9orie, cet effort d&rsquo;\u00e9ducation et de perfectionnement devait prendre la forme d&rsquo;une harmonieuse impr\u00e9gnation : il devait s&rsquo;agir, Mao emprunta l&rsquo;expression \u00e0 Mencius, de la m\u00e9thode \u00ab\u00a0brise l\u00e9g\u00e8re et pluie printani\u00e8re\u00a0\u00bb permettant l&rsquo;\u00e9panouissement de \u00ab\u00a0cent fleurs\u00a0\u00bb et l&rsquo;\u00e9mulation de \u00ab\u00a0cent \u00e9coles\u00a0\u00bb (vocabulaire emprunt\u00e9 aux confuc\u00e9ens canoniques en personne). Marche r\u00e9solue vers un \u00ab\u00a0avenir radieux \u00a0\u00bb sur une route que Mao admettait \u00ab\u00a0sinueuse\u00a0\u00bb, mais que quelques \u00ab\u00a0rectifications\u00a0\u00bb (\u00ab\u00a0zheng feng\u00a0\u00bb en chinois, litt\u00e9ralement \u00ab\u00a0rectifier le vent\u00a0\u00bb) en chemin allaient aplanir. Cela se r\u00e9alisa plus ou moins selon l&rsquo;harmonieux plan pr\u00e9vu jusqu&rsquo;en 1957. Mais, \u00e0 cause des oppositions et critiques qui se firent jour par le biais des \u00ab\u00a0cent fleurs\u00a0\u00bb (qui avaient quelques \u00e9pines !) et sous la pression d&rsquo;\u00e9v\u00e9nements ext\u00e9rieurs (parution du Rapport Khroutchev, \u00e9v\u00e9nements de Budapest&#8230;) Mao fut amen\u00e9 \u00e0 chercher de plus en plus un mod\u00e8le aupr\u00e8s des tenants de la troisi\u00e8me \u00ab\u00a0Ecole\u00a0\u00bb chinoise : les l\u00e9gistes (ou Ecole de la Loi : \u00ab\u00a0fa jia\u00a0\u00bb)<\/p>\n<p>&#8212; Le l\u00e9gisme : la voie qui permit l&rsquo;instauration de l&rsquo;Empire par Qin Shi Huangdi en 221 avant notre \u00e8re. Ses initiateurs, Han Feizi et Li Si, ont pourtant \u00e9t\u00e9 les \u00e9l\u00e8ves d&rsquo;un confuc\u00e9en, Xun Zi (310-235), mais d&rsquo;un confuc\u00e9en h\u00e9t\u00e9rodoxe qui ne devint jamais canonique parce qu&rsquo;il postulait que l&rsquo;Homme \u00e9tait mauvais par nature. C&rsquo;est en effet le postulat adopt\u00e9 par les l\u00e9gistes qui ne croient pas aux bienfaits vertueux de l&rsquo;\u00e9ducation, mais pr\u00e9conisent un syst\u00e8me de gouvernement tr\u00e8s ferme bas\u00e9 sur la rigueur absolue de la loi et la mise ne \u0153uvre syst\u00e9matique, en toute circonstance, du couple ch\u00e2timents \/r\u00e9compenses. Ch\u00e2timents surtout ! La tendance autocratique forte du l\u00e9gisme va transpara\u00eetre dans les choix de Mao \u00e0 partir de 1958. Cela prend la forme d&rsquo;un volontarisme brutalement impos\u00e9 : politique de travaux gigantesques (barrages, creusement de canaux, doublement souterrain des villes&#8230;) \u00e0 l&rsquo;image de l&rsquo;unification de la Grande Muraille par le Premier Empereur. L&rsquo;entra\u00eenement militaire se g\u00e9n\u00e9ralise et le mod\u00e8le en vigueur de \u00ab\u00a0l&rsquo;ouvrier\/paysan\/soldat\u00a0\u00bb renforce l&#8217;embrigadement id\u00e9ologique. Mao lance la Chine dans le d\u00e9fi insens\u00e9 du Grand Bond en avant. L&rsquo;activisme r\u00e9volutionnaire occupe tout le temps disponible de la population et la mobilisation devient permanente autour du concept de \u00ab\u00a0lutte des classes\u00a0\u00bb pour culminer dans le d\u00e9clenchement de la R\u00e9volution Culturelle (1966-1976). Mao vieillissant semble s&rsquo;identifier de plus en plus \u00e0 Qin Shi Huangdi (hasard ? c&rsquo;est en 74 qu&rsquo;on d\u00e9couvre la grande arm\u00e9e d&rsquo;argile de son tombeau) : m\u00eame combat contre les intellectuels, la \u00ab\u00a0neuvi\u00e8me cat\u00e9gorie puante\u00a0\u00bb (Qin Shi Huangdi avait fait br\u00fbler tous les livres confuc\u00e9ens), m\u00eame campagne contre Confucius (le \u00ab\u00a0mouvement\u00a0\u00bb Pi Lin, Pi Kong), m\u00eame difficult\u00e9 \u00e0 assurer sa succession et m\u00eame chute de ses fid\u00e8les (la Bande des Quatre) \u00e0 sa mort en 76.<\/p>\n<p>Nous laissons la conclusion \u00e0 Etiemble (conf\u00e9rence de d\u00e9cembre 1974 \u00e0 l&rsquo;Institut des Hautes Etudes de D\u00e9fense Nationale) : \u00ab\u00a0&#8230;la pens\u00e9e-mao-ts\u00f6-tong, pour employer la formule obligatoire et rituelle, est un ensemble de principes confuc\u00e9ens, corrig\u00e9s par la pratique de Ts&rsquo;in Che Houang-ti, et contamin\u00e9s d&#8217;emprunts au communisme de M\u00f6-tseu.\u00a0\u00bb<\/p>\n<p>Note \u00e0 propos de M\u00f6-tseu \u00e9voqu\u00e9 ci-dessus :<br \/>\nSon apport \u00e0 la pens\u00e9e chinoise antique peut \u00eatre consid\u00e9r\u00e9 comme l&rsquo;amorce d&rsquo;une \u00ab\u00a0quatri\u00e8me voie\u00a0\u00bb, mais demeur\u00e9e mineure et cantonn\u00e9e \u00e0 l&rsquo;\u00e9poque de son initiateur (deuxi\u00e8me moiti\u00e9 du Ve avant notre \u00e8re). Laissons \u00e0 son propos la parole \u00e0 Etiemble :<br \/>\n\u00ab\u00a0&#8230; les Gardes rouges avaient un autre garant en M\u00f6-tseu, th\u00e9oricien de communaut\u00e9s grossi\u00e8rement fraternelles, f\u00e9rocement \u00e9galitaires, hostiles \u00e0 tous les arts et puritaines ; pacifistes militaris\u00e9s \u00e0 outrance, les disciples de M\u00f6-tseu affirmaient qu&rsquo;on doit toujours \u00eatre d&rsquo;accord avec le sup\u00e9rieur, ne jamais l&rsquo;\u00eatre avec l&rsquo;inf\u00e9rieur, et se piquaient de marcher pieds nus sur le fil d&rsquo;une \u00e9p\u00e9e, d&rsquo;entrer dans un brasier sur l&rsquo;ordre de leur chef. Non moins hostiles \u00e0 Confucius antique que les gens du \u00ab\u00a0fa kia\u00a0\u00bb, ils l&rsquo;\u00e9taient pour d&rsquo;autres raisons : reprochant \u00e0 Confucius de perp\u00e9tuer l&rsquo;amour du clan, l&rsquo;esprit de famille, ils pr\u00eachaient un pr\u00e9tendu \u00ab\u00a0amour mutuel\u00a0\u00bb qui n&rsquo; a rien \u00e0 voir avec la charit\u00e9 chr\u00e9tienne et rappelle plut\u00f4t le verbiage humanitaire de ceux qui pleurnichent sur ce qui se passe loin d&rsquo;eux, mais ne sont pas capables de faire pour leur voisin le geste d&rsquo;amour qui le sauverait, ou du moins l&rsquo;aiderait \u00e0 vivre.\u00a0\u00bb (ibid)<\/p>\n<p>R\u00e9f\u00e9rences bibliographiques :<br \/>\nRen\u00e9 Etiemble : \u00ab\u00a0Quarante ans de mon mao\u00efsme\u00a0\u00bb (Gallimard, 1976)<\/p>\n<p>Simon Leys : \u00ab\u00a0Les habits neufs du Pr\u00e9sident Mao\u00a0\u00bb (Champ Libre, 1971)<\/p>\n<p>Claude Larre\u00a0: \u00ab\u00a0Mao et la vieille Chine \u00bb (EPI, 1972)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Billet invit\u00e9. Nous ne ferons ici que reprendre les th\u00e8ses brillamment d\u00e9velopp\u00e9es, et d&rsquo;une extraordinaire clairvoyance, d\u00e8s les ann\u00e9es 70 (en pleine R\u00e9volution culturelle), par Pierre Ryckmans (alias Simon Leys) et Ren\u00e9 Etiemble.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4489],"tags":[4840,182,2994,4839],"class_list":["post-85908","post","type-post","status-publish","format-standard","hentry","category-chine","tag-etiemble","tag-mao","tag-maoisme","tag-simon-leys"],"_links":{"self":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/85908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/comments?post=85908"}],"version-history":[{"count":4,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/85908\/revisions"}],"predecessor-version":[{"id":85912,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/posts\/85908\/revisions\/85912"}],"wp:attachment":[{"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/media?parent=85908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/categories?post=85908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pauljorion.com\/blog\/wp-json\/wp\/v2\/tags?post=85908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}